{"id":7,"count":26,"description":"","link":"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/altcoins\/","name":"\u5c71\u5be8\u5e63\u65b0\u805e","slug":"altcoins","taxonomy":"category","parent":10,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u5c71\u5be8\u5e63\u65b0\u805e - 99Bitcoins China<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/altcoins\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u5c71\u5be8\u5e63\u65b0\u805e - 99Bitcoins China\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/altcoins\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins China\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/category\\\/news\\\/altcoins\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/category\\\/news\\\/altcoins\\\/\",\"name\":\"\u5c71\u5be8\u5e63\u65b0\u805e - 99Bitcoins China\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/category\\\/news\\\/altcoins\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/category\\\/news\\\/altcoins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u65b0\u805e\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u5c71\u5be8\u5e63\u65b0\u805e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/\",\"name\":\"99Bitcoins China\",\"description\":\"A non technical blog about Bitcoin - Tutorial, Reviews and Guides\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/#organization\",\"name\":\"99Bitcoins\",\"alternateName\":\"99Bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2026\\\/02\\\/99Icon.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2026\\\/02\\\/99Icon.svg\",\"width\":38,\"height\":42,\"caption\":\"99Bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/zh-tw\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u5c71\u5be8\u5e63\u65b0\u805e - 99Bitcoins China","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/altcoins\/","og_locale":"en_US","og_type":"article","og_title":"\u5c71\u5be8\u5e63\u65b0\u805e - 99Bitcoins China","og_url":"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/altcoins\/","og_site_name":"99Bitcoins China","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/altcoins\/","url":"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/altcoins\/","name":"\u5c71\u5be8\u5e63\u65b0\u805e - 99Bitcoins China","isPartOf":{"@id":"https:\/\/99bitcoins.com\/zh-tw\/#website"},"breadcrumb":{"@id":"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/altcoins\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/altcoins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/zh-tw\/"},{"@type":"ListItem","position":2,"name":"\u65b0\u805e","item":"https:\/\/99bitcoins.com\/zh-tw\/category\/news\/"},{"@type":"ListItem","position":3,"name":"\u5c71\u5be8\u5e63\u65b0\u805e"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/zh-tw\/#website","url":"https:\/\/99bitcoins.com\/zh-tw\/","name":"99Bitcoins China","description":"A non technical blog about Bitcoin - Tutorial, Reviews and Guides","publisher":{"@id":"https:\/\/99bitcoins.com\/zh-tw\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/zh-tw\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/zh-tw\/#organization","name":"99Bitcoins","alternateName":"99Bitcoins","url":"https:\/\/99bitcoins.com\/zh-tw\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/99bitcoins.com\/zh-tw\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/zh-tw\/wp-content\/uploads\/sites\/17\/2026\/02\/99Icon.svg","contentUrl":"https:\/\/99bitcoins.com\/zh-tw\/wp-content\/uploads\/sites\/17\/2026\/02\/99Icon.svg","width":38,"height":42,"caption":"99Bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/zh-tw\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/zh-tw\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/zh-tw\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/99bitcoins.com\/zh-tw\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/zh-tw\/wp-json\/wp\/v2\/categories\/10"}],"wp:post_type":[{"href":"https:\/\/99bitcoins.com\/zh-tw\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}