{"id":766,"count":1,"description":"","link":"https:\/\/99bitcoins.com\/nl\/tag\/western-union\/","name":"Western Union","slug":"western-union","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Western Union Archives - 99Bitcoins NL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/nl\/tag\/western-union\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Western Union Archives - 99Bitcoins NL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/nl\/tag\/western-union\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins NL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/tag\\\/western-union\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/tag\\\/western-union\\\/\",\"name\":\"Western Union Archives - 99Bitcoins NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/tag\\\/western-union\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/tag\\\/western-union\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Western Union\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/\",\"name\":\"99Bitcoins NL\",\"description\":\"Een niet-technisch blog over Bitcoin - Tutorial, recensies en handleidingen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Western Union Archives - 99Bitcoins NL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/nl\/tag\/western-union\/","og_locale":"nl_NL","og_type":"article","og_title":"Western Union Archives - 99Bitcoins NL","og_url":"https:\/\/99bitcoins.com\/nl\/tag\/western-union\/","og_site_name":"99Bitcoins NL","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/99bitcoins.com\/nl\/tag\/western-union\/","url":"https:\/\/99bitcoins.com\/nl\/tag\/western-union\/","name":"Western Union Archives - 99Bitcoins NL","isPartOf":{"@id":"https:\/\/99bitcoins.com\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/99bitcoins.com\/nl\/tag\/western-union\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/nl\/tag\/western-union\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Western Union"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/nl\/#website","url":"https:\/\/99bitcoins.com\/nl\/","name":"99Bitcoins NL","description":"Een niet-technisch blog over Bitcoin - Tutorial, recensies en handleidingen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/tags\/766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/posts?tags=766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}