{"id":26143,"date":"2026-02-05T14:47:20","date_gmt":"2026-02-05T14:47:20","guid":{"rendered":"https:\/\/99bitcoins.com\/nl\/?p=26143"},"modified":"2026-02-05T14:47:07","modified_gmt":"2026-02-05T14:47:07","slug":"ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/","title":{"rendered":"Ethereum lanceert privacy layer met focus op AI &#8211; kan update ETH naar $3000 stuwen?"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Ethereum ($ETH) lanceert een nieuwe privacy layer met focus op AI, maar de impact op de koers blijft op korte termijn onzeker. Hoewel de update de adoptie op lange termijn kan versnellen, oogt het technische plaatje nog zwak. Hieruit rijst dan ook de vraag: wat gaat Ethereum doen?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">In dit artikel gaan we hier dieper op in en bekijken we wat dit betekent voor <a href=\"https:\/\/99bitcoins.com\/nl\/welke-crypto-kopen\/veelbelovende-crypto\/\">de veelbelovende crypto<\/a>.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Payy lanceert privacy layer-2 op Ethereum<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Cryptoproject Payy, dat een privacygerichte wallet en een crypto-bankkaart aanbiedt, heeft een nieuwe Ethereum layer-2 gelanceerd die is ontworpen voor priv\u00e9-transacties met ERC-20-tokens.<\/span><\/p>\n<p><span style=\"font-weight: 400\">In een aankondiging op X op woensdag liet Payy weten dat gebruikers het netwerk als een aangepaste chain in MetaMask kunnen toevoegen. ERC-20-transacties die op dit netwerk worden uitgevoerd, worden standaard via zogenoemde privacy pools gerouteerd, zonder dat aanpassingen aan smart contracts nodig zijn.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Ethereum is for privacy. <a href=\"https:\/\/t.co\/xnj0sWTC5K\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/xnj0sWTC5K<\/a><\/p>\n<p>&mdash; Ethereum (@ethereum) <a href=\"https:\/\/twitter.com\/ethereum\/status\/2019118651270656246?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">February 4, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Volgens Payy richt het netwerk zich op twee belangrijke gebruikersgroepen: instellingen en fintechbedrijven die financi\u00eble stromen on-chain willen brengen met beperkte publieke traceerbaarheid, en crypto-gebruikers die privacytools willen gebruiken zonder met meerdere wallets te hoeven werken.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Het netwerk is compatibel met elke Ethereum Virtual Machine (EVM)-wallet. Op de website van het project staat dat de layer-2 vooral bedoeld is om priv\u00e9-transacties met stablecoins mogelijk te maken, al ondersteunt het netwerk in principe alle ERC-20-tokens.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Hoe werkt de nieuwe privacy layer?\u00a0<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Een opvallend element van het Payy-netwerk is dat ERC-20-transfers standaard priv\u00e9 verlopen, zonder dat bestaande smart contracts hoeven te worden aangepast. Op het reguliere Ethereum-netwerk zijn transacties volledig transparant, waardoor bedragen en adressen publiek zichtbaar blijven. Dat vormt een drempel voor bedrijven en gebruikers die waarde hechten aan financi\u00eble privacy.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Op Payy\u2019s layer-2 worden tokentransacties automatisch via privacy pools geleid. Hierdoor blijven de betrokken adressen en bedragen afgeschermd, terwijl dezelfde tokens en contracten gebruikt kunnen blijven worden. Dat verlaagt de technische drempel voor adoptie aanzienlijk.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Voor enterprises betekent dit dat ze betalingen, salarisstromen of treasury-transacties on-chain kunnen uitvoeren zonder concurrentiegevoelige data prijs te geven. Tegelijk krijgen privacybewuste gebruikers een eenvoudige manier om ERC-20-tokens discreet te versturen, wat de praktische inzetbaarheid van Ethereum verder vergroot.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Concurrentie groeit voor privacy-oplossingen<\/span><\/h2>\n<p><span style=\"font-weight: 400\">De lancering betekent een flinke uitbreiding ten opzichte van Payy\u2019s oorspronkelijke producten, die bestonden uit een privacygerichte wallet en een crypto-bankkaart die medio 2025 werden ge\u00efntroduceerd. Volgens het bedrijf zijn sindsdien ongeveer 100.000 gebruikers aangesloten.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Met de nieuwe layer-2 begeeft Payy zich in een steeds competitievere privacysector. Op Ethereum gebaseerde oplossingen zoals Aztec Network en Railgun bieden al vergelijkbare functionaliteit. Tegelijkertijd zagen privacygerichte cryptovaluta zoals Zcash en Monero in 2025 een sterke toename in populariteit, tijdens een bredere privacy-hausse in de markt.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ook Ethereum-ontwikkelaars werken aan native privacyverbeteringen. In oktober werd gemeld dat privacyfuncties op wallet-niveau worden overwogen als onderdeel van de zogeheten Kohaku-roadmap. Die moet de afhankelijkheid van gecentraliseerde transactie-trackers verminderen en standaard priv\u00e9 verzenden en ontvangen mogelijk maken.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Toch zal dit positieve Ethereum nieuws niet veel kunnen betekenen voor de koers op korte termijn. Op lange termijn is dit wel een zeer positieve ontwikkeling. Laten we het technische plaatje bekijken om zo een beter beeld te vormen van <a href=\"https:\/\/99bitcoins.com\/nl\/welke-crypto-kopen\/ethereum-verwachting\/#:~:text=Ethereum%20koers%20verwachting%202025,-De%20Ethereum%20koers&amp;text=In%20een%20ongunstig%20scenario%20zakt,blockchains%20zoals%20Solana%20of%20TON.\">de Ethereum verwachting<\/a>.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Kan update ETH naar $3000 stuwen?<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Ethereum laat voorzichtige herstel\u00adsignalen zien nadat de koers een intraday-dieptepunt van $2068 testte en vervolgens weer boven de $2.000 noteerde op donderdag. Toch wordt het herstel afgeremd door de dalende 50-daagse Exponential Moving Average (EMA) rond $2899, de 100-daagse EMA op $3105 en de 200-daagse EMA op $3232. Deze niveaus vormen belangrijke weerstanden.<\/span><\/p>\n<p><span style=\"font-weight: 400\">De Relative Strength Index (RSI) is gedaald naar 22, wat aangeeft dat de daily oversold is en dat bearish momentum toeneemt. Een verdere daling van de RSI kan een uitgebreidere sell-off veroorzaken onder $2000, met een mogelijke beweging richting $1800, een niveau dat begin mei al werd getest.<\/span><\/p>\n<figure style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.fxstreet.com\/_next\/image?url=https%3A%2F%2Feditorial.fxsstatic.com%2Fmiscelaneous%2FETHUSDT_2026-02-05_14-54-40-1770292504330-1770292504331.png&amp;w=1536&amp;q=95\" alt=\"Ethereum koers\" width=\"1536\" height=\"1102\" \/><figcaption class=\"wp-caption-text\">Ethereum koers. Bron: TradingView<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400\">Ondanks het negatieve technische beeld en het feit dat de MACD nog onder de signaallijn ligt, beginnen de rode histogram\u00adbalken te krimpen. Dat kan traders aanzetten tot meer risicobereidheid, wat de koopdruk kan verhogen en een herstel richting de $2400-weerstandszone kan versnellen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ethereum ($ETH) lanceert een nieuwe privacy layer met focus op AI, maar de impact op de koers blijft op korte termijn onzeker. Hoewel de update de adoptie op lange termijn kan versnellen, oogt het technische plaatje nog zwak. Hieruit rijst dan ook de vraag: wat gaat Ethereum doen?\u00a0 In dit artikel gaan we hier dieper..<\/p>\n","protected":false},"author":136177,"featured_media":25508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[10],"tags":[42,105,62,635,576],"coin":[59],"class_list":["post-26143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-eth","tag-ethereum-koers","tag-ethereum-nieuws","tag-privacy-coins-crypto","tag-wat-gaat-ethereum-doen"],"wppr_data":{"cwp_meta_box_check":"No"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ethereum lanceert privacy layer: stijgt de ETH koers naar $3000?<\/title>\n<meta name=\"description\" content=\"Nieuwe privacy layer op Ethereum moet adoptie stimuleren. Kan dit de ETH koers uit de dip trekken en richting $3000 brengen?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ethereum lanceert privacy layer: stijgt de ETH koers naar $3000?\" \/>\n<meta property=\"og:description\" content=\"Nieuwe privacy layer op Ethereum moet adoptie stimuleren. Kan dit de ETH koers uit de dip trekken en richting $3000 brengen?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins NL\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T14:47:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2026\/01\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rutger Kant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rutger Kant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/\"},\"author\":{\"name\":\"Rutger Kant\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#\\\/schema\\\/person\\\/1f5eb2a36a74587fbeb80d0cbc0a35d2\"},\"headline\":\"Ethereum lanceert privacy layer met focus op AI &#8211; kan update ETH naar $3000 stuwen?\",\"datePublished\":\"2026-02-05T14:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/\"},\"wordCount\":694,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2026\\\/01\\\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp\",\"keywords\":[\"ETH\",\"ethereum koers\",\"Ethereum nieuws\",\"privacy coins crypto\",\"wat gaat ethereum doen\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"nl-NL\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/\",\"name\":\"Ethereum lanceert privacy layer: stijgt de ETH koers naar $3000?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2026\\\/01\\\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp\",\"datePublished\":\"2026-02-05T14:47:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#\\\/schema\\\/person\\\/1f5eb2a36a74587fbeb80d0cbc0a35d2\"},\"description\":\"Nieuwe privacy layer op Ethereum moet adoptie stimuleren. Kan dit de ETH koers uit de dip trekken en richting $3000 brengen?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2026\\\/01\\\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2026\\\/01\\\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp\",\"width\":850,\"height\":479,\"caption\":\"Ethereum lanceert privacy layer met focus op AI - kan update ETH naar $3000 stuwen?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nieuws\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ethereum lanceert privacy layer met focus op AI &#8211; kan update ETH naar $3000 stuwen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/\",\"name\":\"99Bitcoins NL\",\"description\":\"Een niet-technisch blog over Bitcoin - Tutorial, recensies en handleidingen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#\\\/schema\\\/person\\\/1f5eb2a36a74587fbeb80d0cbc0a35d2\",\"name\":\"Rutger Kant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g\",\"caption\":\"Rutger Kant\"},\"description\":\"Rutger Kant is een gespecialiseerde cryptojournalist met een achtergrond in technologie en een scherp oog voor marktontwikkelingen binnen het digitale ecosysteem. Zijn interesse in crypto ontstond tijdens de bullmarkt van 2017, toen hij de impact van blockchaintechnologie voor het eerst echt doorzag. In 2025 sloot hij zich aan bij CoinSpeaker als vaste bijdrager. Rutger studeerde Technische Bestuurskunde aan de TU Delft en verdiepte zich tijdens zijn opleiding in de maatschappelijke impact van datagedreven innovaties binnen de financi\u00eble sector. Zijn onderzoek richtte zich onder meer op alternatieve investeringsstrategie\u00ebn in de cryptomarkt.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/author\\\/rutgerkant\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ethereum lanceert privacy layer: stijgt de ETH koers naar $3000?","description":"Nieuwe privacy layer op Ethereum moet adoptie stimuleren. Kan dit de ETH koers uit de dip trekken en richting $3000 brengen?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/","og_locale":"nl_NL","og_type":"article","og_title":"Ethereum lanceert privacy layer: stijgt de ETH koers naar $3000?","og_description":"Nieuwe privacy layer op Ethereum moet adoptie stimuleren. Kan dit de ETH koers uit de dip trekken en richting $3000 brengen?","og_url":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/","og_site_name":"99Bitcoins NL","article_published_time":"2026-02-05T14:47:20+00:00","og_image":[{"width":850,"height":479,"url":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2026\/01\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp","type":"image\/webp"}],"author":"Rutger Kant","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rutger Kant","Est. reading time":"4 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/"},"author":{"name":"Rutger Kant","@id":"https:\/\/99bitcoins.com\/nl\/#\/schema\/person\/1f5eb2a36a74587fbeb80d0cbc0a35d2"},"headline":"Ethereum lanceert privacy layer met focus op AI &#8211; kan update ETH naar $3000 stuwen?","datePublished":"2026-02-05T14:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/"},"wordCount":694,"image":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2026\/01\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp","keywords":["ETH","ethereum koers","Ethereum nieuws","privacy coins crypto","wat gaat ethereum doen"],"articleSection":["Altcoins"],"inLanguage":"nl-NL","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/","url":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/","name":"Ethereum lanceert privacy layer: stijgt de ETH koers naar $3000?","isPartOf":{"@id":"https:\/\/99bitcoins.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2026\/01\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp","datePublished":"2026-02-05T14:47:20+00:00","author":{"@id":"https:\/\/99bitcoins.com\/nl\/#\/schema\/person\/1f5eb2a36a74587fbeb80d0cbc0a35d2"},"description":"Nieuwe privacy layer op Ethereum moet adoptie stimuleren. Kan dit de ETH koers uit de dip trekken en richting $3000 brengen?","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/#primaryimage","url":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2026\/01\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp","contentUrl":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2026\/01\/BlackRock-voorspelt-ETH-toekomst-met-RWA-adoptie-koers-wanneer-stijgt-Ethereum.webp","width":850,"height":479,"caption":"Ethereum lanceert privacy layer met focus op AI - kan update ETH naar $3000 stuwen?"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/ethereum-lanceert-privacy-layer-stijgt-de-eth-koers-naar-3000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Nieuws","item":"https:\/\/99bitcoins.com\/nl\/nieuws\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/nl\/nieuws\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Ethereum lanceert privacy layer met focus op AI &#8211; kan update ETH naar $3000 stuwen?"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/nl\/#website","url":"https:\/\/99bitcoins.com\/nl\/","name":"99Bitcoins NL","description":"Een niet-technisch blog over Bitcoin - Tutorial, recensies en handleidingen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/nl\/#\/schema\/person\/1f5eb2a36a74587fbeb80d0cbc0a35d2","name":"Rutger Kant","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g","caption":"Rutger Kant"},"description":"Rutger Kant is een gespecialiseerde cryptojournalist met een achtergrond in technologie en een scherp oog voor marktontwikkelingen binnen het digitale ecosysteem. Zijn interesse in crypto ontstond tijdens de bullmarkt van 2017, toen hij de impact van blockchaintechnologie voor het eerst echt doorzag. In 2025 sloot hij zich aan bij CoinSpeaker als vaste bijdrager. Rutger studeerde Technische Bestuurskunde aan de TU Delft en verdiepte zich tijdens zijn opleiding in de maatschappelijke impact van datagedreven innovaties binnen de financi\u00eble sector. Zijn onderzoek richtte zich onder meer op alternatieve investeringsstrategie\u00ebn in de cryptomarkt.","url":"https:\/\/99bitcoins.com\/nl\/author\/rutgerkant\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/posts\/26143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/users\/136177"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/comments?post=26143"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/posts\/26143\/revisions"}],"predecessor-version":[{"id":26145,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/posts\/26143\/revisions\/26145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/media\/25508"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/media?parent=26143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/categories?post=26143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/tags?post=26143"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/coin?post=26143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}