{"id":16170,"date":"2025-09-23T13:25:18","date_gmt":"2025-09-23T13:25:18","guid":{"rendered":"https:\/\/99bitcoins.com\/nl\/?p=16170"},"modified":"2025-09-23T13:25:18","modified_gmt":"2025-09-23T13:25:18","slug":"chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/","title":{"rendered":"Chinese AI DeepSeek voorspelt crypto koersen van XRP, ETH en ADA voor eind 2025"},"content":{"rendered":"<p style=\"font-weight: 400\">Het Chinese AI-platform DeepSeek heeft nieuwe voorspellingen gedaan voor de beste altcoins. Volgens hun analyse kan XRP eind 2025 richting $10 stijgen, terwijl Ethereum ($ETH) mogelijk $12.000 tot $15.000 bereikt. Ook Cardano ($ADA) wordt sterk geacht, met een koersdoel van $2 tot $3. In dit artikel gaan we dieper in op deze voorspellingen en bekijken we de koersen op korte termijn.<\/p>\n<h2>XRP kan eind 2025 $10 bereiken<\/h2>\n<p style=\"font-weight: 400\">Volgens een analyse door het Chinese AI-platform DeepSeek zou XRP tegen eind 2025 een aanzienlijke groei kunnen doormaken, waarbij een prijsniveau van\u00a0$3 &#8211; $5\u00a0als een haalbaar scenario wordt gezien. DeepSeek benadrukt dat deze groei vooral afhangt van positieve regelgevingsontwikkelingen en toenemende adoptie voor betalingsverkeer.<img class=\"\" \/><\/p>\n<figure id=\"attachment_16173\" aria-describedby=\"caption-attachment-16173\" style=\"width: 735px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-16173\" src=\"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.26.png\" alt=\"XRP koers\" width=\"735\" height=\"479\" srcset=\"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.26.png 766w, https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.26-300x195.png 300w, https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.26-50x33.png 50w\" sizes=\"(max-width: 735px) 100vw, 735px\" \/><figcaption id=\"caption-attachment-16173\" class=\"wp-caption-text\">XRP voorspelling. Bron: DeepSeek<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Op korte termijn herstelt de koers van de prijs plausibel, boven de 100-daagse Exponential Moving Average op $2,83. Een stabiele RSI op 41 suggereert dat XRP zijwaarts kan bewegen binnen een smalle bandbreedte, met de eerste belangrijke weerstand op $2,94, zoals benadrukt door de 50-daagse EMA. Toch bevestigt de dalende trendlijn vanaf de recordhoogte van $3,66 een algehele neerwaartse trend in de XRP koers.<\/p>\n<figure style=\"width: 741px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/editorial.fxsstatic.com\/miscelaneous\/XRPUSDT_2025-09-23_13-03-51-1758622880186-1758622880186.png\" alt=\"xrp KOERS\" width=\"741\" height=\"519\" \/><figcaption class=\"wp-caption-text\">XRP koers. Bron: TradingView<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Als bulls er niet in slagen om de winst boven de 100-daagse EMA vast te houden, kan handel daaronder leiden tot verliezen richting $2,70, een niveau dat voor het laatst werd getest op 22 september. Bij verdere dalingen komt waarschijnlijk de 200-daagse EMA op $2,59 in beeld.<\/p>\n<h2>$ETH koersdoel 2025: klaar voor $20.000?<\/h2>\n<p style=\"font-weight: 400\">Ten tweede, schetst DeepSeek een buitengewoon <a href=\"https:\/\/99bitcoins.com\/nl\/welke-crypto-kopen\/ethereum-verwachting\/#:~:text=Ethereum%20koers%20verwachting%202025,-De%20Ethereum%20koers&amp;text=In%20een%20ongunstig%20scenario%20zakt,blockchains%20zoals%20Solana%20of%20TON.\">positief vooruitzicht voor Ethereum<\/a>, met een voorspelling die wijst op een prijsbereik van $12.000 &#8211; $15.000 tegen eind 2025. De AI wijt dit potentieel aan de fundamentele kracht van het Ethereum-netwerk en de verwachte instroom van institutioneel kapitaal.<img class=\"\" \/><\/p>\n<figure id=\"attachment_16175\" aria-describedby=\"caption-attachment-16175\" style=\"width: 736px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-16175\" src=\"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.21.png\" alt=\"Ethereum koers\" width=\"736\" height=\"490\" srcset=\"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.21.png 795w, https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.21-300x200.png 300w, https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.21-768x511.png 768w, https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.21-50x33.png 50w\" sizes=\"(max-width: 736px) 100vw, 736px\" \/><figcaption id=\"caption-attachment-16175\" class=\"wp-caption-text\">Ethereum voorspelling. Bron: TradingView<\/figcaption><\/figure>\n<p>Op het moment van schrijven houdt de Ethereum koers stand boven $4200, maar blijft onder de weerstand van de 50-daagse EMA op $4252. Na twee opeenvolgende dagen van verliezen richten de bulls zich op een uitbraak boven een belangrijke dalende trendlijn, wat de weg zou kunnen vrijmaken richting de all-time high van $4956.<\/p>\n<figure style=\"width: 741px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"\" src=\"https:\/\/editorial.fxsstatic.com\/miscelaneous\/ETHUSDT_2025-09-23_12-26-08-1758622869136-1758622869136.png\" alt=\"Ethereum koers\" width=\"741\" height=\"519\" \/><figcaption class=\"wp-caption-text\">Ethereum koers. Bron: TradingView<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Positief is dat de RSI stabiel staat op 41 en tekenen van herstel begint te vertonen. Hogere RSI-waarden duiden op toenemend bullish momentum naarmate de risk-on-sentimenten verbeteren.<\/p>\n<p style=\"font-weight: 400\">Toch houdt de MACD-indicator sinds zaterdag een verkoopsignaal vast, wat wijst op een hardnekkige bearish grip. Zolang de blauwe MACD-lijn onder de rode signaallijn blijft, kan de verwachte uitbraak worden vertraagd en plaatsmaken voor een correctie richting de ronde support op $4000.<\/p>\n<h2>Is het Cardano\u2019s moment om te shinen?<\/h2>\n<p style=\"font-weight: 400\">Ten derde, voorziet DeepSeek&#8217;s model een sterke waardestijging voor Cardano, met een voorspelde prijs van rond $2 &#8211; $3 aan het einde van 2025. De AI geeft aan dat de voltooiing van belangrijke ontwikkelingsmilestones, zoals het Voltaire-bestuurssysteem, een cruciale rol zal spelen.<\/p>\n<figure id=\"attachment_16174\" aria-describedby=\"caption-attachment-16174\" style=\"width: 741px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-16174\" src=\"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.32.png\" alt=\"Cardano koers\" width=\"741\" height=\"471\" srcset=\"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.32.png 790w, https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.32-300x191.png 300w, https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.32-768x488.png 768w, https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/09\/Scherm\u00adafbeelding-2025-09-23-om-15.22.32-50x32.png 50w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/><figcaption id=\"caption-attachment-16174\" class=\"wp-caption-text\">Cardano voorspelling. Bron: DeepSeek<\/figcaption><\/figure>\n<p><img class=\"\" \/>Op korter termijn ziet de koers van Cardano er echter bearish uit. De Cardano koers is maandag onder de stijgende trendlijn gezakt (getrokken door meerdere dieptepunten sinds begin juli) en daalde met 6,1%, waarmee de support op $0,84 naar beneden werd doorbroken. Op dinsdag, ten tijde van schrijven, zet $ADA de correctie voort en handelt het op $0,81.<\/p>\n<figure style=\"width: 739px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"\" src=\"https:\/\/editorial.fxsstatic.com\/miscelaneous\/ADAUSDT_2025-09-23_08-15-58-1758597006803-1758597006805.png\" alt=\"Cardano koers\" width=\"739\" height=\"340\" \/><figcaption class=\"wp-caption-text\">Cardano koers. Bron: TradingView<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Als $ADA zijn neerwaartse trend doorzet, kan de terugval zich uitbreiden richting het 50% retracementniveau op $0,76 (berekend vanaf de juni-low van $0,51 tot de augustus-high van $1,02). Mocht $ADA echter herstellen, dan kan het herstel zich uitbreiden richting het weerstandsniveau van $0,84.<\/p>\n<p style=\"font-weight: 400\">Een <a href=\"https:\/\/99bitcoins.com\/nl\/welke-crypto-kopen\/opkomende-crypto\/#:~:text=Toplist%20opkomende%20crypto%20in%202025,-Hieronder%20vind%20je&amp;text=Bitcoin%20Hyper%20(%24HYPER)%3A%20De,Opkomende%20crypto%20met%20fun%20%26%20verdienmodel.\">opkomende crypto<\/a> die er momenteel interessant uitziet, is <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/nl\/visit\/snorter\" target=\"_blank\" rel=\"noopener nofollow sponsored\">Snorter Bot ($SNORT)<\/a>. Deze trading bot bevindt zich nog in de presale fase, waardoor de token voorlopig geen last heeft van kortetermijnvolatiliteit. Bovendien biedt de meme coin een nuttige utility, wat de kans op brede adoptie vergroot. Zodra de token wordt gelanceerd op exchanges, kan dit leiden tot een sterke koersstijging. Op het moment van schrijven bedraagt de prijs per token $0,1053.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Het Chinese AI-platform DeepSeek heeft nieuwe voorspellingen gedaan voor de beste altcoins. Volgens hun analyse kan XRP eind 2025 richting $10 stijgen, terwijl Ethereum ($ETH) mogelijk $12.000 tot $15.000 bereikt. Ook Cardano ($ADA) wordt sterk geacht, met een koersdoel van $2 tot $3. In dit artikel gaan we dieper in op deze voorspellingen en bekijken..<\/p>\n","protected":false},"author":136177,"featured_media":13279,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[131,9],"tags":[65,105,310],"coin":[56,59,20],"class_list":["post-16170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesponsord","category-nieuws","tag-cardano-koers","tag-ethereum-koers","tag-xrp-koers"],"wppr_data":{"cwp_meta_box_check":"No"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chinese AI DeepSeek Voorspelt XRP, ETH &amp; ADA Koersen<\/title>\n<meta name=\"description\" content=\"XRP kan richting $10, Ethereum naar $15.000 en Cardano naar $3 in 2025, aldus DeepSeek. Lees de volledige analyse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chinese AI DeepSeek Voorspelt XRP, ETH &amp; ADA Koersen\" \/>\n<meta property=\"og:description\" content=\"XRP kan richting $10, Ethereum naar $15.000 en Cardano naar $3 in 2025, aldus DeepSeek. Lees de volledige analyse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins NL\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-23T13:25:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/08\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rutger Kant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rutger Kant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/\"},\"author\":{\"name\":\"Rutger Kant\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#\\\/schema\\\/person\\\/1f5eb2a36a74587fbeb80d0cbc0a35d2\"},\"headline\":\"Chinese AI DeepSeek voorspelt crypto koersen van XRP, ETH en ADA voor eind 2025\",\"datePublished\":\"2025-09-23T13:25:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/\"},\"wordCount\":655,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2025\\\/08\\\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg\",\"keywords\":[\"Cardano koers\",\"ethereum koers\",\"xrp koers\"],\"articleSection\":[\"Gesponsord\",\"Nieuws\"],\"inLanguage\":\"nl-NL\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/\",\"name\":\"Chinese AI DeepSeek Voorspelt XRP, ETH & ADA Koersen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2025\\\/08\\\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg\",\"datePublished\":\"2025-09-23T13:25:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#\\\/schema\\\/person\\\/1f5eb2a36a74587fbeb80d0cbc0a35d2\"},\"description\":\"XRP kan richting $10, Ethereum naar $15.000 en Cardano naar $3 in 2025, aldus DeepSeek. Lees de volledige analyse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2025\\\/08\\\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2025\\\/08\\\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg\",\"width\":750,\"height\":500,\"caption\":\"Chinese AI DeepSeek voorspelt crypto koersen van XRP, ETH en ADA voor eind 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nieuws\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/nieuws\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chinese AI DeepSeek voorspelt crypto koersen van XRP, ETH en ADA voor eind 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/\",\"name\":\"99Bitcoins NL\",\"description\":\"Een niet-technisch blog over Bitcoin - Tutorial, recensies en handleidingen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/#\\\/schema\\\/person\\\/1f5eb2a36a74587fbeb80d0cbc0a35d2\",\"name\":\"Rutger Kant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g\",\"caption\":\"Rutger Kant\"},\"description\":\"Rutger Kant is een gespecialiseerde cryptojournalist met een achtergrond in technologie en een scherp oog voor marktontwikkelingen binnen het digitale ecosysteem. Zijn interesse in crypto ontstond tijdens de bullmarkt van 2017, toen hij de impact van blockchaintechnologie voor het eerst echt doorzag. In 2025 sloot hij zich aan bij CoinSpeaker als vaste bijdrager. Rutger studeerde Technische Bestuurskunde aan de TU Delft en verdiepte zich tijdens zijn opleiding in de maatschappelijke impact van datagedreven innovaties binnen de financi\u00eble sector. Zijn onderzoek richtte zich onder meer op alternatieve investeringsstrategie\u00ebn in de cryptomarkt.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/nl\\\/author\\\/rutgerkant\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chinese AI DeepSeek Voorspelt XRP, ETH & ADA Koersen","description":"XRP kan richting $10, Ethereum naar $15.000 en Cardano naar $3 in 2025, aldus DeepSeek. Lees de volledige analyse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/","og_locale":"nl_NL","og_type":"article","og_title":"Chinese AI DeepSeek Voorspelt XRP, ETH & ADA Koersen","og_description":"XRP kan richting $10, Ethereum naar $15.000 en Cardano naar $3 in 2025, aldus DeepSeek. Lees de volledige analyse.","og_url":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/","og_site_name":"99Bitcoins NL","article_published_time":"2025-09-23T13:25:18+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/08\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg","type":"image\/jpeg"}],"author":"Rutger Kant","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rutger Kant","Est. reading time":"6 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/"},"author":{"name":"Rutger Kant","@id":"https:\/\/99bitcoins.com\/nl\/#\/schema\/person\/1f5eb2a36a74587fbeb80d0cbc0a35d2"},"headline":"Chinese AI DeepSeek voorspelt crypto koersen van XRP, ETH en ADA voor eind 2025","datePublished":"2025-09-23T13:25:18+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/"},"wordCount":655,"image":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/08\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg","keywords":["Cardano koers","ethereum koers","xrp koers"],"articleSection":["Gesponsord","Nieuws"],"inLanguage":"nl-NL","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/","url":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/","name":"Chinese AI DeepSeek Voorspelt XRP, ETH & ADA Koersen","isPartOf":{"@id":"https:\/\/99bitcoins.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/08\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg","datePublished":"2025-09-23T13:25:18+00:00","author":{"@id":"https:\/\/99bitcoins.com\/nl\/#\/schema\/person\/1f5eb2a36a74587fbeb80d0cbc0a35d2"},"description":"XRP kan richting $10, Ethereum naar $15.000 en Cardano naar $3 in 2025, aldus DeepSeek. Lees de volledige analyse.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/#primaryimage","url":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/08\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg","contentUrl":"https:\/\/99bitcoins.com\/nl\/wp-content\/uploads\/sites\/9\/2025\/08\/20250825_1231_Cryptocurrency-Skyline_simple_compose_01k3gce0mrfzqshhw7m18d1q9p-e1756120475125.jpg","width":750,"height":500,"caption":"Chinese AI DeepSeek voorspelt crypto koersen van XRP, ETH en ADA voor eind 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/nl\/nieuws\/chinese-ai-deepseek-voorspelt-xrp-eth-ada-koersen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Nieuws","item":"https:\/\/99bitcoins.com\/nl\/nieuws\/"},{"@type":"ListItem","position":3,"name":"Chinese AI DeepSeek voorspelt crypto koersen van XRP, ETH en ADA voor eind 2025"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/nl\/#website","url":"https:\/\/99bitcoins.com\/nl\/","name":"99Bitcoins NL","description":"Een niet-technisch blog over Bitcoin - Tutorial, recensies en handleidingen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/nl\/#\/schema\/person\/1f5eb2a36a74587fbeb80d0cbc0a35d2","name":"Rutger Kant","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23669acc30ea15e01719ea456fd3f20f5fb439cd87a84157c16acef327b97e7f?s=96&d=mm&r=g","caption":"Rutger Kant"},"description":"Rutger Kant is een gespecialiseerde cryptojournalist met een achtergrond in technologie en een scherp oog voor marktontwikkelingen binnen het digitale ecosysteem. Zijn interesse in crypto ontstond tijdens de bullmarkt van 2017, toen hij de impact van blockchaintechnologie voor het eerst echt doorzag. In 2025 sloot hij zich aan bij CoinSpeaker als vaste bijdrager. Rutger studeerde Technische Bestuurskunde aan de TU Delft en verdiepte zich tijdens zijn opleiding in de maatschappelijke impact van datagedreven innovaties binnen de financi\u00eble sector. Zijn onderzoek richtte zich onder meer op alternatieve investeringsstrategie\u00ebn in de cryptomarkt.","url":"https:\/\/99bitcoins.com\/nl\/author\/rutgerkant\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/posts\/16170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/users\/136177"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/comments?post=16170"}],"version-history":[{"count":4,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/posts\/16170\/revisions"}],"predecessor-version":[{"id":16177,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/posts\/16170\/revisions\/16177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/media\/13279"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/media?parent=16170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/categories?post=16170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/tags?post=16170"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/nl\/wp-json\/wp\/v2\/coin?post=16170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}