{"id":31672,"date":"2026-02-12T00:15:55","date_gmt":"2026-02-11T15:15:55","guid":{"rendered":"https:\/\/99bitcoins.com\/kr\/?p=31672"},"modified":"2026-02-12T00:15:49","modified_gmt":"2026-02-11T15:15:49","slug":"qone-sold-out-in-fear-next-infra-play","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/","title":{"rendered":"\uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 \uadf9\ub2e8 \uad6c\uac04\uc5d0\uc11c\ub3c4 \ub9e4\uc9c4\ub41c \ud050\uc6d0($qONE)&#8230;\uc57d\uc138\uc7a5\uc5d0\uc11c \ud655\uc778\ub41c &#8216;\ud655\uc2e0 \uc790\uae08&#8217;"},"content":{"rendered":"<p>\uae00\ub85c\ubc8c \uc554\ud638\ud654\ud3d0 \ud22c\uc790\uc0ac\uc778 \ucfe1 \uce90\ud53c\ud138(Kook Capital)\uc740 \ucd5c\uadfc \uadf9\ub2e8\uc801\uc778 \uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c\ub3c4 \ud050\uc6d0($qONE) \ud504\ub9ac\uc138\uc77c\uc774 \ube60\ub974\uac8c \ub9e4\uc9c4\ub41c \uc810\uc744 \ub450\uace0, \ud22c\uc790\uc790\ub4e4\uc758 \uac15\ud55c \ud655\uc2e0\uc774 \ubc18\uc601\ub41c \uacb0\uacfc\ub77c\uace0 \ud3c9\uac00\ud588\ub2e4. \ub2f9\uc2dc \uc554\ud638\ud654\ud3d0 \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218\ub294 100\uc810 \ub9cc\uc810\uc5d0 6\uc810\uc73c\ub85c, \uc2dc\uc7a5 \uc2ec\ub9ac\uac00 \uc5ed\uc0ac\uc801\uc73c\ub85c\ub3c4 \ub9e4\uc6b0 \uc704\ucd95\ub41c \uad6c\uac04\uc5d0 \ud574\ub2f9\ud55c\ub2e4.<\/p>\n<p>\uc554\ud638\ud654\ud3d0 \uc2dc\uc7a5\uc5d0\ub294 \uc624\ub79c \uae30\uac04 \ubc18\ubcf5\ub3fc \uc628 \ud558\ub098\uc758 \ud328\ud134\uc774 \uc788\ub2e4. \ub2e4\uc74c \uc0ac\uc774\ud074\uc744 \uc774\ub044\ub294 \ud575\uc2ec \ud504\ub85c\uc81d\ud2b8\ub4e4\uc740 \ub300\uccb4\ub85c \ud604\uc7ac \uc0ac\uc774\ud074\uc758 \ucd5c\uc545\uc758 \uc21c\uac04\uc5d0 \ub4f1\uc7a5\ud55c\ub2e4\ub294 \uc810\uc774\ub2e4. \uc774\ub354\ub9ac\uc6c0\uc740 2014\ub144 \uc57d\uc138\uc7a5 \uc774\ud6c4 \ucd9c\ubc94\ud588\uace0, \uc194\ub77c\ub098\ub294 2020\ub144 \uae09\ub77d\uc7a5 \uc18d\uc5d0\uc11c \ucd08\uae30 \uc0dd\ud0dc\uacc4\ub97c \uad6c\ucd95\ud588\uc73c\uba70, \uccb4\uc778\ub9c1\ud06c \uc5ed\uc2dc \uc2dc\uc7a5\uc774 \uadf9\ub3c4\uc758 \uce68\uccb4\uc5d0 \ube60\uc838 \uc788\uc744 \ub54c \uc874\uc7ac\uac10\uc744 \ud0a4\uc6e0\ub2e4.<\/p>\n<figure style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/%EC%8A%A4%ED%81%AC%EB%A6%B0%EC%83%B7-2026-02-10-%EC%98%A4%ED%9B%84-11.08.46-1024x505.png\" alt=\"\ucf54\uc778 \uacf5\ud3ec \ud0d0\uc695\uc9c0\uc218\" width=\"1024\" height=\"505\" \/><figcaption class=\"wp-caption-text\">\ucd9c\ucc98: \ucf54\uc778\ub9c8\ucf13\ucea1<\/figcaption><\/figure>\n<p>\uacf5\ud1b5\uc810\uc740 \uba85\ud655\ud558\ub2e4. \uc2e4\uc9c8\uc801\uc778 \uc778\ud504\ub77c\ub294 \uac15\uc138\uc7a5\uc774 \uc544\ub2c8\uc5b4\ub3c4 \uc2a4\uc2a4\ub85c\uc758 \uac00\uce58\ub97c \uc99d\uba85\ud560 \uc218 \uc788\ub2e4. \uc8fc\ubaa9\ubc1b\uc9c0 \uc54a\uc744 \ub54c \uad6c\ucd95\ub418\uace0, \uc2dc\uc7a5\uc758 \uad00\uc2ec\uc774 \ub3cc\uc544\uc62c \ub54c \uadf8 \uc131\uacfc\uac00 \ub4dc\ub7ec\ub09c\ub2e4.<\/p>\n<p>$qONE \uc5ed\uc2dc \uc774\ub7f0 \ud750\ub984\uacfc \ub9de\ub2ff\uc544 \uc788\ub2e4. $qONE\uc740 \uc554\ud638\ud654\ud3d0 \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218\uac00 6\uc744 \uae30\ub85d\ud558\ub358 \uc2dc\uc810\uc5d0 95\ub9cc \ub2ec\ub7ec \uaddc\ubaa8\uc758 \ud504\ub9ac\uc138\uc77c \ubb3c\ub7c9\uc744 24\uc2dc\uac04\ub3c4 \ucc44 \ub418\uc9c0 \uc54a\uc544 \ubaa8\ub450 \uc644\ud310\ub410\ub2e4. \ud604\uc7ac \ud1a0\ud070\uc740 \ud558\uc774\ud37c\ub9ac\ud034\ub4dc(Hyperliquid)\uc5d0 \uc0c1\uc7a5\ub3fc \uac70\ub798\ub418\uace0 \uc788\uc73c\uba70, \ucf54\uc778\ub9c8\ucf13\ucea1(CoinMarketCap)\uc5d0 \ub4f1\ub85d\ub410\uace0 \ud37c\ube14\ub9ad \uc138\uc77c \uac00\uaca9\uc744 \uc6c3\ub3c4\ub294 \uc218\uc900\uc5d0\uc11c \ud615\uc131\ub3fc \uc788\ub2e4.<\/p>\n<p>\u27a1 <a href=\"https:\/\/99bitcoins.com\/kr\/visit\/based\" rel=\"nofollow sponsored\" target=\"_blank\"><strong>\ubca0\uc774\uc2a4\ub4dc(Based)\uc5d0\uc11c $qONE \uad6c\ub9e4\ud558\uae30<\/strong><\/a><\/p>\n<h2><b>\uc57d\uc138\uc7a5, \ud22c\uc790\uc790\ub4e4\uc758 \uae30\uc900\uc740 \ub354 \uc5c4\uaca9\ud574\uc9c4\ub2e4.<\/b><\/h2>\n<p>\uc2dc\uc7a5\uc774 \uc0c1\uc2b9\ud560 \ub54c\ub294 \ubb34\uc5c7\uc774\ub4e0 \uc798 \ud314\ub9b0\ub2e4. <a href=\"https:\/\/99bitcoins.com\/kr\/cryptocurrency\/best-meme-presales\/\">\ubc08\ucf54\uc778<\/a>\uc774 \ub300\uaddc\ubaa8 \uc790\uae08\uc744 \ub04c\uc5b4\ubaa8\uc73c\uace0, \uc2e4\uccb4\uac00 \ubd88\ubd84\uba85\ud55c \ud504\ub85c\uc81d\ud2b8\uac00 \ub192\uc740 \ubc38\ub958\uc5d0\uc774\uc158\uc73c\ub85c \ub4f1\uc7a5\ud55c\ub2e4. \uc774 \uc2dc\uae30\uc5d0\ub294 \uc625\uc11d\uc744 \uac00\ub9ac\uae30 \uc5b4\ub835\ub2e4.<\/p>\n<p>\ud558\uc9c0\ub9cc \uc694\uc998\ucc98\ub7fc \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218\uac00 \ud55c \uc790\ub9bf\uc218\ub85c \ub5a8\uc5b4\uc9c8 \ub54c\ub294 \uc0c1\ud669\uc774 \ub2ec\ub77c\uc9c4\ub2e4. \uace0\uc704\ud5d8 \uace0\uc218\uc775\uc744 \ucd94\uad6c\ud558\ub358 \uc790\uae08\uc740 \ube60\uc838\ub098\uac00\uace0, \uc2e4\uc81c \uae30\uc220\ub825\uacfc \uc0ac\uc5c5\uc131\uc744 \uac16\ucd98 \ud504\ub85c\uc81d\ud2b8\ub9cc\uc774 \uc790\uae08\uc744 \ub04c\uc5b4\ub4e4\uc778\ub2e4. \uc774\ub978\ubc14 \u2018\ud655\uc2e0 \uc790\uae08\u2019\uc774\ub9cc \uc2dc\uc7a5\uc5d0 \ub0a8\ub294 \ud615\ud0dc\ub85c \ubcc0\ud654\ud558\uae30 \ub54c\ubb38\uc774\ub2e4.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-31684\" src=\"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.49.34.png\" alt=\"\ud050\ub7a9\uc2a4 \ud30c\ud2b8\ub108\uc2ed\" width=\"700\" height=\"388\" srcset=\"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.49.34.png 974w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.49.34-300x166.png 300w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.49.34-768x426.png 768w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>\ud050\uc6d0($qONE) \ud504\ub9ac\uc138\uc77c\uc5d0\ub294 \uc0c1\ub2f9\ud788 \ubd88\ub9ac\ud55c \ud658\uacbd \uc18d\uc5d0\uc11c \uc57d 1,300\ub9cc \ub2ec\ub7ec \uaddc\ubaa8\uc758 \ub4f1\ub85d \uc218\uc694\uac00 \ubab0\ub838\ub2e4. \ud22c\uc790\uc790\ub4e4\uc740 \ub2e8\uae30 \uac00\uaca9 \uc0c1\uc2b9\uc774 \uc544\ub2c8\ub77c, \ud558\ub098\uc758 \uc804\uc81c\uc5d0 \ud45c\ub97c \ub358\uc84c\ub2e4\uace0 \ud574\uc11d\ud560 \uc218 \uc788\ub2e4. \uc62c\ud574 \uac00\uc7a5 \ud654\uc81c\uac00 \ub418\uace0 \uc788\ub294 \ud2b8\ub80c\ub4dc \ud0a4\uc6cc\ub4dc\uc778 &#8216;\uc591\uc790 \ucef4\ud4e8\ud305&#8217;\uac00 \uae30\uc874 \ube14\ub85d\uccb4\uc778 \uc554\ud638\uccb4\uacc4\ub97c \uc704\ud611\ud560 \uc218 \uc788\uc73c\uba70, \uc774\uc5d0 \ub300\ube44\ud560 \uc218 \uc788\ub294 \uc2e4\uc9c8\uc801\uc778 \ubcf4\uc548 \uc778\ud504\ub77c\ub97c \ud050\ub7a9\uc2a4(qLABS)\uac00 \ubcf4\uc720\ud558\uace0 \uc788\ub2e4\ub294 \ud310\ub2e8\uc774\ub2e4.<\/p>\n<p>\uadf8\ub3d9\uc548 <a href=\"https:\/\/99bitcoins.com\/kr\/cryptocurrency\/\">\uc554\ud638\ud654\ud3d0 \uc5c5\uacc4<\/a>\uc5d0\uc11c \uc8fc\ub85c \uad11\uace0\uc5d0 \uc0ac\uc6a9\ud558\ub358 FOMO \uc790\uadf9 \ubc29\uc2dd\uc774 \uc544\ub2c8\ub77c \uc804\uc81c\uc5d0 \ub300\ud55c \ud655\uc2e0\uc5d0 \uc758\ud574 \ud615\uc131\ub410\ub2e4\ub294 \uc810\uc5d0\uc11c, \ud050\uc6d0 \ud504\ub85c\uc81d\ud2b8\uc758 \ucd9c\ubc1c\uc120\ubd80\ud130 \ub2e4\ub974\ub2e4\ub294 \ud3c9\uac00\uac00 \uc9c0\ubc30\uc801\uc774\ub2e4.<\/p>\n<h2>\uc57d\uc138\uc7a5 \uc790\uae08\uc744 \ub04c\uc5b4\ub4e4\uc778 \ud050\uc6d0(qONE)\ub9cc\uc758 \uac15\uc810<\/h2>\n<p>\ud050\ub7a9\uc2a4(qLABS)\ub294 \uadf8\ub3d9\uc548 \uc591\uc790 \ubcf4\uc548\uacfc \uad00\ub828\ub41c \uc81c\ud488\uad70\uc744 \ud0c4\ud0c4\ud788 \uad6c\ucd95\ud574 \uc654\ub2e4. \uc624\ub298\ub0a0\uacfc \uac19\uc740 &#8216;\uc591\uc790 \ucef4\ud4e8\ud305 \uc2dc\ub300&#8217;\uc5d0 \ub300\ube44\ud574 \uae30\uc874 \ube14\ub85d\uccb4\uc778 \ubcf4\uc548 \uccb4\uacc4\ub97c \ubcf4\uc644\ud558\ub294 \uae30\uc220 \uc778\ud504\ub77c\ub97c \uac16\ucd94\uace0 \uc788\ub2e4\ub294 \uc810\uc774 \ud575\uc2ec\uc774\ub2e4.<\/p>\n<p>\ud504\ub85c\uc81d\ud2b8\uc758 \ubaa8\ud68c\uc0ac\uc778 01 Quantum Inc.\ub294 \uce90\ub098\ub2e4 \uc99d\uc2dc\uc5d0 \uc0c1\uc7a5\ub41c \uae30\uc5c5\uc73c\ub85c, \uc815\uae30\uc801\uc778 \uacf5\uc2dc\uc640 \uc678\ubd80 \uac10\uc0ac, \uaddc\uc81c \uac10\ub3c5\uc744 \ubc1b\uace0 \uc788\ub2e4. \uc77c\ubc18\uc801\uc778 \ucd08\uae30 \ud1a0\ud070 \ud504\ub85c\uc81d\ud2b8\uc640 \ub2ec\ub9ac \uc77c\uc815 \uc218\uc900\uc758 \ud22c\uba85\uc131\uacfc \ucc45\uc784 \uad6c\uc870\ub97c \uac16\ucd94\uace0 \uc788\uc73c\uba70, IronCAP\u2122\uc774\ub77c\ub294 \ud3ec\uc2a4\ud2b8-\uc591\uc790 \uc554\ud638 \uae30\uc220\uc5d0 \ub300\ud574 \ubbf8\uad6d \ud2b9\ud5c8 \ub450 \uac74\uc744 \ubcf4\uc720\ud558\uace0 \uc788\ub2e4. \uc774 \uae30\uc220\uc740 \ub2e8\uc21c\ud55c \uac1c\ub150 \ub2e8\uacc4\uac00 \uc544\ub2c8\ub77c \uc2e4\uc81c \uc0b0\uc5c5 \ud604\uc7a5\uc5d0\uc11c \ud65c\uc6a9\ub418\uace0 \uc788\ub2e4. \ud788\ud0c0\uce58(Hitachi), PwC \ub4f1 \uae00\ub85c\ubc8c \ub300\ud615 \uae30\uc5c5\ub4e4\uc774 \uc774 \uae30\uc220\uc744 \uc6b4\uc601 \ud658\uacbd\uc5d0 \uc801\uc6a9\ud558\uace0 \uc788\ub2e4\ub294 \uc810\ub3c4 \uc774\ub97c \ub4b7\ubc1b\uce68\ud55c\ub2e4.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-31601\" src=\"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-10-\uc624\ud6c4-11.10.07-1024x483.png\" alt=\"\ud050\ub7a9\uc2a4 \" width=\"1024\" height=\"483\" srcset=\"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-10-\uc624\ud6c4-11.10.07-1024x483.png 1024w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-10-\uc624\ud6c4-11.10.07-300x141.png 300w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-10-\uc624\ud6c4-11.10.07-768x362.png 768w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-10-\uc624\ud6c4-11.10.07-1536x724.png 1536w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-10-\uc624\ud6c4-11.10.07.png 2024w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>\uae30\uc220 \ud45c\uc900 \uce21\uba74\uc5d0\uc11c\ub3c4 \ubbf8\uad6d \uad6d\ub9bd\ud45c\uc900\uae30\uc220\uc5f0\uad6c\uc18c(NIST)\uac00 \uc2b9\uc778\ud55c \ud3ec\uc2a4\ud2b8-\uc591\uc790 \uc554\ud638 \uae30\uc900\uc744 \ub530\ub974\uace0 \uc788\ub2e4. \ubbf8\uad6d \uc815\ubd80 \uae30\uad00\uc774 \ucc44\ud0dd\ud55c \ubcf4\uc548 \ubc29\uc2dd\uacfc \uac19\uc740 \uc218\uc900\uc758 \uccb4\uacc4\ub97c \uc801\uc6a9\ud558\uace0 \uc788\ub2e4\ub294 \uc810\uc5d0\uc11c \uc758\ubbf8\uac00 \ud06c\ub2e4. \uc5ec\uae30\uc5d0 \ud575\uc2ec \uacbd\uc601\uc9c4\uacfc \uac1c\ubc1c\uc9c4\uc774 \uc2e4\uba85\uc73c\ub85c \uacf5\uac1c\ub3fc \uc788\uace0, \uacfc\uac70 \ub300\ud615 \ud504\ub85c\uc81d\ud2b8\ub97c \ud1b5\ud574 \uc0c1\ub2f9\ud55c \uc790\uae08\uc744 \uc870\ub2ec\ud55c \uacbd\ud5d8 \uc5ed\uc2dc \ucc28\ubcc4\ud654 \ud3ec\uc778\ud2b8\ub2e4.<\/p>\n<p>\uc694\uc18c\ub97c \uc885\ud569\ud558\uba74, \ud050\uc6d0($qONE)\uc740 \ub2e8\uc21c\ud55c \uc544\uc774\ub514\uc5b4 \ub2e8\uacc4\uc758 \ud5c8\ubb34\ub9f9\ub791\ud55c \ud1a0\ud070\uc774 \uc544\ub2c8\ub77c \uc77c\uc815 \uc218\uc900\uc758 \uae30\uc5c5 \uad6c\uc870\uc640 \uae30\uc220 \uae30\ubc18\uc744 \uac16\ucd98 \ud504\ub85c\uc81d\ud2b8\ub85c \ubcfc \uc218 \uc788\ub2e4. \uc77c\ubc18\uc801\uc778 \uc18c\ud615 \uc554\ud638\ud654\ud3d0 \ud504\ub85c\uc81d\ud2b8\uc640 \ub2ec\ub9ac, \ube44\uad50\uc801 \uccb4\uacc4\ub97c \uac16\ucd98 \uc778\ud504\ub77c \uae30\uc5c5\uc774 \uc57d\uc138\uc7a5\uc5d0\uc11c \ud1a0\ud070\uc744 \ucd9c\uc2dc\ud55c \uc0ac\ub840\ub77c\ub294 \uc810\uc774 \ucc28\ubcc4\ud654 \uc694\uc18c\ub85c \uaf3d\ud78c\ub2e4.<\/p>\n<h2>\ud604 \uc2dc\uc810 \ud050\uc6d0($qONE)\uc758 \uc785\uc9c0<\/h2>\n<p>\ub371\uc2a4\ud234(DEXTools) \uae30\uc900\uc73c\ub85c \ud050\uc6d0($qONE) \uac00\uaca9\uc740 \ucd9c\uc2dc \uc774\ud6c4 \uae30\ub85d\ud55c \uc800\uc810\uc778 0.00189\ub2ec\ub7ec \ub300\ube44 \ud06c\uac8c \uc0c1\uc2b9\ud55c \ub4a4, \ud604\uc7ac\ub294 0.012~0.014\ub2ec\ub7ec \uad6c\uac04\uc5d0\uc11c \uac70\ub798\ub418\uace0 \uc788\ub2e4. \uc774\ub294 \ud37c\ube14\ub9ad \uc138\uc77c \uac00\uaca9\uc778 0.01\ub2ec\ub7ec\ub97c \uc6c3\ub3c4\ub294 \uc218\uc900\uc774\ub2e4.<\/p>\n<figure id=\"attachment_31685\" aria-describedby=\"caption-attachment-31685\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-31685 size-large\" src=\"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.56.43-1024x511.png\" alt=\"\ub371\uc2a4\ud234 \ud050\uc6d0 \ucc28\ud2b8\" width=\"1024\" height=\"511\" srcset=\"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.56.43-1024x511.png 1024w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.56.43-300x150.png 300w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.56.43-768x384.png 768w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.56.43-1536x767.png 1536w, https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-11-\uc624\ud6c4-11.56.43.png 1974w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-31685\" class=\"wp-caption-text\">\ucd9c\ucc98: \ub371\uc2a4\ud234<\/figcaption><\/figure>\n<p>\ud050\uc6d0 \ud1a0\ud070\uc740 \ucf54\uc778\ub9c8\ucf13\ucea1\uacfc \ub371\uc2a4\ud234(DEXTools)\uc5d0 \uc774\ubbf8 \ub4f1\ub85d\ub3fc \uc788\uc73c\uba70, \ub2e4\uc591\ud55c \uc554\ud638\ud654\ud3d0 \uc804\ubb38 \ub9e4\uccb4\ub4e4\uc774 \ud504\ub85c\uc81d\ud2b8 \ucd9c\uc2dc\uc640 \uad00\ub828 \uc18c\uc2dd\uc744 \ubcf4\ub3c4\ud588\ub2e4.<\/p>\n<p>\ud5a5\ud6c4 \uc77c\uc815\ub3c4 \uad6c\uccb4\ud654\ub418\uace0 \uc788\ub2e4. \ub9c8\uc774\ud06c\ub808\uc774\uc158 \ud234\ud0a4\uac00 3\uc6d4 \ub9d0 \ucd9c\uc2dc\uac00 \uc608\uc815\ub3fc \uc788\uace0, \ucd94\uac00 \uac70\ub798\uc18c \uc0c1\uc7a5 \uc5ed\uc2dc \ub17c\uc758\uac00 \uc9c4\ud589 \uc911\uc774\ub2e4. \uc774\uc640 \ud568\uaed8 <a href=\"https:\/\/99bitcoins.com\/kr\/price-predictions\/ethereum-price-prediction\/\">\uc774\ub354\ub9ac\uc6c0<\/a> \uc7ac\ub2e8\uc774 \ud3ec\uc2a4\ud2b8-\uc591\uc790 \ubcf4\uc548\uc744 \uc804\ub7b5\uc801 \uc6b0\uc120 \uacfc\uc81c\ub85c \uc81c\uc2dc\ud558\uba74\uc11c, \uad00\ub828 \uae30\uc220\uc744 \ubcf4\uc720\ud55c \ud504\ub85c\uc81d\ud2b8\uc5d0 \ub300\ud55c \uc2dc\uc7a5\uc758 \uad00\uc2ec\ub3c4 \uc810\ucc28 \ud655\ub300\ub418\ub294 \ubaa8\uc2b5\uc774\ub2e4.<\/p>\n<p>\ud604\uc7ac \ud050\uc6d0($qONE)\uc758 \uc644\uc804\ud76c\uc11d\uac00\uce58(FDV)\ub294 \uc57d 1,300\ub9cc \ub2ec\ub7ec \uc218\uc900\uc73c\ub85c, \uc57d 200\uc5b5 \ub2ec\ub7ec \uaddc\ubaa8\ub85c \ucd94\uc815\ub418\ub294 \uad00\ub828 \ubcf4\uc548 \uc2dc\uc7a5\uacfc \ube44\uad50\ud558\uba74 \uc5ec\uc804\ud788 \ucd08\uae30 \ub2e8\uacc4\uc5d0 \uba38\ubb3c\ub7ec \uc788\ub2e4.<\/p>\n<p>\uacfc\uac70 \uc0ac\uc774\ud074\uc5d0\uc11c\ub3c4 \ud575\uc2ec \uc778\ud504\ub77c \ud504\ub85c\uc81d\ud2b8\ub4e4\uc740 \uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c \uc870\uc6a9\ud788 \uad6c\ucd95\ub418\uace0, \uc774\ud6c4 \uc2dc\uc7a5\uc774 \ud68c\ubcf5\ub418\ub294 \uacfc\uc815\uc5d0\uc11c \uc7ac\ud3c9\uac00\ub97c \ubc1b\uc544\uc654\ub2e4. $qONE \uc5ed\uc2dc \uc720\uc0ac \ud750\ub984\uc758 \ucd08\uc785\uc5d0 \uc11c \uc788\ub2e4.<\/p>\n<p>\uc2dc\uc7a5 \uc804\ubc18\uc774 \uc5ec\uc804\ud788 \ubcc0\ub3d9\uc131 \uad6d\uba74\uc5d0 \uba38\ubb3c\ub7ec \uc788\ub294 \ub9cc\ud07c, \ub2e8\uae30 \uac00\uaca9 \ud750\ub984\ub9cc\uc73c\ub85c \ud504\ub85c\uc81d\ud2b8\uc758 \uc131\ud328\ub97c \ud310\ub2e8\ud558\uae30\ub294 \uc5b4\ub835\ub2e4. \ub2e4\ub9cc \uc57d\uc138\uc7a5 \uc18d\uc5d0\uc11c\ub3c4 \uac1c\ubc1c\uacfc \uc778\ud504\ub77c \uad6c\ucd95\uc774 \uc774\uc5b4\uc9c0\uace0, \uc2e4\uc81c \uc0ac\uc6a9 \uc0ac\ub840\uac00 \ud655\uc7a5\ub418\uace0 \uc788\ub2e4\ub294 \uc810\uc740 \uc911\uc7a5\uae30 \uad00\uc810\uc5d0\uc11c \uc8fc\ubaa9\ud560 \ub9cc\ud55c \uc694\uc18c\ub2e4.<\/p>\n<p><b>\u27a1 <a href=\"https:\/\/99bitcoins.com\/kr\/visit\/hyperliquid\" rel=\"nofollow sponsored\" target=\"_blank\">\ud558\uc774\ud37c\ub9ac\ud034\ub4dc\uc5d0\uc11c \ud050\uc6d0($qONE) \uad6c\ub9e4\ud558\uae30<\/a><\/b><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">\ud050\uc6d0 \ucf54\uc778\ub9c8\ucf13\ucea1 \ub9c1\ud06c:<\/span><a href=\"https:\/\/coinmarketcap.com\/currencies\/qone\/\" rel=\"nofollow\" target=\"_blank\"> <span style=\"font-weight: 400\">https:\/\/coinmarketcap.com\/currencies\/qone\/<\/span><\/a><\/li>\n<li><span style=\"font-weight: 400\">\ub371\uc2a4\ud234 \ucc28\ud2b8:<\/span><a href=\"https:\/\/www.dextools.io\/app\/hyperevm\/pair-explorer\/0xa96c8366828a22cc0e900f9b12273883a56ee148\" rel=\"nofollow\" target=\"_blank\"> <span style=\"font-weight: 400\">https:\/\/www.dextools.io\/app\/hyperevm\/pair-explorer\/0xa96c8366828a22cc0e900f9b12273883a56ee148<\/span><\/a><\/li>\n<li><span style=\"font-weight: 400\">\ud050\uc6d0 \uacf5\uc2dd \uc6f9\uc0ac\uc774\ud2b8:<\/span><a href=\"https:\/\/qlabs.tech\/\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">https:\/\/qlabs.tech\/<\/span><\/a><\/li>\n<li><span style=\"font-weight: 400\">\ud050\uc6d0 \uacf5\uc2dd X \uacc4\uc815: <\/span><a href=\"https:\/\/x.com\/qlabsofficial\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">https:\/\/x.com\/qlabsofficial<\/span><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\uae00\ub85c\ubc8c \uc554\ud638\ud654\ud3d0 \ud22c\uc790\uc0ac\uc778 \ucfe1 \uce90\ud53c\ud138(Kook Capital)\uc740 \ucd5c\uadfc \uadf9\ub2e8\uc801\uc778 \uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c\ub3c4 \ud050\uc6d0($qONE) \ud504\ub9ac\uc138\uc77c\uc774 \ube60\ub974\uac8c \ub9e4\uc9c4\ub41c \uc810\uc744 \ub450\uace0, \ud22c\uc790\uc790\ub4e4\uc758 \uac15\ud55c \ud655\uc2e0\uc774 \ubc18\uc601\ub41c \uacb0\uacfc\ub77c\uace0 \ud3c9\uac00\ud588\ub2e4. \ub2f9\uc2dc \uc554\ud638\ud654\ud3d0 \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218\ub294 100\uc810 \ub9cc\uc810\uc5d0 6\uc810\uc73c\ub85c, \uc2dc\uc7a5 \uc2ec\ub9ac\uac00 \uc5ed\uc0ac\uc801\uc73c\ub85c\ub3c4 \ub9e4\uc6b0 \uc704\ucd95\ub41c \uad6c\uac04\uc5d0 \ud574\ub2f9\ud55c\ub2e4. \uc554\ud638\ud654\ud3d0 \uc2dc\uc7a5\uc5d0\ub294 \uc624\ub79c \uae30\uac04 \ubc18\ubcf5\ub3fc \uc628 \ud558\ub098\uc758 \ud328\ud134\uc774 \uc788\ub2e4. \ub2e4\uc74c \uc0ac\uc774\ud074\uc744 \uc774\ub044\ub294 \ud575\uc2ec \ud504\ub85c\uc81d\ud2b8\ub4e4\uc740 \ub300\uccb4\ub85c \ud604\uc7ac \uc0ac\uc774\ud074\uc758 \ucd5c\uc545\uc758 \uc21c\uac04\uc5d0..<\/p>\n","protected":false},"author":135880,"featured_media":31154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8],"tags":[21],"coin":[23],"class_list":["post-31672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pr-news","tag-presale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c \ub9e4\uc9c4\ub41c $qONE\u2026 \u2018\ub2e4\uc74c \uc778\ud504\ub77c \ud50c\ub808\uc774\u2019\ub85c \uc8fc\ubaa9<\/title>\n<meta name=\"description\" content=\"\uc554\ud638\ud654\ud3d0 \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 6\uc758 \uadf9\ub2e8\uc801 \uacf5\ud3ec \uad6c\uac04\uc5d0\uc11c\ub3c4 $qONE \ud504\ub9ac\uc138\uc77c\uc774 \ub9e4\uc9c4\ub410\ub2e4. \uc57d\uc138\uc7a5\uc5d0\uc11c \ub4f1\uc7a5\ud55c \ud3ec\uc2a4\ud2b8-\uc591\uc790 \ubcf4\uc548 \uc778\ud504\ub77c \ud504\ub85c\uc81d\ud2b8\uc758 \ubc30\uacbd\uacfc \ud604\uc7ac \uc704\uce58\ub97c \uc0b4\ud3b4\ubcf8\ub2e4.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c \ub9e4\uc9c4\ub41c $qONE\u2026 \u2018\ub2e4\uc74c \uc778\ud504\ub77c \ud50c\ub808\uc774\u2019\ub85c \uc8fc\ubaa9\" \/>\n<meta property=\"og:description\" content=\"\uc554\ud638\ud654\ud3d0 \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 6\uc758 \uadf9\ub2e8\uc801 \uacf5\ud3ec \uad6c\uac04\uc5d0\uc11c\ub3c4 $qONE \ud504\ub9ac\uc138\uc77c\uc774 \ub9e4\uc9c4\ub410\ub2e4. \uc57d\uc138\uc7a5\uc5d0\uc11c \ub4f1\uc7a5\ud55c \ud3ec\uc2a4\ud2b8-\uc591\uc790 \ubcf4\uc548 \uc778\ud504\ub77c \ud504\ub85c\uc81d\ud2b8\uc758 \ubc30\uacbd\uacfc \ud604\uc7ac \uc704\uce58\ub97c \uc0b4\ud3b4\ubcf8\ub2e4.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins KR\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-11T15:15:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1226\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Hyunsoo Kim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/cryptomasooter\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hyunsoo Kim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\ubd84\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/\"},\"author\":{\"name\":\"Hyunsoo Kim\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/#\\\/schema\\\/person\\\/e0af83b19922149ad1b9c9c0de6c0367\"},\"headline\":\"\uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 \uadf9\ub2e8 \uad6c\uac04\uc5d0\uc11c\ub3c4 \ub9e4\uc9c4\ub41c \ud050\uc6d0($qONE)&#8230;\uc57d\uc138\uc7a5\uc5d0\uc11c \ud655\uc778\ub41c &#8216;\ud655\uc2e0 \uc790\uae08&#8217;\",\"datePublished\":\"2026-02-11T15:15:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/\"},\"wordCount\":75,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/02\\\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png\",\"keywords\":[\"\ud504\ub9ac\uc138\uc77c\"],\"articleSection\":[\"\ubcf4\ub3c4\uc790\ub8cc\"],\"inLanguage\":\"ko-KR\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/\",\"name\":\"\uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c \ub9e4\uc9c4\ub41c $qONE\u2026 \u2018\ub2e4\uc74c \uc778\ud504\ub77c \ud50c\ub808\uc774\u2019\ub85c \uc8fc\ubaa9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/02\\\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png\",\"datePublished\":\"2026-02-11T15:15:55+00:00\",\"description\":\"\uc554\ud638\ud654\ud3d0 \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 6\uc758 \uadf9\ub2e8\uc801 \uacf5\ud3ec \uad6c\uac04\uc5d0\uc11c\ub3c4 $qONE \ud504\ub9ac\uc138\uc77c\uc774 \ub9e4\uc9c4\ub410\ub2e4. \uc57d\uc138\uc7a5\uc5d0\uc11c \ub4f1\uc7a5\ud55c \ud3ec\uc2a4\ud2b8-\uc591\uc790 \ubcf4\uc548 \uc778\ud504\ub77c \ud504\ub85c\uc81d\ud2b8\uc758 \ubc30\uacbd\uacfc \ud604\uc7ac \uc704\uce58\ub97c \uc0b4\ud3b4\ubcf8\ub2e4.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/#breadcrumb\"},\"inLanguage\":\"ko-KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/02\\\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/02\\\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png\",\"width\":1226,\"height\":628,\"caption\":\"\uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c \ub9e4\uc9c4\ub41c $qONE\u2026 \u2018\ub2e4\uc74c \uc778\ud504\ub77c \ud50c\ub808\uc774\u2019\ub85c \uc8fc\ubaa9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/qone-sold-out-in-fear-next-infra-play\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ub274\uc2a4\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\ubcf4\ub3c4\uc790\ub8cc\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/news\\\/pr-news\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 \uadf9\ub2e8 \uad6c\uac04\uc5d0\uc11c\ub3c4 \ub9e4\uc9c4\ub41c \ud050\uc6d0($qONE)&#8230;\uc57d\uc138\uc7a5\uc5d0\uc11c \ud655\uc778\ub41c &#8216;\ud655\uc2e0 \uc790\uae08&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/\",\"name\":\"99bitcoins KR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko-KR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/08\\\/99bitcoins-og.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/08\\\/99bitcoins-og.png\",\"width\":1200,\"height\":630,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/#\\\/schema\\\/person\\\/e0af83b19922149ad1b9c9c0de6c0367\",\"name\":\"Hyunsoo Kim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fcafca72c553f3b541f6348b56b6711a0d3cf850621e9ef2cc19397cad90aa7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fcafca72c553f3b541f6348b56b6711a0d3cf850621e9ef2cc19397cad90aa7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fcafca72c553f3b541f6348b56b6711a0d3cf850621e9ef2cc19397cad90aa7?s=96&d=mm&r=g\",\"caption\":\"Hyunsoo Kim\"},\"description\":\"\ubcf8 \uc791\uac00\ub294 \ube14\ub85d\uccb4\uc778 \uae30\uc220\uacfc \uc554\ud638\ud654\ud3d0 \uc2dc\uc7a5 \ubd84\uc11d\uc5d0 \uc788\uc5b4 10\ub144 \uc774\uc0c1\uc758 \uacbd\ud5d8\uc744 \uac00\uc9c4 \uc804\ubb38\uac00\uc785\ub2c8\ub2e4. \ud604\uc7ac 99\ube44\ud2b8\ucf54\uc778 \uc18c\uc18d\uc758 \uc815\uaddc \uc791\uac00\ub85c \ud65c\ub3d9\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4. \uacfc\uac70 \ub2e4\uc591\ud55c \uae00\ub85c\ubc8c \uae08\uc735\uae30\uad00\uacfc \ud611\ub825\ud558\uc5ec \uc554\ud638\ud654\ud3d0 \ud22c\uc790 \uc804\ub7b5\uc744 \uac1c\ubc1c\ud558\uace0 \uc2dc\uc7a5 \ub3d9\ud5a5\uc744 \ubd84\uc11d\ud558\uba70 \ud0c1\uc6d4\ud55c \ub2a5\ub825\uc744 \ubc1c\ud718\ud574\uc654\uc2b5\ub2c8\ub2e4. \uc774\ub7ec\ud55c \uacbd\ub825\uc744 \ubc14\ud0d5\uc73c\ub85c, \ud604\uc7ac\ub294 99\ube44\ud2b8\ucf54\uc778\uc5d0\uc11c \uc8fc\uae30\uc801\uc73c\ub85c \uac00\uc774\ub4dc \ubc0f \ub274\uc2a4\ub97c \uae30\uace0\ud558\uba70 \ub3c5\uc790\ub4e4\uc5d0\uac8c \ucd5c\uc2e0 \ud2b8\ub80c\ub4dc\uc640 \ud22c\uc790 \uae30\ud68c\ub97c \uc81c\uacf5\ud558\ub294 \ub370 \uc8fc\ub825\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4. 99\ube44\ud2b8\ucf54\uc778\uc758 \uc8fc \ub2f4\ub2f9 \ubd84\uc57c\ub294 \uac00\uaca9 \uc804\ub9dd, \uad6c\ub9e4 \ubc29\ubc95, \uac70\ub798\uc18c \ub9ac\ubdf0 \ub4f1\uc785\ub2c8\ub2e4.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/cryptomasooter\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/kr\\\/author\\\/hyunsookim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c \ub9e4\uc9c4\ub41c $qONE\u2026 \u2018\ub2e4\uc74c \uc778\ud504\ub77c \ud50c\ub808\uc774\u2019\ub85c \uc8fc\ubaa9","description":"\uc554\ud638\ud654\ud3d0 \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 6\uc758 \uadf9\ub2e8\uc801 \uacf5\ud3ec \uad6c\uac04\uc5d0\uc11c\ub3c4 $qONE \ud504\ub9ac\uc138\uc77c\uc774 \ub9e4\uc9c4\ub410\ub2e4. \uc57d\uc138\uc7a5\uc5d0\uc11c \ub4f1\uc7a5\ud55c \ud3ec\uc2a4\ud2b8-\uc591\uc790 \ubcf4\uc548 \uc778\ud504\ub77c \ud504\ub85c\uc81d\ud2b8\uc758 \ubc30\uacbd\uacfc \ud604\uc7ac \uc704\uce58\ub97c \uc0b4\ud3b4\ubcf8\ub2e4.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/","og_locale":"ko_KR","og_type":"article","og_title":"\uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c \ub9e4\uc9c4\ub41c $qONE\u2026 \u2018\ub2e4\uc74c \uc778\ud504\ub77c \ud50c\ub808\uc774\u2019\ub85c \uc8fc\ubaa9","og_description":"\uc554\ud638\ud654\ud3d0 \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 6\uc758 \uadf9\ub2e8\uc801 \uacf5\ud3ec \uad6c\uac04\uc5d0\uc11c\ub3c4 $qONE \ud504\ub9ac\uc138\uc77c\uc774 \ub9e4\uc9c4\ub410\ub2e4. \uc57d\uc138\uc7a5\uc5d0\uc11c \ub4f1\uc7a5\ud55c \ud3ec\uc2a4\ud2b8-\uc591\uc790 \ubcf4\uc548 \uc778\ud504\ub77c \ud504\ub85c\uc81d\ud2b8\uc758 \ubc30\uacbd\uacfc \ud604\uc7ac \uc704\uce58\ub97c \uc0b4\ud3b4\ubcf8\ub2e4.","og_url":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/","og_site_name":"99bitcoins KR","article_published_time":"2026-02-11T15:15:55+00:00","og_image":[{"width":1226,"height":628,"url":"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png","type":"image\/png"}],"author":"Hyunsoo Kim","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/cryptomasooter","twitter_misc":{"Written by":"Hyunsoo Kim","Est. reading time":"5\ubd84"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/"},"author":{"name":"Hyunsoo Kim","@id":"https:\/\/99bitcoins.com\/kr\/#\/schema\/person\/e0af83b19922149ad1b9c9c0de6c0367"},"headline":"\uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 \uadf9\ub2e8 \uad6c\uac04\uc5d0\uc11c\ub3c4 \ub9e4\uc9c4\ub41c \ud050\uc6d0($qONE)&#8230;\uc57d\uc138\uc7a5\uc5d0\uc11c \ud655\uc778\ub41c &#8216;\ud655\uc2e0 \uc790\uae08&#8217;","datePublished":"2026-02-11T15:15:55+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/"},"wordCount":75,"publisher":{"@id":"https:\/\/99bitcoins.com\/kr\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png","keywords":["\ud504\ub9ac\uc138\uc77c"],"articleSection":["\ubcf4\ub3c4\uc790\ub8cc"],"inLanguage":"ko-KR","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/","url":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/","name":"\uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c \ub9e4\uc9c4\ub41c $qONE\u2026 \u2018\ub2e4\uc74c \uc778\ud504\ub77c \ud50c\ub808\uc774\u2019\ub85c \uc8fc\ubaa9","isPartOf":{"@id":"https:\/\/99bitcoins.com\/kr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png","datePublished":"2026-02-11T15:15:55+00:00","description":"\uc554\ud638\ud654\ud3d0 \uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 6\uc758 \uadf9\ub2e8\uc801 \uacf5\ud3ec \uad6c\uac04\uc5d0\uc11c\ub3c4 $qONE \ud504\ub9ac\uc138\uc77c\uc774 \ub9e4\uc9c4\ub410\ub2e4. \uc57d\uc138\uc7a5\uc5d0\uc11c \ub4f1\uc7a5\ud55c \ud3ec\uc2a4\ud2b8-\uc591\uc790 \ubcf4\uc548 \uc778\ud504\ub77c \ud504\ub85c\uc81d\ud2b8\uc758 \ubc30\uacbd\uacfc \ud604\uc7ac \uc704\uce58\ub97c \uc0b4\ud3b4\ubcf8\ub2e4.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/#breadcrumb"},"inLanguage":"ko-KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/"]}]},{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/#primaryimage","url":"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png","contentUrl":"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2026\/02\/\uc2a4\ud06c\ub9b0\uc0f7-2026-02-03-\uc624\ud6c4-9.33.15.png","width":1226,"height":628,"caption":"\uacf5\ud3ec \uad6d\uba74\uc5d0\uc11c \ub9e4\uc9c4\ub41c $qONE\u2026 \u2018\ub2e4\uc74c \uc778\ud504\ub77c \ud50c\ub808\uc774\u2019\ub85c \uc8fc\ubaa9"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/qone-sold-out-in-fear-next-infra-play\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/kr\/"},{"@type":"ListItem","position":2,"name":"\ub274\uc2a4","item":"https:\/\/99bitcoins.com\/kr\/news\/"},{"@type":"ListItem","position":3,"name":"\ubcf4\ub3c4\uc790\ub8cc","item":"https:\/\/99bitcoins.com\/kr\/news\/pr-news\/"},{"@type":"ListItem","position":4,"name":"\uacf5\ud3ec\u00b7\ud0d0\uc695 \uc9c0\uc218 \uadf9\ub2e8 \uad6c\uac04\uc5d0\uc11c\ub3c4 \ub9e4\uc9c4\ub41c \ud050\uc6d0($qONE)&#8230;\uc57d\uc138\uc7a5\uc5d0\uc11c \ud655\uc778\ub41c &#8216;\ud655\uc2e0 \uc790\uae08&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/kr\/#website","url":"https:\/\/99bitcoins.com\/kr\/","name":"99bitcoins KR","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/kr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/kr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko-KR"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/kr\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/kr\/","logo":{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/99bitcoins.com\/kr\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2024\/08\/99bitcoins-og.png","contentUrl":"https:\/\/99bitcoins.com\/kr\/wp-content\/uploads\/sites\/6\/2024\/08\/99bitcoins-og.png","width":1200,"height":630,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/kr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/kr\/#\/schema\/person\/e0af83b19922149ad1b9c9c0de6c0367","name":"Hyunsoo Kim","image":{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/secure.gravatar.com\/avatar\/0fcafca72c553f3b541f6348b56b6711a0d3cf850621e9ef2cc19397cad90aa7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0fcafca72c553f3b541f6348b56b6711a0d3cf850621e9ef2cc19397cad90aa7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fcafca72c553f3b541f6348b56b6711a0d3cf850621e9ef2cc19397cad90aa7?s=96&d=mm&r=g","caption":"Hyunsoo Kim"},"description":"\ubcf8 \uc791\uac00\ub294 \ube14\ub85d\uccb4\uc778 \uae30\uc220\uacfc \uc554\ud638\ud654\ud3d0 \uc2dc\uc7a5 \ubd84\uc11d\uc5d0 \uc788\uc5b4 10\ub144 \uc774\uc0c1\uc758 \uacbd\ud5d8\uc744 \uac00\uc9c4 \uc804\ubb38\uac00\uc785\ub2c8\ub2e4. \ud604\uc7ac 99\ube44\ud2b8\ucf54\uc778 \uc18c\uc18d\uc758 \uc815\uaddc \uc791\uac00\ub85c \ud65c\ub3d9\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4. \uacfc\uac70 \ub2e4\uc591\ud55c \uae00\ub85c\ubc8c \uae08\uc735\uae30\uad00\uacfc \ud611\ub825\ud558\uc5ec \uc554\ud638\ud654\ud3d0 \ud22c\uc790 \uc804\ub7b5\uc744 \uac1c\ubc1c\ud558\uace0 \uc2dc\uc7a5 \ub3d9\ud5a5\uc744 \ubd84\uc11d\ud558\uba70 \ud0c1\uc6d4\ud55c \ub2a5\ub825\uc744 \ubc1c\ud718\ud574\uc654\uc2b5\ub2c8\ub2e4. \uc774\ub7ec\ud55c \uacbd\ub825\uc744 \ubc14\ud0d5\uc73c\ub85c, \ud604\uc7ac\ub294 99\ube44\ud2b8\ucf54\uc778\uc5d0\uc11c \uc8fc\uae30\uc801\uc73c\ub85c \uac00\uc774\ub4dc \ubc0f \ub274\uc2a4\ub97c \uae30\uace0\ud558\uba70 \ub3c5\uc790\ub4e4\uc5d0\uac8c \ucd5c\uc2e0 \ud2b8\ub80c\ub4dc\uc640 \ud22c\uc790 \uae30\ud68c\ub97c \uc81c\uacf5\ud558\ub294 \ub370 \uc8fc\ub825\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4. 99\ube44\ud2b8\ucf54\uc778\uc758 \uc8fc \ub2f4\ub2f9 \ubd84\uc57c\ub294 \uac00\uaca9 \uc804\ub9dd, \uad6c\ub9e4 \ubc29\ubc95, \uac70\ub798\uc18c \ub9ac\ubdf0 \ub4f1\uc785\ub2c8\ub2e4.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/cryptomasooter"],"url":"https:\/\/99bitcoins.com\/kr\/author\/hyunsookim\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/posts\/31672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/users\/135880"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/comments?post=31672"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/posts\/31672\/revisions"}],"predecessor-version":[{"id":31690,"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/posts\/31672\/revisions\/31690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/media\/31154"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/media?parent=31672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/categories?post=31672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/tags?post=31672"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/kr\/wp-json\/wp\/v2\/coin?post=31672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}