{"id":19640,"date":"2026-03-11T14:11:18","date_gmt":"2026-03-11T14:11:18","guid":{"rendered":"https:\/\/99bitcoins.com\/it\/?p=19640"},"modified":"2026-03-11T14:09:28","modified_gmt":"2026-03-11T14:09:28","slug":"afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/","title":{"rendered":"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP"},"content":{"rendered":"<p>Nella giornata di ieri gli ETF (Exchange-Traded Fund) americani su Bitcoin hanno registrato un aumento degli afflussi, nonostante Bitcoin sia sceso sotto i <strong>70.000 dollari<\/strong>.<\/p>\n<p>Secondo i dati di SoSoValue, gli ETF hanno registrato afflussi per <strong>251 milioni di dollari<\/strong>, incrementando i guadagni di luned\u00ec pari a 167 milioni di dollari.<\/p>\n<p>Gli afflussi continuano a seguire un trend positivo a marzo, con guadagni mensili cumulativi pari a 1,56 miliardi di dollari, rispetto ai 576,6 milioni di dollari di deflussi.<\/p>\n<h2>Le vendite di XRP rallentano mentre Goldman Sachs supera e stacca tutti sulle partecipazioni in ETF XRP<\/h2>\n<p>Negli ultimi tre giorni i fondi XRP hanno registrato circa 3,9 milioni di dollari di deflussi, estendendo la loro serie di vendite alla quarta sessione consecutiva, sebbene il ritmo dei &#8220;prelievi&#8221; sia rallentato rispetto a quelli pi\u00f9 consistenti registrati luned\u00ec.<\/p>\n<p>L&#8217;analista di Bloomberg ETF, <strong>James Seyffart<\/strong>, ha osservato in un post su X che gli ETF XRP hanno retto bene <a href=\"https:\/\/99bitcoins.com\/it\/notizie\/xrp-si-ferma-a-2-1-etf-ripple-raggiungono-1-37b-asset-35-giorni-afflussi-consecutivi\/\">nonostante la volatilit\u00e0 dell&#8217;asset<\/a>. XRP \u00e8 sceso di circa il 5% negli ultimi 30 giorni, attestandosi a 1,38 dollari.<\/p>\n<p>&#8220;Hanno incassato un totale di 1,4 miliardi di dollari dal lancio&#8221;, ha affermato <strong>Seyffart<\/strong>, rilevando come <strong>Goldman Sachs<\/strong> sia diventata oggi il maggiore detentore di ETF XRP. Al 31 dicembre, la banca d&#8217;investimento di Wall Street deteneva circa 154 milioni di dollari in ETF XRP, rispetto ai 23 milioni di dollari e ai 5,3 milioni di dollari detenuti da Millennium Management e Logan Stone Capital.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-19641\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/03\/xrp-possessori.jpeg\" alt=\"\" width=\"691\" height=\"721\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/03\/xrp-possessori.jpeg 691w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/03\/xrp-possessori-288x300.jpeg 288w\" sizes=\"(max-width: 691px) 100vw, 691px\" \/><\/p>\n<p>In un altro post su X, Seyffart ha fornito una ripartizione di quattro gruppi di ETF, evidenziando che gli ETF XRP sono in gran parte guidati dalla domanda al dettaglio.<\/p>\n<p>Solo il 15,9% degli asset in gestione degli ETF XRP \u00e8 riportato nei documenti 13F, rispetto al 48,8% degli ETF SOL, che sono detenuti da investitori istituzionali. Gli ETF su Bitcoin ed Ether si collocano a met\u00e0 strada, con rispettivamente il 24% e il 27% degli asset dichiarati nei documenti.<\/p>\n<h2>XRP sempre pi\u00f9 riferimento nel mondo della finanza globale<\/h2>\n<p class=\"p1\">Sul punto si registra l&#8217;intervento di Gracy Chen, CEO di Bitget, che ha spiegato: <em>&#8220;Il fatto che Goldman Sachs sia diventato il principale detentore istituzionale di ETF spot su XRP, con un\u2019esposizione di circa 154 milioni di dollari, conferma chiaramente il ruolo crescente di questo asset nella finanza globale. Questo sviluppo segnala un crescente interesse istituzionale nell&#8217;utilit\u00e0 di XRP per i pagamenti transfrontalieri e le infrastrutture di liquidit\u00e0, rafforzando la tesi secondo cui selezionati asset digitali stiano guadagnando terreno all&#8217;interno dei portafogli finanziari tradizionali.<\/em><\/p>\n<p class=\"p1\"><em>I capitali confluiti negli ETF spot su XRP hanno superato il miliardo di dollari, portando il patrimonio complessivo a circa 1,44 miliardi. Questo slancio evidenzia un forte allineamento tra il posizionamento dei grandi investitori istituzionali e il sostegno incrollabile della dedicata community di XRP, il cui impegno ha contribuito a sostenere la domanda anche durante i periodi di volatilit\u00e0 del mercato.<\/em><\/p>\n<p class=\"p1\"><em>Questa doppia dinamica \u2014 la partecipazione dei vertici di Wall Street insieme al supporto costante dei piccoli investitori \u2014 rafforza la resilienza di XRP e lo posiziona come un ponte concreto tra i sistemi finanziari tradizionali e gli ecosistemi nativi del mondo crypto.<\/em><\/p>\n<p class=\"p1\"><em>Per il pi\u00f9 ampio mercato delle altcoin, questa tendenza conferma uno spostamento verso narrazioni basate sull&#8217;utilit\u00e0 e sui progressi normativi, piuttosto che su un semplice slancio speculativo. Man mano che il capitale fluisce verso asset con applicazioni nel mondo reale e quadri normativi pi\u00f9 chiari, il comportamento degli investitori sta diventando gradualmente pi\u00f9 equilibrato e focalizzato sul lungo periodo.<\/em><\/p>\n<p class=\"p1\"><em>In definitiva, l\u2019incontro tra capitali istituzionali e supporto della community favorisce una crescita sostenibile del settore. Questo equilibrio attira finanziamenti stabili, senza per\u00f2 soffocare l&#8217;innovazione spontanea e la liquidit\u00e0 che alimentano l&#8217;intero ecosistema&#8221;<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella giornata di ieri gli ETF (Exchange-Traded Fund) americani su Bitcoin hanno registrato un aumento degli afflussi, nonostante Bitcoin sia sceso sotto i 70.000 dollari. Secondo i dati di SoSoValue, gli ETF hanno registrato afflussi per 251 milioni di dollari, incrementando i guadagni di luned\u00ec pari a 167 milioni di dollari. Gli afflussi continuano a..<\/p>\n","protected":false},"author":136067,"featured_media":8681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[197,16],"coin":[2],"class_list":["post-19640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-goldman-sachs","tag-xrp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP - 99bitcoins IT<\/title>\n<meta name=\"description\" content=\"Nella giornata di ieri gli ETF (Exchange-Traded Fund) americani su Bitcoin hanno registrato un aumento degli afflussi, nonostante Bitcoin sia sceso sotto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP - 99bitcoins IT\" \/>\n<meta property=\"og:description\" content=\"Nella giornata di ieri gli ETF (Exchange-Traded Fund) americani su Bitcoin hanno registrato un aumento degli afflussi, nonostante Bitcoin sia sceso sotto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins IT\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-11T14:11:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/07\/xrppp-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"841\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federico Cappellini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Cappellini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/\"},\"author\":{\"name\":\"Federico Cappellini\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/af5a8990396ca6c1ac73bfff31df00b4\"},\"headline\":\"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP\",\"datePublished\":\"2026-03-11T14:11:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/\"},\"wordCount\":614,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/07\\\/xrppp-2.png\",\"keywords\":[\"goldman sachs\",\"XRP\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/\",\"name\":\"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP - 99bitcoins IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/07\\\/xrppp-2.png\",\"datePublished\":\"2026-03-11T14:11:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/af5a8990396ca6c1ac73bfff31df00b4\"},\"description\":\"Nella giornata di ieri gli ETF (Exchange-Traded Fund) americani su Bitcoin hanno registrato un aumento degli afflussi, nonostante Bitcoin sia sceso sotto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/07\\\/xrppp-2.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/07\\\/xrppp-2.png\",\"width\":841,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\",\"name\":\"99bitcoins IT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/af5a8990396ca6c1ac73bfff31df00b4\",\"name\":\"Federico Cappellini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g\",\"caption\":\"Federico Cappellini\"},\"description\":\"SEO copywriter con una solida esperienza nella scrittura di contenuti legati a criptovalute, giochi online e betting. Appassionato di poker e scrittura sportiva, unisce l\u2019analisi strategica al piacere della narrazione, offrendo articoli ricchi di dati ma anche coinvolgenti da leggere. Dal 2018, ha intrapreso un percorso di approfondimento nel mondo delle criptovalute, partecipando a corsi su Intelligenza Artificiale e DeFi. Questa formazione gli consente di offrire contenuti aggiornati e approfonditi, mantenendo uno sguardo critico e informato sulle evoluzioni del settore.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/author\\\/gianlucasisti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP - 99bitcoins IT","description":"Nella giornata di ieri gli ETF (Exchange-Traded Fund) americani su Bitcoin hanno registrato un aumento degli afflussi, nonostante Bitcoin sia sceso sotto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/","og_locale":"it_IT","og_type":"article","og_title":"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP - 99bitcoins IT","og_description":"Nella giornata di ieri gli ETF (Exchange-Traded Fund) americani su Bitcoin hanno registrato un aumento degli afflussi, nonostante Bitcoin sia sceso sotto","og_url":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/","og_site_name":"99bitcoins IT","article_published_time":"2026-03-11T14:11:18+00:00","og_image":[{"width":841,"height":426,"url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/07\/xrppp-2.png","type":"image\/png"}],"author":"Federico Cappellini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Federico Cappellini","Est. reading time":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/"},"author":{"name":"Federico Cappellini","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/af5a8990396ca6c1ac73bfff31df00b4"},"headline":"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP","datePublished":"2026-03-11T14:11:18+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/"},"wordCount":614,"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/07\/xrppp-2.png","keywords":["goldman sachs","XRP"],"articleSection":["Notizie"],"inLanguage":"it-IT","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/","url":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/","name":"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP - 99bitcoins IT","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/07\/xrppp-2.png","datePublished":"2026-03-11T14:11:18+00:00","author":{"@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/af5a8990396ca6c1ac73bfff31df00b4"},"description":"Nella giornata di ieri gli ETF (Exchange-Traded Fund) americani su Bitcoin hanno registrato un aumento degli afflussi, nonostante Bitcoin sia sceso sotto","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/#primaryimage","url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/07\/xrppp-2.png","contentUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/07\/xrppp-2.png","width":841,"height":426},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/it\/notizie\/afflussi-per-251-milioni-di-dollari-sugli-etf-bitcoin-mentre-goldman-sachs-diventa-il-primo-detentore-di-etf-xrp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/it\/"},{"@type":"ListItem","position":2,"name":"Notizie","item":"https:\/\/99bitcoins.com\/it\/notizie\/"},{"@type":"ListItem","position":3,"name":"Afflussi per 251 milioni di dollari sugli ETF Bitcoin mentre Goldman Sachs diventa il primo detentore di ETF XRP"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/it\/#website","url":"https:\/\/99bitcoins.com\/it\/","name":"99bitcoins IT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/af5a8990396ca6c1ac73bfff31df00b4","name":"Federico Cappellini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g","caption":"Federico Cappellini"},"description":"SEO copywriter con una solida esperienza nella scrittura di contenuti legati a criptovalute, giochi online e betting. Appassionato di poker e scrittura sportiva, unisce l\u2019analisi strategica al piacere della narrazione, offrendo articoli ricchi di dati ma anche coinvolgenti da leggere. Dal 2018, ha intrapreso un percorso di approfondimento nel mondo delle criptovalute, partecipando a corsi su Intelligenza Artificiale e DeFi. Questa formazione gli consente di offrire contenuti aggiornati e approfonditi, mantenendo uno sguardo critico e informato sulle evoluzioni del settore.","url":"https:\/\/99bitcoins.com\/it\/author\/gianlucasisti\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/19640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/users\/136067"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/comments?post=19640"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/19640\/revisions"}],"predecessor-version":[{"id":19643,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/19640\/revisions\/19643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media\/8681"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media?parent=19640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/categories?post=19640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/tags?post=19640"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/coin?post=19640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}