{"id":19549,"date":"2026-03-03T12:50:02","date_gmt":"2026-03-03T12:50:02","guid":{"rendered":"https:\/\/99bitcoins.com\/it\/?p=19549"},"modified":"2026-03-03T12:47:16","modified_gmt":"2026-03-03T12:47:16","slug":"il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/","title":{"rendered":"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Nella giornata di luned\u00ec 2 marzo 2026, il CEO di VanEck, Jan van Eck, <\/span><a href=\"https:\/\/www.cnbc.com\/video\/2026\/03\/02\/bitcoin-is-making-a-bottom-says-vaneck-funds-jan-van-eck.html\" rel=\"nofollow\" target=\"_blank\"><b>ha dichiarato<\/b><\/a><span style=\"font-weight: 400\">: \u201cAbbiamo assistito a un ciclo d&#8217;investimento in cui Bitcoin cresce per tre anni consecutivi, per poi subire una contrazione piuttosto marcata nel quarto. Il 2026 coincide proprio con questo quarto anno; ecco perch\u00e9 ci troviamo in una fase di mercato ribassista. Credo che a volte si tenda a complicare eccessivamente le cose. A mio avviso, stiamo toccando il fondo proprio ora\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cLa nostra prospettiva per il 2026 \u00e8 che Bitcoin resti regolato da un&#8217;offerta limitata a 21 milioni di unit\u00e0 e dal ciclo di halving, il meccanismo per cui i miner che sostengono la rete ricevono una ricompensa dimezzata ogni quattro anni\u201d, ha aggiunto.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Sottolineando la fase conclusiva del ciclo quadriennale, van Eck ha spiegato che la sua societ\u00e0 prevede per Bitcoin (BTC) una graduale ripresa nel corso dell&#8217;anno. Secondo il CEO, il ciclo di halving \u00e8 stato il principale driver del prezzo negli ultimi mesi, prevalendo su qualsiasi altro fattore legato ai fondamentali di BTC.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><b>Leggi anche:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-900\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/exchange-crypto\/\"><img decoding=\"async\" width=\"660\" height=\"345\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/exchange-crypto-copertina.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/exchange-crypto-copertina.jpg 660w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/exchange-crypto-copertina-300x157.jpg 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/exchange-crypto\/\">Exchange Crypto &#8211; Le piattaforme italiane migliori per comprare e scambiare Bitcoin nel 2026<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udea8VANECK CEO JAN VAN ECK: &quot;I THINK WE&#39;RE MAKING A BOTTOM&quot; ON BITCOIN<\/p>\n<p>VanEck CEO Jan van Eck stated he believes <a href=\"https:\/\/twitter.com\/search?q=%24BTC&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$BTC<\/a> is forming a market bottom, marking a notable shift in tone from the asset management giant that launched one of the first spot Bitcoin ETFs in the United States.\u2026 <a href=\"https:\/\/t.co\/rYMecqf1JS\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/rYMecqf1JS<\/a><\/p>\n<p>&mdash; BSCN (@BSCNews) <a href=\"https:\/\/twitter.com\/BSCNews\/status\/2028605976597983363?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">March 2, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2><b>Il segnale da 1,1 miliardi $: come si muovono le istituzioni nel settore crypto<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Se il <\/span><a href=\"https:\/\/99bitcoins.com\/it\/notizie\/bitcoin-ha-toccato-il-fondo-morgan-stanley-e-citi-accumulano-mentre-il-sentiment-crolla-ai-minimi-termini\/\"><b>bottom di Bitcoin<\/b><\/a><span style=\"font-weight: 400\"> si sta effettivamente consolidando nel range tra i 60.000 $ e i 64.000 $, il primo obiettivo per i rialzisti \u00e8 riconquistare e difendere con decisione la quota dei 68.400 $. Una rottura confermata sopra i 72.000 $ indicherebbe probabilmente la fine della correzione e la ripresa del rally post-halving.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"chart crypto-chart-instance\" id=\"crypto_chart_6a579b0f947a4\"\n\tdata-coin-id=\"bitcoin\">\n\t<div class=\"chart__header\">\n\t\t<div class=\"chart__info\">\n\t\t\t<div class=\"chart__info-icon\">\n\t\t\t\t<img id=\"crypto_chart_6a579b0f947a4-chart__info-icon-img\" \/>\n\t\t\t\t<div class=\"chart__info-name\" id=\"crypto_chart_6a579b0f947a4-chart__info-name\"><\/div>\n\t\t\t\t<div class=\"chart__info-symbol\" id=\"crypto_chart_6a579b0f947a4-chart__info-symbol\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-current\">\n\t\t\t\t<div class=\"chart__info-price\" id=\"crypto_chart_6a579b0f947a4-chart__info-price\"><\/div>\n\t\t\t\t<div class=\"chart__info-change\" id=\"crypto_chart_6a579b0f947a4-chart__info-change\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-extra\">\n\t\t\t\t<div class=\"chart__info-label\">Market Cap<\/div>\n\t\t\t\t<div class=\"chart__info-marketcap\" id=\"crypto_chart_6a579b0f947a4-chart__info-marketcap\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"chart__controls\">\n\t\t\t<div class=\"chart__controls-group\">\n\t\t\t\t<button class=\"chart__button chart__button--24h\"\n\t\t\t\t\tid=\"crypto_chart_6a579b0f947a4-btn-24h\">24h<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--7d\"\n\t\t\t\t\tid=\"crypto_chart_6a579b0f947a4-btn-7d\">7d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--30d\"\n\t\t\t\t\tid=\"crypto_chart_6a579b0f947a4-btn-30d\">30d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--1y\"\n\t\t\t\t\tid=\"crypto_chart_6a579b0f947a4-btn-1y\">1y<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--all-time\"\n\t\t\t\t\tid=\"crypto_chart_6a579b0f947a4-btn-all-time\">All Time<\/button>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"chart__container\">\n\t\t<canvas class=\"chart__canvas\" id=\"crypto_chart_6a579b0f947a4-cryptoChart\"><\/canvas>\n\t<\/div>\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\">Mentre i titoli dei media si concentrano sulla volatilit\u00e0, <\/span><a href=\"https:\/\/99bitcoins.com\/it\/notizie\/lassalto-di-wall-street-a-bitcoin-oltre-500-milioni-di-inflow-negli-etf\/\"><b>i giganti istituzionali si stanno muovendo<\/b><\/a><span style=\"font-weight: 400\"> in silenzio. Solo nell&#8217;ultima settimana, abbiamo registrato afflussi netti negli ETF Bitcoin per oltre 1,1 miliardi di dollari. Si tratta di una massa di capitale impressionante che suggerisce una sola conclusione: i pi\u00f9 grandi asset manager del mondo ritengono che Bitcoin stia scambiando a prezzi scontati.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Questo approccio \u00e8 tipico del comparto crypto istituzionale. Quando i prezzi flettono e il sentiment dei piccoli risparmiatori volge al pessimo, entit\u00e0 come BlackRock e Fidelity tendono ad accelerare le proprie strategie di accumulo. Non si tratta di operazioni di day trading per un profitto marginale del 5%, ma di un posizionamento strategico in vista della prossima gamba rialzista.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Non si tratta, peraltro, di un fenomeno limitato ai soli colossi statunitensi. Stiamo assistendo a una validazione globale di questa tendenza, come dimostrato dal recente investimento di Intesa Sanpaolo in ETF Bitcoin, a ulteriore conferma che lo &#8220;smart money&#8221; interpreta questi livelli come un&#8217;opportunit\u00e0 d&#8217;ingresso e non come un segnale d&#8217;uscita dal mercato.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><b>Leggi anche:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-628\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/wallet-bitcoin\/\"><img decoding=\"async\" width=\"1366\" height=\"768\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/bitcoin-wallet.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"bitcoin wallet\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/bitcoin-wallet.png 1366w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/bitcoin-wallet-300x169.png 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/bitcoin-wallet-1024x576.png 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/bitcoin-wallet-768x432.png 768w\" sizes=\"(max-width: 1366px) 100vw, 1366px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/wallet-bitcoin\/\">I migliori wallet Bitcoin del 2026<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<h2><b>Che cos&#8217;\u00e8 il ciclo quadriennale di Bitcoin?<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Attualmente il mercato appare profondamente diviso. Analizzando il Fear and Greed Index, il sentiment risulta instabile: i trader retail appaiono esausti a causa dell&#8217;andamento laterale dei prezzi e dei recenti test nell&#8217;area dei 60.000 $.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Secondo il CEO di VanEck, Jan van Eck, la chiave di lettura risiede nella <\/span><a href=\"https:\/\/cointelegraph.com\/news\/bitcoin-forming-bottom-vaneck-ceo\" rel=\"nofollow\" target=\"_blank\"><b>prevedibilit\u00e0 storica di Bitcoin<\/b><\/a><span style=\"font-weight: 400\">. Il manager sostiene che gli analisti spesso complichino inutilmente il quadro, ignorando come il ciclo quadriennale rimanga la forza dominante dietro l&#8217;azione dei prezzi.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tale ciclo ruota attorno all&#8217;halving, un evento programmato nel codice stesso del protocollo che dimezza l&#8217;emissione di nuove monete ogni quattro anni. Storicamente, questo shock dell&#8217;offerta genera un ritmo ciclico: una fase parabolica, un anno di correzione e una fase di recupero.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Van Eck suggerisce che l&#8217;attuale incertezza non sia altro che il <\/span><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/migliori-criptovalute\/\"><b>mercato<\/b><\/a><span style=\"font-weight: 400\"> intento a seguire questo &#8220;copione&#8221; prestabilito. Piuttosto che un mercato compromesso, potremmo essere di fronte alla naturale formazione di un supporto minimo prima che la contrazione dell&#8217;offerta faccia sentire i suoi effetti reali. Questa tesi \u00e8 corroborata dai dati on-chain, i quali indicano che la fase di capitolazione dei miner di Bitcoin \u00e8 ormai agli sgoccioli, un segnale tecnico che, storicamente, ha sempre identificato il pavimento delle principali correzioni.<\/span><\/p>\n<p><span style=\"font-weight: 400\">    <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\"><\/h2>\r\n        <\/span><\/p>\n<p><b>Punti chiave:<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">La domanda istituzionale \u00e8 in forte aumento: registrati oltre 1,1 miliardi di dollari di afflussi negli ETF Bitcoin in una sola settimana, nonostante il timore diffuso tra gli investitori retail.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Gli investitori dovrebbero monitorare il supporto a 58.000 $ come soglia critica, puntando al ritorno sopra i 72.000 $ per confermare il trend rialzista.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">    <\/div>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><span style=\"font-weight: 400\">    <ul class=\"nnbtc-green-checkmarks-list\">\r\n        <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <li class=\"nnbtc-green-checkmarks-list__item\">\r\n        <p class=\"nnbtc-green-checkmarks-list__item-heading\">\r\n            Resta sempre aggiornato con 99Bitcoins        <\/p>\r\n        <\/span><\/p>\n<p><span style=\"font-weight: 400\">\u2192 Non perdere nemmeno un movimento del mercato!<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><b>Segui<\/b><a href=\"https:\/\/twitter.com\/99bitcoinshq\" rel=\"nofollow\" target=\"_blank\"> <b>99Bitcoins su X (Twitter)<\/b><\/a><span style=\"font-weight: 400\"> per ricevere in tempo reale gli ultimi aggiornamenti e i flash news pi\u00f9 caldi del settore.<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Iscriviti al<\/b><a href=\"https:\/\/www.youtube.com\/@99Bitcoins\" rel=\"nofollow\" target=\"_blank\"> <b>canale YouTube<\/b><\/a> <span style=\"font-weight: 400\">per non perdere le analisi quotidiane degli esperti e approfondimenti video che ti aiuteranno a navigare il mercato con consapevolezza.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">    <\/li>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <\/ul>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella giornata di luned\u00ec 2 marzo 2026, il CEO di VanEck, Jan van Eck, ha dichiarato: \u201cAbbiamo assistito a un ciclo d&#8217;investimento in cui Bitcoin cresce per tre anni consecutivi, per poi subire una contrazione piuttosto marcata nel quarto. Il 2026 coincide proprio con questo quarto anno; ecco perch\u00e9 ci troviamo in una fase di..<\/p>\n","protected":false},"author":136055,"featured_media":19550,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[11],"coin":[2],"class_list":["post-19549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa - 99bitcoins IT<\/title>\n<meta name=\"description\" content=\"Nella giornata di luned\u00ec 2 marzo 2026, il CEO di VanEck, Jan van Eck, ha dichiarato: \u201cAbbiamo assistito a un ciclo d&#039;investimento in cui Bitcoin cresce\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa - 99bitcoins IT\" \/>\n<meta property=\"og:description\" content=\"Nella giornata di luned\u00ec 2 marzo 2026, il CEO di VanEck, Jan van Eck, ha dichiarato: \u201cAbbiamo assistito a un ciclo d&#039;investimento in cui Bitcoin cresce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins IT\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-03T12:50:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/03\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Orfeo Barone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Orfeo Barone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/\"},\"author\":{\"name\":\"Orfeo Barone\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/b45375a1ee3d38afb34b2193acf159d5\"},\"headline\":\"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa\",\"datePublished\":\"2026-03-03T12:50:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/\"},\"wordCount\":835,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/03\\\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png\",\"keywords\":[\"Bitcoin\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/\",\"name\":\"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa - 99bitcoins IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/03\\\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png\",\"datePublished\":\"2026-03-03T12:50:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/b45375a1ee3d38afb34b2193acf159d5\"},\"description\":\"Nella giornata di luned\u00ec 2 marzo 2026, il CEO di VanEck, Jan van Eck, ha dichiarato: \u201cAbbiamo assistito a un ciclo d'investimento in cui Bitcoin cresce\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/03\\\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/03\\\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png\",\"width\":650,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\",\"name\":\"99bitcoins IT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/b45375a1ee3d38afb34b2193acf159d5\",\"name\":\"Orfeo Barone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g\",\"caption\":\"Orfeo Barone\"},\"description\":\"Esperto di criptovalute e finanza, noto per la sua capacit\u00e0 di analizzare i mercati digitali con precisione e chiarezza. Con un background in economia e appassionato di tecnologia blockchain, ha scritto per numerose testate specializzate, fornendo approfondimenti su investimenti, strategie di trading e regolamentazioni del settore. Apprezzato per il suo stile diretto e informato, Orfeo Barone \u00e8 una voce autorevole nel panorama della finanza digitale.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/author\\\/giovanni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa - 99bitcoins IT","description":"Nella giornata di luned\u00ec 2 marzo 2026, il CEO di VanEck, Jan van Eck, ha dichiarato: \u201cAbbiamo assistito a un ciclo d'investimento in cui Bitcoin cresce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/","og_locale":"it_IT","og_type":"article","og_title":"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa - 99bitcoins IT","og_description":"Nella giornata di luned\u00ec 2 marzo 2026, il CEO di VanEck, Jan van Eck, ha dichiarato: \u201cAbbiamo assistito a un ciclo d'investimento in cui Bitcoin cresce","og_url":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/","og_site_name":"99bitcoins IT","article_published_time":"2026-03-03T12:50:02+00:00","og_image":[{"width":650,"height":650,"url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/03\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png","type":"image\/png"}],"author":"Orfeo Barone","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Orfeo Barone","Est. reading time":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/"},"author":{"name":"Orfeo Barone","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/b45375a1ee3d38afb34b2193acf159d5"},"headline":"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa","datePublished":"2026-03-03T12:50:02+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/"},"wordCount":835,"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/03\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png","keywords":["Bitcoin"],"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/","url":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/","name":"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa - 99bitcoins IT","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/03\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png","datePublished":"2026-03-03T12:50:02+00:00","author":{"@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/b45375a1ee3d38afb34b2193acf159d5"},"description":"Nella giornata di luned\u00ec 2 marzo 2026, il CEO di VanEck, Jan van Eck, ha dichiarato: \u201cAbbiamo assistito a un ciclo d'investimento in cui Bitcoin cresce","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/#primaryimage","url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/03\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png","contentUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/03\/Il-CEO-di-VanEck-ritiene-che-il-fondo-di-Bitcoin-sia-stato-raggiunto.png","width":650,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/it\/notizie\/il-ceo-di-vaneck-ritiene-che-il-fondo-di-bitcoin-sia-stato-raggiunto-ciclo-quadriennale-e-afflussi-di-etf-da-11-miliardi-indicano-la-ripresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/it\/"},{"@type":"ListItem","position":2,"name":"Notizie","item":"https:\/\/99bitcoins.com\/it\/notizie\/"},{"@type":"ListItem","position":3,"name":"Il CEO di VanEck ritiene che il fondo di Bitcoin sia stato raggiunto: ciclo quadriennale e afflussi di ETF da 1,1 miliardi $ indicano la ripresa"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/it\/#website","url":"https:\/\/99bitcoins.com\/it\/","name":"99bitcoins IT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/b45375a1ee3d38afb34b2193acf159d5","name":"Orfeo Barone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g","caption":"Orfeo Barone"},"description":"Esperto di criptovalute e finanza, noto per la sua capacit\u00e0 di analizzare i mercati digitali con precisione e chiarezza. Con un background in economia e appassionato di tecnologia blockchain, ha scritto per numerose testate specializzate, fornendo approfondimenti su investimenti, strategie di trading e regolamentazioni del settore. Apprezzato per il suo stile diretto e informato, Orfeo Barone \u00e8 una voce autorevole nel panorama della finanza digitale.","url":"https:\/\/99bitcoins.com\/it\/author\/giovanni\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/19549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/users\/136055"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/comments?post=19549"}],"version-history":[{"count":3,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/19549\/revisions"}],"predecessor-version":[{"id":19554,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/19549\/revisions\/19554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media\/19550"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media?parent=19549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/categories?post=19549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/tags?post=19549"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/coin?post=19549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}