{"id":19059,"date":"2026-02-09T12:08:54","date_gmt":"2026-02-09T12:08:54","guid":{"rendered":"https:\/\/99bitcoins.com\/it\/?p=19059"},"modified":"2026-02-09T12:08:54","modified_gmt":"2026-02-09T12:08:54","slug":"crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/","title":{"rendered":"Crollo del mercato azionario 2026: 155 anni di dati dicono che &#8220;sta arrivando&#8221;"},"content":{"rendered":"<p>L&#8217;S&amp;P 500 sta attraversando una serie storica, ma in senso negativo. Dal 1957, gli anni delle elezioni di met\u00e0 mandato (midterm) registrano mediamente ribassi del 18%, con correzioni nel 70% dei cicli.<\/p>\n<p>Questa volta, i <b>dazi di Trump<\/b> stanno dando fuoco al commercio, ai margini e alle catene di approvvigionamento contemporaneamente. Il solito massacro di met\u00e0 mandato con l&#8217;aggiunta di un accelerante.<\/p>\n<p>Ci\u00f2 con cui abbiamo a che fare \u00e8:<\/p>\n<ul>\n<li>\n<p><b>P\/E forward dell&#8217;S&amp;P 500 a 22<\/b> (pari ai livelli della <b>bolla dot-com<\/b>)<\/p>\n<\/li>\n<li>\n<p>Gli anni di elezioni di met\u00e0 mandato vedono ribassi mediani del <b>19%<\/b><\/p>\n<\/li>\n<li>\n<p>I dazi di Trump stanno schiacciando la crescita del PIL<\/p>\n<\/li>\n<\/ul>\n<p><span style=\"font-size: medium\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><strong>Leggi anche:<\/strong><\/p>\n\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-282\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/criptovalute-che-esploderanno\/\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/unnamed-6.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/unnamed-6.jpg 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/unnamed-6-300x300.jpg 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/unnamed-6-150x150.jpg 150w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/unnamed-6-768x768.jpg 768w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/unnamed-6-148x148.jpg 148w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/unnamed-6-64x64.jpg 64w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/unnamed-6-600x600.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/criptovalute-che-esploderanno\/\">Le prossime criptovalute che esploderanno nel 2026<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n\n<\/div><\/div>\n<h3><b>Crollo del mercato 2026: non abbiamo ancora toccato il fondo&#8230; o forse s\u00ec?<\/b><\/h3>\n<p>La storia suggerisce che la volatilit\u00e0 arrivi prima del sollievo. I principali indici azionari hanno spesso raggiunto il picco durante le midterm, per poi subire vendite brusche e infine stabilizzarsi.<\/p>\n<p>In sintesi: aspettatevi un ritracciamento del <b>10-20%<\/b> prima che i compratori ritornino. Una correzione del 10% testerebbe i recenti supporti di breakout. Un ribasso del 18% colpirebbe il supporto del trend a lungo termine che ha tenuto attraverso molteplici cicli. Preparatevi al dolore, ma non abbandonate il trend.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Every <a href=\"https:\/\/twitter.com\/search?q=%24BTC&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$BTC<\/a> cycle bottom has happened 15% below its Long-Term Holder Realized Price.<\/p>\n<p>Right now, it&#39;s sitting around $40,300.<\/p>\n<p>A 15% dip means Bitcoin will bottom around $34,500.<\/p>\n<p>I don&#39;t personally think we could go this low. <a href=\"https:\/\/t.co\/CqPnY2in5U\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/CqPnY2in5U<\/a><\/p>\n<p>&mdash; Ted (@TedPillows) <a href=\"https:\/\/twitter.com\/TedPillows\/status\/2020223164069081576?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">February 7, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>L&#8217;incertezza \u00e8 il motore di tutto questo. Le elezioni di met\u00e0 mandato rimescolano il Congresso, lasciando poco chiara la direzione fiscale e normativa. Dopo il voto, la nebbia si dirada e i mercati si stabilizzano.<\/p>\n<blockquote>\n<p>&#8220;Sono stati persi molti pi\u00f9 soldi dagli investitori che cercavano di anticipare le correzioni di quanti ne siano stati persi nelle correzioni stesse.&#8221;<\/p>\n<\/blockquote>\n<p style=\"text-align: right\">\u2014 <b>Peter Lynch<\/b><\/p>\n<p><span style=\"font-size: medium\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><strong>Leggi anche:<\/strong><\/p>\n\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-6372\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/migliori-criptovalute\/\"><img decoding=\"async\" width=\"683\" height=\"336\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/06\/cover-1.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/06\/cover-1.png 683w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/06\/cover-1-300x148.png 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/06\/cover-1-130x63.png 130w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/06\/cover-1-308x152.png 308w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/06\/cover-1-350x172.png 350w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/migliori-criptovalute\/\">Le Migliori Criptovalute Presenti sul Mercato nel 2026<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n\n<\/div><\/div>\n<p><b>Questi sono i dati che contano in questo momento<\/b><\/p>\n<p>FactSet aggrega oltre 12.800 rating di analisti che indicano un target per l&#8217;indice di <b>8.146 entro febbraio 2027<\/b>, con un rialzo di circa il 17% rispetto ai livelli attuali.<\/p>\n<p>Negli ultimi quattro anni, i target mediani di fine anno sono stati errati di circa 16 punti percentuali. Le valutazioni sono elevate, con un <b>P\/E forward di circa 22,2x<\/b> rispetto a una media quinquennale vicina a 20x, il che aumenta la sensibilit\u00e0 al ribasso in caso di utili deludenti. I dati FRED mostrano un rallentamento della spinta inflazionistica e i prezzi del CME suggeriscono almeno un taglio dei tassi all&#8217;orizzonte, un fattore favorevole nel medio termine.<\/p>\n<p>Inoltre, i numeri della disoccupazione stanno salendo rapidamente:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-19061 \" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/HAjywdOXEAAac8c.jpg\" alt=\"\" width=\"843\" height=\"617\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/HAjywdOXEAAac8c.jpg 975w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/HAjywdOXEAAac8c-300x220.jpg 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/HAjywdOXEAAac8c-768x562.jpg 768w\" sizes=\"(max-width: 843px) 100vw, 843px\" \/><\/p>\n<p>Aspettatevi volatilit\u00e0 fino alle elezioni di met\u00e0 mandato; aspettatevi opportunit\u00e0 subito dopo. Tagliate i titoli a bassa convinzione, mantenete la liquidit\u00e0 pronta e rispettate i livelli di supporto. Io mi preparo per il ritracciamento, non per i titoli dei giornali.<\/p>\n<h3><b>Anche le prevendite Crypto stanno pompando? Maxi Doge \u00e8 il prossimo Shiba Inu?<\/b><\/h3>\n<p>Mentre Bitcoin sta sprofondando nella crosta terrestre e i metalli preziosi (PM) stanno pompando verso la Via Lattea, anche le <a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/crypto-presale\/\">prevendite crypto<\/a> sono sul punto di esplodere. Una di queste \u00e8 <a href=\"https:\/\/99bitcoins.com\/it\/visit\/maxi-doge\/\" rel=\"nofollow sponsored\" target=\"_blank\"><b>Maxi Doge (MAXI)<\/b><\/a>, che punta a diventare la migliore meme-coin a tema animale del 2026.<\/p>\n<p>La prevendita ha gi\u00e0 raccolto oltre <b>4,8 milioni di dollari<\/b> con un prezzo del token di <b>0,0002801 $<\/b>, e il team sta puntando con forza su un mix di ironia e incentivi studiati a tavolino.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"zxx\" dir=\"ltr\"><a href=\"https:\/\/t.co\/g1dSGxsH8s\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/g1dSGxsH8s<\/a><\/p>\n<p>&mdash; MaxiDoge (@MaxiDoge_) <a href=\"https:\/\/twitter.com\/MaxiDoge_\/status\/2013310928817676672?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 19, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Maxi Doge possiede un alto valore memetico; inoltre, circa un quarto della fornitura totale di Maxi Doge \u00e8 destinata ai premi per la community e a partnership con piattaforme di trading ad alta leva, dotando MAXI di un motore integrato per la speculazione e il coinvolgimento degli utenti. I possessori possono anche mettere in staking i propri token per ottenere rendimenti annuali a tre cifre, superiori al <b>100%<\/b>.<\/p>\n<p>In fondo rimane una meme coin, ma la struttura di MAXI dimostra che potrebbe essere qualcosa di pi\u00f9.<\/p>\n<p><span style=\"font-weight: 400\">\ud83d\udccc <\/span>Per ulteriori dettagli consulta anche la nostra <a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/comprare-maxi-doge\/\"><strong>guida su come comprare Maxi Doge<\/strong><\/a>.<\/p>\n<p><span style=\"font-weight: 400\"><a href=\"https:\/\/99bitcoins.com\/it\/visit\/maxi-doge\/\" class=\"sc-button sc-button-green sc-button-medium\" target=\"_blank\"  rel=\"nofollow sponsored\"><span>Vai a Maxi Doge<\/span><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;S&amp;P 500 sta attraversando una serie storica, ma in senso negativo. Dal 1957, gli anni delle elezioni di met\u00e0 mandato (midterm) registrano mediamente ribassi del 18%, con correzioni nel 70% dei cicli. Questa volta, i dazi di Trump stanno dando fuoco al commercio, ai margini e alle catene di approvvigionamento contemporaneamente. Il solito massacro di..<\/p>\n","protected":false},"author":136055,"featured_media":19060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[12],"coin":[2],"class_list":["post-19059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-prevendite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crollo del mercato azionario 2026: 155 anni di dati dicono che &quot;sta arrivando&quot; - 99bitcoins IT<\/title>\n<meta name=\"description\" content=\"L&#039;S&amp;P 500 sta attraversando una serie storica, ma in senso negativo. Dal 1957, gli anni delle elezioni di met\u00e0 mandato (midterm) registrano mediamente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crollo del mercato azionario 2026: 155 anni di dati dicono che &quot;sta arrivando&quot; - 99bitcoins IT\" \/>\n<meta property=\"og:description\" content=\"L&#039;S&amp;P 500 sta attraversando una serie storica, ma in senso negativo. Dal 1957, gli anni delle elezioni di met\u00e0 mandato (midterm) registrano mediamente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins IT\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-09T12:08:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/unnamed-1-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Orfeo Barone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Orfeo Barone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/\"},\"author\":{\"name\":\"Orfeo Barone\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/b45375a1ee3d38afb34b2193acf159d5\"},\"headline\":\"Crollo del mercato azionario 2026: 155 anni di dati dicono che &#8220;sta arrivando&#8221;\",\"datePublished\":\"2026-02-09T12:08:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/\"},\"wordCount\":698,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/02\\\/unnamed-1-3.jpg\",\"keywords\":[\"Prevendite\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/\",\"name\":\"Crollo del mercato azionario 2026: 155 anni di dati dicono che \\\"sta arrivando\\\" - 99bitcoins IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/02\\\/unnamed-1-3.jpg\",\"datePublished\":\"2026-02-09T12:08:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/b45375a1ee3d38afb34b2193acf159d5\"},\"description\":\"L'S&amp;P 500 sta attraversando una serie storica, ma in senso negativo. Dal 1957, gli anni delle elezioni di met\u00e0 mandato (midterm) registrano mediamente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/02\\\/unnamed-1-3.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/02\\\/unnamed-1-3.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Crollo del mercato azionario 2026: 155 anni di dati dicono che &#8220;sta arrivando&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\",\"name\":\"99bitcoins IT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/b45375a1ee3d38afb34b2193acf159d5\",\"name\":\"Orfeo Barone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g\",\"caption\":\"Orfeo Barone\"},\"description\":\"Esperto di criptovalute e finanza, noto per la sua capacit\u00e0 di analizzare i mercati digitali con precisione e chiarezza. Con un background in economia e appassionato di tecnologia blockchain, ha scritto per numerose testate specializzate, fornendo approfondimenti su investimenti, strategie di trading e regolamentazioni del settore. Apprezzato per il suo stile diretto e informato, Orfeo Barone \u00e8 una voce autorevole nel panorama della finanza digitale.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/author\\\/giovanni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crollo del mercato azionario 2026: 155 anni di dati dicono che \"sta arrivando\" - 99bitcoins IT","description":"L'S&amp;P 500 sta attraversando una serie storica, ma in senso negativo. Dal 1957, gli anni delle elezioni di met\u00e0 mandato (midterm) registrano mediamente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/","og_locale":"it_IT","og_type":"article","og_title":"Crollo del mercato azionario 2026: 155 anni di dati dicono che \"sta arrivando\" - 99bitcoins IT","og_description":"L'S&amp;P 500 sta attraversando una serie storica, ma in senso negativo. Dal 1957, gli anni delle elezioni di met\u00e0 mandato (midterm) registrano mediamente","og_url":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/","og_site_name":"99bitcoins IT","article_published_time":"2026-02-09T12:08:54+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/unnamed-1-3.jpg","type":"image\/jpeg"}],"author":"Orfeo Barone","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Orfeo Barone","Est. reading time":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/"},"author":{"name":"Orfeo Barone","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/b45375a1ee3d38afb34b2193acf159d5"},"headline":"Crollo del mercato azionario 2026: 155 anni di dati dicono che &#8220;sta arrivando&#8221;","datePublished":"2026-02-09T12:08:54+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/"},"wordCount":698,"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/unnamed-1-3.jpg","keywords":["Prevendite"],"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/","url":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/","name":"Crollo del mercato azionario 2026: 155 anni di dati dicono che \"sta arrivando\" - 99bitcoins IT","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/unnamed-1-3.jpg","datePublished":"2026-02-09T12:08:54+00:00","author":{"@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/b45375a1ee3d38afb34b2193acf159d5"},"description":"L'S&amp;P 500 sta attraversando una serie storica, ma in senso negativo. Dal 1957, gli anni delle elezioni di met\u00e0 mandato (midterm) registrano mediamente","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/#primaryimage","url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/unnamed-1-3.jpg","contentUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/unnamed-1-3.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/it\/notizie\/crollo-del-mercato-azionario-2026-155-anni-di-dati-dicono-che-sta-arrivando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/it\/"},{"@type":"ListItem","position":2,"name":"Notizie","item":"https:\/\/99bitcoins.com\/it\/notizie\/"},{"@type":"ListItem","position":3,"name":"Crollo del mercato azionario 2026: 155 anni di dati dicono che &#8220;sta arrivando&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/it\/#website","url":"https:\/\/99bitcoins.com\/it\/","name":"99bitcoins IT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/b45375a1ee3d38afb34b2193acf159d5","name":"Orfeo Barone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2be2347ff9814fd59d237861cd96c6fc8efd531d7d052cb40e0b286509d02553?s=96&d=mm&r=g","caption":"Orfeo Barone"},"description":"Esperto di criptovalute e finanza, noto per la sua capacit\u00e0 di analizzare i mercati digitali con precisione e chiarezza. Con un background in economia e appassionato di tecnologia blockchain, ha scritto per numerose testate specializzate, fornendo approfondimenti su investimenti, strategie di trading e regolamentazioni del settore. Apprezzato per il suo stile diretto e informato, Orfeo Barone \u00e8 una voce autorevole nel panorama della finanza digitale.","url":"https:\/\/99bitcoins.com\/it\/author\/giovanni\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/19059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/users\/136055"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/comments?post=19059"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/19059\/revisions"}],"predecessor-version":[{"id":19062,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/19059\/revisions\/19062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media\/19060"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media?parent=19059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/categories?post=19059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/tags?post=19059"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/coin?post=19059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}