{"id":18958,"date":"2026-02-06T08:31:38","date_gmt":"2026-02-06T08:31:38","guid":{"rendered":"https:\/\/99bitcoins.com\/it\/?p=18958"},"modified":"2026-02-06T08:26:33","modified_gmt":"2026-02-06T08:26:33","slug":"burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/","title":{"rendered":"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Il gestore di hedge fund Michael Burry ha recentemente lanciato un pesante monito che ricalca i suoi celebri avvertimenti durante la crisi finanziaria del 2008. Questa volta, l&#8217;attenzione \u00e8 rivolta ai colossi del Big Tech, all&#8217;IA e a Bitcoin (BTC). Nello specifico, Burry teme che un ulteriore calo del prezzo di BTC possa innescare una \u201cspirale mortale\u201d, aggravata dall&#8217;assenza di un \u201ccaso d&#8217;uso organico\u201d per la principale criptovaluta del mercato. Tuttavia, \u00e8 proprio questo ci\u00f2 che <\/span><a href=\"https:\/\/99bitcoins.com\/it\/visit\/bitcoin-hyper\/\" rel=\"nofollow sponsored\" target=\"_blank\"><span style=\"font-weight: 400\">Bitcoin Hyper (HYPER)<\/span><\/a><span style=\"font-weight: 400\"> si propone di rivoluzionare.<\/span><\/p>\n<p><span style=\"font-weight: 400\">In qualit\u00e0 di Layer-2 per Bitcoin pi\u00f9 rapido attualmente in fase di sviluppo, Bitcoin Hyper garantisce una scalabilit\u00e0 estrema con milioni di TPS e una latenza ultra-bassa per un sequenziamento quasi istantaneo. Questa infrastruttura permette a BTC di evolvere oltre il suo attuale ruolo di asset di rischio volatile, trasformandolo in una valuta funzionale la cui domanda possa fungere da cuscinetto durante le fasi di turbolenza dei mercati.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tale approccio alla costruzione di un Layer-2 solido coincide, peraltro, con la <\/span><a href=\"https:\/\/99bitcoins.com\/it\/notizie\/vitalik-buterin-scuote-il-mercato-la-visione-dei-layer-2-di-ethereum-e-superata\/\"><span style=\"font-weight: 400\">visione espressa dal fondatore di Ethereum, Vitalik Buterin<\/span><\/a><span style=\"font-weight: 400\">, riguardo alla nuova rotta necessaria per le catene Layer-2 specializzate.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Alla luce di queste premesse tecnologiche, non sorprende che Bitcoin Hyper abbia gi\u00e0 raccolto oltre 31,25 milioni di dollari nella sua attuale prevendita. I nuovi investitori, o chi desidera incrementare la propria posizione nel token nativo HYPER ai prezzi di prevendita, possono ancora aderire al round in corso a 0,0136751 $.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tuttavia, \u00e8 necessario agire con tempestivit\u00e0: questa tariffa rimarr\u00e0 valida solo per le prossime otto ore, prima dell&#8217;aumento previsto per il round successivo.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><b>Leggi anche:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-298\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/crypto-presale\/\"><img decoding=\"async\" width=\"1200\" height=\"686\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-crypto-presale-2025.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"migliori crypto presale 2025\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-crypto-presale-2025.jpeg 1200w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-crypto-presale-2025-300x172.jpeg 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-crypto-presale-2025-1024x585.jpeg 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-crypto-presale-2025-768x439.jpeg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/crypto-presale\/\">Le migliori crypto presale del 2026 &#8211; Guida per scegliere le migliori prevendite crypto<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<h2><b>Una crisi finanziaria 2.0 secondo Burry?<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Michael Burry, l&#8217;investitore diventato celebre per aver scommesso contro il mercato immobiliare statunitense nel 2008, ha riservato agli investitori crypto un boccone amaro con le sue ultime dichiarazioni. In una <\/span><a href=\"https:\/\/michaeljburry.substack.com\/p\/short-thoughts-february-2-2026\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">serie di post sul suo Substack, Cassandra Unchained<\/span><\/a><span style=\"font-weight: 400\">, Burry sostiene che il settore tecnologico, l&#8217;IA e le criptovalute si trovino attualmente all&#8217;interno di una bolla colossale.<\/span><\/p>\n<p><span style=\"font-weight: 400\">In particolare, egli argomenta che Bitcoin rimanga un asset puramente speculativo, incapace di affermarsi come reale alternativa rifugio all&#8217;oro.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Burry avverte che la contrazione dei prezzi potrebbe innescare una \u201cspirale mortale\u201d, in cui le liquidazioni forzate alimentano un loop di vendite che si auto-rinforza. Con Bitcoin scambiato oggi a 71.000 $, l&#8217;esperto segnala che un eventuale scivolamento verso i 50.000 $ potrebbe spingere numerose aziende di mining sull&#8217;orlo della bancarotta.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Inoltre, ha evidenziato come a fine gennaio il declino del comparto crypto abbia probabilmente costretto investitori istituzionali e tesorerie aziendali a liquidare posizioni in oro e argento per oltre 1 miliardo di dollari al fine di coprire le perdite registrate sul fronte digitale.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Considerando che oltre 200 societ\u00e0 pubbliche detengono complessivamente 80 miliardi di dollari in BTC, e che gli ETF spot custodiscono una cifra ancora superiore, pari a 114 miliardi di dollari, Burry teme che un ribasso prolungato possa precludere a queste aziende l&#8217;accesso ai mercati dei capitali, traducendosi in miliardi di dollari di perdite non realizzate.<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-18960 size-large\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Screenshot-2026-02-05-145854-1024x677.jpg\" alt=\"\" width=\"1024\" height=\"677\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Screenshot-2026-02-05-145854-1024x677.jpg 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Screenshot-2026-02-05-145854-300x198.jpg 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Screenshot-2026-02-05-145854-768x508.jpg 768w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Screenshot-2026-02-05-145854.jpg 1059w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span style=\"font-weight: 400\">Fonte &#8211; <\/span><a href=\"https:\/\/bitcointreasuries.net\/etfs-and-exchanges\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">https:\/\/bitcointreasuries.net\/etfs-and-exchanges<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400\">L&#8217;investitore ha persino messo in guardia sul fatto che il mercato dei futures sui metalli tokenizzati potrebbe \u201ccollassare in un buco nero senza acquirenti\u201d qualora questa spirale dovesse proseguire.<\/span><\/p>\n<p><span style=\"font-weight: 400\">In ultima analisi, secondo Burry, a Bitcoin mancherebbe una reale utilit\u00e0 \u201corganica\u201d che possa frenare o arrestare la sua discesa.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tuttavia, egli potrebbe non aver ancora considerato l&#8217;impatto di <\/span><a href=\"https:\/\/99bitcoins.com\/it\/visit\/bitcoin-hyper\/\" rel=\"nofollow sponsored\" target=\"_blank\"><span style=\"font-weight: 400\">Bitcoin Hyper<\/span><\/a><span style=\"font-weight: 400\"> e la sua missione: creare proprio quel tipo di utilit\u00e0 necessaria per BTC, trasformandolo in un asset ad alta velocit\u00e0 dove le applicazioni, potenziate dalla rapidit\u00e0 di Solana e dalla sicurezza di Bitcoin, lo utilizzino come mezzo di scambio primario.<\/span><\/p>\n<h2><b>Ecco come Bitcoin Hyper introduce casi d\u2019uso organici per BTC<\/b><\/h2>\n<p><a href=\"https:\/\/99bitcoins.com\/it\/visit\/bitcoin-hyper\/\" rel=\"nofollow sponsored\" target=\"_blank\"><span style=\"font-weight: 400\">Bitcoin Hyper<\/span><\/a><span style=\"font-weight: 400\"> sta sviluppando la rete Layer-2 pi\u00f9 veloce su Bitcoin integrando la Solana Virtual Machine (SVM), il motore ad alte prestazioni di Solana, e collegandola al network Bitcoin tramite un bridge canonico. Questa architettura garantisce che la validit\u00e0 delle transazioni sia regolata da ZK Proofs, assicurando una connessione trustless tra i due livelli.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Il bridge canonico opera bloccando i BTC nativi sulla catena base e coniando una versione wrapped, compatibile con SVM, su Bitcoin Hyper. Questo BTC wrapped diventa la valuta operativa dell&#8217;ecosistema, permettendo la proliferazione di <\/span><a href=\"https:\/\/99bitcoins.com\/it\/notizie\/bitcoin-hyper-la-svolta-layer-2-che-rende-btc-piu-veloce-e-spendibile\/\"><span style=\"font-weight: 400\">applicazioni decentralizzate ibride Solana-Bitcoin<\/span><\/a><span style=\"font-weight: 400\">. Queste applicazioni possono coprire una vasta gamma di ambiti, dai servizi finanziari fino ai social network decentralizzati: esattamente il tipo di utilit\u00e0 che Burry ritiene manchi a Bitcoin.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Come accennato in precedenza, questo approccio risponde direttamente ai criteri di specializzazione recentemente indicati dal fondatore di Ethereum. Vitalik sostiene che i moderni Layer-2 debbano evolversi, in quanto non possono essere semplici &#8220;shard brandizzati&#8221; che offrono spazio extra per i blocchi o che collegano una EVM a un bridge multisig.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">There have recently been some discussions on the ongoing role of L2s in the Ethereum ecosystem, especially in the face of two facts:<\/p>\n<p>* L2s&#39; progress to stage 2 (and, secondarily, on interop) has been far slower and more difficult than originally expected<br \/>* L1 itself is scaling,\u2026<\/p>\n<p>&mdash; vitalik.eth (@VitalikButerin) <a href=\"https:\/\/twitter.com\/VitalikButerin\/status\/2018711006394843585?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">February 3, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Al contrario, ritiene che un vero Layer-2 debba offrire un valore specializzato, che includa: una scalabilit\u00e0 estrema capace di gestire milioni di TPS (traguardi irraggiungibili anche per un Layer-1 potenziato), una latenza ultra-bassa per sequenziamenti istantanei dedicati ad applicazioni ad alta velocit\u00e0, e una sicurezza trustless che sostituisca i multisig gestiti da umani con la certezza matematica delle ZK Proofs.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Sfruttando il recente aggiornamento Firedancer della SVM, Bitcoin Hyper punta a un limite teorico di 1 milione di transazioni al secondo, soddisfacendo appieno la specializzazione auspicata da Vitalik. Le ZK Proofs, inoltre, assicurano che ogni operazione sia verificata crittograficamente senza la necessit\u00e0 di intermediari.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Rispettando questi standard tecnici d&#8217;eccellenza, <\/span><a href=\"https:\/\/99bitcoins.com\/it\/visit\/bitcoin-hyper\/\" rel=\"nofollow sponsored\" target=\"_blank\"><span style=\"font-weight: 400\">Bitcoin Hyper<\/span><\/a><span style=\"font-weight: 400\"> dimostra di non essere un semplice protocollo di seconda fascia, ma l&#8217;incarnazione della visione dei Layer-2 di nuova generazione. Progettato specificamente per il network Bitcoin, risponde al bisogno di utilit\u00e0 reale, sostenendo il prezzo di BTC attraverso una domanda generata da casi d&#8217;uso concreti.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><b>Leggi anche:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-1123\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/meme-coin-solana\/\"><img decoding=\"async\" width=\"1472\" height=\"832\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/memecoin-solana.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"memecoin-solana\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/memecoin-solana.png 1472w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/memecoin-solana-300x170.png 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/memecoin-solana-1024x579.png 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/memecoin-solana-768x434.png 768w\" sizes=\"(max-width: 1472px) 100vw, 1472px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/meme-coin-solana\/\">Meme coin Solana: i migliori token da acquistare nel 2026<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<h2><b>Non tutte le profezie si avverano<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Naturalmente, vi \u00e8 chi continua a considerare Michael Burry una sorta di oracolo, convinto che i suoi allarmi siano destinati a realizzarsi puntualmente. Tuttavia, \u00e8 bene ricordare che fin dal 2015 Burry si \u00e8 espresso come un convinto detrattore di Bitcoin, invocando ripetutamente posizioni short che non sempre si sono rivelate corrette, ricordando talvolta la dinamica del pastorello che gridava al lupo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ogni anno le sue dichiarazioni diventano virali. Eppure, quella che egli oggi definisce \u201cspirale mortale\u201d, nel 2015 era un &#8220;imminente collasso del mercato&#8221;, nonostante lo S&amp;P 500 abbia poi intrapreso un rally rialzista durato anni. Nel 2021, invece, parl\u00f2 della pi\u00f9 grande bolla della storia, salvo poi vedere il <\/span><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/migliori-criptovalute\/\"><span style=\"font-weight: 400\">mercato delle criptovalute<\/span><\/a><span style=\"font-weight: 400\"> toccare nuovi record nel 2022.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udea8 BREAKING: Michael Burry predicts a market crash caused by <a href=\"https:\/\/twitter.com\/search?q=%24BTC&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$BTC<\/a>.<\/p>\n<p>Also Michael Burry: <a href=\"https:\/\/t.co\/BBy9dINi2E\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/BBy9dINi2E<\/a><\/p>\n<p>&mdash; Ashot Gabrelyanov (@gabrelyanov) <a href=\"https:\/\/twitter.com\/gabrelyanov\/status\/2018988567645901228?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">February 4, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Ci\u00f2 nonostante, le sue analisi meritano comunque attenzione, poich\u00e9 sollevano questioni rilevanti che ogni investitore dovrebbe approfondire tramite il proprio DYOR (\u201cfai le tue proprie ricerche\u201d). Sebbene Burry abbia ragione nel sottolineare che a Bitcoin manchino attualmente casi d&#8217;uso accessori capaci di stabilizzarne il prezzo, con il lancio di <\/span><a href=\"https:\/\/99bitcoins.com\/it\/visit\/bitcoin-hyper\/\" rel=\"nofollow sponsored\" target=\"_blank\"><span style=\"font-weight: 400\">Bitcoin Hyper<\/span><\/a><span style=\"font-weight: 400\"> lo scenario \u00e8 destinato a mutare radicalmente.<\/span><\/p>\n<h2><b>Come partecipare alla prevendita di Bitcoin Hyper<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Per partecipare attivamente all&#8217;ecosistema che Bitcoin Hyper sta sviluppando per Bitcoin, \u00e8 possibile aderire alla prevendita e assicurarsi i token HYPER prima che vengano quotati sui principali exchange, a prezzi potenzialmente superiori. HYPER \u00e8 un utility token fondamentale per alimentare l&#8217;ambiente Layer-2 e, allo stesso tempo, il token di staking per la messa in sicurezza della rete.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Per partecipare, basta visitare il <\/span><a href=\"https:\/\/99bitcoins.com\/it\/visit\/bitcoin-hyper\/\" rel=\"nofollow sponsored\" target=\"_blank\"><span style=\"font-weight: 400\">sito ufficiale di Bitcoin Hyper<\/span><\/a><span style=\"font-weight: 400\"> e acquistare i token HYPER utilizzando SOL, ETH, USDT, USDC, BNB o carta di credito.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Il team di Bitcoin Hyper suggerisce di utilizzare Best Wallet, considerato attualmente il <\/span><a href=\"https:\/\/99bitcoins.com\/it\/visit\/bestwallet-app\/?transfer=1\" rel=\"nofollow sponsored\" target=\"_blank\"><span style=\"font-weight: 400\">miglior portafoglio per criptovalute e Bitcoin<\/span><\/a><span style=\"font-weight: 400\"> sul mercato. HYPER \u00e8 gi\u00e0 presente nella sezione \u201cUpcoming Tokens\u201d di Best Wallet, facilitando cos\u00ec le operazioni di acquisto, monitoraggio e riscatto dei token una volta che il progetto sar\u00e0 ufficialmente operativo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Infine per restare aggiornati \u00e8 possibile unirsi alla community di Bitcoin Hyper su <\/span><a href=\"https:\/\/t.me\/btchyperz\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">Telegram<\/span><\/a><span style=\"font-weight: 400\"> and <\/span><a href=\"https:\/\/x.com\/BTC_Hyper2\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">X<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><a href=\"https:\/\/99bitcoins.com\/it\/visit\/bitcoin-hyper\/\" class=\"sc-button sc-button-green sc-button-medium\" target=\"_blank\"  rel=\"nofollow sponsored\"><span>Vai al sito di Bitcoin Hyper<\/span><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><b>Leggi anche:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-1037\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/prossimi-listing-su-binance\/\"><img decoding=\"async\" width=\"1472\" height=\"832\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/prossimi-listing-su-binance-1.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"prossimi listing su binance\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/prossimi-listing-su-binance-1.png 1472w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/prossimi-listing-su-binance-1-300x170.png 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/prossimi-listing-su-binance-1-1024x579.png 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/02\/prossimi-listing-su-binance-1-768x434.png 768w\" sizes=\"(max-width: 1472px) 100vw, 1472px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/prossimi-listing-su-binance\/\">Prossimi listing Binance: le crypto in uscita sull\u2019exchange nel 2026<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><span style=\"font-weight: 400\">    <ul class=\"nnbtc-green-checkmarks-list\">\r\n        <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <li class=\"nnbtc-green-checkmarks-list__item\">\r\n        <p class=\"nnbtc-green-checkmarks-list__item-heading\">\r\n            Resta sempre aggiornato con 99Bitcoins        <\/p>\r\n        <\/span><\/p>\n<p><span style=\"font-weight: 400\">\u2192 Non perdere nemmeno un movimento del mercato!<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><b>Segui<\/b><a href=\"https:\/\/twitter.com\/99bitcoinshq\" rel=\"nofollow\" target=\"_blank\"> <b>99Bitcoins su X (Twitter)<\/b><\/a><span style=\"font-weight: 400\"> per ricevere in tempo reale gli ultimi aggiornamenti e i flash news pi\u00f9 caldi del settore.<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Iscriviti al<\/b><a href=\"https:\/\/www.youtube.com\/@99Bitcoins\" rel=\"nofollow\" target=\"_blank\"> <b>canale YouTube<\/b><\/a> <span style=\"font-weight: 400\">per non perdere le analisi quotidiane degli esperti e approfondimenti video che ti aiuteranno a navigare il mercato con consapevolezza.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">    <\/li>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <\/ul>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il gestore di hedge fund Michael Burry ha recentemente lanciato un pesante monito che ricalca i suoi celebri avvertimenti durante la crisi finanziaria del 2008. Questa volta, l&#8217;attenzione \u00e8 rivolta ai colossi del Big Tech, all&#8217;IA e a Bitcoin (BTC). Nello specifico, Burry teme che un ulteriore calo del prezzo di BTC possa innescare una..<\/p>\n","protected":false},"author":136171,"featured_media":18959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[12],"coin":[2],"class_list":["post-18958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-prevendite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione - 99bitcoins IT<\/title>\n<meta name=\"description\" content=\"Il gestore di hedge fund Michael Burry ha recentemente lanciato un pesante monito che ricalca i suoi celebri avvertimenti durante la crisi finanziaria del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione - 99bitcoins IT\" \/>\n<meta property=\"og:description\" content=\"Il gestore di hedge fund Michael Burry ha recentemente lanciato un pesante monito che ricalca i suoi celebri avvertimenti durante la crisi finanziaria del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins IT\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-06T08:31:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1320\" \/>\n\t<meta property=\"og:image:height\" content=\"1056\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniele Morana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniele Morana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/\"},\"author\":{\"name\":\"Daniele Morana\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/af15b4e4d1d89ab841e22854fe5a3d23\"},\"headline\":\"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione\",\"datePublished\":\"2026-02-06T08:31:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/\"},\"wordCount\":1474,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/02\\\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png\",\"keywords\":[\"Prevendite\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/\",\"name\":\"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione - 99bitcoins IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/02\\\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png\",\"datePublished\":\"2026-02-06T08:31:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/af15b4e4d1d89ab841e22854fe5a3d23\"},\"description\":\"Il gestore di hedge fund Michael Burry ha recentemente lanciato un pesante monito che ricalca i suoi celebri avvertimenti durante la crisi finanziaria del\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/02\\\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/02\\\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png\",\"width\":1320,\"height\":1056},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\",\"name\":\"99bitcoins IT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/af15b4e4d1d89ab841e22854fe5a3d23\",\"name\":\"Daniele Morana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e7be8f2ce2e8f4e4e9f7c6e7404e97d71894c747b8bda13707acd501b412659?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e7be8f2ce2e8f4e4e9f7c6e7404e97d71894c747b8bda13707acd501b412659?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e7be8f2ce2e8f4e4e9f7c6e7404e97d71894c747b8bda13707acd501b412659?s=96&d=mm&r=g\",\"caption\":\"Daniele Morana\"},\"description\":\"Appassionato esploratore del mondo delle criptovalute, del trading finanziario e del gambling. Condivide approfondimenti e analisi per aiutare gli utenti a navigare al meglio in questi affascinanti mercati, inclusi aspetti legati al gioco online consapevole.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/author\\\/dariobongiovanni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione - 99bitcoins IT","description":"Il gestore di hedge fund Michael Burry ha recentemente lanciato un pesante monito che ricalca i suoi celebri avvertimenti durante la crisi finanziaria del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/","og_locale":"it_IT","og_type":"article","og_title":"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione - 99bitcoins IT","og_description":"Il gestore di hedge fund Michael Burry ha recentemente lanciato un pesante monito che ricalca i suoi celebri avvertimenti durante la crisi finanziaria del","og_url":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/","og_site_name":"99bitcoins IT","article_published_time":"2026-02-06T08:31:38+00:00","og_image":[{"width":1320,"height":1056,"url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png","type":"image\/png"}],"author":"Daniele Morana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniele Morana","Est. reading time":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/"},"author":{"name":"Daniele Morana","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/af15b4e4d1d89ab841e22854fe5a3d23"},"headline":"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione","datePublished":"2026-02-06T08:31:38+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/"},"wordCount":1474,"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png","keywords":["Prevendite"],"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/","url":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/","name":"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione - 99bitcoins IT","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png","datePublished":"2026-02-06T08:31:38+00:00","author":{"@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/af15b4e4d1d89ab841e22854fe5a3d23"},"description":"Il gestore di hedge fund Michael Burry ha recentemente lanciato un pesante monito che ricalca i suoi celebri avvertimenti durante la crisi finanziaria del","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/#primaryimage","url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png","contentUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/02\/Burry_evoca_una_spirale_mortale_Bitcoin_Hyper_presale.png","width":1320,"height":1056},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/it\/notizie\/burry-evoca-la-spirale-mortale-ma-bitcoin-hyper-hyper-risponde-lutilita-e-la-soluzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/it\/"},{"@type":"ListItem","position":2,"name":"Notizie","item":"https:\/\/99bitcoins.com\/it\/notizie\/"},{"@type":"ListItem","position":3,"name":"Burry evoca la \u201cspirale mortale\u201d, ma Bitcoin Hyper ($HYPER) risponde: l\u2019utilit\u00e0 \u00e8 la soluzione"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/it\/#website","url":"https:\/\/99bitcoins.com\/it\/","name":"99bitcoins IT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/af15b4e4d1d89ab841e22854fe5a3d23","name":"Daniele Morana","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4e7be8f2ce2e8f4e4e9f7c6e7404e97d71894c747b8bda13707acd501b412659?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e7be8f2ce2e8f4e4e9f7c6e7404e97d71894c747b8bda13707acd501b412659?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e7be8f2ce2e8f4e4e9f7c6e7404e97d71894c747b8bda13707acd501b412659?s=96&d=mm&r=g","caption":"Daniele Morana"},"description":"Appassionato esploratore del mondo delle criptovalute, del trading finanziario e del gambling. Condivide approfondimenti e analisi per aiutare gli utenti a navigare al meglio in questi affascinanti mercati, inclusi aspetti legati al gioco online consapevole.","url":"https:\/\/99bitcoins.com\/it\/author\/dariobongiovanni\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/18958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/users\/136171"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/comments?post=18958"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/18958\/revisions"}],"predecessor-version":[{"id":18963,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/18958\/revisions\/18963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media\/18959"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media?parent=18958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/categories?post=18958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/tags?post=18958"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/coin?post=18958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}