{"id":18547,"date":"2026-01-30T12:48:59","date_gmt":"2026-01-30T12:48:59","guid":{"rendered":"https:\/\/99bitcoins.com\/it\/?p=18547"},"modified":"2026-01-30T12:47:01","modified_gmt":"2026-01-30T12:47:01","slug":"metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/","title":{"rendered":"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Prima che MicroStrategy iniziasse ad acquistare Bitcoin nel novembre 2020, era impensabile che una societ\u00e0 pubblica accumulasse criptovalute considerate &#8220;rischiose&#8221;. \u00c8 vero che alcune delle <\/span><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/criptovalute-da-comprare\/\"><b>migliori crypto da acquistare<\/b><\/a><span style=\"font-weight: 400\"> hanno registrato una crescita superiore a 100x dal loro lancio. Tuttavia, la mancanza di normative chiare rappresentava un ostacolo enorme.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Questa situazione \u00e8 cambiata rapidamente dopo che Michael Saylor ha puntato tutto su Bitcoin, acquistando miliardi di dollari in BTC. Nel gennaio 2026, Strategy ha venduto azioni per acquistare oltre 3 miliardi di dollari in Bitcoin. Per non essere da meno, anche Metaplanet sta portando avanti una strategia propria per raccogliere fondi e accumulare Bitcoin.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"ja\" dir=\"ltr\">\u7b2c\u4e09\u8005\u5272\u5f53\u306b\u3088\u308b\u65b0\u682a\u5f0f\u53ca\u3073\u7b2c 25 \u56de\u65b0\u682a\u4e88\u7d04\u6a29\u306e\u767a\u884c\u306b\u95a2\u3059\u308b\u304a\u77e5\u3089\u305b <a href=\"https:\/\/t.co\/YPhua9p7d3\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/YPhua9p7d3<\/a><\/p>\n<p>&mdash; Metaplanet Inc. (@Metaplanet) <a href=\"https:\/\/twitter.com\/Metaplanet\/status\/2016797337729778080?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 29, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Tutto ci\u00f2 sta avvenendo mentre il prezzo di <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> resta bloccato sotto i <\/span><b>90.000 $<\/b><span style=\"font-weight: 400\"> e mentre inizia a svanire la speranza di vedere il prezzo <\/span><b>BTC\/USD<\/b><span style=\"font-weight: 400\"> superare i <\/span><b>100.000 $<\/b><span style=\"font-weight: 400\"> nelle prossime due settimane. Il sentiment del mercato \u00e8 ancora ribassista, tuttavia, guardando ai fondamentali, potrebbe esserci ancora un&#8217;opportunit\u00e0 per gli acquirenti di farsi avanti.<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-18549 size-large\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Crypto-Fear-and-Greed-Chart-1024x596.png\" alt=\"\" width=\"1024\" height=\"596\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Crypto-Fear-and-Greed-Chart-1024x596.png 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Crypto-Fear-and-Greed-Chart-300x175.png 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Crypto-Fear-and-Greed-Chart-768x447.png 768w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Crypto-Fear-and-Greed-Chart-1536x894.png 1536w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Crypto-Fear-and-Greed-Chart.png 1688w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><b>Leggi anche:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-188\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/nuove-criptovalute\/\"><img decoding=\"async\" width=\"650\" height=\"350\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/nuove-criptovalute-copertina.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"nuove criptovalute\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/nuove-criptovalute-copertina.webp 650w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/nuove-criptovalute-copertina-300x162.webp 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/nuove-criptovalute\/\">Nuove criptovalute su cui investire nel 2026 &#8211; Come scegliere i migliori nuovi token in uscita<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<h2><b>Metaplanet pianifica un acquisto di Bitcoin dal valore di 137 milioni di dollari<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Nella giornata di ieri, la societ\u00e0 giapponese Metaplanet ha dato il via libera a un piano per raccogliere fino a 137 milioni di dollari presso investitori esteri, con l&#8217;obiettivo di accrescere le proprie riserve di Bitcoin e rifinanziare il debito. Curiosamente, anche dopo la diffusione di questa notizia, il titolo Metaplanet non ha subito movimenti significativi in borsa, segno che i mercati si aspettano gi\u00e0 un accumulo aggressivo di Bitcoin da parte dell&#8217;azienda. Al contrario, ci\u00f2 conferma che il mercato approva la trasformazione di Metaplanet da semplice operatore alberghiero a vera e propria &#8220;Bitcoin Treasury Company&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Metaplanet collocher\u00e0 nuove azioni e warrant presso investitori istituzionali stranieri. Nello specifico, l&#8217;aumento di capitale \u00e8 diviso in due tranche principali per massimizzare la raccolta gestendo al contempo la diluizione degli attuali azionisti. Verranno emesse 24,5 milioni di nuove azioni ordinarie al prezzo di circa 3 $ l&#8217;una, puntando a raccogliere circa 78 milioni di dollari nell&#8217;immediato.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Metaplanet has closed its first institutional shares + warrants transaction to accelerate our Bitcoin strategy. Total proceeds of up to \u00a521B, comprising \u00a512.2B in shares issued at a 5% premium (\u00a5499) and up to \u00a58.8B from 1-year warrants issued at a 15% premium (\u00a5547 exercise\u2026 <a href=\"https:\/\/t.co\/OprgedN4Fd\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/OprgedN4Fd<\/a><\/p>\n<p>&mdash; Simon Gerovich (@gerovich) <a href=\"https:\/\/twitter.com\/gerovich\/status\/2016825495950938486?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 29, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Gli azionisti hanno inoltre approvato l&#8217;emissione di 159.440 warrant, che conferiscono agli investitori il diritto di acquistare ulteriori azioni in futuro a un prezzo prestabilito. Se tutti i warrant venissero esercitati entro il prossimo anno, l&#8217;operazione potrebbe fruttare altri 56 milioni di dollari.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Va sottolineato che Metaplanet ha mantenuto la massima trasparenza sulla propria strategia d&#8217;acquisto. Una parte consistente dei 137 milioni di dollari sar\u00e0 destinata direttamente nell&#8217;acquisto di Bitcoin. Una volta completata l&#8217;operazione, la societ\u00e0 consolider\u00e0 la propria posizione come uno dei maggiori detentori aziendali di BTC a livello globale.<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-18550 size-full\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Screenshot-2026-01-29T154643.242.png\" alt=\"\" width=\"1425\" height=\"347\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Screenshot-2026-01-29T154643.242.png 1425w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Screenshot-2026-01-29T154643.242-300x73.png 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Screenshot-2026-01-29T154643.242-1024x249.png 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Screenshot-2026-01-29T154643.242-768x187.png 768w\" sizes=\"(max-width: 1425px) 100vw, 1425px\" \/><\/p>\n<p><span style=\"font-weight: 400\">Fonte &#8211; <\/span><a href=\"https:\/\/twitter.com\/AdamBLiv\/status\/2007989255071531092\" rel=\"nofollow\" target=\"_blank\"><b>Bitcoin Treasuries<\/b><\/a><\/p>\n<p><span style=\"font-weight: 400\">Un&#8217;altra quota dell&#8217;importo raccolto verr\u00e0 utilizzata per estinguere i prestiti esistenti. Logicamente, la riduzione dell&#8217;indebitamento permette di ripristinare le linee di credito, garantendo alla societ\u00e0 una maggiore flessibilit\u00e0 finanziaria per contrarre nuovi prestiti\u00a0 qualora il prezzo di Bitcoin dovesse subire una flessione.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tuttavia, a differenza di MicroStrategy, Metaplanet intende mettere a rendimento i propri BTC. L&#8217;azienda sta infatti investendo nel segmento \u201cBitcoin Income\u201d, una divisione che utilizza strumenti derivati, come la vendita di opzioni put, per generare rendimento sulle partecipazioni gi\u00e0 detenute.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><b>Leggi anche:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-355\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/migliori-meme-coin\/\"><img decoding=\"async\" width=\"1200\" height=\"686\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-meme-coin.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"migliori meme coin\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-meme-coin.jpg 1200w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-meme-coin-300x172.jpg 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-meme-coin-1024x585.jpg 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/01\/migliori-meme-coin-768x439.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/migliori-meme-coin\/\">Migliori meme coin da comprare nel 2026<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<h2><b>Si tratta di un nuovo modello per le riserve aziendali in Bitcoin?<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Metaplanet si autodefinisce come una \u201cBitcoin Treasury Company\u201d. Ci\u00f2 significa che Bitcoin rappresenta il fulcro della sua strategia aziendale e non un esperimento marginale. Questo approccio ricalca il modello introdotto da MicroStrategy, ma introduce novit\u00e0 sostanziali nelle modalit\u00e0 di reperimento dei fondi.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La societ\u00e0 detiene gi\u00e0 decine di migliaia di BTC per un controvalore di miliardi di dollari. Puntando agli investitori esteri, principalmente tramite collocamenti privati, Metaplanet attinge a un bacino di capitali molto pi\u00f9 profondo rispetto a quello tipicamente accessibile alle small-cap quotate alla Borsa di Tokyo. Questa flessibilit\u00e0 operativa \u00e8 fondamentale per poter acquistare Bitcoin durante le fasi di correzione dei prezzi.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La logica di fondo \u00e8 chiara: Metaplanet sta sfruttando l&#8217;elevata volatilit\u00e0 del proprio titolo azionario. Poich\u00e9 le azioni scambiano spesso a \u201cpremio\u201d rispetto al valore intrinseco dei Bitcoin in bilancio, la societ\u00e0 pu\u00f2 vendere azioni a prezzi elevati per acquistare Bitcoin a prezzi \u201cscontati\u201d. Si tratta di una strategia ripresa direttamente dal manuale operativo di MicroStrategy.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Inoltre, la diversificazione rispetto allo Yen implica che Metaplanet sia ora focalizzata pi\u00f9 che mai sul BTC Yield, un parametro che misura la quantit\u00e0 di BTC detenuti per singola azione. Nonostante la diluizione del capitale derivante dall&#8217;aumento da 137 milioni di dollari, il BTC Yield \u00e8 destinato a crescere, dato che l&#8217;incremento delle riserve di BTC sar\u00e0 proporzionalmente superiore.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udd25METAPLANET MOON MATH\ud83d\udd25<\/p>\n<p>Metaplanet had a 568.2% BTC Yield last year. <\/p>\n<p>Their small size helped.<\/p>\n<p>Even assuming they never trade at a huge multiple, and assuming a much lower BTC Yield, the returns are still ridiculous over the next 5 years.<\/p>\n<p>1\u00d7 mNAV returns with a 75 % BTC\u2026 <a href=\"https:\/\/t.co\/92zLtbA9rz\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/92zLtbA9rz<\/a><\/p>\n<p>&mdash; Adam Livingston (@AdamBLiv) <a href=\"https:\/\/twitter.com\/AdamBLiv\/status\/2007989255071531092?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 5, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Nel complesso, si tratta di un segnale rialzista per <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\">. Quando societ\u00e0 pubbliche raccolgono capitali reali per acquistare <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\">, si rafforza la percezione istituzionale di <\/span><b>BTC<\/b><span style=\"font-weight: 400\"> come asset di copertura di lungo periodo, non solo come mero strumento di speculazione a breve termine. L&#8217;accumulo da parte delle aziende riduce l&#8217;offerta circolante. Poich\u00e9 <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> ha un limite di offerta prefissato, quando le societ\u00e0 immobilizzano i BTC nei propri bilanci, la quantit\u00e0 di asset scambiabili sul mercato diminuisce. Questo shock dell&#8217;offerta (supply shock) tende a sostenere la crescita dei prezzi nel lungo periodo.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><b>Leggi anche:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-1440\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/prossimi-listing-su-coinbase\/\"><img decoding=\"async\" width=\"1472\" height=\"832\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/03\/prossimi-listing-coinbase.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"prossimi listing coinbase\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/03\/prossimi-listing-coinbase.jpg 1472w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/03\/prossimi-listing-coinbase-300x170.jpg 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/03\/prossimi-listing-coinbase-1024x579.jpg 1024w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/03\/prossimi-listing-coinbase-768x434.jpg 768w\" sizes=\"(max-width: 1472px) 100vw, 1472px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/prossimi-listing-su-coinbase\/\">Prossimi listing su Coinbase: le nuove criptovalute in arrivo sull\u2019exchange<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\">\n\n<div class=\"su-posts su-posts-teaser-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<div id=\"su-post-4547\" class=\"su-post \">\n\t\t\t\t\t\t\t\t\t<a class=\"su-post-thumbnail\" href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/criptovalute-emergenti\/\"><img decoding=\"async\" width=\"750\" height=\"422\" src=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/05\/Criptovalute-emergenti-cover.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/05\/Criptovalute-emergenti-cover.png 750w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/05\/Criptovalute-emergenti-cover-300x169.png 300w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/05\/Criptovalute-emergenti-cover-308x173.png 308w, https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/05\/Criptovalute-emergenti-cover-350x197.png 350w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t\t\t\t<h2 class=\"su-post-title\"><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/criptovalute-emergenti\/\">Criptovalute Emergenti &#8211; I migliori investimenti del 2026<\/a><\/h2>\n\t\t\t<\/div>\n\n\t\t\t\n<\/div>\n<\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<p><span style=\"font-weight: 400\"><div class=\"su-note\"  style=\"border-color:#d7d9e0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F1F3FA;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><\/span><\/p>\n<p><span style=\"font-weight: 400\">    <ul class=\"nnbtc-green-checkmarks-list\">\r\n        <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <li class=\"nnbtc-green-checkmarks-list__item\">\r\n        <p class=\"nnbtc-green-checkmarks-list__item-heading\">\r\n            Resta sempre aggiornato con 99Bitcoins        <\/p>\r\n        <\/span><\/p>\n<p><span style=\"font-weight: 400\">\u2192 Non perdere nemmeno un movimento del mercato!<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><b>Segui<\/b><a href=\"https:\/\/twitter.com\/99bitcoinshq\" rel=\"nofollow\" target=\"_blank\"> <b>99Bitcoins su X (Twitter)<\/b><\/a><span style=\"font-weight: 400\"> per ricevere in tempo reale gli ultimi aggiornamenti e i flash news pi\u00f9 caldi del settore.<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Iscriviti al<\/b><a href=\"https:\/\/www.youtube.com\/@99Bitcoins\" rel=\"nofollow\" target=\"_blank\"> <b>canale YouTube<\/b><\/a> <span style=\"font-weight: 400\">per non perdere le analisi quotidiane degli esperti e approfondimenti video che ti aiuteranno a navigare il mercato con consapevolezza.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">    <\/li>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <\/ul>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\"><\/div><\/div><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prima che MicroStrategy iniziasse ad acquistare Bitcoin nel novembre 2020, era impensabile che una societ\u00e0 pubblica accumulasse criptovalute considerate &#8220;rischiose&#8221;. \u00c8 vero che alcune delle migliori crypto da acquistare hanno registrato una crescita superiore a 100x dal loro lancio. Tuttavia, la mancanza di normative chiare rappresentava un ostacolo enorme. Questa situazione \u00e8 cambiata rapidamente dopo..<\/p>\n","protected":false},"author":136067,"featured_media":18548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[11],"coin":[2],"class_list":["post-18547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera - 99bitcoins IT<\/title>\n<meta name=\"description\" content=\"Prima che MicroStrategy iniziasse ad acquistare Bitcoin nel novembre 2020, era impensabile che una societ\u00e0 pubblica accumulasse criptovalute considerate\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera - 99bitcoins IT\" \/>\n<meta property=\"og:description\" content=\"Prima che MicroStrategy iniziasse ad acquistare Bitcoin nel novembre 2020, era impensabile che una societ\u00e0 pubblica accumulasse criptovalute considerate\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins IT\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T12:48:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federico Cappellini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Cappellini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/\"},\"author\":{\"name\":\"Federico Cappellini\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/af5a8990396ca6c1ac73bfff31df00b4\"},\"headline\":\"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera\",\"datePublished\":\"2026-01-30T12:48:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/\"},\"wordCount\":1036,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/01\\\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png\",\"keywords\":[\"Bitcoin\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/\",\"name\":\"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera - 99bitcoins IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/01\\\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png\",\"datePublished\":\"2026-01-30T12:48:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/af5a8990396ca6c1ac73bfff31df00b4\"},\"description\":\"Prima che MicroStrategy iniziasse ad acquistare Bitcoin nel novembre 2020, era impensabile che una societ\u00e0 pubblica accumulasse criptovalute considerate\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/01\\\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2026\\\/01\\\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png\",\"width\":630,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\",\"name\":\"99bitcoins IT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/af5a8990396ca6c1ac73bfff31df00b4\",\"name\":\"Federico Cappellini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g\",\"caption\":\"Federico Cappellini\"},\"description\":\"SEO copywriter con una solida esperienza nella scrittura di contenuti legati a criptovalute, giochi online e betting. Appassionato di poker e scrittura sportiva, unisce l\u2019analisi strategica al piacere della narrazione, offrendo articoli ricchi di dati ma anche coinvolgenti da leggere. Dal 2018, ha intrapreso un percorso di approfondimento nel mondo delle criptovalute, partecipando a corsi su Intelligenza Artificiale e DeFi. Questa formazione gli consente di offrire contenuti aggiornati e approfonditi, mantenendo uno sguardo critico e informato sulle evoluzioni del settore.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/author\\\/gianlucasisti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera - 99bitcoins IT","description":"Prima che MicroStrategy iniziasse ad acquistare Bitcoin nel novembre 2020, era impensabile che una societ\u00e0 pubblica accumulasse criptovalute considerate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/","og_locale":"it_IT","og_type":"article","og_title":"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera - 99bitcoins IT","og_description":"Prima che MicroStrategy iniziasse ad acquistare Bitcoin nel novembre 2020, era impensabile che una societ\u00e0 pubblica accumulasse criptovalute considerate","og_url":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/","og_site_name":"99bitcoins IT","article_published_time":"2026-01-30T12:48:59+00:00","og_image":[{"width":630,"height":630,"url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png","type":"image\/png"}],"author":"Federico Cappellini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Federico Cappellini","Est. reading time":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/"},"author":{"name":"Federico Cappellini","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/af5a8990396ca6c1ac73bfff31df00b4"},"headline":"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera","datePublished":"2026-01-30T12:48:59+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/"},"wordCount":1036,"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png","keywords":["Bitcoin"],"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/","url":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/","name":"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera - 99bitcoins IT","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png","datePublished":"2026-01-30T12:48:59+00:00","author":{"@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/af5a8990396ca6c1ac73bfff31df00b4"},"description":"Prima che MicroStrategy iniziasse ad acquistare Bitcoin nel novembre 2020, era impensabile che una societ\u00e0 pubblica accumulasse criptovalute considerate","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/#primaryimage","url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png","contentUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2026\/01\/Metaplanet_pianifica_acquisto_Bitcoin_137M_dollari-copia.png","width":630,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/it\/notizie\/metaplanet-pianifica-un-acquisto-di-bitcoin-da-137-milioni-di-dollari-tramite-unoperazione-azionaria-estera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/it\/"},{"@type":"ListItem","position":2,"name":"Notizie","item":"https:\/\/99bitcoins.com\/it\/notizie\/"},{"@type":"ListItem","position":3,"name":"Metaplanet pianifica un acquisto di Bitcoin da 137 milioni di dollari tramite un\u2019operazione azionaria estera"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/it\/#website","url":"https:\/\/99bitcoins.com\/it\/","name":"99bitcoins IT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/af5a8990396ca6c1ac73bfff31df00b4","name":"Federico Cappellini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/087538537588cba2fe934666287ebf89d28faa651be71fb1b9d69f248ed021ed?s=96&d=mm&r=g","caption":"Federico Cappellini"},"description":"SEO copywriter con una solida esperienza nella scrittura di contenuti legati a criptovalute, giochi online e betting. Appassionato di poker e scrittura sportiva, unisce l\u2019analisi strategica al piacere della narrazione, offrendo articoli ricchi di dati ma anche coinvolgenti da leggere. Dal 2018, ha intrapreso un percorso di approfondimento nel mondo delle criptovalute, partecipando a corsi su Intelligenza Artificiale e DeFi. Questa formazione gli consente di offrire contenuti aggiornati e approfonditi, mantenendo uno sguardo critico e informato sulle evoluzioni del settore.","url":"https:\/\/99bitcoins.com\/it\/author\/gianlucasisti\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/18547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/users\/136067"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/comments?post=18547"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/18547\/revisions"}],"predecessor-version":[{"id":18551,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/18547\/revisions\/18551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media\/18548"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media?parent=18547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/categories?post=18547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/tags?post=18547"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/coin?post=18547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}