{"id":14346,"date":"2025-10-15T09:01:22","date_gmt":"2025-10-15T09:01:22","guid":{"rendered":"https:\/\/99bitcoins.com\/it\/?p=14346"},"modified":"2025-10-15T08:58:33","modified_gmt":"2025-10-15T08:58:33","slug":"gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/","title":{"rendered":"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Il governo degli Stati Uniti si prepara ad aggiungere circa 127.271 Bitcoin, per un valore stimato di circa 14,2 miliardi di dollari, a quella che ora definisce Riserva Strategica di Bitcoin (Strategic Bitcoin Reserve).<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/sb0278\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">Durante un\u2019operazione congiunta con le autorit\u00e0 del Regno Unito<\/span><\/a><span style=\"font-weight: 400\">, queste monete sono state confiscate in relazione a una vasta frode in criptovalute guidata da Chen Zhi, cittadino cinese legato al Prince Group, con sede in Cambogia.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Il governo decide di tenere i Bitcoin, non venderli<\/span><\/h2>\n<p><span style=\"font-weight: 400\">A differenza di quanto avviene di solito, il governo non sembra intenzionato a liquidare gli asset, ma a conservarli.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\">Questa decisione segna un potenziale punto di svolta nel modo in cui gli Stati trattano le criptovalute, suggerendo che le autorit\u00e0 vedano ora il Bitcoin come uno strumento finanziario di lungo periodo, piuttosto che un semplice bene da vendere.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Una rete di truffe, traffico di persone e Bitcoin nascosti<\/span><\/h2>\n<p><a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/sb0278\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">Secondo i documenti del tribunale<\/span><\/a><span style=\"font-weight: 400\">, Chen Zhi aveva costruito un impero complesso e inquietante che combinava frodi in criptovalute, corruzione politica, riciclaggio di denaro e traffico di esseri umani.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\"> La sua rete operava da diversi complessi in Cambogia, tra cui Golden Fortune e un altro collegato al Jinbei Hotel and Casino.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le vittime sarebbero state trafficate e costrette a partecipare a elaborate truffe romantiche e d\u2019investimento, note come \u201cpig butchering\u201d.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\"><strong>Questi raggiri potevano durare settimane o mesi<\/strong>, coinvolgendo finte relazioni o opportunit\u00e0 di business per poi svuotare completamente i risparmi delle vittime.<\/span><\/p>\n<p><span style=\"font-weight: 400\">I fondi ottenuti venivano poi dispersi tra societ\u00e0 di comodo, wallet crypto, piattaforme di gioco d\u2019azzardo, operazioni immobiliari e mining farm.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\">Molte vittime sarebbero state minacciate, isolate o perfino maltrattate fisicamente.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">L\u2019Ordine Esecutivo che ha aperto la strada<\/span><\/h2>\n<p><span style=\"font-weight: 400\">La base legale che consente agli Stati Uniti di trattenere questi Bitcoin invece di venderli deriva da un Ordine Esecutivo firmato all\u2019inizio del 2025, che ha formalmente istituito la <strong>Strategic Bitcoin Reserve<\/strong>. <\/span><span style=\"font-weight: 400\">L\u2019ordine stabilisce che qualsiasi criptovaluta confiscata in procedimenti penali o civili debba essere trasferita nella nuova riserva, anzich\u00e9 messa all\u2019asta o convertita in valuta fiat.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Sebbene il principio sembri chiaro, rimangono diversi passaggi legali:<strong> i tribunali devono approvare la confisca, e Chen Zhi o i suoi collaboratori potrebbero ancora contestare la decisione<\/strong>. <\/span><span style=\"font-weight: 400\">Anche superati questi ostacoli, il governo dovr\u00e0 comunque stabilire come custodire e gestire in modo sicuro oltre 14 miliardi di dollari in <\/span><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/comprare-bitcoin\/\"><b>Bitcoin<\/b><\/a><span style=\"font-weight: 400\">. <\/span><span style=\"font-weight: 400\">Attualmente, diverse agenzie \u2014 tra cui il Dipartimento del Tesoro, FinCEN e OFAC \u2014 stanno coordinando la gestione degli asset, monitorandone l\u2019origine e garantendone la sicurezza.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Bitcoin come risorsa di Stato?<\/span><\/h2>\n<p><span style=\"font-weight: 400\">La decisione di mantenere i Bitcoin invece di venderli potrebbe avere implicazioni profonde. <\/span><span style=\"font-weight: 400\">Suggerisce che il governo stia iniziando a <\/span><a href=\"https:\/\/99bitcoins.com\/it\/previsioni-bitcoin\/\"><b>trattare Bitcoin come un bene di riserva<\/b><\/a><span style=\"font-weight: 400\">, simile all\u2019oro. <\/span><span style=\"font-weight: 400\">Tenendo queste monete fuori dal mercato, le autorit\u00e0 possono evitare una pressione di vendita massiccia, che spesso fa crollare i prezzi quando grandi quantit\u00e0 vengono immesse tutte insieme.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Se questa strategia dovesse consolidarsi, potrebbe influenzare altri Paesi, spingendoli a ripensare il modo in cui gestiscono le criptovalute sequestrate.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\"> Potrebbe persino aprire la strada a discussioni pi\u00f9 ampie sul ruolo degli asset digitali nelle riserve nazionali.<\/span><\/p>\n<p><a href=\"https:\/\/99bitcoins.com\/it\/criptovalute\/wallet-bitcoin\/\"><b>SCOPRI: Migliori Wallet Bitcoin<\/b><\/a><\/p>\n<h2><span style=\"font-weight: 400\">Una prova ancora tutta da superare<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Il successo di questa operazione dipender\u00e0 da come le autorit\u00e0 gestiranno il processo.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\"> Un\u2019esecuzione efficace potrebbe ridefinire il modo in cui gli Stati Uniti trattano i sequestri di criptovalute di alto valore e diventare un modello per altri governi.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\"> Potrebbe anche stabilire nuove norme sulla custodia, la regolamentazione e la classificazione degli asset digitali.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ma il piano potrebbe anche fallire: se il processo legale si prolungasse troppo, se i sistemi di custodia non fossero affidabili o se emergessero problemi di gestione interna, ci\u00f2 potrebbe minare la fiducia pubblica e quella dei mercati. <\/span><span style=\"font-weight: 400\">Per ora, quei 127.271 BTC restano in custodia. <\/span><span style=\"font-weight: 400\">Ci\u00f2 che accadr\u00e0 nei prossimi mesi potrebbe plasmare il futuro delle politiche statali sulle criptovalute.<\/span><\/p>\n<p><span style=\"font-weight: 400\">    <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\"><\/h2>\r\n        <\/span><\/p>\n<h3><span style=\"font-weight: 400\">Punti chiave<\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Il governo USA intende trattenere 127.271 Bitcoin, per un valore di circa 14,2 miliardi di dollari, come parte della Strategic Bitcoin Reserve, invece di venderli.<\/span>&nbsp;<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Gli asset sono stati sequestrati dalla rete criminale di Chen Zhi, che univa frode crypto, traffico di esseri umani e riciclaggio di denaro su larga scala.<\/span>&nbsp;<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Un Ordine Esecutivo del 2025 ha stabilito che le criptovalute confiscate vengano trasferite nella riserva, e non pi\u00f9 messe all\u2019asta.<\/span>&nbsp;<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Conservare i Bitcoin pu\u00f2 consentire agli Stati Uniti di trattarli come un bene di riserva, ridurre la pressione di vendita e segnare un cambiamento di politica economica a livello statale.<\/span>&nbsp;<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">L\u2019esito dipender\u00e0 da come il governo gestir\u00e0 le sfide legali, la custodia e il coordinamento tra le agenzie per amministrare i 14 miliardi di dollari in Bitcoin.<\/span>&nbsp;<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">    <\/div>\r\n    <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il governo degli Stati Uniti si prepara ad aggiungere circa 127.271 Bitcoin, per un valore stimato di circa 14,2 miliardi di dollari, a quella che ora definisce Riserva Strategica di Bitcoin (Strategic Bitcoin Reserve). Durante un\u2019operazione congiunta con le autorit\u00e0 del Regno Unito, queste monete sono state confiscate in relazione a una vasta frode in..<\/p>\n","protected":false},"author":136122,"featured_media":14347,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[11],"coin":[2],"class_list":["post-14346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica - 99bitcoins IT<\/title>\n<meta name=\"description\" content=\"Il governo degli Stati Uniti si prepara ad aggiungere circa 127.271 Bitcoin, per un valore stimato di circa 14,2 miliardi di dollari, a quella che ora\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica - 99bitcoins IT\" \/>\n<meta property=\"og:description\" content=\"Il governo degli Stati Uniti si prepara ad aggiungere circa 127.271 Bitcoin, per un valore stimato di circa 14,2 miliardi di dollari, a quella che ora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins IT\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T09:01:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/10\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clara Rosati\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clara Rosati\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/\"},\"author\":{\"name\":\"Clara Rosati\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/3cba1881884545bb80bd855e63659a51\"},\"headline\":\"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica\",\"datePublished\":\"2025-10-15T09:01:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/\"},\"wordCount\":792,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/10\\\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg\",\"keywords\":[\"Bitcoin\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/\",\"name\":\"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica - 99bitcoins IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/10\\\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg\",\"datePublished\":\"2025-10-15T09:01:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/3cba1881884545bb80bd855e63659a51\"},\"description\":\"Il governo degli Stati Uniti si prepara ad aggiungere circa 127.271 Bitcoin, per un valore stimato di circa 14,2 miliardi di dollari, a quella che ora\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/10\\\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/10\\\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notizie\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/notizie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\",\"name\":\"99bitcoins IT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/3cba1881884545bb80bd855e63659a51\",\"name\":\"Clara Rosati\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea9d8bab077637f81f917d72fbea674b39c9ee6cae263e33eb4efb7d30527653?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea9d8bab077637f81f917d72fbea674b39c9ee6cae263e33eb4efb7d30527653?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea9d8bab077637f81f917d72fbea674b39c9ee6cae263e33eb4efb7d30527653?s=96&d=mm&r=g\",\"caption\":\"Clara Rosati\"},\"description\":\"Ha conseguito una laurea magistrale con una tesi sull\u2019evoluzione della tecnologia blockchain, approfondendo in particolare le sue applicazioni nei sistemi economici digitali. Ha collaborato con diverse testate scrivendo articoli su criptovalute, finanza decentralizzata e innovazione tecnologica, e ha partecipato a conferenze dedicate all\u2019ecosistema Ethereum.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/author\\\/clara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica - 99bitcoins IT","description":"Il governo degli Stati Uniti si prepara ad aggiungere circa 127.271 Bitcoin, per un valore stimato di circa 14,2 miliardi di dollari, a quella che ora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/","og_locale":"it_IT","og_type":"article","og_title":"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica - 99bitcoins IT","og_description":"Il governo degli Stati Uniti si prepara ad aggiungere circa 127.271 Bitcoin, per un valore stimato di circa 14,2 miliardi di dollari, a quella che ora","og_url":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/","og_site_name":"99bitcoins IT","article_published_time":"2025-10-15T09:01:22+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/10\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg","type":"image\/jpeg"}],"author":"Clara Rosati","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Clara Rosati","Est. reading time":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/"},"author":{"name":"Clara Rosati","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/3cba1881884545bb80bd855e63659a51"},"headline":"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica","datePublished":"2025-10-15T09:01:22+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/"},"wordCount":792,"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/10\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg","keywords":["Bitcoin"],"articleSection":["Notizie"],"inLanguage":"it-IT","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/","url":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/","name":"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica - 99bitcoins IT","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/10\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg","datePublished":"2025-10-15T09:01:22+00:00","author":{"@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/3cba1881884545bb80bd855e63659a51"},"description":"Il governo degli Stati Uniti si prepara ad aggiungere circa 127.271 Bitcoin, per un valore stimato di circa 14,2 miliardi di dollari, a quella che ora","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/#primaryimage","url":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/10\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg","contentUrl":"https:\/\/99bitcoins.com\/it\/wp-content\/uploads\/sites\/10\/2025\/10\/U.S.-to-Hold-14-Billion-in-Bitcoin-After-Major-Crypto-Seizure.jpg","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/it\/notizie\/gli-stati-uniti-pronti-a-mettere-in-cassaforte-14-miliardi-di-dollari-in-bitcoin-come-parte-della-riserva-strategica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/it\/"},{"@type":"ListItem","position":2,"name":"Notizie","item":"https:\/\/99bitcoins.com\/it\/notizie\/"},{"@type":"ListItem","position":3,"name":"Gli Stati Uniti Pronti a Mettere in Cassaforte 14 Miliardi di Dollari in Bitcoin Come Parte della Riserva Strategica"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/it\/#website","url":"https:\/\/99bitcoins.com\/it\/","name":"99bitcoins IT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/3cba1881884545bb80bd855e63659a51","name":"Clara Rosati","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ea9d8bab077637f81f917d72fbea674b39c9ee6cae263e33eb4efb7d30527653?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea9d8bab077637f81f917d72fbea674b39c9ee6cae263e33eb4efb7d30527653?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea9d8bab077637f81f917d72fbea674b39c9ee6cae263e33eb4efb7d30527653?s=96&d=mm&r=g","caption":"Clara Rosati"},"description":"Ha conseguito una laurea magistrale con una tesi sull\u2019evoluzione della tecnologia blockchain, approfondendo in particolare le sue applicazioni nei sistemi economici digitali. Ha collaborato con diverse testate scrivendo articoli su criptovalute, finanza decentralizzata e innovazione tecnologica, e ha partecipato a conferenze dedicate all\u2019ecosistema Ethereum.","url":"https:\/\/99bitcoins.com\/it\/author\/clara\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/14346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/users\/136122"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/comments?post=14346"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/14346\/revisions"}],"predecessor-version":[{"id":14349,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/posts\/14346\/revisions\/14349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media\/14347"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media?parent=14346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/categories?post=14346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/tags?post=14346"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/coin?post=14346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}