{"id":421,"date":"2025-01-28T12:35:29","date_gmt":"2025-01-28T12:35:29","guid":{"rendered":"https:\/\/99bitcoins.com\/it\/?page_id=421"},"modified":"2025-01-28T12:35:29","modified_gmt":"2025-01-28T12:35:29","slug":"gdpr","status":"publish","type":"page","link":"https:\/\/99bitcoins.com\/it\/gdpr\/","title":{"rendered":"GDPR 99Bitcoins"},"content":{"rendered":"<p><a href=\"https:\/\/99bitcoins.com\/it\/gdpr\/accesso-dati-personali\/\"><span style=\"vertical-align: inherit\">Accesso ai dati personali<\/span><\/a><\/p>\n<p><a href=\"https:\/\/99bitcoins.com\/it\/gdpr\/dimenticami\/\"><span style=\"vertical-align: inherit\">Dimenticami<\/span><\/a><\/p>\n<p><a href=\"https:\/\/99bitcoins.com\/it\/gdpr\/rettifica-dati\/\"><span style=\"vertical-align: inherit\">Rettifica dei dati<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Accesso ai dati personali Dimenticami Rettifica dei dati<\/p>\n","protected":false},"author":136007,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-421","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GDPR 99Bitcoins - 99bitcoins IT<\/title>\n<meta name=\"description\" content=\"Scopri come 99Bitcoins protegge i tuoi dati personali in conformit\u00e0 al GDPR. Leggi i tuoi diritti, come accedere, correggere o cancellare le tue informazioni personali\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/it\/gdpr\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GDPR 99Bitcoins - 99bitcoins IT\" \/>\n<meta property=\"og:description\" content=\"Scopri come 99Bitcoins protegge i tuoi dati personali in conformit\u00e0 al GDPR. Leggi i tuoi diritti, come accedere, correggere o cancellare le tue informazioni personali\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/it\/gdpr\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins IT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/gdpr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/gdpr\\\/\"},\"author\":{\"name\":\"Antonio Pennetta\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/33fc2c8f7218cb60b7efa21869aac25e\"},\"headline\":\"GDPR 99Bitcoins\",\"datePublished\":\"2025-01-28T12:35:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/gdpr\\\/\"},\"wordCount\":10,\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/gdpr\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/gdpr\\\/\",\"name\":\"GDPR 99Bitcoins - 99bitcoins IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\"},\"datePublished\":\"2025-01-28T12:35:29+00:00\",\"description\":\"Scopri come 99Bitcoins protegge i tuoi dati personali in conformit\u00e0 al GDPR. Leggi i tuoi diritti, come accedere, correggere o cancellare le tue informazioni personali\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/gdpr\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/it\\\/gdpr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/gdpr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GDPR 99Bitcoins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/\",\"name\":\"99bitcoins IT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/#\\\/schema\\\/person\\\/33fc2c8f7218cb60b7efa21869aac25e\",\"name\":\"Antonio Pennetta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/da5ddcfee784211ba2796b5385992c0613f852ac3a9f72d89153fee8402092f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/da5ddcfee784211ba2796b5385992c0613f852ac3a9f72d89153fee8402092f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/da5ddcfee784211ba2796b5385992c0613f852ac3a9f72d89153fee8402092f6?s=96&d=mm&r=g\",\"caption\":\"Antonio Pennetta\"},\"description\":\"Antonio Pennetta \u00e8 un appassionato delle ultime tecnologie, in particolare del settore delle criptovalute e della finanza decentralizzata. Dal 2015 \u00e8 stato profondamente attratto dall'universo delle criptovalute e ha acquisito una vasta conoscenza su vari argomenti tra cui la tecnologia blockchain, la DeFi e le risorse digitali. E' stato consulente editoriale per diverse testate web del settore delle criptovalute. La sua esperienza e il suo impegno lo rendono una voce assai richiesta nella comunit\u00e0 crypto italiana.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/it\\\/author\\\/antonio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GDPR 99Bitcoins - 99bitcoins IT","description":"Scopri come 99Bitcoins protegge i tuoi dati personali in conformit\u00e0 al GDPR. Leggi i tuoi diritti, come accedere, correggere o cancellare le tue informazioni personali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/it\/gdpr\/","og_locale":"it_IT","og_type":"article","og_title":"GDPR 99Bitcoins - 99bitcoins IT","og_description":"Scopri come 99Bitcoins protegge i tuoi dati personali in conformit\u00e0 al GDPR. Leggi i tuoi diritti, come accedere, correggere o cancellare le tue informazioni personali","og_url":"https:\/\/99bitcoins.com\/it\/gdpr\/","og_site_name":"99bitcoins IT","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/it\/gdpr\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/gdpr\/"},"author":{"name":"Antonio Pennetta","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/33fc2c8f7218cb60b7efa21869aac25e"},"headline":"GDPR 99Bitcoins","datePublished":"2025-01-28T12:35:29+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/it\/gdpr\/"},"wordCount":10,"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/it\/gdpr\/","url":"https:\/\/99bitcoins.com\/it\/gdpr\/","name":"GDPR 99Bitcoins - 99bitcoins IT","isPartOf":{"@id":"https:\/\/99bitcoins.com\/it\/#website"},"datePublished":"2025-01-28T12:35:29+00:00","description":"Scopri come 99Bitcoins protegge i tuoi dati personali in conformit\u00e0 al GDPR. Leggi i tuoi diritti, come accedere, correggere o cancellare le tue informazioni personali","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/it\/gdpr\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/it\/gdpr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/it\/gdpr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/it\/"},{"@type":"ListItem","position":2,"name":"GDPR 99Bitcoins"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/it\/#website","url":"https:\/\/99bitcoins.com\/it\/","name":"99bitcoins IT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/it\/#\/schema\/person\/33fc2c8f7218cb60b7efa21869aac25e","name":"Antonio Pennetta","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/da5ddcfee784211ba2796b5385992c0613f852ac3a9f72d89153fee8402092f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/da5ddcfee784211ba2796b5385992c0613f852ac3a9f72d89153fee8402092f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/da5ddcfee784211ba2796b5385992c0613f852ac3a9f72d89153fee8402092f6?s=96&d=mm&r=g","caption":"Antonio Pennetta"},"description":"Antonio Pennetta \u00e8 un appassionato delle ultime tecnologie, in particolare del settore delle criptovalute e della finanza decentralizzata. Dal 2015 \u00e8 stato profondamente attratto dall'universo delle criptovalute e ha acquisito una vasta conoscenza su vari argomenti tra cui la tecnologia blockchain, la DeFi e le risorse digitali. E' stato consulente editoriale per diverse testate web del settore delle criptovalute. La sua esperienza e il suo impegno lo rendono una voce assai richiesta nella comunit\u00e0 crypto italiana.","url":"https:\/\/99bitcoins.com\/it\/author\/antonio\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/pages\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/users\/136007"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/comments?post=421"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/pages\/421\/revisions"}],"predecessor-version":[{"id":440,"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/pages\/421\/revisions\/440"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/it\/wp-json\/wp\/v2\/media?parent=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}