{"id":29447,"date":"2025-12-18T13:30:38","date_gmt":"2025-12-18T13:30:38","guid":{"rendered":"https:\/\/99bitcoins.com\/fr\/?p=29447"},"modified":"2025-12-18T11:02:35","modified_gmt":"2025-12-18T11:02:35","slug":"pepenode-mine-to-earn-gamefi","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/","title":{"rendered":"Oubliez le \u00ab\u00a0Play-to-Earn\u00a0\u00bb : PepeNode lance la r\u00e9volution du \u00ab\u00a0Mine-to-Earn\u00a0\u00bb"},"content":{"rendered":"<p>Durant l&rsquo;hiver crypto de 2022 \u00e0 2023, la plupart des secteurs ont ralenti alors que les prix s&rsquo;effondraient, mais <strong>l&rsquo;activit\u00e9 li\u00e9e au gaming<\/strong> s&rsquo;est maintenue sur le march\u00e9. M\u00eame avec des valorisations en baisse, le GameFi a r\u00e9ussi \u00e0 garder l&rsquo;engagement des utilisateurs, contrairement \u00e0 de nombreux autres pans de l&rsquo;industrie crypto qui se sont vid\u00e9s.<\/p>\n<p>Cette p\u00e9riode a \u00e9galement r\u00e9v\u00e9l\u00e9 pourquoi de nombreux premiers titres GameFi n&rsquo;ont pas surv\u00e9cu. Leurs \u00e9conomies de jetons \u00e9taient inflationnistes et d\u00e9pendantes d&rsquo;<strong>afflux constants<\/strong>. Alors que ces mod\u00e8les s&rsquo;effondraient, <a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" target=\"_blank\" rel=\"noopener nofollow sponsored\">PepeNode (PEPENODE)<\/a> a commenc\u00e9 son d\u00e9veloppement en tant que nouveau type de projet GameFi, con\u00e7u pour rem\u00e9dier aux inefficacit\u00e9s des jeux crypto pr\u00e9c\u00e9dents.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-29453 size-full\" src=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2.jpg\" alt=\"\" width=\"1999\" height=\"1999\" srcset=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2.jpg 1999w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2-300x300.jpg 300w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2-1024x1024.jpg 1024w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2-150x150.jpg 150w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2-768x768.jpg 768w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2-148x148.jpg 148w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2-64x64.jpg 64w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2-1536x1536.jpg 1536w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2-1200x1200.jpg 1200w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image3-1-2-600x600.jpg 600w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<p>Pr\u00e9sent\u00e9 comme le premier jeu <strong>\u00ab\u00a0mine-to-earn\u00a0\u00bb<\/strong> de l&rsquo;industrie, PepeNode est une simulation gamifi\u00e9e du minage r\u00e9el le processus industriel qui fait fonctionner Bitcoin (BTC). Il ne mine pas directement du BTC. Au lieu de cela, les joueurs exploitent des syst\u00e8mes de minage qui g\u00e9n\u00e8rent des r\u00e9compenses pay\u00e9es en m\u00e8me coins, incluant des jetons \u00e9tablis comme <strong>Pepe (PEPE) et Fartcoin (FARTCOIN)<\/strong>, entre autres. Le succ\u00e8s dans ce monde de minage gamifi\u00e9 est d\u00e9termin\u00e9 par les choix d&rsquo;allocation, les am\u00e9liorations et l&rsquo;efficacit\u00e9 du syst\u00e8me, plut\u00f4t que par des clics passifs.<\/p>\n<p>Cette approche a d\u00e9j\u00e0 attir\u00e9 des capitaux. Les premiers soutiens ont engag\u00e9 <strong>2,36 millions de dollars<\/strong>, pariant qu&rsquo;un jeu construit autour d&rsquo;une profondeur de gestion, plus proche de <a href=\"https:\/\/99bitcoins.com\/news\/pr-news\/factorio-meets-crypto-mine-to-earn-pepenode-breaks-2-2m-in-ico\/\" target=\"_blank\" rel=\"noopener\">Factorio<\/a> ou <a href=\"https:\/\/99bitcoins.com\/news\/pr-news\/miss-zoo-tycoon-now-you-can-earn-for-real-with-crypto-mining-tycoon-game\/\" target=\"_blank\" rel=\"noopener\">Zoo Tycoon<\/a> que des boucles \u00ab\u00a0play-to-earn\u00a0\u00bb typiques peut soutenir des r\u00e9compenses crypto sans r\u00e9p\u00e9ter les raccourcis \u00e9conomiques qui ont bris\u00e9 les projets GameFi pr\u00e9c\u00e9dents.<\/p>\n<p>Pour les investisseurs pr\u00e9coces, <strong>le calendrier est fixe<\/strong>. La pr\u00e9vente de <a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" target=\"_blank\" rel=\"noopener nofollow sponsored\">PEPENODE<\/a> a encore <strong>22 jours<\/strong> devant elle, avec des jetons au prix de <strong>0,0011968 $<\/strong>. Une fois la vente termin\u00e9e, le jeton passera sur les \u00e9changes, o\u00f9 le prix sera d\u00e9termin\u00e9 par la liquidit\u00e9 et la demande, plut\u00f4t que par des remises pr\u00e9d\u00e9finies.<\/p>\n<a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" class=\"sc-button sc-button-green sc-button-medium\" target=\"_blank\"  rel=\"nofollow sponsored\"><span>D\u00e9couvrir PepeNode<\/span><\/a>\n<div style=\"font-size: 12px;color: #b1b1b1;margin-top: 2px;text-align: center\"><em>Les crypto-actifs repr\u00e9sentent un investissement risqu\u00e9.<\/em><\/div>\n<h2>Le GameFi a surv\u00e9cu \u00e0 l&rsquo;hiver, pas son \u00e9conomie<\/h2>\n<p>Dans le rapport \u00ab\u00a0State of GameFi 2022\u00a0\u00bb de ChainPlay, la toile de fond \u00e9tait un march\u00e9 encore sous le choc de <strong>l&rsquo;effondrement de Terra-Luna<\/strong>, qui a an\u00e9anti la confiance et entra\u00een\u00e9 la crypto dans un long hiver qui s&rsquo;est \u00e9tendu sur les ann\u00e9es suivantes.<\/p>\n<p>Le rapport a montr\u00e9 comment cet environnement a mis le GameFi <strong>\u00e0 l&rsquo;\u00e9preuve<\/strong> d&rsquo;une mani\u00e8re que les march\u00e9s haussiers ne font jamais. Trois r\u00e9pondants sur quatre ont d\u00e9clar\u00e9 que le GameFi \u00e9tait leur point d&rsquo;entr\u00e9e dans la crypto, soulignant \u00e0 quel point <strong>les jeux restaient centraux<\/strong> pour l&rsquo;int\u00e9gration des utilisateurs m\u00eame lorsque les prix chutaient.<\/p>\n<p><em><a href=\"https:\/\/chainplay.gg\/state-of-gamefi-2022\/\" target=\"_blank\" rel=\"noopener nofollow\"><img decoding=\"async\" class=\"alignnone wp-image-29451 size-full\" src=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image1-1-1.jpg\" alt=\"\" width=\"1999\" height=\"691\" srcset=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image1-1-1.jpg 1999w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image1-1-1-300x104.jpg 300w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image1-1-1-1024x354.jpg 1024w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image1-1-1-768x265.jpg 768w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image1-1-1-1536x531.jpg 1536w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a><\/em><\/p>\n<p style=\"text-align: center\"><em><strong>Source :<\/strong> <a href=\"https:\/\/chainplay.gg\/state-of-gamefi-2022\/\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/chainplay.gg\/state-of-gamefi-2022\/<\/a><\/em><\/p>\n<p>Malgr\u00e9 la chute de la valeur des jetons, les participants passaient toujours en moyenne <strong>2,5 heures par jour<\/strong> dans des jeux bas\u00e9s sur la blockchain. Cet engagement en temps s&rsquo;est maintenu m\u00eame si les r\u00e9sultats financiers se d\u00e9t\u00e9rioraient, <strong>89 %<\/strong> des r\u00e9pondants signalant des profits inf\u00e9rieurs \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<p>Lorsqu&rsquo;on leur a demand\u00e9 pourquoi les rendements avaient diminu\u00e9, <strong>58 %<\/strong> ont point\u00e9 directement une mauvaise conception \u00e9conomique du jeu.<\/p>\n<p>Les structures de r\u00e9compense fortement inflationnistes et <strong>les \u00e9missions de jetons incontr\u00f4l\u00e9es<\/strong> sont apparues \u00e0 plusieurs reprises comme des acc\u00e9l\u00e9rateurs plut\u00f4t que des solutions. La confiance s&rsquo;est encore \u00e9rod\u00e9e alors que <strong>73 %<\/strong> des joueurs ont signal\u00e9 des pr\u00e9occupations concernant les \u00ab\u00a0rug pulls\u00a0\u00bb et les m\u00e9canismes de type Ponzi \u00e0 travers le secteur.<\/p>\n<p>Dans l&rsquo;ensemble, les donn\u00e9es indiquaient un secteur qui maintenait <strong>l&rsquo;engagement des utilisateurs<\/strong> pendant le ralentissement, tandis que ses mod\u00e8les \u00e9conomiques vacillaient une fois l&rsquo;\u00e9lan dissip\u00e9.<\/p>\n<p>Alors que l&rsquo;industrie crypto glisse dans un autre ralentissement familier, <strong>le gaming<\/strong> reste l&rsquo;un des rares domaines qui continue de retenir l&rsquo;attention des utilisateurs.<\/p>\n<p>Mais une traction durable d\u00e9pendra de <strong>la correction des erreurs<\/strong> qui ont min\u00e9 les cycles GameFi pr\u00e9c\u00e9dents.<\/p>\n<p>Un projet qui tente de faire exactement cela est <strong><a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" target=\"_blank\" rel=\"noopener nofollow sponsored\">PepeNode<\/a><\/strong>.<\/p>\n<h2>Ce qui se passe quand le GameFi est con\u00e7u comme un vrai jeu<\/h2>\n<p>PepeNode transforme le minage en un syst\u00e8me virtuel, le simulant assez fid\u00e8lement pour que jouer au jeu revienne effectivement \u00e0 <strong>g\u00e9rer une op\u00e9ration de minage<\/strong>. Les joueurs ach\u00e8tent des n\u0153uds (nodes) en utilisant des jetons <a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" target=\"_blank\" rel=\"noopener nofollow sponsored\">PEPENODE<\/a>, chaque n\u0153ud portant des traits diff\u00e9rents, et le d\u00e9fi r\u00e9side dans la combinaison de ceux-ci de mani\u00e8re \u00e0 ce qu&rsquo;ils fonctionnent r\u00e9ellement ensemble plut\u00f4t que de les empiler aveugl\u00e9ment.<\/p>\n<p>\u00c0 partir de l\u00e0, les jetons doivent \u00eatre allou\u00e9s \u00e0 travers <strong>des priorit\u00e9s concurrentes<\/strong>, telles que l&rsquo;expansion des installations, la mise \u00e0 niveau de l&rsquo;infrastructure et l&rsquo;optimisation des performances. L&rsquo;objectif est de maintenir le fonctionnement de l&rsquo;op\u00e9ration de mani\u00e8re efficace, en maintenant un taux de hachage \u00e9lev\u00e9 et en s\u00e9curisant une part significative du taux de hachage total du r\u00e9seau pour am\u00e9liorer les chances de miner plus de jetons.<\/p>\n<p>Les m\u00e9canismes futurs devraient aller plus loin. <strong>La consommation d&rsquo;\u00e9nergie<\/strong>, les contraintes de refroidissement et d&rsquo;autres compromis du monde r\u00e9el pourraient \u00eatre introduits, for\u00e7ant les joueurs \u00e0 prendre des d\u00e9cisions qui refl\u00e8tent les op\u00e9rations de minage r\u00e9elles. Ce choix de conception est d\u00e9lib\u00e9r\u00e9 car il s&rsquo;\u00e9loigne des jeux crypto pr\u00e9c\u00e9dents qui r\u00e9duisaient le gameplay \u00e0 taper sur des \u00e9crans, r\u00e9pondre \u00e0 des invites sans rapport, grinder des mini-jeux superficiels, marcher jusqu&rsquo;\u00e0 la blessure, ou combattre des cr\u00e9atures relook\u00e9es juste pour collecter un paiement quotidien en jetons qui \u00e9tait imm\u00e9diatement vendu.<\/p>\n<p>Ce changement s&rsquo;aligne avec les pr\u00e9f\u00e9rences plus larges des joueurs. Le rapport \u00ab\u00a0State of GameFi 2022\u00a0\u00bb a r\u00e9v\u00e9l\u00e9 que <strong>81 %<\/strong> des investisseurs GameFi privil\u00e9gient le plaisir par rapport aux gains lors de l&rsquo;\u00e9valuation des projets futurs et c&rsquo;est une exigence, pas un bonus, si les jeux sont destin\u00e9s \u00e0 durer.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-29454 size-full\" src=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image4-3.jpg\" alt=\"\" width=\"1999\" height=\"722\" srcset=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image4-3.jpg 1999w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image4-3-300x108.jpg 300w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image4-3-1024x370.jpg 1024w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image4-3-768x277.jpg 768w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image4-3-1536x555.jpg 1536w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<p style=\"text-align: center\"><em><strong>Source :<\/strong> <a href=\"https:\/\/chainplay.gg\/state-of-gamefi-2022\/\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/chainplay.gg\/state-of-gamefi-2022\/<\/a><\/em><\/p>\n<p>Les r\u00e9compenses en jetons comptent toujours, mais elles ne peuvent pas exister <strong>de mani\u00e8re isol\u00e9e<\/strong>. Les joueurs ont besoin de raisons de d\u00e9penser de la valeur dans le jeu plut\u00f4t que de l&rsquo;extraire imm\u00e9diatement, et cela ne se produit que lorsqu&rsquo;une r\u00e8gle fondamentale de la conception de jeu est respect\u00e9e, <strong>l&rsquo;exp\u00e9rience doit \u00eatre amusante<\/strong> en elle-m\u00eame.<\/p>\n<p>Une fois cette fondation en place, dans le cas de <a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" target=\"_blank\" rel=\"noopener nofollow sponsored\">PepeNode<\/a>, en fondant le gameplay sur des syst\u00e8mes qui ressemblent au minage r\u00e9el, <strong>l&rsquo;\u00e9conomie du jeu<\/strong> a de la place pour se stabiliser. La tokenomics devient alors une couche de soutien, et non le focus principal, renfor\u00e7ant la r\u00e9tention \u00e0 long terme au lieu d&rsquo;essayer de la fabriquer.<\/p>\n<h2>Pourquoi PepeNode refuse les m\u00e9caniques d&rsquo;argent facile<\/h2>\n<p>La tokenomics ne peut pas simplement \u00eatre superpos\u00e9e \u00e0 un jeu sans r\u00e9parer <strong>ce qui a \u00e9chou\u00e9 auparavant<\/strong>. La promesse int\u00e9gr\u00e9e au \u00ab\u00a0play-to-earn\u00a0\u00bb (que vous pouvez gagner de l&rsquo;argent simplement en jouant) est impossible \u00e0 ignorer pour les joueurs, surtout dans un march\u00e9 o\u00f9 la plupart des participants sont encore motiv\u00e9s \u00e9conomiquement.<\/p>\n<p>Les gens joueront <strong>pour de l&rsquo;argent<\/strong>. Cette r\u00e9alit\u00e9 ne dispara\u00eet pas simplement parce qu&rsquo;un jeu est \u00ab\u00a0amusant\u00a0\u00bb. <a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" target=\"_blank\" rel=\"noopener nofollow sponsored\">PepeNode<\/a> aborde cela en poussant ses r\u00e9compenses les plus significatives vers des niveaux sup\u00e9rieurs, o\u00f9 le jeton natif, PEPENODE, est li\u00e9 \u00e0 <strong>l&rsquo;utilit\u00e9<\/strong> plut\u00f4t qu&rsquo;\u00e0 l&rsquo;extraction passive.<\/p>\n<a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" class=\"sc-button sc-button-green sc-button-medium\" target=\"_blank\"  rel=\"nofollow sponsored\"><span>D\u00e9couvrir PepeNode<\/span><\/a>\n<div style=\"font-size: 12px;color: #b1b1b1;margin-top: 2px;text-align: center\"><em>Les crypto-actifs repr\u00e9sentent un investissement risqu\u00e9.<\/em><\/div>\n<p>\u00c0 mesure que les joueurs d\u00e9pensent plus pour \u00e9tendre et affiner leurs op\u00e9rations de minage gr\u00e2ce \u00e0 une allocation appropri\u00e9e des jetons PEPENODE, ils augmentent leurs chances de gagner des actifs \u00e0 plus forte demande, y compris <strong>des m\u00e8me coins<\/strong> comme PEPE et FARTCOIN. Comme mentionn\u00e9, selon la fa\u00e7on dont le jeu se d\u00e9veloppe et gagne en traction, ces r\u00e9compenses pourraient \u00e9ventuellement s&rsquo;\u00e9tendre au BTC.<\/p>\n<p>Cependant, cela laisse toujours le probl\u00e8me de l&rsquo;inflation qui a min\u00e9 les projets GameFi pr\u00e9c\u00e9dents. PepeNode y fait face directement par <strong>une r\u00e9duction agressive de l&rsquo;offre<\/strong>. Environ <strong>70 % des jetons<\/strong> utilis\u00e9s pour les am\u00e9liorations sont br\u00fbl\u00e9s de mani\u00e8re permanente, les retirant de la circulation.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-29455 size-full\" src=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image5.jpg\" alt=\"\" width=\"1476\" height=\"1054\" srcset=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image5.jpg 1476w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image5-300x214.jpg 300w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image5-1024x731.jpg 1024w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/image5-768x548.jpg 768w\" sizes=\"(max-width: 1476px) 100vw, 1476px\" \/><\/p>\n<p>Avec une offre totale fixe de <strong>210 milliards de jetons<\/strong>, le syst\u00e8me permet aux r\u00e9compenses de diminuer avec le temps, faisant \u00e9cho au mod\u00e8le de \u00ab\u00a0halving\u00a0\u00bb de Bitcoin. Les joueurs peuvent, en fait, suivre les prochaines r\u00e9ductions de r\u00e9compenses \u00e0 l&rsquo;int\u00e9rieur du jeu, tandis que le m\u00e9canisme de burn accentue la pression <strong>d\u00e9flationniste<\/strong>.<\/p>\n<p>Le r\u00e9sultat est un syst\u00e8me o\u00f9 la croissance ne signifie pas automatiquement <strong>dilution<\/strong>. La progression du gameplay et l&rsquo;\u00e9conomie des jetons sont align\u00e9es au lieu de se combattre.<\/p>\n<p>Cette combinaison de m\u00e9canismes fonctionnels avec un mod\u00e8le d&rsquo;offre contrainte est la raison pour laquelle PepeNode est construit avec <strong>des horizons temporels plus longs<\/strong> \u00e0 l&rsquo;esprit.<\/p>\n<p>Plut\u00f4t que de compter sur des afflux constants, il vise \u00e0 <strong>tenir bon<\/strong> \u00e0 mesure que la participation augmente.<\/p>\n<p>Cette approche tourn\u00e9e vers l&rsquo;avenir a d\u00e9j\u00e0 attir\u00e9 l&rsquo;attention. Le commentateur crypto Michael Wrubel, qui compte plus de <strong>315 000 abonn\u00e9s<\/strong> sur YouTube, a publiquement soulign\u00e9 <a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" target=\"_blank\" rel=\"noopener nofollow sponsored\">PEPENODE<\/a> comme l&rsquo;un des jetons qu&rsquo;il surveille cette ann\u00e9e.<\/p>\n<p><iframe loading=\"lazy\" title=\"Pepe Node: Top Mine To Earn Crypto To Buy In 2025\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/_1NwphdDxWQ?start=32&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h2>Comment le prochain cycle GameFi prend forme et comment vous pouvez rejoindre<\/h2>\n<p>En effet, PepeNode se forme \u00e0 l&rsquo;avant-garde d&rsquo;un <strong>nouveau cycle<\/strong>, ce qui signifie que les premiers participants peuvent gagner une exposition avant que l&rsquo;\u00e9lan plus large ne revienne.<\/p>\n<p>Pour rejoindre avant la fin de la pr\u00e9vente dans <strong>22 jours<\/strong>, <a href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" target=\"_blank\" rel=\"noopener nofollow sponsored\">rendez-vous sur le site de la pr\u00e9vente<\/a> pour acheter des jetons PEPENODE aujourd&rsquo;hui en utilisant <strong>ETH, BNB, USDT<\/strong> (ERC-20 et BEP-20), et m\u00eame des cartes de cr\u00e9dit ou de d\u00e9bit.<\/p>\n<p>Les acheteurs peuvent se connecter en utilisant leur portefeuille pr\u00e9f\u00e9r\u00e9, tel que <strong>Best Wallet<\/strong>, qui est consid\u00e9r\u00e9 comme le <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/fr\/visit\/bestwallet\" target=\"_blank\" rel=\"noopener nofollow sponsored\">meilleur portefeuille crypto et Bitcoin<\/a> de l&rsquo;industrie. PepeNode est list\u00e9 sur le nouvel outil de s\u00e9lection de projets de Best Wallet, <strong>Upcoming Tokens<\/strong>, vous pouvez donc acheter, suivre et r\u00e9clamer une fois le projet en ligne.<\/p>\n<p>Le contrat intelligent du projet a \u00e9t\u00e9 audit\u00e9 par <a href=\"https:\/\/app.coinsult.net\/eth\/0xd29191a6d2aae7c0e60f4722018832addf4b9831\" target=\"_blank\" rel=\"noopener nofollow\">Coinsult<\/a>, ce qui donne aux investisseurs une tranquillit\u00e9 d&rsquo;esprit quant \u00e0 la s\u00e9curit\u00e9 de son code.<\/p>\n<p>Suivez le projet sur <a href=\"https:\/\/x.com\/pepenode_io\" target=\"_blank\" rel=\"noopener nofollow\">X<\/a> et <a href=\"https:\/\/t.me\/pepe_node\" target=\"_blank\" rel=\"noopener nofollow\">Telegram<\/a> pour les derni\u00e8res mises \u00e0 jour.<\/p>\n<p><a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/fr\/visit\/pepenode\" target=\"_blank\" rel=\"noopener nofollow sponsored\">Visitez PepeNode.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durant l&rsquo;hiver crypto de 2022 \u00e0 2023, la plupart des secteurs ont ralenti alors que les prix s&rsquo;effondraient, mais l&rsquo;activit\u00e9 li\u00e9e au gaming s&rsquo;est maintenue sur le march\u00e9. M\u00eame avec des valorisations en baisse, le GameFi a r\u00e9ussi \u00e0 garder l&rsquo;engagement des utilisateurs, contrairement \u00e0 de nombreux autres pans de l&rsquo;industrie crypto qui se sont..<\/p>\n","protected":false},"author":136161,"featured_media":29457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[113],"tags":[12],"coin":[15],"class_list":["post-29447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-pr","tag-prevente"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oubliez le &quot;Play-to-Earn&quot; : PepeNode lance la r\u00e9volution du &quot;Mine-to-Earn&quot;<\/title>\n<meta name=\"description\" content=\"PepeNode relance le GameFi avec un jeu mine-to-earn plus durable, burn de tokens et gestion fa\u00e7on tycoon, avant la fin de pr\u00e9vente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oubliez le &quot;Play-to-Earn&quot; : PepeNode lance la r\u00e9volution du &quot;Mine-to-Earn&quot;\" \/>\n<meta property=\"og:description\" content=\"PepeNode relance le GameFi avec un jeu mine-to-earn plus durable, burn de tokens et gestion fa\u00e7on tycoon, avant la fin de pr\u00e9vente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins FR\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T13:30:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/Miniatures-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guillaume Caras\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guillaume Caras\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/\"},\"author\":{\"name\":\"Guillaume Caras\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/d8c48b93c5402c5a8d4581c987b6ad62\"},\"headline\":\"Oubliez le \u00ab\u00a0Play-to-Earn\u00a0\u00bb : PepeNode lance la r\u00e9volution du \u00ab\u00a0Mine-to-Earn\u00a0\u00bb\",\"datePublished\":\"2025-12-18T13:30:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/\"},\"wordCount\":1862,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/12\\\/Miniatures-5.jpg\",\"keywords\":[\"Pr\u00e9ventes\"],\"articleSection\":[\"actu pr\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/\",\"name\":\"Oubliez le \\\"Play-to-Earn\\\" : PepeNode lance la r\u00e9volution du \\\"Mine-to-Earn\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/12\\\/Miniatures-5.jpg\",\"datePublished\":\"2025-12-18T13:30:38+00:00\",\"description\":\"PepeNode relance le GameFi avec un jeu mine-to-earn plus durable, burn de tokens et gestion fa\u00e7on tycoon, avant la fin de pr\u00e9vente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/12\\\/Miniatures-5.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/12\\\/Miniatures-5.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/pepenode-mine-to-earn-gamefi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"actu pr\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/actu-pr\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Oubliez le \u00ab\u00a0Play-to-Earn\u00a0\u00bb : PepeNode lance la r\u00e9volution du \u00ab\u00a0Mine-to-Earn\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"name\":\"99bitcoins FR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/d8c48b93c5402c5a8d4581c987b6ad62\",\"name\":\"Guillaume Caras\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de178832cb92be11cb7ad6e33d0f4d666a9eef917ae2a048bf5a692e8989d888?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de178832cb92be11cb7ad6e33d0f4d666a9eef917ae2a048bf5a692e8989d888?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de178832cb92be11cb7ad6e33d0f4d666a9eef917ae2a048bf5a692e8989d888?s=96&d=mm&r=g\",\"caption\":\"Guillaume Caras\"},\"description\":\"Apr\u00e8s un bachelor en journalisme plurim\u00e9dia \u00e0 l\u2019EFJ Bordeaux, il se sp\u00e9cialise dans la production vid\u00e9o et l\u2019enqu\u00eate. Curieux de nature, il d\u00e9couvre l\u2019univers crypto en suivant les \u00e9volutions du Bitcoin et les promesses de la blockchain. D\u2019abord attir\u00e9 par les enjeux g\u00e9opolitiques et technologiques du secteur, il s\u2019int\u00e9resse aujourd\u2019hui de pr\u00e8s aux cryptomonnaies, \u00e0 la DeFi et au Web3. Son regard critique et sa rigueur journalistique lui permettent d\u2019apporter une information claire, contextualis\u00e9e et accessible \u00e0 tous les lecteurs, qu\u2019ils soient n\u00e9ophytes ou initi\u00e9s.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/author\\\/guillaumecaras\\\/\"}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/_1NwphdDxWQ\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"325\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:upload_date\" content=\"2025-12-18T13:30:38+00:00\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oubliez le \"Play-to-Earn\" : PepeNode lance la r\u00e9volution du \"Mine-to-Earn\"","description":"PepeNode relance le GameFi avec un jeu mine-to-earn plus durable, burn de tokens et gestion fa\u00e7on tycoon, avant la fin de pr\u00e9vente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/","og_locale":"fr_FR","og_type":"article","og_title":"Oubliez le \"Play-to-Earn\" : PepeNode lance la r\u00e9volution du \"Mine-to-Earn\"","og_description":"PepeNode relance le GameFi avec un jeu mine-to-earn plus durable, burn de tokens et gestion fa\u00e7on tycoon, avant la fin de pr\u00e9vente.","og_url":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/","og_site_name":"99bitcoins FR","article_published_time":"2025-12-18T13:30:38+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/Miniatures-5.jpg","type":"image\/jpeg"}],"author":"Guillaume Caras","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Guillaume Caras","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/"},"author":{"name":"Guillaume Caras","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/d8c48b93c5402c5a8d4581c987b6ad62"},"headline":"Oubliez le \u00ab\u00a0Play-to-Earn\u00a0\u00bb : PepeNode lance la r\u00e9volution du \u00ab\u00a0Mine-to-Earn\u00a0\u00bb","datePublished":"2025-12-18T13:30:38+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/"},"wordCount":1862,"publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/Miniatures-5.jpg","keywords":["Pr\u00e9ventes"],"articleSection":["actu pr"],"inLanguage":"fr-FR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/","url":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/","name":"Oubliez le \"Play-to-Earn\" : PepeNode lance la r\u00e9volution du \"Mine-to-Earn\"","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/Miniatures-5.jpg","datePublished":"2025-12-18T13:30:38+00:00","description":"PepeNode relance le GameFi avec un jeu mine-to-earn plus durable, burn de tokens et gestion fa\u00e7on tycoon, avant la fin de pr\u00e9vente.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/#primaryimage","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/Miniatures-5.jpg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/Miniatures-5.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/pepenode-mine-to-earn-gamefi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais","item":"https:\/\/99bitcoins.com\/fr\/actu\/"},{"@type":"ListItem","position":3,"name":"actu pr","item":"https:\/\/99bitcoins.com\/fr\/actu\/actu-pr\/"},{"@type":"ListItem","position":4,"name":"Oubliez le \u00ab\u00a0Play-to-Earn\u00a0\u00bb : PepeNode lance la r\u00e9volution du \u00ab\u00a0Mine-to-Earn\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/fr\/#website","url":"https:\/\/99bitcoins.com\/fr\/","name":"99bitcoins FR","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/fr\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/d8c48b93c5402c5a8d4581c987b6ad62","name":"Guillaume Caras","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/de178832cb92be11cb7ad6e33d0f4d666a9eef917ae2a048bf5a692e8989d888?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de178832cb92be11cb7ad6e33d0f4d666a9eef917ae2a048bf5a692e8989d888?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de178832cb92be11cb7ad6e33d0f4d666a9eef917ae2a048bf5a692e8989d888?s=96&d=mm&r=g","caption":"Guillaume Caras"},"description":"Apr\u00e8s un bachelor en journalisme plurim\u00e9dia \u00e0 l\u2019EFJ Bordeaux, il se sp\u00e9cialise dans la production vid\u00e9o et l\u2019enqu\u00eate. Curieux de nature, il d\u00e9couvre l\u2019univers crypto en suivant les \u00e9volutions du Bitcoin et les promesses de la blockchain. D\u2019abord attir\u00e9 par les enjeux g\u00e9opolitiques et technologiques du secteur, il s\u2019int\u00e9resse aujourd\u2019hui de pr\u00e8s aux cryptomonnaies, \u00e0 la DeFi et au Web3. Son regard critique et sa rigueur journalistique lui permettent d\u2019apporter une information claire, contextualis\u00e9e et accessible \u00e0 tous les lecteurs, qu\u2019ils soient n\u00e9ophytes ou initi\u00e9s.","url":"https:\/\/99bitcoins.com\/fr\/author\/guillaumecaras\/"}]},"og_video":"https:\/\/www.youtube.com\/embed\/_1NwphdDxWQ","og_video_type":"text\/html","og_video_duration":"325","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_upload_date":"2025-12-18T13:30:38+00:00","ya_ovs_allow_embed":"true"},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/29447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/users\/136161"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/comments?post=29447"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/29447\/revisions"}],"predecessor-version":[{"id":29458,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/29447\/revisions\/29458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media\/29457"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media?parent=29447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/categories?post=29447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/tags?post=29447"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/coin?post=29447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}