{"id":28749,"date":"2025-12-06T13:00:50","date_gmt":"2025-12-06T13:00:50","guid":{"rendered":"https:\/\/99bitcoins.com\/fr\/?p=28749"},"modified":"2025-12-03T00:29:49","modified_gmt":"2025-12-03T00:29:49","slug":"bitcoin-bottom-55000-bollinger","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/","title":{"rendered":"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$"},"content":{"rendered":"<p>Pr\u00e9dire le \u00ab\u00a0vrai\u00a0\u00bb bas de cycle de Bitcoin ressemble souvent plus \u00e0 un <strong>concours de sensations fortes<\/strong> qu&rsquo;\u00e0 une analyse. Entre ceux qui annoncent un retour \u00e0 35 000 $ et d&rsquo;autres qui parlent d\u00e9j\u00e0 de nouveau bullrun, un analyste a d\u00e9cid\u00e9 de poser des <strong>bornes claires<\/strong> en s&rsquo;appuyant uniquement sur les graphiques. Pour lui, le fameux sc\u00e9nario d&rsquo;un retour \u00e0 35 000 $ n&rsquo;a tout simplement <strong>aucun sens<\/strong> au regard des donn\u00e9es techniques actuelles.<\/p>\n<h2>Pourquoi les 35 000 $ ne tiennent pas la route<\/h2>\n<p>L&rsquo;analyste connu sous le pseudo \u00ab\u00a0Sykodelic\u00a0\u00bb ne tourne pas autour du pot : l&rsquo;id\u00e9e d&rsquo;un Bitcoin \u00e0 35 000 $ en 2026 est, selon lui, \u00ab\u00a0<strong>pure absurdit\u00e9<\/strong>\u00ab\u00a0. Il rappelle qu&rsquo;une telle chute impliquerait une correction d&rsquo;environ <strong>72 %<\/strong> depuis le sommet \u00e0 126 000 $, ce qui renvoie aux drawdowns violents des cycles pass\u00e9s, comme la baisse de 77 % entre 69 000 $ et 15 500 $ entre 2021 et 2022.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">This is a very important chart analysis for you to understand.<\/p>\n<p>I am seeing people talking about $35k levels next year and it&#39;s absolute rubbish.<\/p>\n<p>Firstly, for Bitcoin to retrace 75% it actually has to fully expand, and this cycle, it just did not do that.<\/p>\n<p>Those kinds of\u2026 <a href=\"https:\/\/t.co\/VZp5aAdjXe\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/VZp5aAdjXe<\/a><\/p>\n<p>&mdash; Sykodelic \ud83d\udd2a (@Sykodelic_) <a href=\"https:\/\/twitter.com\/Sykodelic_\/status\/1995660813907149150?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">December 2, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Sauf que, pour lui, ce type de saign\u00e9e n&rsquo;arrive pas dans le vide. Elle n&rsquo;est possible que lorsque le march\u00e9 a connu une phase d'\u00a0\u00bb<strong>expansion<\/strong>\u00a0\u00bb extr\u00eame, visible notamment dans le RSI. Plus le <strong>RSI<\/strong> part loin en surachat, plus la contraction peut \u00eatre profonde derri\u00e8re.<\/p>\n<p>Or, dans ce cycle, l&rsquo;indicateur n&rsquo;a jamais montr\u00e9 cette esp\u00e8ce d&rsquo;<strong>euphorie technique totale<\/strong> que l&rsquo;on avait connue sur les pr\u00e9c\u00e9dents sommets. Aujourd&rsquo;hui, <a href=\"https:\/\/99bitcoins.com\/fr\/actu\/analyse-bitcoin-125-000-franchis-correction-est-elle-deja-en-marche\/\">Bitcoin<\/a> est environ 31 % sous son pic d&rsquo;octobre autour de 126 000 $.<\/p>\n<p>Une respiration de cet ordre en plein <strong>march\u00e9 haussier<\/strong> reste statistiquement classique. Pour que le prix soit tra\u00een\u00e9 jusqu&rsquo;\u00e0 35 000 $, il faudrait un d\u00e9gonflement bien plus violent que ce que sugg\u00e8rent les <strong>indicateurs de momentum<\/strong>.<\/p>\n<h2>Les Bollinger en mensuel comme garde-fou<\/h2>\n<p>L&rsquo;argument central de Sykodelic repose pourtant moins sur le RSI que sur les <a href=\"https:\/\/www.tradingview.com\/ideas\/bollingerbands\/\" target=\"_blank\" rel=\"noopener nofollow\">bandes de Bollinger<\/a> en unit\u00e9 mensuelle. Sur ce timeframe, rappelle-t-il, Bitcoin n&rsquo;a encore jamais cl\u00f4tur\u00e9 sous la <strong>bande basse<\/strong>. M\u00eame en 2018 ou en 2022, lors des phases jug\u00e9es les plus brutales, le prix est venu tester les zones basses, sans les enfoncer durablement.<\/p>\n<p>Il compare ce cycle \u00e0 celui de 2017 : l&rsquo;expansion avait \u00e9t\u00e9 beaucoup plus forte, pourtant le retracement n&rsquo;avait pas plong\u00e9 sous la <strong>bande inf\u00e9rieure en mensuel<\/strong>. La question devient alors presque rh\u00e9torique : si cette ann\u00e9e l&rsquo;expansion a \u00e9t\u00e9 l&rsquo;une des plus faibles d&rsquo;un point de vue purement technique, pourquoi le march\u00e9 offrirait-il la <strong>contraction la plus profonde<\/strong> de l&rsquo;histoire moderne de Bitcoin.<\/p>\n<p>Selon son sc\u00e9nario \u00ab\u00a0pire cas\u00a0\u00bb, si la bougie mensuelle venait \u00e0 cl\u00f4turer sous la <strong>ligne m\u00e9diane<\/strong> des bandes de Bollinger, la zone de bas de cycle se situerait autour de 55 000 $, pas en dessous. Il pr\u00e9sente ce niveau comme le <strong>maximum de douleur<\/strong> envisageable dans une hypoth\u00e8se de \u00ab\u00a0gros bear\u00a0\u00bb, et non comme la cible centrale de son sc\u00e9nario.<\/p>\n<p>Pour l&rsquo;instant, BTC tient encore cette m\u00e9diane en mensuel, ce qui donne un peu d&rsquo;air au camp des <strong>haussiers patients<\/strong>.<\/p>\n<h2>Un march\u00e9 plus profond, des corrections moins violentes<\/h2>\n<p>Son argument tient moins aux indicateurs qu&rsquo;\u00e0 la <strong>structure du march\u00e9<\/strong>. Selon lui, le fameux sch\u00e9ma du cycle en quatre ans se d\u00e9lite progressivement \u00e0 mesure que Bitcoin devient un <strong>actif institutionnel<\/strong>.<\/p>\n<p>Entre la profondeur accumul\u00e9e sur les carnets, le r\u00f4le des ETF et l&rsquo;\u00e9largissement de la base d&rsquo;investisseurs, il juge beaucoup moins probable un nouveau <strong>drawdown de 70 \u00e0 80 %<\/strong> comme dans les cycles pr\u00e9c\u00e9dents. Autrement dit, les <a href=\"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-casse-niveau-historique-correction-pourrait-amplifier\/\">corrections<\/a> restent douloureuses, mais plus \u00ab\u00a0ordinaires\u00a0\u00bb.<\/p>\n<p>Les mouvements sont violents en intraday, cependant les <strong>zones de soutien<\/strong> se construisent plus haut, et les capitulations sont davantage absorb\u00e9es par un march\u00e9 devenu plus large et plus fractur\u00e9.<\/p>\n<h2>Le vrai point de rupture \u00e0 surveiller<\/h2>\n<p>Tout cela ne veut pas dire que le risque a disparu. Le mouvement de liquidation pourrait prendre un caract\u00e8re beaucoup plus dangereux. Il y a la perspective de \u00ab\u00a0<strong>stops loss<\/strong>\u00a0\u00bb li\u00e9s aux ventes automatiques des DATs, aux positions de Strategy et \u00e0 l&rsquo;effet boule de neige sur l&rsquo;ensemble des bilans expos\u00e9s au BTC.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">It&#39;s wild that people think this is impossible. That bitcoin can&#39;t hit $35K to $40K before Dec 2026.<br \/>All bear markets have lasted roughly 365 days exactly from the top to the very bottom in 2014, 2018, and 2022.<br \/>All bear markets dropped 78% to 86%.<br \/>So how&#39;s this not possible? <a href=\"https:\/\/t.co\/3zDG11xNke\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/3zDG11xNke<\/a><\/p>\n<p>&mdash; Philakone (@PhilakoneCrypto) <a href=\"https:\/\/twitter.com\/PhilakoneCrypto\/status\/1990635483802538176?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">November 18, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Dans ce genre de sc\u00e9nario, les mod\u00e8les techniques perdent temporairement la main, tant la <strong>m\u00e9canique de vente forc\u00e9e<\/strong> domine tout. Pour l&rsquo;instant, Bitcoin se d\u00e9bat bien au-dessus de ces niveaux.<\/p>\n<p>L&rsquo;analyse de Sykodelic ne promet pas un avenir lin\u00e9aire. Elle ne garantit pas que 55 000 $ sera touch\u00e9, ni m\u00eame que le bas est d\u00e9j\u00e0 derri\u00e8re nous. Elle pose surtout une borne : pour qu&rsquo;un crash \u00e0 35 000 $ devienne cr\u00e9dible, il faudrait un <strong>niveau d&rsquo;exc\u00e8s<\/strong> que ce cycle n&rsquo;a jamais vraiment atteint.<\/p>\n<p>Tant que les bandes de Bollinger en mensuel restent intactes et que la <a href=\"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-stabilise-sentiment-grimpe-signaux-de-bottom-se-multiplient\/\">profondeur du march\u00e9<\/a> continue de se renforcer, le sc\u00e9nario du gouffre \u00e0 35 000 $ ressemble davantage \u00e0 un <strong>fantasme de chartiste<\/strong> en manque de catastrophe qu&rsquo;\u00e0 une trajectoire statistiquement coh\u00e9rente.<\/p>\n<hr \/>\n<p><strong>Sur le m\u00eame sujet :<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/99bitcoins.com\/fr\/actu\/analyse-bitcoin-125-000-franchis-correction-est-elle-deja-en-marche\/\">Analyse Bitcoin : 125 000 $ franchis, la correction est-elle d\u00e9j\u00e0 en marche ?<\/a><\/li>\n<li><a href=\"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-casse-niveau-historique-correction-pourrait-amplifier\/\">Bitcoin casse un niveau historique, la correction pourrait s&rsquo;amplifier<\/a><\/li>\n<li><a href=\"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-stabilise-sentiment-grimpe-signaux-de-bottom-se-multiplient\/\">Bitcoin se stabilise, le sentiment grimpe et les signaux de bottom se multiplient<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9dire le \u00ab\u00a0vrai\u00a0\u00bb bas de cycle de Bitcoin ressemble souvent plus \u00e0 un concours de sensations fortes qu&rsquo;\u00e0 une analyse. Entre ceux qui annoncent un retour \u00e0 35 000 $ et d&rsquo;autres qui parlent d\u00e9j\u00e0 de nouveau bullrun, un analyste a d\u00e9cid\u00e9 de poser des bornes claires en s&rsquo;appuyant uniquement sur les graphiques. Pour lui,..<\/p>\n","protected":false},"author":135978,"featured_media":28752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8,6],"tags":[13],"coin":[15],"class_list":["post-28749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","category-actu","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$<\/title>\n<meta name=\"description\" content=\"Les Bollinger Bands et le RSI sugg\u00e8rent que Bitcoin ne tombera pas sous 55 000 $. Un analyste rejette le sc\u00e9nario d\u2019un crash \u00e0 35 000 $.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$\" \/>\n<meta property=\"og:description\" content=\"Les Bollinger Bands et le RSI sugg\u00e8rent que Bitcoin ne tombera pas sous 55 000 $. Un analyste rejette le sc\u00e9nario d\u2019un crash \u00e0 35 000 $.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins FR\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-06T13:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/99BTC199.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Pelletier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Pelletier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/\"},\"author\":{\"name\":\"Martin Pelletier\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/d6acaa19de409b9e22e3f740da472d70\"},\"headline\":\"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$\",\"datePublished\":\"2025-12-06T13:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/\"},\"wordCount\":862,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/12\\\/99BTC199.jpg\",\"keywords\":[\"Bitcoin\"],\"articleSection\":[\"Bitcoin\",\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/\",\"name\":\"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/12\\\/99BTC199.jpg\",\"datePublished\":\"2025-12-06T13:00:50+00:00\",\"description\":\"Les Bollinger Bands et le RSI sugg\u00e8rent que Bitcoin ne tombera pas sous 55 000 $. Un analyste rejette le sc\u00e9nario d\u2019un crash \u00e0 35 000 $.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/12\\\/99BTC199.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/12\\\/99BTC199.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/bitcoin-bottom-55000-bollinger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"name\":\"99bitcoins FR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/d6acaa19de409b9e22e3f740da472d70\",\"name\":\"Martin Pelletier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g\",\"caption\":\"Martin Pelletier\"},\"description\":\"Journaliste et analyste sp\u00e9cialis\u00e9 dans les crypto-monnaies et la blockchain, Martin Pelletier explore les dynamiques du Web3 et des nouvelles technologies financi\u00e8res depuis 2019. Fort d\u2019une exp\u00e9rience dans la finance traditionnelle, il s\u2019est tourn\u00e9 vers le monde des actifs num\u00e9riques pour \u00e9clairer les lecteurs sur les d\u00e9fis et les opportunit\u00e9s de cet \u00e9cosyst\u00e8me en constante \u00e9volution. \u00c0 travers des articles d'analyse, des interviews d\u2019experts et des rapports d\u00e9taill\u00e9s, Martin propose des contenus p\u00e9dagogiques et accessibles pour d\u00e9mocratiser des sujets complexes comme la finance d\u00e9centralis\u00e9e (DeFi), les NFT, et les monnaies num\u00e9riques des banques centrales (CBDC).\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/martin-pelletier-a923ba343\\\/\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/author\\\/martinpelletier\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$","description":"Les Bollinger Bands et le RSI sugg\u00e8rent que Bitcoin ne tombera pas sous 55 000 $. Un analyste rejette le sc\u00e9nario d\u2019un crash \u00e0 35 000 $.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/","og_locale":"fr_FR","og_type":"article","og_title":"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$","og_description":"Les Bollinger Bands et le RSI sugg\u00e8rent que Bitcoin ne tombera pas sous 55 000 $. Un analyste rejette le sc\u00e9nario d\u2019un crash \u00e0 35 000 $.","og_url":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/","og_site_name":"99bitcoins FR","article_published_time":"2025-12-06T13:00:50+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/99BTC199.jpg","type":"image\/jpeg"}],"author":"Martin Pelletier","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Martin Pelletier","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/"},"author":{"name":"Martin Pelletier","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/d6acaa19de409b9e22e3f740da472d70"},"headline":"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$","datePublished":"2025-12-06T13:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/"},"wordCount":862,"publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/99BTC199.jpg","keywords":["Bitcoin"],"articleSection":["Bitcoin","Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais"],"inLanguage":"fr-FR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/","url":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/","name":"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/99BTC199.jpg","datePublished":"2025-12-06T13:00:50+00:00","description":"Les Bollinger Bands et le RSI sugg\u00e8rent que Bitcoin ne tombera pas sous 55 000 $. Un analyste rejette le sc\u00e9nario d\u2019un crash \u00e0 35 000 $.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/#primaryimage","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/99BTC199.jpg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/12\/99BTC199.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-bottom-55000-bollinger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais","item":"https:\/\/99bitcoins.com\/fr\/actu\/"},{"@type":"ListItem","position":3,"name":"BTC : un analyste d\u00e9monte le sc\u00e9nario d\u2019un crash \u00e0 35 000$"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/fr\/#website","url":"https:\/\/99bitcoins.com\/fr\/","name":"99bitcoins FR","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/fr\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/d6acaa19de409b9e22e3f740da472d70","name":"Martin Pelletier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g","caption":"Martin Pelletier"},"description":"Journaliste et analyste sp\u00e9cialis\u00e9 dans les crypto-monnaies et la blockchain, Martin Pelletier explore les dynamiques du Web3 et des nouvelles technologies financi\u00e8res depuis 2019. Fort d\u2019une exp\u00e9rience dans la finance traditionnelle, il s\u2019est tourn\u00e9 vers le monde des actifs num\u00e9riques pour \u00e9clairer les lecteurs sur les d\u00e9fis et les opportunit\u00e9s de cet \u00e9cosyst\u00e8me en constante \u00e9volution. \u00c0 travers des articles d'analyse, des interviews d\u2019experts et des rapports d\u00e9taill\u00e9s, Martin propose des contenus p\u00e9dagogiques et accessibles pour d\u00e9mocratiser des sujets complexes comme la finance d\u00e9centralis\u00e9e (DeFi), les NFT, et les monnaies num\u00e9riques des banques centrales (CBDC).","sameAs":["https:\/\/www.linkedin.com\/in\/martin-pelletier-a923ba343\/"],"url":"https:\/\/99bitcoins.com\/fr\/author\/martinpelletier\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/28749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/users\/135978"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/comments?post=28749"}],"version-history":[{"count":3,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/28749\/revisions"}],"predecessor-version":[{"id":28756,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/28749\/revisions\/28756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media\/28752"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media?parent=28749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/categories?post=28749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/tags?post=28749"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/coin?post=28749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}