{"id":26130,"date":"2025-11-09T16:37:18","date_gmt":"2025-11-09T16:37:18","guid":{"rendered":"https:\/\/99bitcoins.com\/fr\/?p=26130"},"modified":"2025-11-09T16:29:47","modified_gmt":"2025-11-09T16:29:47","slug":"usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/","title":{"rendered":"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Cette semaine, non pas un, mais deux stablecoins algorithmique ont perdu leur parit\u00e9 avec le dollar am\u00e9ricain. En effet, l\u2019USDX de Stable Labs s\u2019est effondr\u00e9 de 1 $ \u00e0 0,30 $, tandis que le deUSD Elixir Finance a plong\u00e9 sous la barre des 0,015 $. La perte de capitalisation cumul\u00e9e est estim\u00e9e \u00e0 3,2 milliards de dollars d\u00e9clenchant une cascade de liquidation sur les protocoles DeFi. Une question revient sur toutes les l\u00e8vres, avons-nous r\u00e9ellement tir\u00e9 des le\u00e7ons de l\u2019effondrement de Terra Luna en 2022 ?<\/span><\/p>\n<h2><strong>La vuln\u00e9rabilit\u00e9 des stablecoins algorithmiques<\/strong><\/h2>\n<p><span style=\"font-weight: 400\">Pour bien comprendre l&rsquo;impact d\u00e9vastateur de ces effondrements r\u00e9currents des stablecoins algorithmiques, il est avant tout essentiel de bien saisir la diff\u00e9rence entre <strong>les stablecoins garantis et les stablecoins algorithmiques<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les stablecoins traditionnels comme l&rsquo;USDT de Tether et l&rsquo;USDC de Circle ont une garantie de parit\u00e9 s&rsquo;appuyant notamment sur des r\u00e9serves en dollars. \u00c0 l&rsquo;inverse, l&rsquo;USDX et autres stablecoins algorithmiques s&rsquo;appuient<\/span><span style=\"font-weight: 400\"> sur des m\u00e9canismes plus risqu\u00e9s pour maintenir leur ancrage \u00e0 flot. Ryan Sean Adams, un analyste crypto le souligne en pr\u00e9cisant :<\/span><\/p>\n<blockquote><p>Les stablecoins algorithmiques ne sont pas r\u00e9ellement stables. Ce sont des instruments \u00e0 effet de levier d\u00e9guis\u00e9s en stablecoins. Lorsque l&rsquo;effet de levier se dissipe, les lois de la physique reprennent leurs droits.<\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">Pour rappel, l&rsquo;USDX avait mis en place un mod\u00e8le permettant aux utilisateurs de cr\u00e9er des USDX en d\u00e9posant des cryptomonnaies en guise de collat\u00e9ral. Cela cr\u00e9ait alors une certaine solvabilit\u00e9 th\u00e9orique de ce syst\u00e8me mais c&rsquo;\u00e9tait sans compter <strong>de la forte volatilit\u00e9 du march\u00e9<\/strong>. Au moindre mouvement brutal, c&rsquo;est la chute libre entra\u00eenant des cascades de liquidations sur le march\u00e9.<\/span><\/p>\n<h2><strong>Le hack de Balancer : l&rsquo;\u00e9l\u00e9ment d\u00e9clencheur ?<\/strong><\/h2>\n<p><span style=\"font-weight: 400\">Le hack de la plateforme DeFi qui a entra\u00een\u00e9 128 millions de dollars de pertes, a pu servir de d\u00e9clic. Effectivement, Balancer d\u00e9tenait d&rsquo;importantes sommes en USDX dans ses pools de liquidit\u00e9s. Ainsi, lorsque le pirate a commenc\u00e9 \u00e0 vendre les UDSX vol\u00e9s, des ventes forc\u00e9es se sont enclench\u00e9es se transformant en cascade de liquidation et inondant ainsi toutes les plateformes DeFi.<\/span><\/p>\n<p><span style=\"font-weight: 400\">L&rsquo;effet domino ne faisait que de commencer. Lista DAO, qui avait int\u00e9gr\u00e9 l&rsquo;USDX comme pilier central pour assurer la stabilit\u00e9 de son mod\u00e8le, a subi une pression imm\u00e9diate. Les pools d&rsquo;USDX sur PancakeSwap ont \u00e9galement <strong>connu un slippage jamais vu<\/strong>, empressant ceux qui avaient d\u00e9pos\u00e9 de la liquidit\u00e9 \u00e0 retirer leurs positions dans la panique. Il n&rsquo;a fallu que quelques heures seulement pour que la collat\u00e9ralisation de l&rsquo;USDX chute sous un seuil critique.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">3 relatively big so-called stablecoins lost their peg this week<\/p>\n<p>\u2022 xUSD<br \/>\u2022 deUSD<br \/>\u2022 USDX<\/p>\n<p>Rough week for DeFi. <\/p>\n<p>Not every token with USD in its name is actually stable. Stay safe out there.<\/p>\n<p>&mdash; The DeFi Investor \ud83d\udd0e (@TheDeFinvestor) <a href=\"https:\/\/twitter.com\/TheDeFinvestor\/status\/1987522967647953013?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">November 9, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Ainsi le stablecoin a depeg \u00e0 0,30 $ sur toutes les plateformes d&rsquo;\u00e9change soit une perte de 70 %. Ses d\u00e9tenteurs ont ainsi vu leur crypto soit disant stable s&rsquo;\u00e9vaporer. Suite \u00e0 cette catastrophe, PeckShield a r\u00e9v\u00e9l\u00e9 que plus de 1,2 milliard de dollars de liquidations ont \u00e9t\u00e9 d\u00e9clench\u00e9es sur les protocoles de pr\u00eat. Cette contagion \u00e0 \u00e9galement toucher le deUSD, un autre stablecoin algorithmique qui a suivi le m\u00eame sch\u00e9ma de mani\u00e8re plus dramatique. En effet, il a perdu son peg de 98,5 % en moins de 48 heures atteignant une valeur de 0,015 centimes de dollars.<\/span><\/p>\n<h2>Un air de d\u00e9j\u00e0-vu dans la DeFi<\/h2>\n<p><span style=\"font-weight: 400\">Le parall\u00e8le avec l&rsquo;effondrement de Terra Luna en 2022 laisse un go\u00fbt amer. <a href=\"https:\/\/coinmarketcap.com\/currencies\/terra-luna-v2\/\" rel=\"nofollow\" target=\"_blank\">Luna<\/a> s&rsquo;\u00e9tait effectivement effondr\u00e9 en tentant de garder le peg au dollar sur le stablecoin algorithmique de l&rsquo;UST. Ainsi 40 milliards de dollars avaient disparu en quelques semaines. Quatre ans plus tard, <strong>les protocoles continuent de construire des stablecoins synth\u00e9tiques<\/strong>, tout en connaissant pourtant les risques associ\u00e9s. Ulrich M\u00fcller, ancien conseiller de la SEC et de la CFTC d\u00e9clare :<\/span><\/p>\n<blockquote><p>Nous assistons \u00e0 la r\u00e9p\u00e9tition de ces cycles car chaque g\u00e9n\u00e9ration de d\u00e9veloppeurs croit avoir r\u00e9solu le probl\u00e8me que ses pr\u00e9d\u00e9cesseurs n&rsquo;avaient pas su r\u00e9soudre. Or, ce n&rsquo;est pas le cas. Ils n&rsquo;ont fait que reformuler le d\u00e9faut fondamental : il est impossible de cr\u00e9er de la stabilit\u00e9 par algorithme sans actifs productifs sous-jacents.<\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-26136\" src=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/UST-Luna-CoinMarketCap.jpeg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/UST-Luna-CoinMarketCap.jpeg 1200w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/UST-Luna-CoinMarketCap-300x200.jpeg 300w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/UST-Luna-CoinMarketCap-1024x683.jpeg 1024w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/UST-Luna-CoinMarketCap-768x512.jpeg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><span style=\"font-weight: 400\">Les effondrements de l&rsquo;USDX et du deUSD ont mis une nouvelle fois en lumi\u00e8re que les stablecoins algorithmiques ne sont pas sans risque. L&rsquo;Autorit\u00e9 bancaire europ\u00e9enne (ABE) a imm\u00e9diatement class\u00e9 <strong>tous les stablecoins non garantis comme des actifs \u00e0 haut risque<\/strong> tandis que le pr\u00e9sident de la SEC, Gary Gensler, a cit\u00e9 explicitement l&rsquo;USDX dans une d\u00e9claration :<\/span><\/p>\n<blockquote><p>Le secteur n&rsquo;a pas suffisamment pris en compte les risques syst\u00e9miques li\u00e9s aux m\u00e9canismes de stabilit\u00e9 algorithmiques.<\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">La plupart des acteurs institutionnels sont parvenus \u00e0 une conclusion radicale : les stablecoins synth\u00e9tiques pr\u00e9sentent un risque inacceptable. Pour les particuliers, la le\u00e7on est une nouvelle fois douloureuse. Lorsqu&rsquo;un stablecoin algorithmique se dit stable sans expliquer les raisons, le doute est de mise.<\/span><\/p>\n<hr>\n<p><strong>Sur le m\u00eame sujet :<\/strong><\/p>\n<ul>\n<li>\n<div class=\"lSfe4c r5bEn aI5QMe\">\n<div class=\"SoAPf\">\n<div class=\"n0jPhd ynAwRc MBeuO nDgy9d\" role=\"heading\">Le hack \u00e0 116M$ de Balancer aurait \u00e9t\u00e9 pr\u00e9par\u00e9 pendant des mois<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"lSfe4c r5bEn aI5QMe\">\n<div class=\"SoAPf\">\n<div class=\"n0jPhd ynAwRc MBeuO nDgy9d\" role=\"heading\"><a href=\"https:\/\/99bitcoins.com\/fr\/actu\/zachxbt-decouvre-une-fausse-app-hyperliquid-281-000-sont-derobes\/\">ZachXBT d\u00e9couvre une fausse app Hyperliquid : 281 000 $ sont d\u00e9rob\u00e9s<\/a><\/div>\n<\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"lSfe4c r5bEn aI5QMe\">\n<div class=\"SoAPf\">\n<div class=\"n0jPhd ynAwRc MBeuO nDgy9d\" role=\"heading\">\n<div class=\"lSfe4c r5bEn aI5QMe\">\n<div class=\"SoAPf\">\n<div class=\"n0jPhd ynAwRc MBeuO nDgy9d\" role=\"heading\">Le Pakistan veut lancer un stablecoin en roupies<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cette semaine, non pas un, mais deux stablecoins algorithmique ont perdu leur parit\u00e9 avec le dollar am\u00e9ricain. En effet, l\u2019USDX de Stable Labs s\u2019est effondr\u00e9 de 1 $ \u00e0 0,30 $, tandis que le deUSD Elixir Finance a plong\u00e9 sous la barre des 0,015 $. La perte de capitalisation cumul\u00e9e est estim\u00e9e \u00e0 3,2 milliards..<\/p>\n","protected":false},"author":136117,"featured_media":26142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[10,6],"tags":[178],"coin":[15],"class_list":["post-26130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","category-actu","tag-stablecoins"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?<\/title>\n<meta name=\"description\" content=\"Deux stablecoins algorithmique ont perdu leur parit\u00e9. L\u2019USDX s\u2019est effondr\u00e9 \u00e0 0,30 $, tandis que le deUSD a plong\u00e9 sous la barre des 0,015 $.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?\" \/>\n<meta property=\"og:description\" content=\"Deux stablecoins algorithmique ont perdu leur parit\u00e9. L\u2019USDX s\u2019est effondr\u00e9 \u00e0 0,30 $, tandis que le deUSD a plong\u00e9 sous la barre des 0,015 $.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins FR\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-09T16:37:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1162\" \/>\n\t<meta property=\"og:image:height\" content=\"769\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Esteban Durant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Esteban Durant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/\"},\"author\":{\"name\":\"Esteban Durant\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/b32c31c709197c43c282001738666e5e\"},\"headline\":\"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?\",\"datePublished\":\"2025-11-09T16:37:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/\"},\"wordCount\":887,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png\",\"keywords\":[\"Stablecoins\"],\"articleSection\":[\"Altcoins\",\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/\",\"name\":\"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png\",\"datePublished\":\"2025-11-09T16:37:18+00:00\",\"description\":\"Deux stablecoins algorithmique ont perdu leur parit\u00e9. L\u2019USDX s\u2019est effondr\u00e9 \u00e0 0,30 $, tandis que le deUSD a plong\u00e9 sous la barre des 0,015 $.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png\",\"width\":1162,\"height\":769},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"name\":\"99bitcoins FR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/b32c31c709197c43c282001738666e5e\",\"name\":\"Esteban Durant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g\",\"caption\":\"Esteban Durant\"},\"description\":\"Trader en crypto-actifs depuis plusieurs ann\u00e9es et passionn\u00e9 par l\u2019univers d\u00e9centralis\u00e9, je combine analyse technique, compr\u00e9hension des fondamentaux et suivi macro\u00e9conomique pour naviguer efficacement sur les march\u00e9s volatils. J\u2019ai d\u00e9couvert le Bitcoin en 2016, mais c\u2019est en 2018, en pleine phase baissi\u00e8re, que j\u2019ai r\u00e9ellement plong\u00e9 dans l\u2019analyse des cycles, des projets et des opportunit\u00e9s que propose l\u2019\u00e9cosyst\u00e8me crypto. Aujourd\u2019hui, je consacre mon temps \u00e0 l\u2019\u00e9tude des tendances du march\u00e9, \u00e0 la recherche de projets innovants, et au partage de strat\u00e9gies accessibles aussi bien aux d\u00e9butants qu\u2019aux investisseurs aguerris. En parall\u00e8le, je suis \u00e9galement r\u00e9dacteur sp\u00e9cialis\u00e9 en crypto et finance d\u00e9centralis\u00e9e. Mon objectif : rendre l\u2019information claire, p\u00e9dagogique et fiable, dans un univers o\u00f9 la d\u00e9sinformation peut co\u00fbter cher. J\u2019interviens sur ce site pour proposer des analyses, d\u00e9crypter l\u2019actualit\u00e9, vulgariser des concepts complexes, et offrir des perspectives concr\u00e8tes sur les mouvements du march\u00e9. Que ce soit pour du swing trading, du scalping ou de l\u2019investissement long terme, je m\u2019efforce d\u2019apporter une vision structur\u00e9e et pragmatique. La crypto est plus qu\u2019un march\u00e9 : c\u2019est une r\u00e9volution en marche. Et je suis l\u00e0 pour vous aider \u00e0 y voir clair.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/author\\\/estebandurant\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?","description":"Deux stablecoins algorithmique ont perdu leur parit\u00e9. L\u2019USDX s\u2019est effondr\u00e9 \u00e0 0,30 $, tandis que le deUSD a plong\u00e9 sous la barre des 0,015 $.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/","og_locale":"fr_FR","og_type":"article","og_title":"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?","og_description":"Deux stablecoins algorithmique ont perdu leur parit\u00e9. L\u2019USDX s\u2019est effondr\u00e9 \u00e0 0,30 $, tandis que le deUSD a plong\u00e9 sous la barre des 0,015 $.","og_url":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/","og_site_name":"99bitcoins FR","article_published_time":"2025-11-09T16:37:18+00:00","og_image":[{"width":1162,"height":769,"url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png","type":"image\/png"}],"author":"Esteban Durant","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Esteban Durant","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/"},"author":{"name":"Esteban Durant","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/b32c31c709197c43c282001738666e5e"},"headline":"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?","datePublished":"2025-11-09T16:37:18+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/"},"wordCount":887,"publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png","keywords":["Stablecoins"],"articleSection":["Altcoins","Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais"],"inLanguage":"fr-FR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/","url":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/","name":"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png","datePublished":"2025-11-09T16:37:18+00:00","description":"Deux stablecoins algorithmique ont perdu leur parit\u00e9. L\u2019USDX s\u2019est effondr\u00e9 \u00e0 0,30 $, tandis que le deUSD a plong\u00e9 sous la barre des 0,015 $.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/#primaryimage","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-9-2025-depuis-iLoveIMG.png","width":1162,"height":769},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/fr\/actu\/usdx-et-deusd-seffondrent-les-stablecoins-algorithmiques-sont-ils-condamnes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais","item":"https:\/\/99bitcoins.com\/fr\/actu\/"},{"@type":"ListItem","position":3,"name":"USDX et deUSD s\u2019effondrent : les stablecoins algorithmiques sont-ils condamn\u00e9s ?"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/fr\/#website","url":"https:\/\/99bitcoins.com\/fr\/","name":"99bitcoins FR","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/fr\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/b32c31c709197c43c282001738666e5e","name":"Esteban Durant","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g","caption":"Esteban Durant"},"description":"Trader en crypto-actifs depuis plusieurs ann\u00e9es et passionn\u00e9 par l\u2019univers d\u00e9centralis\u00e9, je combine analyse technique, compr\u00e9hension des fondamentaux et suivi macro\u00e9conomique pour naviguer efficacement sur les march\u00e9s volatils. J\u2019ai d\u00e9couvert le Bitcoin en 2016, mais c\u2019est en 2018, en pleine phase baissi\u00e8re, que j\u2019ai r\u00e9ellement plong\u00e9 dans l\u2019analyse des cycles, des projets et des opportunit\u00e9s que propose l\u2019\u00e9cosyst\u00e8me crypto. Aujourd\u2019hui, je consacre mon temps \u00e0 l\u2019\u00e9tude des tendances du march\u00e9, \u00e0 la recherche de projets innovants, et au partage de strat\u00e9gies accessibles aussi bien aux d\u00e9butants qu\u2019aux investisseurs aguerris. En parall\u00e8le, je suis \u00e9galement r\u00e9dacteur sp\u00e9cialis\u00e9 en crypto et finance d\u00e9centralis\u00e9e. Mon objectif : rendre l\u2019information claire, p\u00e9dagogique et fiable, dans un univers o\u00f9 la d\u00e9sinformation peut co\u00fbter cher. J\u2019interviens sur ce site pour proposer des analyses, d\u00e9crypter l\u2019actualit\u00e9, vulgariser des concepts complexes, et offrir des perspectives concr\u00e8tes sur les mouvements du march\u00e9. Que ce soit pour du swing trading, du scalping ou de l\u2019investissement long terme, je m\u2019efforce d\u2019apporter une vision structur\u00e9e et pragmatique. La crypto est plus qu\u2019un march\u00e9 : c\u2019est une r\u00e9volution en marche. Et je suis l\u00e0 pour vous aider \u00e0 y voir clair.","url":"https:\/\/99bitcoins.com\/fr\/author\/estebandurant\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/26130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/users\/136117"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/comments?post=26130"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/26130\/revisions"}],"predecessor-version":[{"id":26139,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/26130\/revisions\/26139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media\/26142"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media?parent=26130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/categories?post=26130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/tags?post=26130"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/coin?post=26130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}