{"id":26053,"date":"2025-11-08T18:00:06","date_gmt":"2025-11-08T18:00:06","guid":{"rendered":"https:\/\/99bitcoins.com\/fr\/?p=26053"},"modified":"2025-11-08T13:29:11","modified_gmt":"2025-11-08T13:29:11","slug":"ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/","title":{"rendered":"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant pour Ethereum ?"},"content":{"rendered":"<p><span style=\"font-weight: 400\">ARK Invest, la soci\u00e9t\u00e9 d&rsquo;investissement dirig\u00e9e par la c\u00e9l\u00e8bre Cathie Wood, a op\u00e9r\u00e9 un changement de cap en investissant massivement dans BitMine. Cette semaine, ARK a ainsi vendu ses 72 000 actions Tesla pour une valeur estim\u00e9e \u00e0 30 millions de dollars. Cette mesure renforce sa position dans BitMine, une soci\u00e9t\u00e9 de tr\u00e9sorerie ax\u00e9e sur Ethereum, dirig\u00e9e par Tom Lee. Ainsi, cette op\u00e9ration repr\u00e9sente un recalibrage de taille pour la soci\u00e9t\u00e9 qui a longtemps consid\u00e9r\u00e9 Tesla comme son actif principal.<\/span><\/p>\n<h2><strong>Un r\u00e9\u00e9quilibrage pour ARK Invest<\/strong><\/h2>\n<p><span style=\"font-weight: 400\">La vente des actions Tesla par ARK Invest s&rsquo;inscrit dans une strat\u00e9gie bien \u00e9tablie vers Ethereum. Selon les informations publi\u00e9es par ARK, cette d\u00e9cision ne r\u00e9sulte en rien la confiance envers les v\u00e9hicules \u00e9lectriques d&rsquo;Elon Musk.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Malgr\u00e9 cette vente, Tesla demeure encore la principale participation d&rsquo;ARK si l&rsquo;on en croit son portefeuille, repr\u00e9sentant <strong>une valeur de plus de 180 millions de dollars<\/strong>. Wood a d&rsquo;ailleurs d\u00e9clar\u00e9 que si elle ne pouvait investir que dans une seule action, ce serait Tesla. Tout en ajoutant : <\/span><\/p>\n<blockquote><p>Notre objectif de cours pour 2030 est de 2 600 $. Il n&rsquo;a pas chang\u00e9 depuis un certain temps. 90 % de cette valorisation est li\u00e9e aux robotaxis.<\/p><\/blockquote>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Cathie Wood today reiterated her $2,600 price target for Tesla <a href=\"https:\/\/twitter.com\/search?q=%24TSLA&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$TSLA<\/a> by 2030<\/p>\n<p> <a href=\"https:\/\/t.co\/bBPOM7zK29\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/bBPOM7zK29<\/a><\/p>\n<p>&mdash; Ark Invest Tracker (@ArkkDaily) <a href=\"https:\/\/twitter.com\/ArkkDaily\/status\/1986447298700681351?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">November 6, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">On comprend mieux cette vente lorsque l&rsquo;on regarde de plus pr\u00e8s les r\u00e8gles de gestion de portefeuille d&rsquo;ARK Invest. En effet, la soci\u00e9t\u00e9 limite chaque position \u00e0 10% des actifs totaux. La r\u00e9cente mont\u00e9e en fl\u00e8che de Tesla a fait monter de 15,4 % la position de la soci\u00e9t\u00e9, soit la plus \u00e9lev\u00e9e en 10 ans d&rsquo;existence. La vente r\u00e9sulte tout simplement d&rsquo;une prise de profit et d&rsquo;une lib\u00e9ration de capitaux pour <strong>investir dans un secteur \u00e9mergent<\/strong> tel que les cryptomonnaies et plus pr\u00e9cis\u00e9ment <a href=\"https:\/\/coinmarketcap.com\/currencies\/ethereum\/\" rel=\"nofollow\" target=\"_blank\">Ethereum<\/a>.<\/span><\/p>\n<h2><strong>Un investissement massif dans Ethereum<\/strong><\/h2>\n<p><span style=\"font-weight: 400\">En r\u00e9duisant sa participation dans Tesla, le fonds a investi massivement dans les actions de BitMine Immersion Technologies. ARK Invest a achet\u00e9 ainsi 240 507 actions BMNR pour la coquette somme de 9,2 millions de dollars par le biais de ses ETF. Le total des actions de BitMine dans lequel a investi l&rsquo;entreprise s&rsquo;\u00e9l\u00e8ve \u00e0<strong>\u00a07 millions d&rsquo;actions pour une valeur de 260 millions de dollars<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La confiance d&rsquo;ARK envers BitMine intervient malgr\u00e9 la forte volatilit\u00e9 du titre. L&rsquo;action BMNR a cl\u00f4tur\u00e9 \u00e0 37,37 dollars jeudi, en baisse de 9,8 % sur la journ\u00e9e, de 20 % sur la semaine et de 42,5 % sur le mois \u00e9coul\u00e9. N\u00e9anmoins, le cours de l&rsquo;action reste en hausse de 769 % depuis juin, date \u00e0 laquelle la soci\u00e9t\u00e9 a lanc\u00e9 sa strat\u00e9gie de tr\u00e9sorerie en ether, et a progress\u00e9 d&rsquo;environ 415 % depuis le d\u00e9but de l&rsquo;ann\u00e9e.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-26065\" src=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/BitMine-99bitcoins.jpeg\" alt=\"\" width=\"1200\" height=\"900\" srcset=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/BitMine-99bitcoins.jpeg 1200w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/BitMine-99bitcoins-300x225.jpeg 300w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/BitMine-99bitcoins-1024x768.jpeg 1024w, https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/BitMine-99bitcoins-768x576.jpeg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><span style=\"font-weight: 400\">La strat\u00e9gie d&rsquo;investissement d&rsquo;ARK dans BitMine repose sur la lubie de Tom Lee visant \u00e0 accumuler 5 % de l&rsquo;offre totale d&rsquo;ether en circulation. A l&rsquo;heure o\u00f9 ces lignes sont \u00e9crites, BitMine d\u00e9tient 3,4 millions d&rsquo;ETH, d&rsquo;une valeur de 11,3 milliards de dollars, soit 2,8 % de l&rsquo;offre en circulation. Lee d\u00e9clare :\u00a0<\/span><\/p>\n<blockquote><p>Nous avons d\u00e9sormais d\u00e9pass\u00e9 la moiti\u00e9 de notre objectif.<\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">Lui, qui a rejoint BitMine en tant que pr\u00e9sident en juin dernier, \u00e0 positionner l&rsquo;entreprise comme le point de bascule entre Wall Street et Ethereum. Il explique clairement que :\u00a0<\/span><\/p>\n<blockquote><p>Ethereum est la blockchain sur laquelle s&rsquo;effectuent la plupart des transactions de stablecoins ; par cons\u00e9quent, l&rsquo;ETH devrait b\u00e9n\u00e9ficier de cette expansion.<\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">BitMine est aujourd&rsquo;hui <strong>la plus grande soci\u00e9t\u00e9 de tr\u00e9sorerie Ethereum<\/strong> et la deuxi\u00e8me plus grande soci\u00e9t\u00e9 de tr\u00e9sorerie de cryptomonnaies, juste derri\u00e8re les quelque 65 milliards de dollars de BTC d\u00e9tenus par Strategy, la soci\u00e9t\u00e9 de Michael Saylor.<\/span><\/p>\n<h2><strong>L&rsquo;expansion de Ark Invest vers les cryptomonnaies<\/strong><\/h2>\n<p><span style=\"font-weight: 400\">L&rsquo;investissement dans BitMine n&rsquo;est que la partie visible de l&rsquo;iceberg de ARK Invest vers les cryptomonnaies. \u00c0 travers ses trois fonds phares l&rsquo;exposition d&rsquo;ARK aux entreprises li\u00e9es \u00e0 la blockchain <strong>d\u00e9passe d\u00e9sormais 2,15 milliards de dollars<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le changement de strat\u00e9gie de Wood intervient alors qu&rsquo;elle a revu \u00e0 la baisse ses pr\u00e9visions \u00e0 long terme concernant le Bitcoin, en raison de la mont\u00e9e en puissance rapide des stablecoins. Elle a expliqu\u00e9 que :<\/span><\/p>\n<blockquote><p>Les stablecoins s&rsquo;approprient une partie du r\u00f4le que nous pensions que le Bitcoin jouerait. Compte tenu de l&rsquo;\u00e9volution des stablecoins, nous pourrions r\u00e9duire d&rsquo;environ 300 000 $ nos pr\u00e9visions optimistes.<\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">Cathie Wood rejoint alors le cercle de personnes pensant que les stablecoins servent de plus en plus de monnaie num\u00e9rique pour les paiements dans le monde entier. Elle s&rsquo;est quand m\u00eame montr\u00e9 rassurant en indiquant que<strong> le potentiel \u00e0 long terme des crypto<\/strong> restait intact.<\/span><\/p>\n<blockquote><p>Le Bitcoin continue de renforcer son r\u00f4le de r\u00e9serve de valeur mondiale, mais dans le domaine des paiements, les stablecoins deviennent une solution plus pratique.<\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">Seul le temps nous dira si la r\u00e9duction des positions sur Tesla et l&rsquo;accumulation de BitMine par ARK Invest repr\u00e9sentent un pari potentiellement gagnant. Quoi qu&rsquo;il en soit, Ethereum deviendra un \u00e9l\u00e9ment essentiel des portefeuilles institutionnels \u00e0 mesure que la technologie blockchain gagnera en maturit\u00e9.<\/span><\/p>\n<hr>\n<p><strong>Sur le m\u00eame sujet :<\/strong><\/p>\n<ul>\n<li>Cathie Wood mise sur BTC et ETH mais garde un \u0153il sur Hyperliquid<\/li>\n<li><a href=\"https:\/\/99bitcoins.com\/fr\/actu\/tom-lee-ethereum-pourrait-depasser-la-capitalisation-de-bitcoin\/\">Tom Lee : \u00ab Ethereum pourrait d\u00e9passer la capitalisation de Bitcoin \u00bb<\/a><\/li>\n<li>Ethereum en correction, BitMine l\u00e8ve 365 M$ pour acheter<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>ARK Invest, la soci\u00e9t\u00e9 d&rsquo;investissement dirig\u00e9e par la c\u00e9l\u00e8bre Cathie Wood, a op\u00e9r\u00e9 un changement de cap en investissant massivement dans BitMine. Cette semaine, ARK a ainsi vendu ses 72 000 actions Tesla pour une valeur estim\u00e9e \u00e0 30 millions de dollars. Cette mesure renforce sa position dans BitMine, une soci\u00e9t\u00e9 de tr\u00e9sorerie ax\u00e9e sur..<\/p>\n","protected":false},"author":136117,"featured_media":26070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[10,6],"tags":[],"coin":[15],"class_list":["post-26053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","category-actu"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant ?<\/title>\n<meta name=\"description\" content=\"ARK Invest, la soci\u00e9t\u00e9 d&#039;investissement dirig\u00e9e par la c\u00e9l\u00e8bre Cathie Wood, a op\u00e9r\u00e9 un changement de cap en investissant dans BitMine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant ?\" \/>\n<meta property=\"og:description\" content=\"ARK Invest, la soci\u00e9t\u00e9 d&#039;investissement dirig\u00e9e par la c\u00e9l\u00e8bre Cathie Wood, a op\u00e9r\u00e9 un changement de cap en investissant dans BitMine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins FR\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-08T18:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-8-2025-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Esteban Durant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Esteban Durant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/\"},\"author\":{\"name\":\"Esteban Durant\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/b32c31c709197c43c282001738666e5e\"},\"headline\":\"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant pour Ethereum ?\",\"datePublished\":\"2025-11-08T18:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/\"},\"wordCount\":927,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/Capture-decran-Nov-8-2025-1.png\",\"articleSection\":[\"Altcoins\",\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/\",\"name\":\"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/Capture-decran-Nov-8-2025-1.png\",\"datePublished\":\"2025-11-08T18:00:06+00:00\",\"description\":\"ARK Invest, la soci\u00e9t\u00e9 d'investissement dirig\u00e9e par la c\u00e9l\u00e8bre Cathie Wood, a op\u00e9r\u00e9 un changement de cap en investissant dans BitMine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/Capture-decran-Nov-8-2025-1.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/Capture-decran-Nov-8-2025-1.png\",\"width\":1170,\"height\":772},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant pour Ethereum ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"name\":\"99bitcoins FR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/b32c31c709197c43c282001738666e5e\",\"name\":\"Esteban Durant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g\",\"caption\":\"Esteban Durant\"},\"description\":\"Trader en crypto-actifs depuis plusieurs ann\u00e9es et passionn\u00e9 par l\u2019univers d\u00e9centralis\u00e9, je combine analyse technique, compr\u00e9hension des fondamentaux et suivi macro\u00e9conomique pour naviguer efficacement sur les march\u00e9s volatils. J\u2019ai d\u00e9couvert le Bitcoin en 2016, mais c\u2019est en 2018, en pleine phase baissi\u00e8re, que j\u2019ai r\u00e9ellement plong\u00e9 dans l\u2019analyse des cycles, des projets et des opportunit\u00e9s que propose l\u2019\u00e9cosyst\u00e8me crypto. Aujourd\u2019hui, je consacre mon temps \u00e0 l\u2019\u00e9tude des tendances du march\u00e9, \u00e0 la recherche de projets innovants, et au partage de strat\u00e9gies accessibles aussi bien aux d\u00e9butants qu\u2019aux investisseurs aguerris. En parall\u00e8le, je suis \u00e9galement r\u00e9dacteur sp\u00e9cialis\u00e9 en crypto et finance d\u00e9centralis\u00e9e. Mon objectif : rendre l\u2019information claire, p\u00e9dagogique et fiable, dans un univers o\u00f9 la d\u00e9sinformation peut co\u00fbter cher. J\u2019interviens sur ce site pour proposer des analyses, d\u00e9crypter l\u2019actualit\u00e9, vulgariser des concepts complexes, et offrir des perspectives concr\u00e8tes sur les mouvements du march\u00e9. Que ce soit pour du swing trading, du scalping ou de l\u2019investissement long terme, je m\u2019efforce d\u2019apporter une vision structur\u00e9e et pragmatique. La crypto est plus qu\u2019un march\u00e9 : c\u2019est une r\u00e9volution en marche. Et je suis l\u00e0 pour vous aider \u00e0 y voir clair.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/author\\\/estebandurant\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant ?","description":"ARK Invest, la soci\u00e9t\u00e9 d'investissement dirig\u00e9e par la c\u00e9l\u00e8bre Cathie Wood, a op\u00e9r\u00e9 un changement de cap en investissant dans BitMine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/","og_locale":"fr_FR","og_type":"article","og_title":"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant ?","og_description":"ARK Invest, la soci\u00e9t\u00e9 d'investissement dirig\u00e9e par la c\u00e9l\u00e8bre Cathie Wood, a op\u00e9r\u00e9 un changement de cap en investissant dans BitMine.","og_url":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/","og_site_name":"99bitcoins FR","article_published_time":"2025-11-08T18:00:06+00:00","og_image":[{"width":1170,"height":772,"url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-8-2025-1.png","type":"image\/png"}],"author":"Esteban Durant","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Esteban Durant","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/"},"author":{"name":"Esteban Durant","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/b32c31c709197c43c282001738666e5e"},"headline":"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant pour Ethereum ?","datePublished":"2025-11-08T18:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/"},"wordCount":927,"publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-8-2025-1.png","articleSection":["Altcoins","Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais"],"inLanguage":"fr-FR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/","url":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/","name":"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant ?","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-8-2025-1.png","datePublished":"2025-11-08T18:00:06+00:00","description":"ARK Invest, la soci\u00e9t\u00e9 d'investissement dirig\u00e9e par la c\u00e9l\u00e8bre Cathie Wood, a op\u00e9r\u00e9 un changement de cap en investissant dans BitMine.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/#primaryimage","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-8-2025-1.png","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/11\/Capture-decran-Nov-8-2025-1.png","width":1170,"height":772},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/fr\/actu\/ark-invest-passe-de-tesla-a-bitmine-un-pari-gagnant-pour-ethereum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais","item":"https:\/\/99bitcoins.com\/fr\/actu\/"},{"@type":"ListItem","position":3,"name":"ARK Invest passe de Tesla \u00e0 BitMine : un pari gagnant pour Ethereum ?"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/fr\/#website","url":"https:\/\/99bitcoins.com\/fr\/","name":"99bitcoins FR","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/fr\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/b32c31c709197c43c282001738666e5e","name":"Esteban Durant","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g","caption":"Esteban Durant"},"description":"Trader en crypto-actifs depuis plusieurs ann\u00e9es et passionn\u00e9 par l\u2019univers d\u00e9centralis\u00e9, je combine analyse technique, compr\u00e9hension des fondamentaux et suivi macro\u00e9conomique pour naviguer efficacement sur les march\u00e9s volatils. J\u2019ai d\u00e9couvert le Bitcoin en 2016, mais c\u2019est en 2018, en pleine phase baissi\u00e8re, que j\u2019ai r\u00e9ellement plong\u00e9 dans l\u2019analyse des cycles, des projets et des opportunit\u00e9s que propose l\u2019\u00e9cosyst\u00e8me crypto. Aujourd\u2019hui, je consacre mon temps \u00e0 l\u2019\u00e9tude des tendances du march\u00e9, \u00e0 la recherche de projets innovants, et au partage de strat\u00e9gies accessibles aussi bien aux d\u00e9butants qu\u2019aux investisseurs aguerris. En parall\u00e8le, je suis \u00e9galement r\u00e9dacteur sp\u00e9cialis\u00e9 en crypto et finance d\u00e9centralis\u00e9e. Mon objectif : rendre l\u2019information claire, p\u00e9dagogique et fiable, dans un univers o\u00f9 la d\u00e9sinformation peut co\u00fbter cher. J\u2019interviens sur ce site pour proposer des analyses, d\u00e9crypter l\u2019actualit\u00e9, vulgariser des concepts complexes, et offrir des perspectives concr\u00e8tes sur les mouvements du march\u00e9. Que ce soit pour du swing trading, du scalping ou de l\u2019investissement long terme, je m\u2019efforce d\u2019apporter une vision structur\u00e9e et pragmatique. La crypto est plus qu\u2019un march\u00e9 : c\u2019est une r\u00e9volution en marche. Et je suis l\u00e0 pour vous aider \u00e0 y voir clair.","url":"https:\/\/99bitcoins.com\/fr\/author\/estebandurant\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/26053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/users\/136117"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/comments?post=26053"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/26053\/revisions"}],"predecessor-version":[{"id":31610,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/26053\/revisions\/31610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media\/26070"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media?parent=26053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/categories?post=26053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/tags?post=26053"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/coin?post=26053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}