{"id":24448,"date":"2025-10-27T12:00:41","date_gmt":"2025-10-27T12:00:41","guid":{"rendered":"https:\/\/99bitcoins.com\/fr\/?p=24448"},"modified":"2025-10-27T12:45:54","modified_gmt":"2025-10-27T12:45:54","slug":"mt-gox-hack-ia-claude-detecte-failles-code-source","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/","title":{"rendered":"Mt Gox : 10 ans apr\u00e8s le hack, l&rsquo;IA Claude d\u00e9tecte les failles du code source"},"content":{"rendered":"<p>L\u2019effondrement de Mt. Gox reste l\u2019un des chapitres les plus marquants de l\u2019histoire des cryptomonnaies. En 2011, la plateforme qui traitait plus de 70 % des transactions en Bitcoin cesse brutalement ses retraits et se d\u00e9clare en faillite. <strong>Victime d&rsquo;un hack qui laisse encore des zones d&rsquo;ombres<\/strong>, la plateforme disparait et une partie des BTC pr\u00e9sents dessus aussi.<\/p>\n<p>Aujourd\u2019hui, <strong>l\u2019ex directeur g\u00e9n\u00e9ral, Marc Karpel\u00e8s affirme avoir soumis l\u2019ancien code source de Mt. Gox \u00e0 l&rsquo;IA Claude<\/strong>. Elle a \u00e9t\u00e9 en mesure, plus de 10 ans apr\u00e8s, d&rsquo;y diagnostiquer des vuln\u00e9rabilit\u00e9s critiques. L\u2019intelligence artificielle, si elle avait \u00e9t\u00e9 appliqu\u00e9e \u00e0 l\u2019\u00e9poque, aurait-elle pu pr\u00e9venir cette catastrophe ?<\/p>\n<h2>Les failles de Mt. Gox : un d\u00e9sastre pr\u00e9visible ?<\/h2>\n<p>Depuis sa cr\u00e9ation, Mt. Gox a souffert de <strong>dysfonctionnements techniques, de mauvaise gouvernance et d\u2019une s\u00e9curit\u00e9 d\u00e9faillante<\/strong>. La plateforme avait \u00e9t\u00e9 rachet\u00e9e en 2011 par Mark Karpel\u00e8s, et quelques mois plus tard, elle subissait des pertes massives.<\/p>\n<p>Des vuln\u00e9rabilit\u00e9s li\u00e9es aux identifiants compromis et \u00e0 des transactions frauduleuses ont permis \u00e0 des attaquants d\u2019acc\u00e9der \u00e0 des portefeuilles d\u2019utilisateurs. En f\u00e9vrier 2014, <strong>Mt. Gox suspend tous les retraits et admet avoir perdu plus de 650 000 bitcoins<\/strong>. La soci\u00e9t\u00e9 bas\u00e9e au Japon d\u00e9pose le bilan dans la foul\u00e9e.<\/p>\n<p>Parmi les causes, on \u00e9voque d&rsquo;abord un bug du protocole Bitcoin qui aurait permis de faire appara\u00eetre des retraits non effectu\u00e9s. Des <strong>proc\u00e8s contre l&rsquo;entreprise et son ex PDG sont toujours en cours<\/strong>, et nous venons d&rsquo;apprendre que les d\u00e9lais d&rsquo;indemnisation des clients ont encore \u00e9t\u00e9 repouss\u00e9s.<\/p>\n<p>Alors que l&rsquo;affaire judiciaire n&rsquo;est toujours pas r\u00e9gl\u00e9e, Marc Karpel\u00e8s a d\u00e9clar\u00e9 avoir fourni le code source de la plateforme \u00e0 l&rsquo;IA Claude. Sa mission \u00e9tait simple : analyser ce code pour potentiellement y trouver des failles. Cela ne rendra pas les BTC perdus dans le hack mais <strong>pourrait apporter une nouvelle lumi\u00e8re au cas Mt. Gox<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">So I tried feeding MtGox&#39;s 2011 codebase and various data (git history, access logs, dumps released by hacker, etc) to <a href=\"https:\/\/twitter.com\/AnthropicAI?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@AnthropicAI<\/a>&#39;s Claude, and let it analyze its way through all the stuff.<\/p>\n<p>The result:<a href=\"https:\/\/t.co\/r8oxCUW3Qp\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/r8oxCUW3Qp<\/a><\/p>\n<p>&mdash; Mark Karpel\u00e8s (@MagicalTux) <a href=\"https:\/\/twitter.com\/MagicalTux\/status\/1982550955116929312?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">October 26, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>C&rsquo;est l&rsquo;occasion de fournir un exercice \u00ab\u00a0r\u00e9el\u00a0\u00bb de cybers\u00e9curit\u00e9 \u00e0 une intelligence artificielle, <strong>Claude \u00e9tant parmi les mod\u00e8les les plus performants pour \u00e9crire\/relire du code informatique<\/strong>.<\/p>\n<p>Karpel\u00e8s lui a donc fourni le code de 2011, les journaux d\u2019acc\u00e8s, <a class=\"general-link\" href=\"https:\/\/github.com\/MagicalTux\/mtgox-2011-analysis\" target=\"_blank\" rel=\"noopener nofollow\">l\u2019historique GitHub<\/a> et afin d\u2019y identifier failles syst\u00e9miques. <strong>Selon Claude, ces vuln\u00e9rabilit\u00e9s auraient d\u00fb d\u00e9clencher \u00e0 l\u2019\u00e9poque un audit<\/strong> ou au moins une alerte.<\/p>\n<p>Cette affaire pose une question cruciale. Dans un secteur o\u00f9 les montants sont \u00e9normes, comment peut-on tol\u00e9rer des syst\u00e8mes d\u2019\u00e9change aussi fragiles ? <strong>Fort heureusement, l&rsquo;industrie a largement \u00e9volu\u00e9 depuis<\/strong>, et les processus de s\u00e9curit\u00e9 sont devenus plus robustes.<\/p>\n<h2>L\u2019IA au service de la cybers\u00e9curit\u00e9 crypto ?<\/h2>\n<p>Pour autant, le risque z\u00e9ro n&rsquo;existe pas. Le <a href=\"https:\/\/99bitcoins.com\/fr\/actu\/bunni-dex-fermeture-hack\/\">dernier hack en date, celui de Bunni DEX<\/a> nous rappelle \u00e0 quel point certaines plateformes peuvent \u00eatre fragiles. Mais visiblement, <strong>les IA d\u00e9sormais facilement accessibles pourrait aider \u00e0 endiguer ce ph\u00e9nom\u00e8ne et contenir les risques<\/strong>.<\/p>\n<p>L\u2019id\u00e9e que l\u2019IA aurait pu rep\u00e9rer \u00e0 l\u2019avance les failles de Mt. Gox suscite autant l\u2019enthousiasme que la prudence. Sur le plan technique, <strong>l\u2019intelligence artificielle est d\u00e9sormais capable d\u2019analyser des bases de code<\/strong>, de tracer les journaux d\u2019acc\u00e8s voire de d\u00e9tecter des anomalies.<\/p>\n<p>Elle a donc la capacit\u00e9 de <strong>rep\u00e9rer des vuln\u00e9rabilit\u00e9s avant qu\u2019elles soient exploit\u00e9es par des acteurs malicieux<\/strong>. Mais l\u2019IA n&rsquo;est \u00e0 aucun moment auto suffisante : ce n&rsquo;est qu&rsquo;un outil. Certes sa puissance de calcul permet de gagner beaucoup de temps, mais elle n&rsquo;est pas pr\u00e8s de remplacer parfaitement le facteur humain.<\/p>\n<p>Or ce dernier est souvent responsable des hacks survenus ces derni\u00e8res ann\u00e9es. <strong>Il faut donc \u00e9galement des processus humains, des gouvernances rigoureuses et des audits r\u00e9guliers<\/strong>. D&rsquo;autant plus alors que le secteur de l&rsquo;informatique quantique progresse un peu plus tous les ans. Le sujet divise les experts, mais <a href=\"https:\/\/99bitcoins.com\/fr\/actu\/ordinateurs-quantiques-google-menacer-bitcoin-cryptos\/\">repr\u00e9sente tout de m\u00eame une menace potentielle<\/a> qu&rsquo;il faut prendre en compte.<\/p>\n<p>Il y a fort \u00e0 parier que <strong>les intelligences artificielles prennent une place pr\u00e9pond\u00e9rante dans la cybers\u00e9curit\u00e9<\/strong>. Bien que chaque mod\u00e8le disponible ait ses forces et ses faiblesses, ces IA restent g\u00e9n\u00e9ralistes. Des LLM (Large Language Model) sp\u00e9cialis\u00e9s pour un secteur ou une t\u00e2che pourraient aider renforcer la vigilance et la pr\u00e9vention des risques crypto.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Our vision is to rebuild the creator economy from the ground up. Too many creators are held back by outdated systems and inefficient platforms. We\u2019re here to change that, giving creators the power to earn, grow, and truly own their content. That&#39;s why we\u2019re building the AI\u2026 <a href=\"https:\/\/t.co\/Dk6c8jAfSz\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/Dk6c8jAfSz<\/a><\/p>\n<p>&mdash; SUBBD (@SUBBDofficial) <a href=\"https:\/\/twitter.com\/SUBBDofficial\/status\/1970886279546999186?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">September 24, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>En tout cas l&rsquo;IA est d\u00e9j\u00e0 utile en crypto et certains projets s&rsquo;appuient dessus. <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/fr\/visit\/subbd\" target=\"_blank\" rel=\"noopener nofollow sponsored\">SUBBD<\/a> est <strong>une plateforme cr\u00e9ateurs dop\u00e9e \u00e0 l\u2019IA<\/strong> o\u00f9 le jeton alimente les paiements, l&rsquo;acc\u00e8s \u00e0 du contenu exclusif et des avantages r\u00e9serv\u00e9s aux d\u00e9tenteurs.<\/p>\n<a href=\"https:\/\/99bitcoins.com\/fr\/visit\/subbd\" class=\"sc-button sc-button-green sc-button-medium\" target=\"_blank\"  rel=\"nofollow sponsored\"><span>Visiter SUBBD<\/span><\/a>\n<p style=\"text-align: center\"><em>Les crypto-actifs repr\u00e9sentent un investissement risqu\u00e9.<\/em><\/p>\n<hr>\n<p><strong>Sur le m\u00eame sujet :<\/strong><\/p>\n<ul>\n<li>Ripple mise un milliard en XRP pendant que tout s\u2019effondre<\/li>\n<li><a class=\"general-link\" title=\"Bitcoin recule vers 100 000 $, le halving perd-il son pouvoir ?\" href=\"https:\/\/99bitcoins.com\/fr\/actu\/bitcoin-recule-vers-100-000-halving-perd-il-pouvoir\/\" rel=\"\">Bitcoin recule vers 100 000 $, le halving perd-il son pouvoir ?<\/a><\/li>\n<li>Bitcoin retrouve des couleurs : vers une cl\u00f4ture mensuelle historique ?<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019effondrement de Mt. Gox reste l\u2019un des chapitres les plus marquants de l\u2019histoire des cryptomonnaies. En 2011, la plateforme qui traitait plus de 70 % des transactions en Bitcoin cesse brutalement ses retraits et se d\u00e9clare en faillite. Victime d&rsquo;un hack qui laisse encore des zones d&rsquo;ombres, la plateforme disparait et une partie des BTC..<\/p>\n","protected":false},"author":136117,"featured_media":24482,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[113,6],"tags":[12],"coin":[15],"class_list":["post-24448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-pr","category-actu","tag-prevente"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mt Gox : 10 ans apr\u00e8s le hack, l&#039;IA Claude d\u00e9tecte les failles du code source<\/title>\n<meta name=\"description\" content=\"L&#039;histoire aurait probablement \u00e9t\u00e9 diff\u00e9rente pour Mt Gox si les outils d&#039;intelligence artificielle existaient il y a 10 ans.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mt Gox : 10 ans apr\u00e8s le hack, l&#039;IA Claude d\u00e9tecte les failles du code source\" \/>\n<meta property=\"og:description\" content=\"L&#039;histoire aurait probablement \u00e9t\u00e9 diff\u00e9rente pour Mt Gox si les outils d&#039;intelligence artificielle existaient il y a 10 ans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins FR\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T12:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T12:45:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/mt-gox.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Esteban Durant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Esteban Durant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/\"},\"author\":{\"name\":\"Esteban Durant\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/b32c31c709197c43c282001738666e5e\"},\"headline\":\"Mt Gox : 10 ans apr\u00e8s le hack, l&rsquo;IA Claude d\u00e9tecte les failles du code source\",\"datePublished\":\"2025-10-27T12:00:41+00:00\",\"dateModified\":\"2025-10-27T12:45:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/\"},\"wordCount\":905,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/mt-gox.jpg\",\"keywords\":[\"Pr\u00e9ventes\"],\"articleSection\":[\"actu pr\",\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/\",\"name\":\"Mt Gox : 10 ans apr\u00e8s le hack, l'IA Claude d\u00e9tecte les failles du code source\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/mt-gox.jpg\",\"datePublished\":\"2025-10-27T12:00:41+00:00\",\"dateModified\":\"2025-10-27T12:45:54+00:00\",\"description\":\"L'histoire aurait probablement \u00e9t\u00e9 diff\u00e9rente pour Mt Gox si les outils d'intelligence artificielle existaient il y a 10 ans.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/mt-gox.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/mt-gox.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/mt-gox-hack-ia-claude-detecte-failles-code-source\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mt Gox : 10 ans apr\u00e8s le hack, l&rsquo;IA Claude d\u00e9tecte les failles du code source\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"name\":\"99bitcoins FR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/b32c31c709197c43c282001738666e5e\",\"name\":\"Esteban Durant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g\",\"caption\":\"Esteban Durant\"},\"description\":\"Trader en crypto-actifs depuis plusieurs ann\u00e9es et passionn\u00e9 par l\u2019univers d\u00e9centralis\u00e9, je combine analyse technique, compr\u00e9hension des fondamentaux et suivi macro\u00e9conomique pour naviguer efficacement sur les march\u00e9s volatils. J\u2019ai d\u00e9couvert le Bitcoin en 2016, mais c\u2019est en 2018, en pleine phase baissi\u00e8re, que j\u2019ai r\u00e9ellement plong\u00e9 dans l\u2019analyse des cycles, des projets et des opportunit\u00e9s que propose l\u2019\u00e9cosyst\u00e8me crypto. Aujourd\u2019hui, je consacre mon temps \u00e0 l\u2019\u00e9tude des tendances du march\u00e9, \u00e0 la recherche de projets innovants, et au partage de strat\u00e9gies accessibles aussi bien aux d\u00e9butants qu\u2019aux investisseurs aguerris. En parall\u00e8le, je suis \u00e9galement r\u00e9dacteur sp\u00e9cialis\u00e9 en crypto et finance d\u00e9centralis\u00e9e. Mon objectif : rendre l\u2019information claire, p\u00e9dagogique et fiable, dans un univers o\u00f9 la d\u00e9sinformation peut co\u00fbter cher. J\u2019interviens sur ce site pour proposer des analyses, d\u00e9crypter l\u2019actualit\u00e9, vulgariser des concepts complexes, et offrir des perspectives concr\u00e8tes sur les mouvements du march\u00e9. Que ce soit pour du swing trading, du scalping ou de l\u2019investissement long terme, je m\u2019efforce d\u2019apporter une vision structur\u00e9e et pragmatique. La crypto est plus qu\u2019un march\u00e9 : c\u2019est une r\u00e9volution en marche. Et je suis l\u00e0 pour vous aider \u00e0 y voir clair.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/author\\\/estebandurant\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mt Gox : 10 ans apr\u00e8s le hack, l'IA Claude d\u00e9tecte les failles du code source","description":"L'histoire aurait probablement \u00e9t\u00e9 diff\u00e9rente pour Mt Gox si les outils d'intelligence artificielle existaient il y a 10 ans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/","og_locale":"fr_FR","og_type":"article","og_title":"Mt Gox : 10 ans apr\u00e8s le hack, l'IA Claude d\u00e9tecte les failles du code source","og_description":"L'histoire aurait probablement \u00e9t\u00e9 diff\u00e9rente pour Mt Gox si les outils d'intelligence artificielle existaient il y a 10 ans.","og_url":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/","og_site_name":"99bitcoins FR","article_published_time":"2025-10-27T12:00:41+00:00","article_modified_time":"2025-10-27T12:45:54+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/mt-gox.jpg","type":"image\/jpeg"}],"author":"Esteban Durant","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Esteban Durant","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/"},"author":{"name":"Esteban Durant","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/b32c31c709197c43c282001738666e5e"},"headline":"Mt Gox : 10 ans apr\u00e8s le hack, l&rsquo;IA Claude d\u00e9tecte les failles du code source","datePublished":"2025-10-27T12:00:41+00:00","dateModified":"2025-10-27T12:45:54+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/"},"wordCount":905,"publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/mt-gox.jpg","keywords":["Pr\u00e9ventes"],"articleSection":["actu pr","Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais"],"inLanguage":"fr-FR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/","url":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/","name":"Mt Gox : 10 ans apr\u00e8s le hack, l'IA Claude d\u00e9tecte les failles du code source","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/mt-gox.jpg","datePublished":"2025-10-27T12:00:41+00:00","dateModified":"2025-10-27T12:45:54+00:00","description":"L'histoire aurait probablement \u00e9t\u00e9 diff\u00e9rente pour Mt Gox si les outils d'intelligence artificielle existaient il y a 10 ans.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/#primaryimage","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/mt-gox.jpg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/mt-gox.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/fr\/actu\/mt-gox-hack-ia-claude-detecte-failles-code-source\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais","item":"https:\/\/99bitcoins.com\/fr\/actu\/"},{"@type":"ListItem","position":3,"name":"Mt Gox : 10 ans apr\u00e8s le hack, l&rsquo;IA Claude d\u00e9tecte les failles du code source"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/fr\/#website","url":"https:\/\/99bitcoins.com\/fr\/","name":"99bitcoins FR","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/fr\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/b32c31c709197c43c282001738666e5e","name":"Esteban Durant","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4612e4c10d00d2e68478864de7346bf5c83a2d5a754c96ef605a8574a2432cef?s=96&d=mm&r=g","caption":"Esteban Durant"},"description":"Trader en crypto-actifs depuis plusieurs ann\u00e9es et passionn\u00e9 par l\u2019univers d\u00e9centralis\u00e9, je combine analyse technique, compr\u00e9hension des fondamentaux et suivi macro\u00e9conomique pour naviguer efficacement sur les march\u00e9s volatils. J\u2019ai d\u00e9couvert le Bitcoin en 2016, mais c\u2019est en 2018, en pleine phase baissi\u00e8re, que j\u2019ai r\u00e9ellement plong\u00e9 dans l\u2019analyse des cycles, des projets et des opportunit\u00e9s que propose l\u2019\u00e9cosyst\u00e8me crypto. Aujourd\u2019hui, je consacre mon temps \u00e0 l\u2019\u00e9tude des tendances du march\u00e9, \u00e0 la recherche de projets innovants, et au partage de strat\u00e9gies accessibles aussi bien aux d\u00e9butants qu\u2019aux investisseurs aguerris. En parall\u00e8le, je suis \u00e9galement r\u00e9dacteur sp\u00e9cialis\u00e9 en crypto et finance d\u00e9centralis\u00e9e. Mon objectif : rendre l\u2019information claire, p\u00e9dagogique et fiable, dans un univers o\u00f9 la d\u00e9sinformation peut co\u00fbter cher. J\u2019interviens sur ce site pour proposer des analyses, d\u00e9crypter l\u2019actualit\u00e9, vulgariser des concepts complexes, et offrir des perspectives concr\u00e8tes sur les mouvements du march\u00e9. Que ce soit pour du swing trading, du scalping ou de l\u2019investissement long terme, je m\u2019efforce d\u2019apporter une vision structur\u00e9e et pragmatique. La crypto est plus qu\u2019un march\u00e9 : c\u2019est une r\u00e9volution en marche. Et je suis l\u00e0 pour vous aider \u00e0 y voir clair.","url":"https:\/\/99bitcoins.com\/fr\/author\/estebandurant\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/24448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/users\/136117"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/comments?post=24448"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/24448\/revisions"}],"predecessor-version":[{"id":24495,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/24448\/revisions\/24495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media\/24482"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media?parent=24448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/categories?post=24448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/tags?post=24448"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/coin?post=24448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}