{"id":22941,"date":"2025-10-14T10:00:01","date_gmt":"2025-10-14T10:00:01","guid":{"rendered":"https:\/\/99bitcoins.com\/fr\/?p=22941"},"modified":"2025-10-14T06:33:52","modified_gmt":"2025-10-14T06:33:52","slug":"ripple-immunefi-offrent-200k-securiser-xrp-ledger","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/","title":{"rendered":"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger"},"content":{"rendered":"<p>Ripple et Immunefi lancent une offensive de s\u00e9curit\u00e9 in\u00e9dite sur le XRP Ledger. Avec une r\u00e9compense pouvant atteindre<strong> 200 000 dollars<\/strong>, l\u2019\u201cAttackathon\u201d invite les hackers \u00e9thiques du monde entier \u00e0 traquer les failles du nouveau protocole de pr\u00eat XRP.<\/p>\n<p>L\u2019objectif : tester la<strong> r\u00e9silience du code<\/strong> avant son passage au vote des validateurs. Liquidation, solvabilit\u00e9, logique d\u2019int\u00e9r\u00eats\u2026 tout est pass\u00e9 au crible. Une phase \u00e9ducative d\u00e9marre d\u00e8s le 27 octobre, suivie d\u2019une mise \u00e0 l\u2019\u00e9preuve intense jusqu\u2019au 24 novembre.<\/p>\n<h2>Ripple Mobilise la Communaut\u00e9 : 200 000 $ pour s\u00e9curiser son Nouveau Protocole de Pr\u00eat<\/h2>\n<p><a class=\"general-link\" href=\"https:\/\/ripple.com\/\" target=\"_blank\" rel=\"noopener nofollow\">Ripple<\/a> propose une prime allant <strong>jusqu&rsquo;\u00e0 200 000 dollars<\/strong> aux utilisateurs qui identifient des failles de s\u00e9curit\u00e9 dans le protocole de pr\u00eat propos\u00e9 pour le XRP Ledger. Ainsi, la soci\u00e9t\u00e9 encourage activement les hackers \u00e9thiques \u00e0 \u00ab attaquer \u00bb sa future plateforme.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">We\u2019ve partnered with <a href=\"https:\/\/twitter.com\/RippleXDev?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@rippleXDev<\/a> to launch a $200,000 Attackathon helping secure the proposed XRPL Lending Protocol.<\/p>\n<p>This is a time-boxed, adversarial competition to identify vulnerabilities before the protocol reaches production. <a href=\"https:\/\/t.co\/792uz2fRNZ\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/792uz2fRNZ<\/a><\/p>\n<p>&mdash; Immunefi (@immunefi) <a href=\"https:\/\/twitter.com\/immunefi\/status\/1977745239545700728?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">October 13, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Ces r\u00e9compenses s&rsquo;inscrivent dans le cadre d&rsquo;un \u00ab attackathon \u00bb que Ripple et la soci\u00e9t\u00e9 de s\u00e9curit\u00e9 blockchain Immunefi organisent. Par cons\u00e9quent, ils invitent les chercheurs en s\u00e9curit\u00e9 \u00e0<strong> examiner minutieusement le code<\/strong> pour d\u00e9celer les failles potentielles. Une attention particuli\u00e8re est accord\u00e9e, en effet, aux bogues qui menacent la s\u00e9curit\u00e9 des fonds et la solvabilit\u00e9 des coffres.<\/p>\n<blockquote><p>\u00ab La communaut\u00e9 XRPL se pr\u00e9pare pour l&rsquo;une de ses mises \u00e0 niveau les plus importantes avec ce protocole de pr\u00eat. D&rsquo;ailleurs, un vote des validateurs est pr\u00e9vu avant la fin de l&rsquo;ann\u00e9e. Avant qu&rsquo;une modification majeure comme celle-ci ne soit mise en \u0153uvre, il est crucial de garantir un code \u00e0 toute \u00e9preuve \u00bb, a d\u00e9clar\u00e9 un porte-parole.<\/p><\/blockquote>\n<p>Pour encourager les personnes <strong>sans exp\u00e9rience sur le XRP Ledger<\/strong>, les entreprises ouvrent une p\u00e9riode de formation de deux semaines. Pendant ce d\u00e9lai, les chercheurs peuvent b\u00e9n\u00e9ficier du soutien des ing\u00e9nieurs de Ripple, acc\u00e9der \u00e0 des guides et \u00e0 des environnements de test sur le r\u00e9seau de d\u00e9veloppement, et bien plus encore.<\/p>\n<p>Finalement, une fois la p\u00e9riode de formation termin\u00e9e, l&rsquo;attackathon<strong> d\u00e9butera le 27 octobre<\/strong> pour se cl\u00f4turer le 29 novembre.<\/p>\n<h2>Ripple et le XRP Ledger, un Partenariat Strat\u00e9gique<\/h2>\n<p>Ripple a pr\u00e9sent\u00e9 le protocole de pr\u00eat du XRP Ledger \u00e0 l&rsquo;automne dernier, lors du sommet XRP Ledger Apex. Ainsi, l&rsquo;entreprise a cr\u00e9\u00e9 un <strong>\u00e9v\u00e9nement d\u00e9di\u00e9<\/strong> \u00e0 stimuler le d\u00e9veloppement de ce r\u00e9seau d\u00e9centralis\u00e9.<\/p>\n<p>Concr\u00e8tement, le protocole vise \u00e0 introduire des pr\u00eats \u00e0 terme fixe et sans collateral directement sur le XRP Ledger. Pour ce faire, il \u00e9vite d\u00e9lib\u00e9r\u00e9ment l&rsquo;usage de smart contracts ou d&rsquo;actifs wrapp\u00e9s. En lieu et place, le syst\u00e8me s&rsquo;appuie sur <strong>des proc\u00e9dures hors cha\u00eene<\/strong> pour \u00e9valuer la solvabilit\u00e9. Ensuite, les fonds sont mutualis\u00e9s sur la blockchain et les remboursements suivent des conditions strictement appliqu\u00e9es par le protocole.<\/p>\n<p>Lors de cet attackathon, les participants<strong> cibleront notamment<\/strong> la logique de liquidation, les bogues d&rsquo;int\u00e9r\u00eats qui pourraient avantager la mauvaise partie, ou encore les attaques administratives permettant de modifier les registres du protocole.<\/p>\n<p>Enfin, bien que la soci\u00e9t\u00e9 de paiement Ripple soit associ\u00e9e<strong> au jeton natif XRP<\/strong> et soit un contributeur majeur du registre, elle n&rsquo;entretient aucun lien avec la majorit\u00e9 des validateurs du XRP Ledger.<\/p>\n<h2>XRP continue sa perc\u00e9e dans les ETF<\/h2>\n<p>La demande des investisseurs pour les<strong> instruments financiers bas\u00e9s sur le XRP<\/strong> conna\u00eet une forte croissance. Cette dynamique s&rsquo;explique par <a href=\"https:\/\/99bitcoins.com\/fr\/actu\/wall-street-se-rue-sur-crypto-5-9-milliards-une-semaine\/\">l&rsquo;int\u00e9r\u00eat institutionnel croissant<\/a> pour une exposition r\u00e9gul\u00e9e aux actifs num\u00e9riques. Grayscale Investments a d\u00e9pos\u00e9 une premi\u00e8re modification de son formulaire S-1 aupr\u00e8s de la SEC am\u00e9ricaine le 10 octobre pour le Grayscale XRP Trust.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Be honest guys, will the SEC approve SPOT <a href=\"https:\/\/twitter.com\/hashtag\/XRP?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">#XRP<\/a> ETFs this month? <\/p>\n<p>YES or NO? <a href=\"https:\/\/t.co\/EcX1W9lsVv\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/EcX1W9lsVv<\/a><\/p>\n<p>&mdash; JackTheRippler \u00a9\ufe0f (@RippleXrpie) <a href=\"https:\/\/twitter.com\/RippleXrpie\/status\/1977809282239451279?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">October 13, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Ce fonds du Delaware, qui portera le nom de Grayscale XRP Trust ETF apr\u00e8s l&rsquo;approbation, a pour objectif de permettre aux investisseurs de <strong>s&rsquo;exposer indirectement au XRP<\/strong>. Ainsi, ils n&rsquo;auront pas besoin de d\u00e9tenir directement les jetons ni d&rsquo;en g\u00e9rer la custodie.<\/p>\n<p>Le Fonds pr\u00e9voit d&rsquo;\u00e9mettre des actions de mani\u00e8re continue et enregistre un nombre ind\u00e9termin\u00e9 de parts. Il pr\u00e9voit que ces actions seront vendues au public \u00e0 des prix variables, d\u00e9termin\u00e9s en fonction, entre autres, <strong>du prix du XRP<\/strong> et de la valeur de n\u00e9gociation des actions sur le NYSE Arca au moment de chaque vente.<\/p>\n<p>Tous ces signaux sont <strong>plus qu\u2019encourageants<\/strong> pour le futur du XRP. Les holders peuvent se r\u00e9jouir, la s\u00e9curit\u00e9 renforc\u00e9e et l\u2019adoption institutionnelle pourraient bien se refl\u00e9ter dans le prix. \u00a0L&rsquo;avenir du XRP se joue d\u00e9sormais sur deux fronts : le code et les march\u00e9s.<\/p>\n<hr \/>\n<p><strong>Sur le m\u00eame sujet :<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/99bitcoins.com\/fr\/actu\/bnb-doge-tete-rebond-post-crash\/\">BNB et DOGE en t\u00eate du rebond post-crash<\/a><\/li>\n<li><a class=\"general-link\" title=\"Wall Street se rue sur la crypto, 5,9 milliards $ en une semaine\" href=\"https:\/\/99bitcoins.com\/fr\/actu\/wall-street-se-rue-sur-crypto-5-9-milliards-une-semaine\/\" rel=\"\">Wall Street se rue sur la crypto, 5,9 milliards $ en une semaine<\/a><\/li>\n<li><a href=\"https:\/\/99bitcoins.com\/fr\/actu\/binance-lache-45-m-bnb-pour-sauver-traders-memecoin\/\">Binance l\u00e2che 45 M $ en BNB pour sauver ses traders memecoin<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ripple et Immunefi lancent une offensive de s\u00e9curit\u00e9 in\u00e9dite sur le XRP Ledger. Avec une r\u00e9compense pouvant atteindre 200 000 dollars, l\u2019\u201cAttackathon\u201d invite les hackers \u00e9thiques du monde entier \u00e0 traquer les failles du nouveau protocole de pr\u00eat XRP. L\u2019objectif : tester la r\u00e9silience du code avant son passage au vote des validateurs. Liquidation, solvabilit\u00e9,..<\/p>\n","protected":false},"author":135978,"featured_media":22960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[10,6],"tags":[11],"coin":[192],"class_list":["post-22941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","category-actu","tag-altcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger<\/title>\n<meta name=\"description\" content=\"Ripple et Immunefi lancent une prime de 200K$ pour renforcer la s\u00e9curit\u00e9 du XRP Ledger. Une initiative pour prot\u00e9ger l\u2019\u00e9cosyst\u00e8me.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger\" \/>\n<meta property=\"og:description\" content=\"Ripple et Immunefi lancent une prime de 200K$ pour renforcer la s\u00e9curit\u00e9 du XRP Ledger. Une initiative pour prot\u00e9ger l\u2019\u00e9cosyst\u00e8me.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins FR\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-14T10:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/Canva_99BTC_7_optimized_1000.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1881\" \/>\n\t<meta property=\"og:image:height\" content=\"1254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Martin Pelletier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Pelletier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/\"},\"author\":{\"name\":\"Martin Pelletier\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/d6acaa19de409b9e22e3f740da472d70\"},\"headline\":\"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger\",\"datePublished\":\"2025-10-14T10:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/\"},\"wordCount\":846,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/Canva_99BTC_7_optimized_1000.png\",\"keywords\":[\"Altcoin\"],\"articleSection\":[\"Altcoins\",\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/\",\"name\":\"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/Canva_99BTC_7_optimized_1000.png\",\"datePublished\":\"2025-10-14T10:00:01+00:00\",\"description\":\"Ripple et Immunefi lancent une prime de 200K$ pour renforcer la s\u00e9curit\u00e9 du XRP Ledger. Une initiative pour prot\u00e9ger l\u2019\u00e9cosyst\u00e8me.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/Canva_99BTC_7_optimized_1000.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/Canva_99BTC_7_optimized_1000.png\",\"width\":1881,\"height\":1254},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/actu\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"name\":\"99bitcoins FR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/d6acaa19de409b9e22e3f740da472d70\",\"name\":\"Martin Pelletier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g\",\"caption\":\"Martin Pelletier\"},\"description\":\"Journaliste et analyste sp\u00e9cialis\u00e9 dans les crypto-monnaies et la blockchain, Martin Pelletier explore les dynamiques du Web3 et des nouvelles technologies financi\u00e8res depuis 2019. Fort d\u2019une exp\u00e9rience dans la finance traditionnelle, il s\u2019est tourn\u00e9 vers le monde des actifs num\u00e9riques pour \u00e9clairer les lecteurs sur les d\u00e9fis et les opportunit\u00e9s de cet \u00e9cosyst\u00e8me en constante \u00e9volution. \u00c0 travers des articles d'analyse, des interviews d\u2019experts et des rapports d\u00e9taill\u00e9s, Martin propose des contenus p\u00e9dagogiques et accessibles pour d\u00e9mocratiser des sujets complexes comme la finance d\u00e9centralis\u00e9e (DeFi), les NFT, et les monnaies num\u00e9riques des banques centrales (CBDC).\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/martin-pelletier-a923ba343\\\/\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/author\\\/martinpelletier\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger","description":"Ripple et Immunefi lancent une prime de 200K$ pour renforcer la s\u00e9curit\u00e9 du XRP Ledger. Une initiative pour prot\u00e9ger l\u2019\u00e9cosyst\u00e8me.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/","og_locale":"fr_FR","og_type":"article","og_title":"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger","og_description":"Ripple et Immunefi lancent une prime de 200K$ pour renforcer la s\u00e9curit\u00e9 du XRP Ledger. Une initiative pour prot\u00e9ger l\u2019\u00e9cosyst\u00e8me.","og_url":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/","og_site_name":"99bitcoins FR","article_published_time":"2025-10-14T10:00:01+00:00","og_image":[{"width":1881,"height":1254,"url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/Canva_99BTC_7_optimized_1000.png","type":"image\/png"}],"author":"Martin Pelletier","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Martin Pelletier","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/"},"author":{"name":"Martin Pelletier","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/d6acaa19de409b9e22e3f740da472d70"},"headline":"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger","datePublished":"2025-10-14T10:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/"},"wordCount":846,"publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/Canva_99BTC_7_optimized_1000.png","keywords":["Altcoin"],"articleSection":["Altcoins","Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais"],"inLanguage":"fr-FR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/","url":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/","name":"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/Canva_99BTC_7_optimized_1000.png","datePublished":"2025-10-14T10:00:01+00:00","description":"Ripple et Immunefi lancent une prime de 200K$ pour renforcer la s\u00e9curit\u00e9 du XRP Ledger. Une initiative pour prot\u00e9ger l\u2019\u00e9cosyst\u00e8me.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/#primaryimage","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/Canva_99BTC_7_optimized_1000.png","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/10\/Canva_99BTC_7_optimized_1000.png","width":1881,"height":1254},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/fr\/actu\/ripple-immunefi-offrent-200k-securiser-xrp-ledger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Derni\u00e8res Actualit\u00e9s Crypto en Fran\u00e7ais","item":"https:\/\/99bitcoins.com\/fr\/actu\/"},{"@type":"ListItem","position":3,"name":"Ripple et Immunefi offrent 200K$ pour s\u00e9curiser le XRP Ledger"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/fr\/#website","url":"https:\/\/99bitcoins.com\/fr\/","name":"99bitcoins FR","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/fr\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/d6acaa19de409b9e22e3f740da472d70","name":"Martin Pelletier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/619e41ea263b14379ed26acd8625eb311d3bfa4305a6b2b05fb2ad7937b9e869?s=96&d=mm&r=g","caption":"Martin Pelletier"},"description":"Journaliste et analyste sp\u00e9cialis\u00e9 dans les crypto-monnaies et la blockchain, Martin Pelletier explore les dynamiques du Web3 et des nouvelles technologies financi\u00e8res depuis 2019. Fort d\u2019une exp\u00e9rience dans la finance traditionnelle, il s\u2019est tourn\u00e9 vers le monde des actifs num\u00e9riques pour \u00e9clairer les lecteurs sur les d\u00e9fis et les opportunit\u00e9s de cet \u00e9cosyst\u00e8me en constante \u00e9volution. \u00c0 travers des articles d'analyse, des interviews d\u2019experts et des rapports d\u00e9taill\u00e9s, Martin propose des contenus p\u00e9dagogiques et accessibles pour d\u00e9mocratiser des sujets complexes comme la finance d\u00e9centralis\u00e9e (DeFi), les NFT, et les monnaies num\u00e9riques des banques centrales (CBDC).","sameAs":["https:\/\/www.linkedin.com\/in\/martin-pelletier-a923ba343\/"],"url":"https:\/\/99bitcoins.com\/fr\/author\/martinpelletier\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/22941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/users\/135978"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/comments?post=22941"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/22941\/revisions"}],"predecessor-version":[{"id":22964,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/22941\/revisions\/22964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media\/22960"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media?parent=22941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/categories?post=22941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/tags?post=22941"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/coin?post=22941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}