{"id":1752,"date":"2024-12-09T16:13:34","date_gmt":"2024-12-09T16:13:34","guid":{"rendered":"https:\/\/99bitcoins.com\/fr\/?p=1752"},"modified":"2024-12-09T16:13:34","modified_gmt":"2024-12-09T16:13:34","slug":"une-fortune-en-bitcoins-dort-dans-cette-decharge","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/","title":{"rendered":"Une fortune en Bitcoins dort dans cette d\u00e9charge depuis plus de 10 ans"},"content":{"rendered":"<p>En 2013, James Howells, un informaticien de Newport, au Pays de Galles, a accidentellement jet\u00e9 un <strong>disque dur contenant 8 000 Bitcoins.<\/strong> \u00c0 l\u2019\u00e9poque, ces bouts de code ne valaient pas grand-chose, mais aujourd\u2019hui leur valeur a explos\u00e9 \u00e0 environ 600 millions de livres sterling.<\/p>\n<p>Le probl\u00e8me ? Ce disque dur repose depuis dix ans sous une montagne d\u2019ordures dans une d\u00e9charge municipale. Aujourd\u2019hui, Howells se bat avec acharnement pour r\u00e9cup\u00e9rer cette fortune num\u00e9rique, mais sa qu\u00eate se heurte \u00e0 une barri\u00e8re juridique, \u00e9cologique et bureaucratique.<\/p>\n<h2>Quand une erreur banale se transforme en trag\u00e9die financi\u00e8re<\/h2>\n<p>Tout a commenc\u00e9 comme une histoire compl\u00e8tement ordinaire. James Howells, f\u00e9ru de technologies qui minait avec des <a href=\"https:\/\/99bitcoins.com\/fr\/crypto-monnaie\/acheter-bitcoin\/\">Bitcoins<\/a> bien avant que tout le monde s\u2019y mette, a fait un peu de tri chez lui. Il a rang\u00e9 le disque dur dans un sac noir et sa copine de l\u2019\u00e9poque, pensant que c\u2019\u00e9tait juste des d\u00e9chets, a envoy\u00e9 le tout \u00e0 la d\u00e9charge de Docksway.<\/p>\n<p>Jusque-l\u00e0 il n\u2019y a pas de quoi en faire un drame, sauf qu\u2019apr\u00e8s quelques ann\u00e9es, la valeur du Bitcoin a explos\u00e9 et ce vieux disque dur est devenu <strong>l\u2019\u00e9quivalent num\u00e9rique d\u2019un coffre rempli d\u2019or.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">JAMES HOWELLS\u2019 EX TOSSED $787M BTC IN THE TRASH\u2014BUT IT\u2019S COMPLICATED<\/p>\n<p>James Howells\u2019 ex just spilled the tea: she dumped his $787M Bitcoin-filled hard drive because he told her to.<\/p>\n<p>Now, he\u2019s locked in a legal battle with Newport City Council to dig through 1.4M tons of landfill\u2026 <a href=\"https:\/\/t.co\/YuTkseJWfp\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/YuTkseJWfp<\/a><\/p>\n<p>&mdash; Mario Nawfal\u2019s Roundtable (@RoundtableSpace) <a href=\"https:\/\/twitter.com\/RoundtableSpace\/status\/1861048444892135573?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">November 25, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Howells n\u2019a pas tard\u00e9 \u00e0 se mobiliser pour retrouver son bien. Il a approch\u00e9 le conseil municipal de Newport pour demander l\u2019autorisation de fouiller la d\u00e9charge de Docksway, mais il s\u2019est heurt\u00e9 \u00e0 un mur de refus.<\/p>\n<p>Le disque dur, d\u00e9sormais enseveli sous des tonnes de d\u00e9chets, est rest\u00e9 hors de port\u00e9e. Le temps et les couches successives de d\u00e9chets n\u2019ont fait qu\u2019ajouter \u00e0 la complexit\u00e9 de la t\u00e2che, mais pour Howells, l\u2019id\u00e9e d\u2019abandonner est impensable.<\/p>\n<h2>Le poids du droit et des enjeux \u00e9cologiques dans une bataille judiciaire sans fin<\/h2>\n<p>Depuis cette perte, Howells <strong>a engag\u00e9 une lutte acharn\u00e9e<\/strong> contre le conseil municipal de Newport, esp\u00e9rant r\u00e9cup\u00e9rer son disque dur ou, \u00e0 d\u00e9faut, obtenir une compensation financi\u00e8re. Mais ce n\u2019est pas aussi simple. Le probl\u00e8me, c\u2019est que la loi dit que tout ce qui finit dans une d\u00e9charge devient la propri\u00e9t\u00e9 des autorit\u00e9s locales.<\/p>\n<p>En plus, les r\u00e8gles environnementales emp\u00eachent de retourner la d\u00e9charge pour creuser, sous pr\u00e9texte que \u00e7a pourrait mettre du chaos dans la zone.<\/p>\n<p>De leur c\u00f4t\u00e9, les bureaucrates de Newport se montrent inflexibles : hors de question de gaspiller du temps et de l\u2019argent public pour aider quelqu\u2019un \u00e0 mettre la main sur une fortune priv\u00e9e. Mais Howells ne l\u00e2che rien. Il a mont\u00e9 une \u00e9quipe d\u2019experts pour \u00e9laborer un plan hyper pr\u00e9cis.<\/p>\n<p>Ils pensent pouvoir cibler exactement la zone o\u00f9 le disque se trouve. Howells a m\u00eame <strong>propos\u00e9 de partager 10 % de sa fortune<\/strong> aux habitants de la ville, histoire de convaincre le conseil.<\/p>\n<p>Sauf que \u00e7a s\u2019est retourn\u00e9 contre lui : les avocats de Newport ont cri\u00e9 \u00e0 la corruption et ont qualifi\u00e9 sa qu\u00eate de mission impossible. Malgr\u00e9 tout, Howells maintient que le disque dur peut se r\u00e9cup\u00e9rer sans provoquer de dommages majeurs, mais le conseil municipal continue de rejeter ses requ\u00eates et a m\u00eame demand\u00e9 \u00e0 un juge de classer l\u2019affaire avant qu\u2019elle n\u2019aille en proc\u00e8s.<\/p>\n<h2>Quand les crypto-monnaies et l\u2019\u00e9cologie se croisent dans une impasse morale<\/h2>\n<p>Cette histoire est une collision entre deux mondes : le virtuel et le bien r\u00e9el. D\u2019un c\u00f4t\u00e9, on a James Howells, totalement obs\u00e9d\u00e9 par son disque dur. Il est<strong> soutenu par des investisseurs et des experts<\/strong> pr\u00eats \u00e0 creuser co\u00fbte que co\u00fbte pour r\u00e9cup\u00e9rer une richesse planqu\u00e9e dans le n\u00e9ant de d\u00e9charge.<\/p>\n<p>De l\u2019autre, on a le conseil municipal, qui<strong> joue la carte du l\u00e9gal et de l\u2019\u00e9cologie.<\/strong> Ils disent qu\u2019autoriser Howells, c\u2019est ouvrir la bo\u00eete de Pandore, avec d\u2019autres personnes qui pourraient d\u00e9barquer pour r\u00e9clamer leurs vieux objets.<\/p>\n<p>Ils mettent aussi en avant les risques environnementaux, m\u00eame si Howells affirme que son \u00e9quipe a tout pr\u00e9vu pour \u00e9viter le chaos. Mais pour le moment, il est bloqu\u00e9. Pendant ce temps, le disque dur reste enterr\u00e9 quelque part sous des tonnes d\u2019ordures, tandis que le tribunal est charg\u00e9 de d\u00e9cider si cette qu\u00eate m\u00e9rite un proc\u00e8s ou si elle doit \u00eatre d\u00e9finitivement abandonn\u00e9e.<\/p>\n<hr>\n<p>Sur le m\u00eame sujet :<\/p>\n<ul>\n<li>Bonne nouvelle : CatSlap arrive sur MEXC d\u00e8s ce vendredi<\/li>\n<li>La nouvelle pr\u00e9vente de ce token $WEPE fait fureur<\/li>\n<li>L\u2019industrie crypto est-elle enti\u00e8rement satisfaite du retour de Trump au pouvoir ?<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En 2013, James Howells, un informaticien de Newport, au Pays de Galles, a accidentellement jet\u00e9 un disque dur contenant 8 000 Bitcoins. \u00c0 l\u2019\u00e9poque, ces bouts de code ne valaient pas grand-chose, mais aujourd\u2019hui leur valeur a explos\u00e9 \u00e0 environ 600 millions de livres sterling. Le probl\u00e8me ? Ce disque dur repose depuis dix ans..<\/p>\n","protected":false},"author":135871,"featured_media":1754,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8],"tags":[13],"coin":[15],"class_list":["post-1752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ce wallet rempli de Bitcoins se trouve dans une d\u00e9charge<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez cette histoire de cet individu qui a jet\u00e9 une fortune en Bitcoins dans une d\u00e9charge et apprenez-en plus sur le sujet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ce wallet rempli de Bitcoins se trouve dans une d\u00e9charge\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez cette histoire de cet individu qui a jet\u00e9 une fortune en Bitcoins dans une d\u00e9charge et apprenez-en plus sur le sujet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins FR\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T16:13:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/12\/coverDechargebtc.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1745\" \/>\n\t<meta property=\"og:image:height\" content=\"885\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre Kryzowski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Kryzowski\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/\"},\"author\":{\"name\":\"Pierre Kryzowski\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/d9562003459082617e9d9d523e442c85\"},\"headline\":\"Une fortune en Bitcoins dort dans cette d\u00e9charge depuis plus de 10 ans\",\"datePublished\":\"2024-12-09T16:13:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/\"},\"wordCount\":813,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/12\\\/coverDechargebtc.png\",\"keywords\":[\"Bitcoin\"],\"articleSection\":[\"Bitcoin\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/\",\"name\":\"Ce wallet rempli de Bitcoins se trouve dans une d\u00e9charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/12\\\/coverDechargebtc.png\",\"datePublished\":\"2024-12-09T16:13:34+00:00\",\"description\":\"D\u00e9couvrez cette histoire de cet individu qui a jet\u00e9 une fortune en Bitcoins dans une d\u00e9charge et apprenez-en plus sur le sujet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/12\\\/coverDechargebtc.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/12\\\/coverDechargebtc.png\",\"width\":1745,\"height\":885},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/une-fortune-en-bitcoins-dort-dans-cette-decharge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bitcoin\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/bitcoin\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Une fortune en Bitcoins dort dans cette d\u00e9charge depuis plus de 10 ans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"name\":\"99bitcoins FR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/person\\\/d9562003459082617e9d9d523e442c85\",\"name\":\"Pierre Kryzowski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca8ab3fdb54f372aa4edf72d2bbf7b8b3521cd214ef35ca6c6d962b29bcf4a2b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca8ab3fdb54f372aa4edf72d2bbf7b8b3521cd214ef35ca6c6d962b29bcf4a2b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca8ab3fdb54f372aa4edf72d2bbf7b8b3521cd214ef35ca6c6d962b29bcf4a2b?s=96&d=mm&r=g\",\"caption\":\"Pierre Kryzowski\"},\"description\":\"Pierre Kryzowski est un sp\u00e9cialiste du monde de la crypto-monnaie et est impliqu\u00e9 dans le secteur depuis 2017. En tant qu'investisseur et passionn\u00e9, il a rejoint les rangs de 99Bitcoins pour partager son savoir \u00e0 l'ensemble de la communaut\u00e9. Pierre analyse l'actualit\u00e9 du Web3 et de la DeFi quotidiennement et d\u00e9niche toujours d'excellents projets technologiques que l'on peut r\u00e9guli\u00e8rement pr\u00e9senter \u00e0 nos lecteurs.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/author\\\/pierregolebiewski\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ce wallet rempli de Bitcoins se trouve dans une d\u00e9charge","description":"D\u00e9couvrez cette histoire de cet individu qui a jet\u00e9 une fortune en Bitcoins dans une d\u00e9charge et apprenez-en plus sur le sujet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/","og_locale":"fr_FR","og_type":"article","og_title":"Ce wallet rempli de Bitcoins se trouve dans une d\u00e9charge","og_description":"D\u00e9couvrez cette histoire de cet individu qui a jet\u00e9 une fortune en Bitcoins dans une d\u00e9charge et apprenez-en plus sur le sujet.","og_url":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/","og_site_name":"99bitcoins FR","article_published_time":"2024-12-09T16:13:34+00:00","og_image":[{"width":1745,"height":885,"url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/12\/coverDechargebtc.png","type":"image\/png"}],"author":"Pierre Kryzowski","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pierre Kryzowski","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/"},"author":{"name":"Pierre Kryzowski","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/d9562003459082617e9d9d523e442c85"},"headline":"Une fortune en Bitcoins dort dans cette d\u00e9charge depuis plus de 10 ans","datePublished":"2024-12-09T16:13:34+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/"},"wordCount":813,"commentCount":0,"publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/12\/coverDechargebtc.png","keywords":["Bitcoin"],"articleSection":["Bitcoin"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/","url":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/","name":"Ce wallet rempli de Bitcoins se trouve dans une d\u00e9charge","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/12\/coverDechargebtc.png","datePublished":"2024-12-09T16:13:34+00:00","description":"D\u00e9couvrez cette histoire de cet individu qui a jet\u00e9 une fortune en Bitcoins dans une d\u00e9charge et apprenez-en plus sur le sujet.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/#primaryimage","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/12\/coverDechargebtc.png","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/12\/coverDechargebtc.png","width":1745,"height":885},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/fr\/bitcoin\/une-fortune-en-bitcoins-dort-dans-cette-decharge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Bitcoin","item":"https:\/\/99bitcoins.com\/fr\/bitcoin\/"},{"@type":"ListItem","position":3,"name":"Une fortune en Bitcoins dort dans cette d\u00e9charge depuis plus de 10 ans"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/fr\/#website","url":"https:\/\/99bitcoins.com\/fr\/","name":"99bitcoins FR","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/fr\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/person\/d9562003459082617e9d9d523e442c85","name":"Pierre Kryzowski","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ca8ab3fdb54f372aa4edf72d2bbf7b8b3521cd214ef35ca6c6d962b29bcf4a2b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca8ab3fdb54f372aa4edf72d2bbf7b8b3521cd214ef35ca6c6d962b29bcf4a2b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca8ab3fdb54f372aa4edf72d2bbf7b8b3521cd214ef35ca6c6d962b29bcf4a2b?s=96&d=mm&r=g","caption":"Pierre Kryzowski"},"description":"Pierre Kryzowski est un sp\u00e9cialiste du monde de la crypto-monnaie et est impliqu\u00e9 dans le secteur depuis 2017. En tant qu'investisseur et passionn\u00e9, il a rejoint les rangs de 99Bitcoins pour partager son savoir \u00e0 l'ensemble de la communaut\u00e9. Pierre analyse l'actualit\u00e9 du Web3 et de la DeFi quotidiennement et d\u00e9niche toujours d'excellents projets technologiques que l'on peut r\u00e9guli\u00e8rement pr\u00e9senter \u00e0 nos lecteurs.","url":"https:\/\/99bitcoins.com\/fr\/author\/pierregolebiewski\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/1752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/users\/135871"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/comments?post=1752"}],"version-history":[{"count":4,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/1752\/revisions"}],"predecessor-version":[{"id":32008,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/posts\/1752\/revisions\/32008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media\/1754"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media?parent=1752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/categories?post=1752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/tags?post=1752"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/coin?post=1752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}