{"id":61,"date":"2024-08-09T08:23:57","date_gmt":"2024-08-09T08:23:57","guid":{"rendered":"https:\/\/99bitcoins.com\/fr\/?page_id=61"},"modified":"2025-04-15T11:33:51","modified_gmt":"2025-04-15T11:33:51","slug":"conditions-dutilisation","status":"publish","type":"page","link":"https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/","title":{"rendered":"Conditions d&rsquo;utilisation"},"content":{"rendered":"<p>Bienvenue sur <a href=\"https:\/\/99bitcoins.com\/fr\/\">99bitcoins.com<\/a> (le \u00ab\u2009<strong>Site Web<\/strong>\u2009\u00bb).<\/p>\n<ol>\n<li>Le site Web est fourni uniquement \u00e0 des fins d\u2019information et ne doit pas \u00eatre utilis\u00e9 comme base pour un investissement ou pour d\u2019autres fins.<\/li>\n<li>Les termes \u00ab\u2009<strong>nous<\/strong>\u2009\u00bb, \u00ab\u2009<strong>notre<\/strong>\u2009\u00bb et \u00ab\u2009<strong>99btc<\/strong>\u2009\u00bb font r\u00e9f\u00e9rence \u00e0 99 Bitcoins Inc., enregistr\u00e9e \u00e0 Marshall Islands, aux op\u00e9rateurs du site Web ou \u00e0 toute personne agissant en leur nom. Le terme \u00ab\u2009<strong>vous<\/strong>\u2009\u00bb fait r\u00e9f\u00e9rence au client qui visite le site Web, contribue au contenu du site Web ou agit de toute autre mani\u00e8re en lien avec le site Web.<\/li>\n<li>Le site Web vous est propos\u00e9 \u00e0 condition que vous acceptiez sans modification tous les termes, conditions et avis \u00e9nonc\u00e9s ci-dessous (collectivement, les \u00ab\u2009<strong>Conditions<\/strong>\u2009\u00bb). <strong><em>En acc\u00e9dant ou en utilisant le site Web de quelque mani\u00e8re que ce soit, vous acceptez d\u2019\u00eatre soumis \u00e0 ces Conditions. Veuillez lire attentivement ces Conditions. Si vous n\u2019acceptez pas toutes ces conditions, veuillez ne pas utiliser le site Web<\/em><\/strong><em>.<\/em><\/li>\n<li>Nous vous recommandons de v\u00e9rifier r\u00e9guli\u00e8rement ces Conditions pour voir si elles ont \u00e9t\u00e9 mises \u00e0 jour. Nous nous r\u00e9servons le droit, \u00e0 tout moment et \u00e0 notre seule discr\u00e9tion, de modifier ou de changer ces Conditions sans pr\u00e9avis, et votre acc\u00e8s ou utilisation continue du site Web signifie votre acceptation des Conditions mises \u00e0 jour ou modifi\u00e9es.<\/li>\n<\/ol>\n<p><strong>UTILISATION DU SITE WEB<\/strong><\/p>\n<ol>\n<li>Vous pouvez utiliser le site Web uniquement \u00e0 des fins priv\u00e9es et personnelles. Il est interdit d\u2019utiliser le site Web ou son contenu \u00e0 des fins commerciales.<\/li>\n<li>Vous devez avoir au moins 18 ans pour utiliser notre site Web. En utilisant notre site et en acceptant ces conditions d\u2019utilisation, vous garantissez que vous avez au moins 18 ans.<\/li>\n<li><strong>Notre site Web utilise des cookies<\/strong>. En utilisant notre site Web et en acceptant ces conditions d\u2019utilisation, vous consentez \u00e0 notre utilisation des cookies conform\u00e9ment \u00e0 notre politique de confidentialit\u00e9.<\/li>\n<\/ol>\n<p><strong>CONTENU UTILISATEUR<\/strong><\/p>\n<ol>\n<li>Le site Web permet aux utilisateurs de soumettre et de publier des commentaires et du contenu dans divers endroits (\u00ab\u2009<strong>Contenu<\/strong>\u2009\u00bb). Vous assumez l\u2019enti\u00e8re responsabilit\u00e9 de votre Contenu et des cons\u00e9quences de sa publication.<\/li>\n<li>Le Contenu soumis par les utilisateurs ne refl\u00e8te pas les opinions du site Web. La publication de Contenu ne garantit pas sa validit\u00e9, sa fiabilit\u00e9, son exactitude, sa l\u00e9galit\u00e9 ou sa mise \u00e0 jour.<\/li>\n<\/ol>\n<p><strong>ACTIVIT\u00c9S INTERDITES<\/strong><\/p>\n<ol>\n<li>Tout contenu et information se trouvant sur le site Web, quel qu\u2019il soit (y compris, mais sans s\u2019y limiter, les donn\u00e9es, textes, photos, graphiques, vid\u00e9os, etc.), nous appartient. Vous acceptez de ne pas modifier, copier, distribuer, transmettre, afficher, reproduire, publier, conc\u00e9der sous licence, cr\u00e9er des \u0153uvres d\u00e9riv\u00e9es, transf\u00e9rer, vendre, revendre ou utiliser de quelque mani\u00e8re que ce soit, sauf pour une lecture priv\u00e9e. De plus, vous acceptez de ne pas\u00a0:<\/li>\n<\/ol>\n<ul>\n<li>Utiliser le site Web ou son contenu \u00e0 des fins commerciales\u2009;<\/li>\n<li>Acc\u00e9der, surveiller ou copier un contenu ou une information du site Web en utilisant un robot, un crawler, un scraper de site ou tout autre moyen automatis\u00e9 ou manuel \u00e0 des fins quelconques sans notre autorisation \u00e9crite expresse\u2009;<\/li>\n<li>\u00ab\u2009Encadrer\u2009\u00bb, \u00ab\u2009miroiter\u2009\u00bb ou int\u00e9grer une partie du site Web dans un autre site sans notre autorisation \u00e9crite pr\u00e9alable\u2009;<\/li>\n<li>Porter atteinte ou enfreindre nos droits de propri\u00e9t\u00e9 ou ceux d\u2019autrui, y compris, mais sans s\u2019y limiter, les droits d\u2019auteur et les marques d\u00e9pos\u00e9es\u2009;<\/li>\n<li>Ajouter du contenu qui porte atteinte \u00e0 l\u2019int\u00e9grit\u00e9, la vie priv\u00e9e, la s\u00e9curit\u00e9 ou la sant\u00e9 d\u2019une personne\u2009;<\/li>\n<li>Ajouter du contenu identifiant d\u2019autres personnes sans obtenir leur consentement pour la divulgation de leurs informations personnelles, ou concernant des mineurs et identifiant ces derniers, leurs informations personnelles ou leurs coordonn\u00e9es\u2009;<\/li>\n<li>Ajouter du contenu ill\u00e9gal, diffamatoire, calomnieux ou portant atteinte \u00e0 la vie priv\u00e9e d\u2019autrui\u2009;<\/li>\n<li>Ajouter du contenu harcelant, offensant, mena\u00e7ant ou vulgaire\u2009;<\/li>\n<li>Ajouter du contenu caract\u00e9ris\u00e9 par, ou encourageant le racisme ou la discrimination ill\u00e9gale fond\u00e9e sur la race, l\u2019origine, l\u2019ethnicit\u00e9, la nationalit\u00e9, la religion, le genre, l\u2019occupation, l\u2019orientation sexuelle, la maladie, le handicap physique ou mental, la foi, la vue politique ou la classe socio-\u00e9conomique\u2009;<\/li>\n<li>Ajouter du contenu encourageant une conduite consid\u00e9r\u00e9e comme une infraction p\u00e9nale ou donnant lieu \u00e0 une responsabilit\u00e9 civile ou \u00e0 d\u2019autres poursuites\u2009;<\/li>\n<li>Ajouter du contenu promouvant des syst\u00e8mes pyramidaux, des cha\u00eenes de lettres ou des messages commerciaux ou publicitaires perturbateurs, ou tout autre \u00e9l\u00e9ment interdit par la loi ou par les pr\u00e9sentes conditions d\u2019utilisation\u2009;<\/li>\n<li>Ajouter du contenu contenant des promotions, des campagnes politiques, de la publicit\u00e9, des concours, des tirages au sort ou des sollicitations\u2009;<\/li>\n<li>Ajouter du contenu comportant des virus, des donn\u00e9es corrompues ou d\u2019autres fichiers nuisibles, perturbateurs ou destructeurs\u2009;<\/li>\n<li>Ajouter du contenu qui exprime ou sous-entend faussement que ce contenu est sponsoris\u00e9 ou approuv\u00e9 par nous\u2009;<\/li>\n<li>Ajouter du contenu qui, \u00e0 notre seul jugement, (a) viole les sous-sections pr\u00e9c\u00e9dentes, (b) est r\u00e9pr\u00e9hensible, (c) restreint ou emp\u00eache toute autre personne d\u2019utiliser ou de profiter du site Web, ou (d) peut nous exposer, ainsi que nos affili\u00e9s, utilisateurs ou toute personne li\u00e9e \u00e0 nous, \u00e0 un pr\u00e9judice ou \u00e0 une responsabilit\u00e9 de quelque nature que ce soit.<\/li>\n<\/ul>\n<ol>\n<li>Nous d\u00e9clinons toute responsabilit\u00e9 et n\u2019assumons aucune responsabilit\u00e9 pour tout contenu publi\u00e9, stock\u00e9 ou t\u00e9l\u00e9charg\u00e9 par vous ou tout autre tiers, ni pour toute perte ou pour tout dommage qui en d\u00e9coulerait. De plus, nous ne sommes pas responsables des erreurs, diffamations, calomnies, injures, omissions, mensonges, obsc\u00e9nit\u00e9s, pornographie, vulgarit\u00e9 ou tout autre contenu r\u00e9pr\u00e9hensible que vous pourriez rencontrer.<\/li>\n<li>En tant que fournisseurs de ce site Web, nous ne sommes pas responsables des d\u00e9clarations, repr\u00e9sentations ou contenus fournis par ses utilisateurs sur le site. Bien que nous n\u2019ayons aucune obligation de filtrer, modifier ou surveiller les contenus publi\u00e9s ou distribu\u00e9s via le site Web, nous nous r\u00e9servons le droit, \u00e0 notre enti\u00e8re discr\u00e9tion, d\u2019examiner le contenu avant ou apr\u00e8s sa publication, d\u2019emp\u00eacher la publication de contenu inappropri\u00e9 ou autrement inad\u00e9quat ou erron\u00e9, ou de retirer ce contenu apr\u00e8s sa publication, si nous le jugeons n\u00e9cessaire (m\u00eame si ce contenu ne viole pas les pr\u00e9sentes conditions d\u2019utilisation). Cependant, nous n\u2019exer\u00e7ons g\u00e9n\u00e9ralement pas notre droit de surveiller le contenu et ne le faisons que dans de rares cas.<\/li>\n<li>Nous conservons notre enti\u00e8re discr\u00e9tion pour d\u00e9terminer quel contenu sera publi\u00e9, la dur\u00e9e de sa publication, son emplacement, son design et tout autre aspect li\u00e9 \u00e0 la publication de contenu sur le site Web. Nous ne garantissons pas que tout le contenu sera publi\u00e9, en g\u00e9n\u00e9ral, ou pour une dur\u00e9e limit\u00e9e.<\/li>\n<li>Si vous constatez une atteinte \u00e0 votre marque ou \u00e0 la n\u00f4tre, \u00e0 votre contenu ou \u00e0 l\u2019un de vos droits, veuillez nous en informer par email \u00e0 l\u2019adresse\u00a0<a href=\"mailto:support@99bitcoins.com\">support@99bitcoins.com<\/a>.<\/li>\n<li>Toute utilisation du site contraire aux dispositions ci-dessus constitue une violation et peut entra\u00eener, entre autres, la r\u00e9siliation ou la suspension de vos droits d\u2019utilisation du site ou d\u2019y r\u00e9pondre.<\/li>\n<\/ol>\n<p><strong>PAIEMENT DES SERVICES ET SERVICES RESTREINTS<\/strong><\/p>\n<ol>\n<li>Nous nous r\u00e9servons le droit de transformer toute partie ou tout service du site en un service payant, limitant ainsi l\u2019acc\u00e8s \u00e0 certaines sections du site, sauf si une certaine redevance (d\u00e9taill\u00e9e sur le site) nous est pay\u00e9e.<\/li>\n<li>Nous nous r\u00e9servons \u00e9galement le droit de restreindre l\u2019acc\u00e8s \u00e0 d\u2019autres parties du site, ou au site entier, \u00e0 notre discr\u00e9tion.<\/li>\n<\/ol>\n<p><strong>DROITS D\u2019AUTEUR ET PROPRI\u00c9T\u00c9 INTELLECTUELLE<\/strong><\/p>\n<ol>\n<li>Tous les droits de propri\u00e9t\u00e9 intellectuelle relatifs au site, y compris les articles, textes, graphiques et autres \u0153uvres, tels que les droits d\u2019auteur, les marques, etc., sont notre propri\u00e9t\u00e9 exclusive ou sont sous licence. Le site est prot\u00e9g\u00e9, entre autres, par la loi isra\u00e9lienne sur les droits d\u2019auteur de 2007 (Israeli Copyright Law, 2017), la loi singapourienne sur les droits d\u2019auteur de 2006 (Singapore Copyright Act, 2006) ou par les dispositions de toute autre loi pertinente en Isra\u00ebl, \u00e0 Singapour et \u00e0 l\u2019\u00e9tranger.<\/li>\n<li>Il est strictement interdit de copier, distribuer, afficher publiquement, offrir au public, transf\u00e9rer au public, modifier, adapter, traiter, cr\u00e9er des \u0153uvres d\u00e9riv\u00e9es, vendre, louer ou utiliser de toute autre mani\u00e8re, sauf pour une consultation priv\u00e9e, toute partie du site, de quelque mani\u00e8re ou moyen que ce soit, sans notre consentement \u00e9crit pr\u00e9alable.<\/li>\n<\/ol>\n<p><strong>LIMITATION DE RESPONSABILIT\u00c9 ET GARANTIE<\/strong><\/p>\n<ol>\n<li>LE CONTENU DU SITE WEB, AINSI QUE TOUTE INFORMATION, PRODUIT OU SERVICE PUBLI\u00c9 SUR LE SITE, PEUT CONTENIR DES INEXACTITUDES OU DES ERREURS. NOUS NE GARANTISSONS PAS L\u2019EXACTITUDE DE CES INFORMATIONS ET D\u00c9CLINONS TOUTE RESPONSABILIT\u00c9 POUR LES ERREURS OU AUTRES INEXACTITUDES RELATIVES AUX INFORMATIONS ET DESCRIPTIONS AFFICH\u00c9ES SUR LE SITE. CES ERREURS ET OMISSIONS SONT INH\u00c9RENTES \u00c0 TOUT SERVICE COMMUNAUTAIRE BAS\u00c9 SUR LES CONTRIBUTIONS DES UTILISATEURS ET SUR LES INFORMATIONS FOURNIES PAR EUX. LE SITE VOUS EST PROPOS\u00c9 \u00ab\u2009TEL QUEL\u2009\u00bb ET NE DOIT PAS \u00caTRE UTILIS\u00c9 \u00c0 D\u2019AUTRES FINS QUE POUR UNE LECTURE G\u00c9N\u00c9RALE PERSONNELLE (ET SURTOUT PAS COMME BASE POUR UN INVESTISSEMENT DANS LE BITCOIN OU DANS TOUTE AUTRE TECHNOLOGIE, PRODUIT OU \u00c9L\u00c9MENT D\u00c9CRIT ICI).<\/li>\n<li>NOUS NE FAISONS AUCUNE D\u00c9CLARATION QUANT \u00c0 L\u2019AD\u00c9QUATION DES INFORMATIONS, CONTENUS, DONN\u00c9ES, PRODUITS ET SERVICES CONTENUS SUR LE SITE POUR QUELQUE USAGE QUE CE SOIT, ET L\u2019INCLUSION OU L\u2019OFFRE DE TOUT PRODUIT OU SERVICE SUR LE SITE NE CONSTITUE PAS UNE APPROBATION OU UNE RECOMMANDATION DE CES PRODUITS OU SERVICES PAR NOUS. TOUS CES \u00c9L\u00c9MENTS SONT FOURNIS \u00ab\u2009EN L\u2019\u00c9TAT\u2009\u00bb ET \u00ab\u2009SELON DISPONIBILIT\u00c9\u2009\u00bb, SANS AUCUNE GARANTIE D\u2019AUCUNE SORTE. NOUS D\u00c9CLINONS TOUTES GARANTIES ET CONDITIONS QUE LE SITE, SES SERVEURS OU TOUT EMAIL ENVOY\u00c9 PAR NOUS SONT EXEMPTS DE VIRUS OU D\u2019AUTRES COMPOSANTS NUISIBLES. NOUS D\u00c9CLINONS PAR LA PR\u00c9SENTE TOUTES GARANTIES ET CONDITIONS CONCERNANT CES INFORMATIONS, LOGICIELS, PRODUITS, DONN\u00c9ES, \u0152UVRES ET SERVICES, Y COMPRIS TOUTES LES GARANTIES IMPLICITES DE QUALIT\u00c9 MARCHANDE, D\u2019AD\u00c9QUATION \u00c0 UN USAGE PARTICULIER, DE TITRE ET DE NON-VIOLATION.<\/li>\n<li>EN AUCUN CAS, NOUS (NOS DIRIGEANTS, ADMINISTRATEURS ET AFFILI\u00c9S) NE SERONS RESPONSABLES DES DOMMAGES DIRECTS, INDIRECTS, PUNITIFS, ACCESSOIRES, SP\u00c9CIAUX OU CONS\u00c9CUTIFS R\u00c9SULTANT DE, OU EN RELATION AVEC, VOTRE ACC\u00c8S, AFFICHAGE OU UTILISATION DU SITE OU AVEC LE RETARD OU L\u2019INCAPACIT\u00c9 D\u2019ACC\u00c9DER, D\u2019AFFICHER OU D\u2019UTILISER LE SITE (Y COMPRIS, MAIS SANS S\u2019Y LIMITER, VOTRE CONFIANCE DANS LES OPINIONS APPARAISSANT SUR LE SITE\u2009; TOUT VIRUS INFORMATIQUE, INFORMATION, LOGICIEL, SITES LI\u00c9S, PRODUITS ET SERVICES OBTENUS VIA LE SITE\u2009; OU AUTREMENT D\u00c9COULANT DE L\u2019ACC\u00c8S, DE L\u2019AFFICHAGE OU DE L\u2019UTILISATION DU SITE), QU\u2019ILS SOIENT BAS\u00c9S SUR UNE TH\u00c9ORIE DE LA N\u00c9GLIGENCE, DU CONTRAT, DU D\u00c9LIT, DE LA RESPONSABILIT\u00c9 STRICTE, OU AUTRE, M\u00caME SI LE COMPARANT A \u00c9T\u00c9 INFORM\u00c9 DE LA POSSIBILIT\u00c9 DE TELS DOMMAGES.<\/li>\n<li>EN TOUT \u00c9TAT DE CAUSE, VOTRE SEUL RECOURS SE LIMITERA \u00c0 LA CORRECTION DE CES ERREURS OU DYSFONCTIONNEMENTS, EN FONCTION DES CIRCONSTANCES PERTINENTES.<\/li>\n<li>De plus, sans d\u00e9roger \u00e0 la clause ci-dessus, nous ne serons pas responsables d\u2019aucune forme de responsabilit\u00e9 d\u00e9coulant de votre confiance dans le contenu des informations commerciales publi\u00e9es sur le site ou en lien avec l\u2019utilisation de ce contenu.<\/li>\n<li>Cette limitation de responsabilit\u00e9 refl\u00e8te la r\u00e9partition des risques entre les parties. Les limitations sp\u00e9cifi\u00e9es dans cette section resteront en vigueur et s\u2019appliqueront, m\u00eame si un recours limit\u00e9 sp\u00e9cifi\u00e9 dans les pr\u00e9sentes conditions d\u2019utilisation \u00e9chouait dans son objectif essentiel.<\/li>\n<\/ol>\n<p><strong>LIENS ET INFORMATIONS COMMERCIALES DANS LE LOGICIEL<\/strong><\/p>\n<ol>\n<li>Nous pouvons int\u00e9grer des publicit\u00e9s et\/ou des informations de nature commerciale sur le site Web. Ces informations peuvent provenir de nous ou de tiers. Nous ne pouvons pas garantir leur fiabilit\u00e9 ou leur exactitude. Il est soulign\u00e9 que la publicit\u00e9 ou la publication de contenu commercial par nous ne constitue ni une recommandation ni une incitation \u00e0 acheter les biens ou services annonc\u00e9s.<\/li>\n<li>Dans la mesure o\u00f9 le site Web inclut des liens vers des services ou des applications qui ne sont pas exploit\u00e9s ou g\u00e9r\u00e9s par nous, nous ne serons pas responsables des cons\u00e9quences d\u00e9coulant de votre confiance en ces services et applications ou en lien avec leur contenu, y compris, mais sans s\u2019y limiter, leurs exhaustivit\u00e9, exactitude, correction ou mise \u00e0 jour. Nous ne serons pas responsables des dommages directs ou indirects, financiers ou autres, r\u00e9sultant de votre utilisation ou de votre confiance dans le contenu des services auxquels vous avez acc\u00e9d\u00e9 via des liens sur le site Web.<\/li>\n<\/ol>\n<p><strong>MODIFICATIONS DU SITE WEB<\/strong><\/p>\n<ol>\n<li>Nous pouvons, en totalit\u00e9 ou en partie et sans obligation de pr\u00e9avis, modifier, adapter ou changer le site Web (ou son contenu), ainsi que la port\u00e9e et la disponibilit\u00e9 de ses contenus, ou tout autre aspect li\u00e9 au site. Vous ne pourrez pas formuler de r\u00e9clamation, plainte ou demande d\u2019explication \u00e0 notre encontre pour l\u2019application de ces modifications ou pour les \u00e9ventuels probl\u00e8mes qui en d\u00e9coulent.<\/li>\n<\/ol>\n<p><strong>R\u00c9SILIATION DU SERVICE<\/strong><\/p>\n<ol>\n<li>Vous pouvez renoncer \u00e0 votre utilisation du site Web \u00e0 tout moment et pour toute raison, sans obligation d\u2019informer le site de cette r\u00e9siliation.<\/li>\n<li>Nous pouvons, \u00e0 tout moment, suspendre ou mettre fin \u00e0 la fourniture du site Web, enti\u00e8rement ou partiellement, temporairement ou d\u00e9finitivement, \u00e0 notre seule discr\u00e9tion.<\/li>\n<\/ol>\n<p><strong>LOI APPLICABLE ET JURIDICTION<\/strong><\/p>\n<ol>\n<li>Les pr\u00e9sentes conditions d\u2019utilisation seront r\u00e9gies uniquement par les lois de Singapour, sans tenir compte des principes de conflit de lois. Tout litige, r\u00e9clamation ou controverse d\u00e9coulant ou li\u00e9 aux pr\u00e9sentes conditions d\u2019utilisations, au site Web ou \u00e0 son contenu sera soumis \u00e0 la juridiction exclusive des tribunaux comp\u00e9tents de Singapour.<\/li>\n<\/ol>\n<p><strong>RESTRICTIONS<\/strong><\/p>\n<ol>\n<li>Si vous souhaitez engager une proc\u00e9dure judiciaire contre nous, d\u00e9coulant de votre acc\u00e8s ou utilisation du site Web, vous devez le faire dans un d\u00e9lai de deux (2) ans \u00e0 compter du jour o\u00f9 vous avez pris connaissance de la cause d\u2019action. Le non-respect de ce d\u00e9lai entra\u00eenera l\u2019extinction d\u00e9finitive de la cause d\u2019action, limitera votre r\u00e9clamation et constituera votre renonciation totale et d\u00e9finitive \u00e0 l\u2019action en justice.<\/li>\n<\/ol>\n<p><strong>CONDITIONS D\u2019UTILISATION COMPL\u00c8TES<\/strong><\/p>\n<ol>\n<li>Les pr\u00e9sentes conditions d\u2019utilisation, ainsi que notre <a href=\"https:\/\/99bitcoins.com\/privacy-policy\/\">Politique de confidentialit\u00e9<\/a> (qui est int\u00e9gr\u00e9e ici), constituent l\u2019int\u00e9gralit\u00e9 de l\u2019accord qui existe entre vous et nous pour l\u2019utilisation du site Web.<\/li>\n<li>Si une partie des pr\u00e9sentes conditions est jug\u00e9e invalide ou inapplicable selon la l\u00e9gislation en vigueur, y compris, mais sans s\u2019y limiter, les exclusions de garantie et les limitations de responsabilit\u00e9 mentionn\u00e9es ci-dessus, la disposition invalide ou inapplicable sera remplac\u00e9e par une disposition valide et applicable qui refl\u00e8te au mieux l\u2019intention de la disposition originale, et les autres dispositions resteront en vigueur.<\/li>\n<\/ol>\n<p><strong>CESSION<\/strong><\/p>\n<ol>\n<li>Nous pouvons transf\u00e9rer, sous-traiter ou autrement g\u00e9rer nos droits et\/ou obligations en vertu des pr\u00e9sentes conditions d\u2019utilisation (ci-apr\u00e8s \u00ab\u2009<strong>Transf\u00e9r\u00e9s<\/strong>\u2009\u00bb) sans vous en informer ou obtenir votre consentement. De plus, tout contenu ou base de donn\u00e9es se rapportant au site Web peut \u00eatre transf\u00e9r\u00e9 \u00e0 des tiers de notre choix, et en utilisant le site Web, vous acceptez cela.<\/li>\n<\/ol>\n<p><strong>NOUS CONTACTER<\/strong><\/p>\n<ol>\n<li>Vous pouvez nous contacter pour toute question li\u00e9e au site Web via la page \u00ab\u2009Contactez-nous\u2009\u00bb du site Web ou en utilisant cette adresse email\u00a0: <a href=\"mailto:support@99bitcoins.com\">support@99bitcoins.com<\/a>. Nous ferons de notre mieux pour r\u00e9pondre rapidement \u00e0 votre demande.<\/li>\n<\/ol>\n<h2><strong>PROTECTION DES DONN\u00c9ES<\/strong><\/h2>\n<p>En ce qui concerne les donn\u00e9es collect\u00e9es sur ce site Web, 99bitcoins.com est le contr\u00f4leur des donn\u00e9es.<\/p>\n<p><strong>Protection des donn\u00e9es personnelles<\/strong><\/p>\n<p>99bitcoins.com prend la protection et la s\u00e9curit\u00e9 des donn\u00e9es personnelles tr\u00e8s au s\u00e9rieux et traitera ces informations conform\u00e9ment \u00e0 la l\u00e9gislation sur la protection des donn\u00e9es en vigueur et au pr\u00e9sent accord. Pour fournir les services, 99bitcoins.com peut traiter des donn\u00e9es personnelles concernant les utilisateurs et d\u2019autres personnes acc\u00e9dant aux services.<\/p>\n<p>L\u2019utilisation du service est \u00e9galement r\u00e9gie par la Politique de Confidentialit\u00e9 de 99bitcoins.com. Veuillez consulter notre Politique de Confidentialit\u00e9, qui contient des informations importantes sur la mani\u00e8re dont nous collectons, traitons et utilisons vos donn\u00e9es personnelles en relation avec les services. La politique de confidentialit\u00e9 est disponible ici\u00a0:<\/p>\n<p><a href=\"https:\/\/99bitcoins.com\/fr\/politique-de-confidentialite\/\">https:\/\/99bitcoins.com\/fr\/politique-de-confidentialite\/<\/a>.<\/p>\n<p>Les \u00ab\u2009donn\u00e9es personnelles\u2009\u00bb sont des informations se rapportant \u00e0 une personne physique identifi\u00e9e ou identifiable.<\/p>\n<p>LES DIFF\u00c9RENTS TYPES DE DONN\u00c9ES PERSONNELLES QUE NOUS COLLECTONS ET UTILISONS\u00a0:<\/p>\n<ul>\n<li>email et adresse Bitcoin publique<\/li>\n<li>Informations techniques (adresse IP, syst\u00e8me d\u2019exploitation et type de navigateur)<\/li>\n<\/ul>\n<p>99bitcoins.com peut d\u00e9signer un sous-traitant pour traiter les donn\u00e9es personnelles dans le cadre de cet accord (les Donn\u00e9es prot\u00e9g\u00e9es) et veillera \u00e0 ce que ce sous-traitant soit soumis aux m\u00eames obligations relatives aux Donn\u00e9es prot\u00e9g\u00e9es que celles \u00e9nonc\u00e9es dans cette clause.<\/p>\n<p>Sans pr\u00e9judice de la g\u00e9n\u00e9ralit\u00e9 de cette clause, concernant les Donn\u00e9es prot\u00e9g\u00e9es divulgu\u00e9es \u00e0 99bitcoins.com dans le cadre de cet accord (qu\u2019elles soient divulgu\u00e9es par le Client, les personnes concern\u00e9es ou autrement), 99bitcoins.com veillera \u00e0 ce qu\u2019elle\u00a0:<\/p>\n<ul>\n<li>Respecte enti\u00e8rement les principes de protection des donn\u00e9es dans le traitement des Donn\u00e9es prot\u00e9g\u00e9es\u2009;<\/li>\n<li>Ne traite les Donn\u00e9es prot\u00e9g\u00e9es que pour les finalit\u00e9s notifi\u00e9es par le Client et\/ou les personnes concern\u00e9es\u2009;<\/li>\n<li>Suit les proc\u00e9dures et politiques convenues par les Parties le cas \u00e9ch\u00e9ant\u2009;<\/li>\n<li>Ne transf\u00e9rera pas les Donn\u00e9es prot\u00e9g\u00e9es (ni une partie de celles-ci) en dehors de l\u2019Espace \u00e9conomique europ\u00e9en sans une protection ad\u00e9quate\u2009;<\/li>\n<li>Maintienne des mesures techniques et organisationnelles appropri\u00e9es (y compris, mais sans s\u2019y limiter, des politiques appropri\u00e9es communiqu\u00e9es aux employ\u00e9s, la gestion et la r\u00e9vision de la conformit\u00e9 continue et des mesures de s\u00e9curit\u00e9 efficaces) pour prot\u00e9ger convenablement les Donn\u00e9es personnelles contre la destruction, la perte, l\u2019alt\u00e9ration, la divulgation non autoris\u00e9e ou l\u2019acc\u00e8s non autoris\u00e9 aux Donn\u00e9es personnelles.<\/li>\n<\/ul>\n<p>99bitcoins.com dispose d\u2019un programme de protection de l\u2019information (\u00ab\u2009Programme de S\u00e9curit\u00e9\u2009\u00bb) comprenant des mesures administratives, techniques et physiques adapt\u00e9es \u00e0 sa taille et \u00e0 sa complexit\u00e9, ainsi qu\u2019\u00e0 la nature et \u00e0 l\u2019\u00e9tendue de ses activit\u00e9s et \u00e0 la sensibilit\u00e9 des donn\u00e9es clients transmises ou re\u00e7ues dans le cadre de cet accord.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue sur 99bitcoins.com (le \u00ab\u2009Site Web\u2009\u00bb). Le site Web est fourni uniquement \u00e0 des fins d\u2019information et ne doit pas \u00eatre utilis\u00e9 comme base pour un investissement ou pour d\u2019autres fins. Les termes \u00ab\u2009nous\u2009\u00bb, \u00ab\u2009notre\u2009\u00bb et \u00ab\u200999btc\u2009\u00bb font r\u00e9f\u00e9rence \u00e0 99 Bitcoins Inc., enregistr\u00e9e \u00e0 Marshall Islands, aux op\u00e9rateurs du site Web ou \u00e0 toute..<\/p>\n","protected":false},"author":135978,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-61","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conditions d&#039;utilisation du site 99Bitcoins FR<\/title>\n<meta name=\"description\" content=\"La consultation et l&#039;utilisation du site web 99Bitcoins France sont r\u00e9gies par des conditions sp\u00e9cifiques, expliqu\u00e9es dans ce pr\u00e9sent article\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conditions d&#039;utilisation du site 99Bitcoins FR\" \/>\n<meta property=\"og:description\" content=\"La consultation et l&#039;utilisation du site web 99Bitcoins France sont r\u00e9gies par des conditions sp\u00e9cifiques, expliqu\u00e9es dans ce pr\u00e9sent article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins FR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-15T11:33:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/conditions-dutilisation\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/conditions-dutilisation\\\/\",\"name\":\"Conditions d'utilisation du site 99Bitcoins FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\"},\"datePublished\":\"2024-08-09T08:23:57+00:00\",\"dateModified\":\"2025-04-15T11:33:51+00:00\",\"description\":\"La consultation et l'utilisation du site web 99Bitcoins France sont r\u00e9gies par des conditions sp\u00e9cifiques, expliqu\u00e9es dans ce pr\u00e9sent article\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/conditions-dutilisation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/conditions-dutilisation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/conditions-dutilisation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conditions d&#8217;utilisation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"name\":\"99bitcoins FR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions d'utilisation du site 99Bitcoins FR","description":"La consultation et l'utilisation du site web 99Bitcoins France sont r\u00e9gies par des conditions sp\u00e9cifiques, expliqu\u00e9es dans ce pr\u00e9sent article","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/","og_locale":"fr_FR","og_type":"article","og_title":"Conditions d'utilisation du site 99Bitcoins FR","og_description":"La consultation et l'utilisation du site web 99Bitcoins France sont r\u00e9gies par des conditions sp\u00e9cifiques, expliqu\u00e9es dans ce pr\u00e9sent article","og_url":"https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/","og_site_name":"99bitcoins FR","article_modified_time":"2025-04-15T11:33:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/","url":"https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/","name":"Conditions d'utilisation du site 99Bitcoins FR","isPartOf":{"@id":"https:\/\/99bitcoins.com\/fr\/#website"},"datePublished":"2024-08-09T08:23:57+00:00","dateModified":"2025-04-15T11:33:51+00:00","description":"La consultation et l'utilisation du site web 99Bitcoins France sont r\u00e9gies par des conditions sp\u00e9cifiques, expliqu\u00e9es dans ce pr\u00e9sent article","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/fr\/conditions-dutilisation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Conditions d&#8217;utilisation"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/fr\/#website","url":"https:\/\/99bitcoins.com\/fr\/","name":"99bitcoins FR","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/fr\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/pages\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/users\/135978"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/comments?post=61"}],"version-history":[{"count":4,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/pages\/61\/revisions"}],"predecessor-version":[{"id":4128,"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/pages\/61\/revisions\/4128"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/fr\/wp-json\/wp\/v2\/media?parent=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}