{"id":135891,"name":"Melissa Camacho","url":"","description":"Melissa es una escritora con casi una d\u00e9cada analizando los mercados de criptomonedas y acciones para distintos medios impresos y audiovisuales en Am\u00e9rica Latina, Estados Unidos y Espa\u00f1a, con acercamiento al universo de las inversiones minoristas en el apartado tecnol\u00f3gico. Graduada de Comunicadora Social, menci\u00f3n Periodismo Impreso, de la Universidad Santa Mar\u00eda de Caracas, Venezuela, ha hecho \u00e9nfasis en su carrera a la econom\u00eda blockchain y a su impacto en el\u00a0mundo\u00a0moderno.","link":"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/","slug":"marimelissamc","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=96&d=mm&r=g"},"meta":[],"acf":{"upload_avatar":196,"custom_author_title":"","custom_author_label":"","custom_author_fact_checker_label":"","enable_profile_page_schema":false,"profile_page_same_as_urls":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Melissa Camacho, Autor en 99bitcoins ES<\/title>\n<meta name=\"description\" content=\"Todo el contenido de Melissa Camacho en 99bitcoins ES.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Melissa Camacho, Autor en 99bitcoins ES\" \/>\n<meta property=\"og:description\" content=\"Todo el contenido de Melissa Camacho en 99bitcoins ES.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/marimelissamc\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/marimelissamc\\\/\",\"name\":\"Melissa Camacho, Autor en 99bitcoins ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"description\":\"Todo el contenido de Melissa Camacho en 99bitcoins ES.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/marimelissamc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/marimelissamc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/marimelissamc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivos para Melissa Camacho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/03cf2d30b7af07854de778050e846511\",\"name\":\"Melissa Camacho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=96&d=mm&r=g\",\"caption\":\"Melissa Camacho\"},\"description\":\"Melissa es una escritora con casi una d\u00e9cada analizando los mercados de criptomonedas y acciones para distintos medios impresos y audiovisuales en Am\u00e9rica Latina, Estados Unidos y Espa\u00f1a, con acercamiento al universo de las inversiones minoristas en el apartado tecnol\u00f3gico. Graduada de Comunicadora Social, menci\u00f3n Periodismo Impreso, de la Universidad Santa Mar\u00eda de Caracas, Venezuela, ha hecho \u00e9nfasis en su carrera a la econom\u00eda blockchain y a su impacto en el\u00a0mundo\u00a0moderno.\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/marimelissamc\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Melissa Camacho, Autor en 99bitcoins ES","description":"Todo el contenido de Melissa Camacho en 99bitcoins ES.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/","og_locale":"es_ES","og_type":"profile","og_title":"Melissa Camacho, Autor en 99bitcoins ES","og_description":"Todo el contenido de Melissa Camacho en 99bitcoins ES.","og_url":"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/","og_site_name":"99bitcoins ES","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/","url":"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/","name":"Melissa Camacho, Autor en 99bitcoins ES","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"description":"Todo el contenido de Melissa Camacho en 99bitcoins ES.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Archivos para Melissa Camacho"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/03cf2d30b7af07854de778050e846511","name":"Melissa Camacho","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e05b2b08ceddf91c5fd4c1ae726e67db810b42905dc1bd2593c4cbab0220a005?s=96&d=mm&r=g","caption":"Melissa Camacho"},"description":"Melissa es una escritora con casi una d\u00e9cada analizando los mercados de criptomonedas y acciones para distintos medios impresos y audiovisuales en Am\u00e9rica Latina, Estados Unidos y Espa\u00f1a, con acercamiento al universo de las inversiones minoristas en el apartado tecnol\u00f3gico. Graduada de Comunicadora Social, menci\u00f3n Periodismo Impreso, de la Universidad Santa Mar\u00eda de Caracas, Venezuela, ha hecho \u00e9nfasis en su carrera a la econom\u00eda blockchain y a su impacto en el\u00a0mundo\u00a0moderno.","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/author\/marimelissamc\/"}}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users"}]}}