{"id":34135,"date":"2026-06-20T12:00:31","date_gmt":"2026-06-20T12:00:31","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=34135"},"modified":"2026-06-20T13:50:00","modified_gmt":"2026-06-20T13:50:00","slug":"fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/","title":{"rendered":"FCA advierte a clubes de la Premier League por patrocinios crypto"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">La Autoridad de Conducta Financiera (FCA) ha enviado una carta formal de advertencia a los clubes de f\u00fatbol brit\u00e1nicos, principalmente a los de la <strong>Premier League<\/strong>, alertando que los acuerdos de patrocinio con firmas de criptomonedas y plataformas de trading internacionales no autorizadas podr\u00edan vulnerar la legislaci\u00f3n del Reino Unido.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El momento elegido no es casual: con Inglaterra, Escocia y otras naciones locales prepar\u00e1ndose para la Copa Mundial de la FIFA 2026 en Estados Unidos, M\u00e9xico y Canad\u00e1, que comienza el 11 de junio, los reguladores exigen que el problema se resuelva antes de que inicie el frenes\u00ed publicitario.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">UK FCA: Football Clubs Face Legal and Money Laundering Risks From Unauthorized Crypto Sponsors<br><br>Reuters reported that the UK Financial Conduct Authority warned Premier League and other football clubs that sponsorship deals with unauthorized crypto firms and trading platforms\u2026 <a href=\"https:\/\/t.co\/3AmIjUvlvx\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/3AmIjUvlvx<\/a><\/p>&mdash; Wu Blockchain (@WuBlockchain) <a href=\"https:\/\/x.com\/WuBlockchain\/status\/2062053988414235069?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">June 3, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El art\u00edculo analiza una tensi\u00f3n central: los clubes de f\u00fatbol necesitan ingresos por patrocinio, las empresas de criptomonedas buscan credibilidad en el mercado general y la ley de promoci\u00f3n financiera del Reino Unido se interpone directamente entre ambos.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Bajo las reglas actuales, promocionar criptoactivos a consumidores brit\u00e1nicos sin la autorizaci\u00f3n de la FCA no es solo una zona gris regulatoria; es un delito penal potencial. Adem\u00e1s, los clubes que exhiben estos logotipos podr\u00edan no estar tan protegidos de la responsabilidad legal como sus equipos jur\u00eddicos asumieron en un principio.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">F\u00fatbol en el Reino Unido: Lo que realmente dice la advertencia de la FCA<\/h2>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La advertencia de la FCA no afirma que los clubes de la <a class=\"general-link\" href=\"https:\/\/www.premierleague.com\/\" target=\"_blank\" rel=\"noopener nofollow\">Premier League<\/a> ayuden a criminales a sabiendas. En cambio, sugiere que, al asociarse con exchanges de criptomonedas offshore no autorizados, los clubes podr\u00edan estar promocionando productos financieros ilegales entre sus aficionados.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Bajo el R\u00e9gimen de Promoci\u00f3n Financiera del Reino Unido, cualquier empresa que comercialice productos financieros a consumidores brit\u00e1nicos debe estar autorizada por la FCA o contar con el respaldo de una firma autorizada. Esta regla se aplica ahora espec\u00edficamente a los criptoactivos.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Muchos exchanges que patrocinan a clubes de la Premier League tienen su sede en jurisdicciones offshore y carecen de registro en la FCA. Esto significa que mostrar sus logotipos o enlazar a sus plataformas puede constituir una promoci\u00f3n financiera no autorizada.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Lucy Castledine, de la FCA, enfatiz\u00f3 que los clubes no deben permitir que firmas no autorizadas exploten la lealtad de los fans promocionando productos potencialmente riesgosos. La FCA ha instado a los clubes a realizar una debida diligencia exhaustiva antes de firmar acuerdos de patrocinio y est\u00e1 colaborando con el gobierno y los reguladores del f\u00fatbol para mantener estos est\u00e1ndares.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">C\u00f3mo las cripto llegaron a las camisetas de la Premier League<\/h2>\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\ud83d\udea8 PREMIER LEAGUE CLUBS WARNED OVER CRYPTO SPONSORS<br><br>Britain&#39;s financial regulator warns football clubs over partnerships with crypto and trading firms not authorised to operate in Britain.<br><br>The FCA says these companies may be using club badges to promote risky products to\u2026 <a href=\"https:\/\/t.co\/Oj9l5WU41Q\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/Oj9l5WU41Q<\/a><\/p>&mdash; Coin Bureau (@coinbureau) <a href=\"https:\/\/x.com\/coinbureau\/status\/2062066387024220333?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">June 3, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Para entender la exposici\u00f3n actual de muchos clubes, es importante considerar el vac\u00edo comercial que el patrocinio de criptomonedas intent\u00f3 llenar. Tras la revisi\u00f3n de la legislaci\u00f3n sobre juegos de azar por parte del gobierno brit\u00e1nico, la Premier League acord\u00f3 eliminar gradualmente los patrocinadores de apuestas en el frente de las camisetas para el final de la temporada 2025\u201326, creando un d\u00e9ficit de ingresos.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Las empresas de criptomonedas, ansiosas por tener presencia en el mercado, llenaron r\u00e1pidamente este vac\u00edo. Para la temporada 2023\u201324, alrededor del 70% de los clubes de la Premier League ten\u00edan al menos un patrocinador de criptomonedas o de trading online. Una investigaci\u00f3n transfronteriza revel\u00f3 53 acuerdos de patrocinio que involucraban a 36 empresas de cripto en las cinco grandes ligas de Europa en una sola temporada.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Los clubes suelen actuar de buena fe, ya que muchas firmas de cripto parec\u00edan ser negocios establecidos. Sin embargo, la debida diligencia est\u00e1ndar de patrocinio no tuvo en cuenta los matices de la regulaci\u00f3n financiera del Reino Unido. Las reglas de promoci\u00f3n de <a class=\"general-link\" href=\"http:\/\/99bitcoins.com\" target=\"_blank\" rel=\"noopener\">criptomonedas<\/a> brit\u00e1nicas se centran en si las promociones llegaron a los consumidores sin autorizaci\u00f3n, independientemente de la intenci\u00f3n.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u00bfEs esto un delito? Alcance de la ley de promoci\u00f3n financiera<\/h2>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Tres partes enfrentan niveles de riesgo distintos:<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>El Exchange:<\/strong> Una firma de cripto offshore que se dirige a los consumidores del f\u00fatbol brit\u00e1nico sin autorizaci\u00f3n de la FCA enfrenta el mayor riesgo legal, ya que el regulador toma medidas activas contra plataformas no registradas, como se ha visto en casos como HTX y Justin Sun.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>El Club:<\/strong> Los clubes de f\u00fatbol pueden enfrentar responsabilidad por facilitar promociones ilegales, incluso si no las crearon ellos. Expertos legales han advertido que los patrocinios de criptomonedas conllevan riesgos regulatorios y de lavado de dinero \u00fanicos. Aunque ning\u00fan club ha enfrentado cargos todav\u00eda, la carta de la FCA indica que esto podr\u00eda cambiar.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>El Fan:<\/strong> Los seguidores que utilizan plataformas de criptomonedas promocionadas por los clubes tienen la menor exposici\u00f3n legal, pero enfrentan un riesgo financiero significativo. Si la plataforma no est\u00e1 registrada, carece de protecci\u00f3n regulatoria y ofrece opciones limitadas para recuperar fondos perdidos.<\/p>\r\n<p class=\"p1\"><b>LEE sobre los <\/b><a href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/juegos-para-ganar\/\"><span class=\"s1\"><b>juegos para ganar criptomonedas<\/b><b><\/b><\/span><\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>La FCA de Reino Unido advierte a clubes de la Premier League sobre riesgos legales por patrocinios con firmas de criptomonedas no autorizadas.<\/p>\n","protected":false},"author":135885,"featured_media":34134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[249],"tags":[7],"coin":[74],"class_list":["post-34135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-criptomonedas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FCA advierte a clubes de la Premier League por patrocinios crypto - 99bitcoins ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FCA advierte a clubes de la Premier League por patrocinios crypto - 99bitcoins ES\" \/>\n<meta property=\"og:description\" content=\"La FCA de Reino Unido advierte a clubes de la Premier League sobre riesgos legales por patrocinios con firmas de criptomonedas no autorizadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-20T12:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T13:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaume Mart\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Mart\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/\"},\"author\":{\"name\":\"Jaume Mart\u00edn\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\"},\"headline\":\"FCA advierte a clubes de la Premier League por patrocinios crypto\",\"datePublished\":\"2026-06-20T12:00:31+00:00\",\"dateModified\":\"2026-06-20T13:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/\"},\"wordCount\":825,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg\",\"keywords\":[\"Noticias Criptomonedas\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/\",\"name\":\"FCA advierte a clubes de la Premier League por patrocinios crypto - 99bitcoins ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg\",\"datePublished\":\"2026-06-20T12:00:31+00:00\",\"dateModified\":\"2026-06-20T13:50:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"FCA advierte a clubes de la Premier League por patrocinios crypto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\",\"name\":\"Jaume Mart\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"caption\":\"Jaume Mart\u00edn\"},\"description\":\"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/jaimemartin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FCA advierte a clubes de la Premier League por patrocinios crypto - 99bitcoins ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/","og_locale":"es_ES","og_type":"article","og_title":"FCA advierte a clubes de la Premier League por patrocinios crypto - 99bitcoins ES","og_description":"La FCA de Reino Unido advierte a clubes de la Premier League sobre riesgos legales por patrocinios con firmas de criptomonedas no autorizadas.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/","og_site_name":"99bitcoins ES","article_published_time":"2026-06-20T12:00:31+00:00","article_modified_time":"2026-06-20T13:50:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg","type":"image\/jpeg"}],"author":"Jaume Mart\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jaume Mart\u00edn","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/"},"author":{"name":"Jaume Mart\u00edn","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d"},"headline":"FCA advierte a clubes de la Premier League por patrocinios crypto","datePublished":"2026-06-20T12:00:31+00:00","dateModified":"2026-06-20T13:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/"},"wordCount":825,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg","keywords":["Noticias Criptomonedas"],"articleSection":["Altcoins"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/","name":"FCA advierte a clubes de la Premier League por patrocinios crypto - 99bitcoins ES","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg","datePublished":"2026-06-20T12:00:31+00:00","dateModified":"2026-06-20T13:50:00+00:00","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorsh-featured.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/fca-warns-premier-league-clubs-unauthorized-crypto-sponsorships\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/"},{"@type":"ListItem","position":4,"name":"FCA advierte a clubes de la Premier League por patrocinios crypto"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d","name":"Jaume Mart\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","caption":"Jaume Mart\u00edn"},"description":"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.","url":"https:\/\/99bitcoins.com\/es\/author\/jaimemartin\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/34135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135885"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=34135"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/34135\/revisions"}],"predecessor-version":[{"id":34422,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/34135\/revisions\/34422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/34134"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=34135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=34135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=34135"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=34135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}