{"id":34063,"date":"2026-06-17T10:00:26","date_gmt":"2026-06-17T10:00:26","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=34063"},"modified":"2026-06-17T15:21:00","modified_gmt":"2026-06-17T15:21:00","slug":"xrp-price-analysis-whale-selling-bitcoin-hyper-presale","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/","title":{"rendered":"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">El precio de XRP cotiza actualmente en torno a los $1,26, lo que representa una ca\u00edda de aproximadamente el -3,5% en las \u00faltimas 24 horas. Tras acumular una p\u00e9rdida del -6% durante la \u00faltima semana, los gr\u00e1ficos sugieren que la presi\u00f3n vendedora a\u00fan no ha terminado.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Desde el pasado fin de semana, los grupos de ballenas han estado reduciendo sus posiciones discretamente, dejando un nivel t\u00e9cnico cr\u00edtico como la \u00faltima l\u00ednea de defensa. La capacidad de los compradores para defender ese punto ser\u00e1 lo que defina el rumbo de junio.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Desde mediados de febrero, XRP ha venido dibujando m\u00e1ximos decrecientes dentro de un canal descendente. Aunque el token intent\u00f3 acercarse a la l\u00ednea media del canal tras una reciente liquidaci\u00f3n, mantenerse cerca de ese punto medio no es lo mismo que haber logrado escapar de la tendencia bajista.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Mientras tanto, los datos on-chain de los dos grupos de ballenas m\u00e1s grandes cuentan una historia preocupante: el grupo de poseedores de entre 100M y 1B de XRP redujo su participaci\u00f3n del 11,54% a aproximadamente el 9,9%. Por su parte, el grupo de entre 10M y 100M de XRP baj\u00f3 del 17,61% al 17,36%. El hecho de que ambos indicadores se muevan a la baja simult\u00e1neamente apunta a una distribuci\u00f3n generalizada del mercado y no a un \u00fanico vendedor liquidando su posici\u00f3n.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u00bfPodr\u00e1 XRP reclamar los $1,30 antes de que los osos tomen el control?<\/h2>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Seg\u00fan datos de TradingView, el precio de XRP se sit\u00faa cerca de los $1,26, con un descenso del 3,4% en las \u00faltimas 24 horas tras un inicio de mes complicado. El volumen de negociaci\u00f3n ha disminuido notablemente en comparaci\u00f3n con los picos vistos durante el reciente repunte de varias semanas, lo que reduce las probabilidades de una recuperaci\u00f3n explosiva sin un nuevo catalizador.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Los analistas t\u00e9cnicos vigilan de cerca dos niveles principales: la media m\u00f3vil exponencial (EMA) de 20 d\u00edas, situada cerca de los $1,22, y la zona de soporte psicol\u00f3gico de $1.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La historia reciente sirve de gu\u00eda: cuando XRP perdi\u00f3 su EMA de 20 d\u00edas a mediados de mayo, sufri\u00f3 una correcci\u00f3n de aproximadamente el 11%. Por el contrario, cuando recuper\u00f3 esa l\u00ednea a principios de mayo, logr\u00f3 un ascenso de casi el 11%.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se plantean tres escenarios a partir de ahora:<\/p>\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n\t<li><strong>Escenario alcista:<\/strong> Los compradores defienden firmemente los $1,25, el volumen regresa y XRP supera la resistencia de $1,30\u2013$1,40, que corresponde al m\u00e1ximo local de la semana pasada. Una ruptura confirmada por encima de esa zona abrir\u00eda el camino hacia los $2.<\/li>\r\n\t<li><strong>Escenario base:<\/strong> XRP se mantiene en un rango lateral entre $1,20 y $1,30, consolidando el movimiento reciente a la espera de un catalizador regulatorio o noticias sobre un ETF que rompa el estancamiento.<\/li>\r\n\t<li><strong>Escenario bajista:<\/strong> El nivel de $1,20 cede ante la continua presi\u00f3n de venta de las ballenas, lo que convertir\u00eda a los soportes inferiores en el nuevo foco de atenci\u00f3n.<\/li>\r\n<\/ul>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Bitcoin Hyper apunta a un crecimiento temprano mientras XRP pone a prueba niveles clave<\/h2>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La tesis a medio plazo de XRP sigue vigente: la claridad regulatoria, la posibilidad de un ETF y la narrativa de Ripple en los pagos transfronterizos son vientos de cola reales. Sin embargo, el problema es que, con una capitalizaci\u00f3n de mercado de miles de millones de d\u00f3lares, las ganancias f\u00e1ciles podr\u00edan estar ya descontadas. \u00bfHacia d\u00f3nde dirigirse cuando el potencial de subida se mide en porcentajes y no en m\u00faltiplos?<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Esa pregunta es precisamente la raz\u00f3n por la que Bitcoin Hyper ($HYPER) est\u00e1 captando una atenci\u00f3n considerable. El proyecto se posiciona como la primera Capa 2 de Bitcoin con integraci\u00f3n total de la Solana Virtual Machine (SVM), buscando ofrecer ejecuci\u00f3n de contratos inteligentes en menos de un segundo bajo la seguridad de Bitcoin, sin sacrificar una por la otra.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La preventa ya ha recaudado m\u00e1s de $32,7 millones a un precio actual de $0,013681 por $HYPER, ofreciendo adem\u00e1s recompensas por staking para los participantes iniciales.<\/p>\r\n<p class=\"p1\"><b>Los <\/b><a href=\"https:\/\/99bitcoins.com\/es\/mejores-exchanges-cripto\/exchange-sin-kyc\/\"><span class=\"s1\"><b>mejores exchanges crypto sin KYC<\/b><b><\/b><\/span><\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>XRP cotiza a $1,26 con una ca\u00edda del 3,5%. Las ballenas reducen sus tenencias mientras el mercado vigila el soporte cr\u00edtico de $1,22.<\/p>\n","protected":false},"author":135885,"featured_media":34062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[249],"tags":[7],"coin":[74],"class_list":["post-34063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-criptomonedas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas - 99bitcoins ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas - 99bitcoins ES\" \/>\n<meta property=\"og:description\" content=\"XRP cotiza a $1,26 con una ca\u00edda del 3,5%. Las ballenas reducen sus tenencias mientras el mercado vigila el soporte cr\u00edtico de $1,22.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-17T10:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T15:21:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaume Mart\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Mart\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/\"},\"author\":{\"name\":\"Jaume Mart\u00edn\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\"},\"headline\":\"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas\",\"datePublished\":\"2026-06-17T10:00:26+00:00\",\"dateModified\":\"2026-06-17T15:21:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/\"},\"wordCount\":688,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg\",\"keywords\":[\"Noticias Criptomonedas\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/\",\"name\":\"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas - 99bitcoins ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg\",\"datePublished\":\"2026-06-17T10:00:26+00:00\",\"dateModified\":\"2026-06-17T15:21:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\",\"name\":\"Jaume Mart\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"caption\":\"Jaume Mart\u00edn\"},\"description\":\"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/jaimemartin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas - 99bitcoins ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/","og_locale":"es_ES","og_type":"article","og_title":"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas - 99bitcoins ES","og_description":"XRP cotiza a $1,26 con una ca\u00edda del 3,5%. Las ballenas reducen sus tenencias mientras el mercado vigila el soporte cr\u00edtico de $1,22.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/","og_site_name":"99bitcoins ES","article_published_time":"2026-06-17T10:00:26+00:00","article_modified_time":"2026-06-17T15:21:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg","type":"image\/jpeg"}],"author":"Jaume Mart\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jaume Mart\u00edn","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/"},"author":{"name":"Jaume Mart\u00edn","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d"},"headline":"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas","datePublished":"2026-06-17T10:00:26+00:00","dateModified":"2026-06-17T15:21:00+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/"},"wordCount":688,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg","keywords":["Noticias Criptomonedas"],"articleSection":["Altcoins"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/","name":"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas - 99bitcoins ES","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg","datePublished":"2026-06-17T10:00:26+00:00","dateModified":"2026-06-17T15:21:00+00:00","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale-featured.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/xrp-price-analysis-whale-selling-bitcoin-hyper-presale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/"},{"@type":"ListItem","position":4,"name":"XRP lucha por mantener los $1,26 ante la presi\u00f3n de ballenas"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d","name":"Jaume Mart\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","caption":"Jaume Mart\u00edn"},"description":"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.","url":"https:\/\/99bitcoins.com\/es\/author\/jaimemartin\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/34063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135885"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=34063"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/34063\/revisions"}],"predecessor-version":[{"id":34385,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/34063\/revisions\/34385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/34062"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=34063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=34063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=34063"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=34063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}