{"id":34032,"date":"2026-06-16T07:11:53","date_gmt":"2026-06-16T07:11:53","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=34032"},"modified":"2026-06-16T15:20:00","modified_gmt":"2026-06-16T15:20:00","slug":"cardano-community-vetoes-two-million-dollar-summit-proposal-governance","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/","title":{"rendered":"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Los titulares de <strong>ADA<\/strong> acaban de vetar una propuesta de 7,8 millones de ADA, aproximadamente 2 millones de d\u00f3lares, destinada a financiar el <strong>Cardano Summit 2026<\/strong> en Singapur. Tras la votaci\u00f3n, la <strong>Fundaci\u00f3n Cardano<\/strong> ha confirmado que el evento queda oficialmente cancelado.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Este resultado trasciende la importancia de una simple conferencia. Representa la prueba real m\u00e1s clara hasta la fecha de que la transici\u00f3n de <strong>Cardano<\/strong> hacia una gobernanza on-chain tiene un impacto directo y vinculante en el ecosistema.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">C\u00f3mo el voto comunitario detuvo la propuesta de $2 millones<\/h2>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La propuesta se gestion\u00f3 a trav\u00e9s de <strong>Intersect<\/strong>, la organizaci\u00f3n basada en miembros que administra los procesos de gobernanza de <strong>Cardano<\/strong>, y solicitaba al tesoro de la red los fondos para organizar su cumbre insignia.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El requerimiento ascend\u00eda a 7,8 millones de ADA, valorados en unos 2 millones de d\u00f3lares al momento de la votaci\u00f3n. El objetivo era realizar un evento de alta visibilidad, el tipo de escaparate que otros proyectos de blockchain suelen financiar sin mayores cuestionamientos.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Governance requires not only participation, but also a commitment to accept collective decisions. The Cardano community has spoken and we respect the outcome.<br><br>Following the outcome of the Treasury proposal votes, the Cardano Foundation&#39;s proposed Cardano Summit 2026, will not\u2026<\/p>&mdash; Cardano Foundation (@Cardano_CF) <a href=\"https:\/\/x.com\/Cardano_CF\/status\/2060730272400732255?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">May 30, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Bajo las reglas de gobernanza de la era <strong>Voltaire<\/strong>, el gasto del tesoro requiere la aprobaci\u00f3n de los holders de ADA y de sus Representantes Descentralizados (<strong>DReps<\/strong>). Los informes indican que cerca del 65% de los votantes participantes apoyaron la propuesta, una mayor\u00eda bajo est\u00e1ndares comunes, pero insuficiente en este sistema.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Los umbrales de aprobaci\u00f3n de <strong>Cardano<\/strong> son deliberadamente altos y la propuesta no logr\u00f3 superar la barrera necesaria. El veto es definitivo.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Este no es un caso aislado. Otra solicitud del tesoro por 33 millones de ADA, destinada a la investigaci\u00f3n de resistencia cu\u00e1ntica para el proyecto <strong>Leios<\/strong>, fue rechazada por el 86% de los votantes. Las propuestas de gasto a gran escala enfrentan ahora un escrutinio riguroso, lo que marca un patr\u00f3n claro y no un simple voto de protesta puntual.<\/p>\r\n<p class=\"p1\"><b>LEE <\/b><a href=\"https:\/\/99bitcoins.com\/es\/guias\/como-comprar-hyperliquid\/\"><span class=\"s1\"><b>c\u00f3mo comprar Hyperliquid<\/b><b><\/b><\/span><\/a><\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Opiniones divididas: los argumentos de ambas partes<\/h2>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Quienes se opusieron a la propuesta del summit presentaron un argumento s\u00f3lido: 2 millones de d\u00f3lares es una cifra elevada para un solo evento, y el retorno de inversi\u00f3n para el ecosistema general de <strong>Cardano<\/strong> no fue demostrado con claridad.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Varios miembros de la comunidad expresaron su preferencia por dirigir los fondos del tesoro hacia el desarrollo t\u00e9cnico central en lugar de exhibiciones de marketing. El razonamiento de fondo es que los holders de ADA deben actuar como una junta directiva disciplinada y no como un mero tr\u00e1mite de aprobaci\u00f3n autom\u00e1tica.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">This is sad, because 1.8% decided that we cannot show our tech to all the devs\/businesses\/vcs with a dedicated event this year. As i have already booked my flight and hotel last year, i will still be around in Singapore for the Token2049 and Sideevents. <br><br>Who else is still in\u2026 <a href=\"https:\/\/t.co\/G76UP2u6ny\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/G76UP2u6ny<\/a><\/p>&mdash; ATADA \/ ATAD2 Cardano StakePool Austria (@ATADA_Stakepool) <a href=\"https:\/\/x.com\/ATADA_Stakepool\/status\/2060767494814450021?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">May 30, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Por otro lado, los defensores de la propuesta argumentaron que la visibilidad es crucial en el sector cripto. Un evento de este nivel genera prensa, atrae desarrolladores y se\u00f1ala que el ecosistema est\u00e1 activo y en crecimiento. Al cancelarlo, advierten, se corre el riesgo de que <strong>Cardano<\/strong> parezca un proyecto incapaz de organizar una presentaci\u00f3n de impacto internacional.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Las presiones externas sobre el ecosistema, incluyendo el escrutinio regulatorio y la competencia en el sector <strong>DeFi<\/strong>, a\u00f1aden peso a esta preocupaci\u00f3n, sugiriendo que el proyecto no puede permitirse pasar desapercibido.<\/p>\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Charles Hoskinson<\/strong> ha declarado p\u00fablicamente que los holders de ADA no son espectadores pasivos, sino participantes activos en un sistema de gobernanza dise\u00f1ado para ser cuestionado. El voto refleja precisamente ese dise\u00f1o; si el resultado es una pol\u00edtica sabia o una precauci\u00f3n costosa, depende de a qui\u00e9n se le pregunte.<\/p>\r\n<p class=\"p1\"><span class=\"s1\"><a href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/telegram\/\"><b>Telegram criptomonedas<\/b><b><\/b><\/a><\/span><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>La comunidad de Cardano rechaza una propuesta de 7.8 millones de ADA para el Summit 2026, reafirmando el control de los holders sobre el tesoro.<\/p>\n","protected":false},"author":135885,"featured_media":34029,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[249],"tags":[7],"coin":[74],"class_list":["post-34032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-criptomonedas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunidad Cardano veta presupuesto de $2M para cumbre de 2026 - 99bitcoins ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026 - 99bitcoins ES\" \/>\n<meta property=\"og:description\" content=\"La comunidad de Cardano rechaza una propuesta de 7.8 millones de ADA para el Summit 2026, reafirmando el control de los holders sobre el tesoro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-16T07:11:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T15:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaume Mart\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Mart\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/\"},\"author\":{\"name\":\"Jaume Mart\u00edn\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\"},\"headline\":\"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026\",\"datePublished\":\"2026-06-16T07:11:53+00:00\",\"dateModified\":\"2026-06-16T15:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/\"},\"wordCount\":590,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg\",\"keywords\":[\"Noticias Criptomonedas\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/\",\"name\":\"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026 - 99bitcoins ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg\",\"datePublished\":\"2026-06-16T07:11:53+00:00\",\"dateModified\":\"2026-06-16T15:20:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\",\"name\":\"Jaume Mart\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"caption\":\"Jaume Mart\u00edn\"},\"description\":\"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/jaimemartin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026 - 99bitcoins ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/","og_locale":"es_ES","og_type":"article","og_title":"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026 - 99bitcoins ES","og_description":"La comunidad de Cardano rechaza una propuesta de 7.8 millones de ADA para el Summit 2026, reafirmando el control de los holders sobre el tesoro.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/","og_site_name":"99bitcoins ES","article_published_time":"2026-06-16T07:11:53+00:00","article_modified_time":"2026-06-16T15:20:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg","type":"image\/jpeg"}],"author":"Jaume Mart\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jaume Mart\u00edn","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/"},"author":{"name":"Jaume Mart\u00edn","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d"},"headline":"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026","datePublished":"2026-06-16T07:11:53+00:00","dateModified":"2026-06-16T15:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/"},"wordCount":590,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg","keywords":["Noticias Criptomonedas"],"articleSection":["Altcoins"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/","name":"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026 - 99bitcoins ES","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg","datePublished":"2026-06-16T07:11:53+00:00","dateModified":"2026-06-16T15:20:00+00:00","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/cardano-community-vetoes-two-million-dollar-summit-proposal-featured.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/cardano-community-vetoes-two-million-dollar-summit-proposal-governance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Comunidad Cardano veta presupuesto de $2M para cumbre de 2026"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d","name":"Jaume Mart\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","caption":"Jaume Mart\u00edn"},"description":"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.","url":"https:\/\/99bitcoins.com\/es\/author\/jaimemartin\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/34032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135885"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=34032"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/34032\/revisions"}],"predecessor-version":[{"id":34374,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/34032\/revisions\/34374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/34029"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=34032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=34032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=34032"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=34032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}