{"id":33781,"date":"2026-06-11T07:00:53","date_gmt":"2026-06-11T07:00:53","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=33781"},"modified":"2026-06-11T15:32:00","modified_gmt":"2026-06-11T15:32:00","slug":"uk-sanctions-htx-justin-sun-russia-finance-evasion","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/","title":{"rendered":"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa"},"content":{"rendered":"<p>El gobierno del Reino Unido ha sancionado formalmente a HTX, uno de los exchanges de criptomonedas m\u00e1s grandes del mundo y liderado por el fundador de Tron, <strong>Justin Sun<\/strong>. Las autoridades citan el presunto papel de la plataforma en ayudar a Rusia a evadir las restricciones econ\u00f3micas occidentales. Estas sanciones, anunciadas como parte de una acci\u00f3n de cumplimiento m\u00e1s amplia en mayo de 2026 contra 18 individuos y entidades vinculadas a redes de finanzas il\u00edcitas, convierten a HTX en el primer exchange de criptomonedas en ser designado bajo el marco de sanciones contra Rusia del Reino Unido.<\/p>\r\n<p>HTX es propiedad del empresario multimillonario Justin Sun, una figura prominente en los c\u00edrculos cripto de habla china, y fue fundada originalmente en China bajo el nombre de Huobi. El Ministerio de Asuntos Exteriores del Reino Unido design\u00f3 a la entidad operativa del exchange, <strong>Huobi Global S.A.<\/strong>, alegando la prestaci\u00f3n de servicios financieros a dos entidades vinculadas al Kremlin.<\/p>\r\n<p><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">UK sanctions HTX and EXMO over alleged Kremlin money-moving network<br><br>The UK Foreign Office (<a href=\"https:\/\/x.com\/FCDOGovUK?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@FCDOGovUK<\/a>) designated Huobi Global S.A. (<a href=\"https:\/\/x.com\/HuobiGlobal?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@HuobiGlobal<\/a>), the Panama-registered entity behind crypto exchange HTX, under its Russia sanctions regime on Tuesday. EXMO Exchange was hit in the\u2026 <a href=\"https:\/\/t.co\/8yYtZsiDm3\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/8yYtZsiDm3<\/a><\/p>&mdash; BSCN (@BSCNews) <a href=\"https:\/\/x.com\/BSCNews\/status\/2059317136640602147?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">May 26, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\r\n<p>Dichas entidades son <strong>A7<\/strong>, una red de criptomonedas respaldada por el Kremlin, y <strong>Garantex<\/strong>, un exchange con sede en Mosc\u00fa; ambas ya hab\u00edan sido sancionadas previamente por el gobierno de los Estados Unidos. Seg\u00fan el aviso oficial del Reino Unido, HTX supuestamente ayud\u00f3 a procesar y canalizar m\u00e1s de 1.500 millones de d\u00f3lares hacia Rusia a trav\u00e9s de estas redes.<\/p>\r\n<p>Para los usuarios comunes que tienen fondos en HTX en este momento, esto plantea una interrogante pr\u00e1ctica inmediata. La tensi\u00f3n central radica en que, aunque el exchange sigue operando, el terreno regulatorio bajo sus pies se ha desplazado de tal forma que afecta directamente el acceso a retiros, las relaciones bancarias y la estabilidad de la plataforma.<\/p>\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/content-img-1-54.jpg\" alt=\"\" \/><\/figure>\r\n\r\n<h2>Qu\u00e9 significan realmente las sanciones del Reino Unido para los usuarios<\/h2>\r\n<p>Cuando un gobierno sanciona a una entidad financiera, no cierra la plataforma de inmediato. En su lugar, limita gradualmente su capacidad operativa, ya que los socios bancarios y los procesadores de pagos est\u00e1n obligados a cortar v\u00ednculos.<\/p>\r\n<p>En el Reino Unido, cualquier individuo o instituci\u00f3n que proporcione apoyo financiero a Huobi Global S.A. se arriesga a responsabilidades penales, y los bancos brit\u00e1nicos deben bloquear las transacciones con la entidad designada. Los usuarios podr\u00edan ver interrumpida su capacidad para depositar o retirar fondos debido a acciones de su propio banco, y no necesariamente por el exchange en s\u00ed.<\/p>\r\n<p>Este movimiento marca la primera vez que el Reino Unido incluye a un exchange de criptomonedas en sus sanciones contra Rusia, lo que indica un cambio significativo en la regulaci\u00f3n de las plataformas centralizadas, trat\u00e1ndolas de forma similar a las instituciones financieras tradicionales.<\/p>\r\n<p>Adem\u00e1s, la <strong>Financial Conduct Authority (FCA)<\/strong> del Reino Unido ya hab\u00eda tomado acciones legales contra HTX en febrero de 2025 por promociones ilegales a usuarios minoristas, lo que convierte a estas sanciones en una escalada de tensiones y no en un incidente aislado.<\/p>\r\n<p><strong>Conoce las <a href=\"https:\/\/99bitcoins.com\/es\/mejores-wallets\/tron\/\">mejores wallets para Tron<\/a><\/strong><\/p>\r\n<h2>\u00bfEst\u00e1 seguro su dinero? Lo que los usuarios de HTX deben saber<\/h2>\r\n<p>La respuesta honesta depende de su situaci\u00f3n y ubicaci\u00f3n geogr\u00e1fica respecto a HTX.<\/p>\r\n<p>1. <strong>Si tiene fondos en HTX:<\/strong> Su riesgo ha aumentado considerablemente. Aunque no se han anunciado suspensiones de retiros, las sanciones podr\u00edan congelar inesperadamente los canales de retiro de dinero f\u00edat. Los retiros de cripto a cripto podr\u00edan funcionar por m\u00e1s tiempo, pero el riesgo operativo y legal es mayor. Recuerde el lema: \u00absi no son sus llaves, no son sus monedas\u00bb.<\/p>\r\n<p>2. <strong>Si espera un retiro o dep\u00f3sito f\u00edat:<\/strong> P\u00f3ngase en contacto con el soporte de HTX de inmediato y documente todo. Las sanciones pueden paralizar las transacciones, haciendo que la recuperaci\u00f3n de fondos a trav\u00e9s de una entidad sancionada sea mucho m\u00e1s dif\u00edcil.<\/p>\r\n<p>3. <strong>Si ya ha retirado sus fondos:<\/strong> Est\u00e1 menos expuesto al riesgo, pero debe estar atento a cualquier obligaci\u00f3n fiscal o de cumplimiento relacionada con sus transacciones recientes en HTX, ya que los reguladores podr\u00edan escudri\u00f1ar la actividad en plataformas designadas. Asimismo, vigile la verificaci\u00f3n de <strong>prueba de reservas<\/strong> de HTX, clave para evaluar la solvencia de la plataforma.<\/p>\r\n<h2>HTX y Justin Sun: Por qu\u00e9 los reguladores act\u00faan ahora<\/h2>\r\n<p><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">As an advisor to the HTX exchange, I was first made aware today of the recent developments and will continue to monitor the situation closely. <br><br>We believe in full compliance with all applicable laws and cooperation with law\u2011enforcement agencies worldwide. <br><br>I&#39;m confident that\u2026 <a href=\"https:\/\/t.co\/isgzB1UjjO\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/isgzB1UjjO<\/a><\/p>&mdash; H.E. Justin Sun \ud83d\udc68\u200d\ud83d\ude80 \ud83c\udf1e (@justinsuntron) <a href=\"https:\/\/x.com\/justinsuntron\/status\/2059384559129723317?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">May 26, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\r\n<p>La acci\u00f3n contra HTX no llega de forma aislada. Justin Sun y sus entidades asociadas han acumulado un historial regulatorio considerable. En 2023, la <strong>SEC de EE. UU.<\/strong> present\u00f3 una demanda personal contra \u00e9l, alegando ofertas de valores no registrados y manipulaci\u00f3n de mercado relacionada con los tokens <strong>TRX<\/strong> y <strong>BTT<\/strong>, cargos que permanecen activos. Aunque esas acusaciones son independientes del caso de evasi\u00f3n de sanciones rusas, refuerzan un patr\u00f3n de preocupaci\u00f3n regulatoria en m\u00faltiples jurisdicciones.<\/p>\r\n<p>La dimensi\u00f3n actual es espec\u00edfica: las autoridades brit\u00e1nicas alegan que HTX proporcion\u00f3 infraestructura financiera a A7 y Garantex, entidades que el Tesoro de EE. UU. ya hab\u00eda se\u00f1alado como conductos para mover dinero en nombre del estado ruso. No se trata de un simple fallo administrativo de KYC (conozca a su cliente), sino de una acusaci\u00f3n de que la plataforma sirvi\u00f3 activamente como un nodo en lo que el gobierno del Reino Unido denomina la \u00abred financiera en la sombra\u00bb de Rusia.<\/p>\r\n<p>El perfil de Sun tambi\u00e9n ha cambiado recientemente; fue un destacado patrocinador de las aventuras cripto de la familia Trump antes de un distanciamiento p\u00fablico, una relaci\u00f3n que elev\u00f3 brevemente su visibilidad en los c\u00edrculos pol\u00edticos y financieros de EE. UU. Las sanciones aterrizan precisamente en este complejo contexto.<\/p>\r\n<p><a href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/telegram\/\"><strong>Telegram criptomonedas<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El Reino Unido sanciona a HTX (Huobi) por presuntos v\u00ednculos con Rusia. Descubre qu\u00e9 significa esto para tus fondos y el futuro del exchange de Justin Sun.<\/p>\n","protected":false},"author":135885,"featured_media":33778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[249],"tags":[7],"coin":[74],"class_list":["post-33781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-criptomonedas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa - 99bitcoins ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa - 99bitcoins ES\" \/>\n<meta property=\"og:description\" content=\"El Reino Unido sanciona a HTX (Huobi) por presuntos v\u00ednculos con Rusia. Descubre qu\u00e9 significa esto para tus fondos y el futuro del exchange de Justin Sun.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-11T07:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T15:32:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaume Mart\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Mart\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/\"},\"author\":{\"name\":\"Jaume Mart\u00edn\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\"},\"headline\":\"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa\",\"datePublished\":\"2026-06-11T07:00:53+00:00\",\"dateModified\":\"2026-06-11T15:32:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/\"},\"wordCount\":957,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg\",\"keywords\":[\"Noticias Criptomonedas\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/\",\"name\":\"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa - 99bitcoins ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg\",\"datePublished\":\"2026-06-11T07:00:53+00:00\",\"dateModified\":\"2026-06-11T15:32:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/uk-sanctions-htx-justin-sun-russia-finance-evasion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\",\"name\":\"Jaume Mart\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"caption\":\"Jaume Mart\u00edn\"},\"description\":\"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/jaimemartin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa - 99bitcoins ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/","og_locale":"es_ES","og_type":"article","og_title":"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa - 99bitcoins ES","og_description":"El Reino Unido sanciona a HTX (Huobi) por presuntos v\u00ednculos con Rusia. Descubre qu\u00e9 significa esto para tus fondos y el futuro del exchange de Justin Sun.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/","og_site_name":"99bitcoins ES","article_published_time":"2026-06-11T07:00:53+00:00","article_modified_time":"2026-06-11T15:32:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg","type":"image\/jpeg"}],"author":"Jaume Mart\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jaume Mart\u00edn","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/"},"author":{"name":"Jaume Mart\u00edn","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d"},"headline":"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa","datePublished":"2026-06-11T07:00:53+00:00","dateModified":"2026-06-11T15:32:00+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/"},"wordCount":957,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg","keywords":["Noticias Criptomonedas"],"articleSection":["Altcoins"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/","name":"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa - 99bitcoins ES","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg","datePublished":"2026-06-11T07:00:53+00:00","dateModified":"2026-06-11T15:32:00+00:00","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/uk-sanctions-htx-justin-sun-russia-finance-evasion-featured.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/uk-sanctions-htx-justin-sun-russia-finance-evasion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Reino Unido sanciona a HTX: El exchange de Justin Sun bajo la lupa"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d","name":"Jaume Mart\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","caption":"Jaume Mart\u00edn"},"description":"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.","url":"https:\/\/99bitcoins.com\/es\/author\/jaimemartin\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/33781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135885"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=33781"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/33781\/revisions"}],"predecessor-version":[{"id":33936,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/33781\/revisions\/33936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/33778"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=33781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=33781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=33781"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=33781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}