{"id":33115,"date":"2026-05-19T07:00:06","date_gmt":"2026-05-19T07:00:06","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=33115"},"modified":"2026-05-19T10:43:00","modified_gmt":"2026-05-19T10:43:00","slug":"ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/","title":{"rendered":"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?"},"content":{"rendered":"<p>Strategy, el mayor poseedor corporativo de Bitcoin en el mundo con 818.334 BTC en sus libros, acaba de comunicar al mercado que vender\u00e1 Bitcoin cuando tenga sentido financiero.<\/p>\n<p>Esa frase habr\u00eda sido impensable hace dos a\u00f1os. Para una empresa construida enteramente sobre la filosof\u00eda de que nunca, bajo ninguna circunstancia, se vende Bitcoin, esto representa un cambio s\u00edsmico y conlleva un mensaje directo para los inversores minoristas que han estado siguiendo el mismo manual de estrategias.<\/p>\n<p><iframe loading=\"lazy\" title=\"DON&#039;T BUY BITCOIN NOW!\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Fy4XAQiCMPk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>El anuncio fue realizado por Phong Le, presidente y CEO de Strategy, durante la llamada de resultados del primer trimestre de 2026 de la compa\u00f1\u00eda. Strategy registr\u00f3 una p\u00e9rdida neta de 12.500 millones de USD en el trimestre, impulsada por la ca\u00edda del precio de Bitcoin a principios de a\u00f1o.<\/p>\n<p>El contexto importa: incluso el HODLer institucional m\u00e1s comprometido del planeta est\u00e1 diciendo ahora que las matem\u00e1ticas, y no el mantra, deben guiar la decisi\u00f3n de vender.<\/p>\n<p class=\"p1\"><div class=\"chart crypto-chart-instance\" id=\"crypto_chart_6a57e0ce9db5a\"\n\tdata-coin-id=\"bitcoin\">\n\t<div class=\"chart__header\">\n\t\t<div class=\"chart__info\">\n\t\t\t<div class=\"chart__info-icon\">\n\t\t\t\t<img id=\"crypto_chart_6a57e0ce9db5a-chart__info-icon-img\" \/>\n\t\t\t\t<div class=\"chart__info-name\" id=\"crypto_chart_6a57e0ce9db5a-chart__info-name\"><\/div>\n\t\t\t\t<div class=\"chart__info-symbol\" id=\"crypto_chart_6a57e0ce9db5a-chart__info-symbol\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-current\">\n\t\t\t\t<div class=\"chart__info-price\" id=\"crypto_chart_6a57e0ce9db5a-chart__info-price\"><\/div>\n\t\t\t\t<div class=\"chart__info-change\" id=\"crypto_chart_6a57e0ce9db5a-chart__info-change\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-extra\">\n\t\t\t\t<div class=\"chart__info-label\">Market Cap<\/div>\n\t\t\t\t<div class=\"chart__info-marketcap\" id=\"crypto_chart_6a57e0ce9db5a-chart__info-marketcap\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"chart__controls\">\n\t\t\t<div class=\"chart__controls-group\">\n\t\t\t\t<button class=\"chart__button chart__button--24h\"\n\t\t\t\t\tid=\"crypto_chart_6a57e0ce9db5a-btn-24h\">24h<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--7d\"\n\t\t\t\t\tid=\"crypto_chart_6a57e0ce9db5a-btn-7d\">7d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--30d\"\n\t\t\t\t\tid=\"crypto_chart_6a57e0ce9db5a-btn-30d\">30d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--1y\"\n\t\t\t\t\tid=\"crypto_chart_6a57e0ce9db5a-btn-1y\">1y<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--all-time\"\n\t\t\t\t\tid=\"crypto_chart_6a57e0ce9db5a-btn-all-time\">All Time<\/button>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"chart__container\">\n\t\t<canvas class=\"chart__canvas\" id=\"crypto_chart_6a57e0ce9db5a-cryptoChart\"><\/canvas>\n\t<\/div>\n<\/div>\n\n<h2>Qu\u00e9 significa realmente HODL y por qu\u00e9 se consolid\u00f3<\/h2>\n<p>HODL se origin\u00f3 como una errata de un usuario de un foro de Bitcoin en 2013 que escribi\u00f3 \u201cI AM HODLING\u201d mientras estaba ebrio. Se convirti\u00f3 en un grito de guerra y en un acr\u00f3nimo de \u201cHold On for Dear Life\u201d (resistir a toda costa), promoviendo la creencia de que la trayectoria a largo plazo de Bitcoin es ascendente y alentando a los inversores a no vender nunca a pesar de las oscilaciones de precios.<\/p>\n<p>Esta estrategia enriqueci\u00f3 a muchos durante las rachas alcistas de 2020 y 2024, pero tambi\u00e9n llev\u00f3 a otros a sufrir p\u00e9rdidas significativas cuando los mercados cayeron.<\/p>\n<p>La mayor\u00eda de los principiantes carecen del colch\u00f3n financiero para soportar ca\u00eddas sustanciales. Las estrategias HODL a menudo asumen que se puede resistir una ca\u00edda del 80% sin vender por p\u00e1nico, pero eso es poco realista para muchos inversores minoristas.<\/p>\n<p>Las instituciones pueden capear p\u00e9rdidas masivas gracias a sus reservas, mientras que los inversores individuales normalmente no pueden. Comprender los factores que impulsan la volatilidad de Bitcoin es crucial para desarrollar una estrategia de inversi\u00f3n m\u00e1s resiliente.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">JUST IN: Michael Saylor&#39;s Strategy proposes selling some Bitcoin to pay dividends. <\/p>\n<p>&quot;You buy Bitcoin with credit, you let it appreciate, and then you sell Bitcoin to pay the dividend.&quot; <a href=\"https:\/\/t.co\/WPCHk7fn7P\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/WPCHk7fn7P<\/a><\/p>\n<p>&mdash; Watcher.Guru (@WatcherGuru) <a href=\"https:\/\/twitter.com\/WatcherGuru\/status\/2051797790494261301?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">May 5, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>DESCUBRE: <a href=\"https:\/\/99bitcoins.com\/es\/guias\/vender-bitcoin\/\">C\u00f3mo vender Bitcoin<\/a><\/strong><\/p>\n<h2>Lo que el cambio de Strategy dice realmente a los inversores minoristas<\/h2>\n<p>Le declar\u00f3 en la llamada de resultados: \u201cVenderemos bitcoin cuando sea ventajoso para la empresa\u201d. La nueva estrategia se centra en una m\u00e9trica denominada bitcoin por acci\u00f3n, que eval\u00faa cu\u00e1nta exposici\u00f3n a BTC representa cada acci\u00f3n. Si vender una parte de las tenencias puede mejorar esa m\u00e9trica y amortizar deuda, proceder\u00e1n a hacerlo.<\/p>\n<p>El presidente Michael Saylor compar\u00f3 esto con el sector inmobiliario, donde los promotores compran terrenos a bajo precio, los venden con beneficios y reinvierten de forma inteligente. Saylor enfatiz\u00f3 que la venta debe verse como una estrategia activa de gesti\u00f3n de riesgos y no como una debilidad.<\/p>\n<p>El analista Dylan LeClair calific\u00f3 este movimiento como una \u201cevoluci\u00f3n pragm\u00e1tica\u201d, se\u00f1alando el riesgo de combinar el apalancamiento con la ideolog\u00eda, especialmente cuando el ratio de apalancamiento de Strategy alcanz\u00f3 2,8x.<\/p>\n<p>Las tendencias institucionales respaldan este enfoque; por ejemplo, el ETF IBIT de BlackRock posee unos 852.000 BTC y emplea un reequilibrio sistem\u00e1tico, tratando la venta como una herramienta estrat\u00e9gica. Los inversores minoristas que ven la venta de forma negativa operan bajo reglas diferentes a las de los profesionales institucionales.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-345861 size-full\" src=\"https:\/\/99bitcoins.com\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-06-at-09.17.34-scaled.png\" alt=\"Bitcoin est\u00e1 en 81.500 USD, y con los analistas pronosticando un regreso a los 100k, los inversores luchan por hacer HODL\" width=\"2560\" height=\"1345\" \/><\/p>\n<p>(<a class=\"general-link\" href=\"https:\/\/www.coinglass.com\/etf\/bitcoin\" target=\"_blank\" rel=\"noopener nofollow\">FUENTE: CoinGlass<\/a>)<\/p>\n<h2>C\u00f3mo construir su propia estrategia de trading de Bitcoin con salidas planificadas<\/h2>\n<p>El cambio de \u201cnunca vender\u201d a \u201cvender cuando sea inteligente\u201d no requiere que abandone su convicci\u00f3n en Bitcoin. Requiere separar la emoci\u00f3n de la ejecuci\u00f3n. He aqu\u00ed c\u00f3mo pensarlo de forma pr\u00e1ctica.<\/p>\n<p>El enfoque que est\u00e1 ganando m\u00e1s tracci\u00f3n entre los estrategas se denomina venta por umbral: establecer niveles de precio espec\u00edficos y predeterminados o porcentajes de cartera en los que se vende una parte fija de las tenencias, independientemente de c\u00f3mo se sienta respecto a Bitcoin ese d\u00eda.<\/p>\n<p>Para los principiantes, una versi\u00f3n sencilla es la siguiente: decida de antemano que vender\u00e1 el 10% de su Bitcoin cada vez que duplique el precio de compra. De este modo, asegura beneficios, reduce su base de costes y sigue manteniendo una posici\u00f3n significativa para posibles subidas adicionales.<\/p>\n<p>Tomar ganancias no significa salir de Bitcoin por completo. Significa tratar sus ganancias como dinero real antes de que el mercado las revierta. Despu\u00e9s de que <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/news\/bitcoin-btc\/bitcoin-news-what-next-after-btc-usd-80000-breakout\/\" target=\"_blank\" rel=\"noopener\">Bitcoin rompe hitos de precios importantes<\/a>, los datos hist\u00f3ricos muestran que la volatilidad se dispara bruscamente, exactamente cuando los inversores indisciplinados mantienen la posici\u00f3n demasiado tiempo y devuelven meses de ganancias en cuesti\u00f3n de d\u00edas.<\/p>\n<p>Algunos puntos de anclaje pr\u00e1cticos para su estrategia de trading de Bitcoin:<\/p>\n<ul>\n<li><strong>Establezca sus umbrales antes de comprar.<\/strong> Decida a qu\u00e9 niveles de precio retirar\u00e1 un 5\u201310%. Escr\u00edbalo. Comprom\u00e9tase con ello antes de que el FOMO aparezca en la subida o el p\u00e1nico en la bajada.<\/li>\n<li><strong>Recupere su capital inicial primero.<\/strong> Una regla clara: venda lo suficiente en su primer objetivo importante para recuperar su inversi\u00f3n original. Todo lo que quede en Bitcoin despu\u00e9s de eso es beneficio puro, psicol\u00f3gicamente mucho m\u00e1s f\u00e1cil de mantener durante la volatilidad.<\/li>\n<li><strong>Reequilibre cuando Bitcoin domine su cartera.<\/strong> Si Bitcoin crece hasta representar m\u00e1s del 20\u201330% de sus ahorros totales, es una se\u00f1al para recortar, no porque Bitcoin sea malo, sino porque el riesgo de concentraci\u00f3n es real independientemente del activo.<\/li>\n<\/ul>\n<p>El objetivo de la gesti\u00f3n de riesgos en cripto no es maximizar sus tenencias de Bitcoin a toda costa. Es asegurar que un mal trimestre \u2014como el que acaba de tener Strategy\u2014 no borre a\u00f1os de ganancias que nunca lleg\u00f3 a asegurar.<\/p>\n<p><strong>EXPLORA:<a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/staking\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\"> staking<\/a><\/strong><\/p>\n<p><strong>Siga a 99Bitcoins en <a class=\"general-link\" href=\"https:\/\/twitter.com\/99bitcoins\" target=\"_blank\" rel=\"noopener nofollow\">X<\/a>, <a class=\"general-link\" href=\"https:\/\/www.youtube.com\/99bitcoins\" target=\"_blank\" rel=\"noopener nofollow\">YouTube<\/a> y <a class=\"general-link\" href=\"https:\/\/t.me\/s\/bitcoinnews99\" target=\"_blank\" rel=\"noopener nofollow\">Telegram<\/a> para m\u00e1s noticias y an\u00e1lisis de criptomonedas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfHa muerto el HODL? Expertos recomiendan a los principiantes vender Bitcoin<\/p>\n","protected":false},"author":135885,"featured_media":33112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[248],"tags":[10],"coin":[74],"class_list":["post-33115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?<\/title>\n<meta name=\"description\" content=\"El analista Dylan LeClair calific\u00f3 este movimiento como una \u201cevoluci\u00f3n pragm\u00e1tica\u201d, se\u00f1alando el riesgo de combinar el apalancamiento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?\" \/>\n<meta property=\"og:description\" content=\"El analista Dylan LeClair calific\u00f3 este movimiento como una \u201cevoluci\u00f3n pragm\u00e1tica\u201d, se\u00f1alando el riesgo de combinar el apalancamiento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-19T07:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T10:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaume Mart\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Mart\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/\"},\"author\":{\"name\":\"Jaume Mart\u00edn\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\"},\"headline\":\"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?\",\"datePublished\":\"2026-05-19T07:00:06+00:00\",\"dateModified\":\"2026-05-19T10:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/\"},\"wordCount\":1014,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg\",\"keywords\":[\"Noticias Bitcoin\"],\"articleSection\":[\"Bitcoin\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/\",\"name\":\"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg\",\"datePublished\":\"2026-05-19T07:00:06+00:00\",\"dateModified\":\"2026-05-19T10:43:00+00:00\",\"description\":\"El analista Dylan LeClair calific\u00f3 este movimiento como una \u201cevoluci\u00f3n pragm\u00e1tica\u201d, se\u00f1alando el riesgo de combinar el apalancamiento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bitcoin\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\",\"name\":\"Jaume Mart\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"caption\":\"Jaume Mart\u00edn\"},\"description\":\"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/jaimemartin\\\/\"}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/Fy4XAQiCMPk\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"1739\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:upload_date\" content=\"2026-05-19T07:00:06+00:00\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?","description":"El analista Dylan LeClair calific\u00f3 este movimiento como una \u201cevoluci\u00f3n pragm\u00e1tica\u201d, se\u00f1alando el riesgo de combinar el apalancamiento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?","og_description":"El analista Dylan LeClair calific\u00f3 este movimiento como una \u201cevoluci\u00f3n pragm\u00e1tica\u201d, se\u00f1alando el riesgo de combinar el apalancamiento.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/","og_site_name":"99bitcoins ES","article_published_time":"2026-05-19T07:00:06+00:00","article_modified_time":"2026-05-19T10:43:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg","type":"image\/jpeg"}],"author":"Jaume Mart\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jaume Mart\u00edn","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/"},"author":{"name":"Jaume Mart\u00edn","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d"},"headline":"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?","datePublished":"2026-05-19T07:00:06+00:00","dateModified":"2026-05-19T10:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/"},"wordCount":1014,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg","keywords":["Noticias Bitcoin"],"articleSection":["Bitcoin"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/","name":"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg","datePublished":"2026-05-19T07:00:06+00:00","dateModified":"2026-05-19T10:43:00+00:00","description":"El analista Dylan LeClair calific\u00f3 este movimiento como una \u201cevoluci\u00f3n pragm\u00e1tica\u201d, se\u00f1alando el riesgo de combinar el apalancamiento.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/michael-saylor-laughing-maniacally-eating-bitcoin-cake.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/ha-muerto-el-hodl-es-hora-de-vender-su-bitcoin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Bitcoin","item":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/"},{"@type":"ListItem","position":4,"name":"\u00bfHa muerto el \u2018HODL\u2019? \u00bfEs hora de vender su Bitcoin?"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d","name":"Jaume Mart\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","caption":"Jaume Mart\u00edn"},"description":"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.","url":"https:\/\/99bitcoins.com\/es\/author\/jaimemartin\/"}]},"og_video":"https:\/\/www.youtube.com\/embed\/Fy4XAQiCMPk","og_video_type":"text\/html","og_video_duration":"1739","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_upload_date":"2026-05-19T07:00:06+00:00","ya_ovs_allow_embed":"true"},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/33115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135885"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=33115"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/33115\/revisions"}],"predecessor-version":[{"id":33422,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/33115\/revisions\/33422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/33112"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=33115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=33115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=33115"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=33115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}