{"id":33043,"date":"2026-05-12T07:12:03","date_gmt":"2026-05-12T07:12:03","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=33043"},"modified":"2026-05-12T07:46:00","modified_gmt":"2026-05-12T07:46:00","slug":"carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/","title":{"rendered":"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD"},"content":{"rendered":"<p>Carrot, un protocolo de rendimiento DeFi basado en Solana, anunci\u00f3 su cierre permanente el 30 de abril de 2026, tras perder aproximadamente 8 millones de USD en valor total bloqueado \u2014casi la mitad de su TVL\u2014 debido a las repercusiones del <a class=\"general-link\" href=\"https:\/\/news.bitcoin.com\/solana-yield-protocol-carrot-shuts-down-after-drift-exploit-drains-8m-in-tvl\/\" target=\"_blank\" rel=\"noopener nofollow\">exploit del 1 de abril en Drift Protocol<\/a> que dren\u00f3 un estimado de 285 millones de USD de una de las plataformas de futuros perpetuos m\u00e1s grandes de Solana.<\/p>\n<p>Carrot no fue hackeado directamente. Fue derribado por un protocolo del que depend\u00eda, y esa distinci\u00f3n es lo que hace que esta historia sea algo m\u00e1s que el resumen de un exploit rutinario.<\/p>\n<p>Los usuarios tienen hasta el 14 de mayo de 2026 para retirar voluntariamente sus fondos de los tres productos principales de Carrot. Tras esa fecha l\u00edmite, el equipo comenzar\u00e1 el desapalancamiento forzoso de todas las posiciones restantes a un apalancamiento de 1x, liberando liquidez para los reembolsos finales de la stablecoin CRT.<\/p>\n<p>La cuenta oficial de Carrot en X confirm\u00f3 la decisi\u00f3n de forma clara: \u201cCarrot cierra sus puertas. Ciertamente, este no es el resultado m\u00e1s deseado, pero la situaci\u00f3n con el exploit de Drift ha resultado catastr\u00f3fica para la continuidad de nuestras operaciones\u201d.<\/p>\n<p>Se tom\u00f3 una instant\u00e1nea (snapshot) de las tenencias del token CRT a las 20:00 UTC del 1 de abril, el momento exacto del exploit de Drift, para preservar los derechos proporcionales de cualquier distribuci\u00f3n futura de recuperaci\u00f3n de Drift pagada a trav\u00e9s de tokens IOU.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">1\/ Carrot is shutting down<\/p>\n<p>This is certainly not the outcome we wanted, but the situation with the Drift exploit, has proven to be catastrophic for our continued operations.<\/p>\n<p>&mdash; Carrot (@DeFiCarrot) <a href=\"https:\/\/twitter.com\/DeFiCarrot\/status\/2049907092664762624?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 30, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>El detalle que la mayor\u00eda de los titulares pasan por alto es que Carrot nunca tuvo una vulnerabilidad en su propio c\u00f3digo. Sus productos Boost y Turbo enrutaban los fondos de los usuarios a trav\u00e9s de b\u00f3vedas integradas en Drift, lo que significa que la seguridad de Drift era tambi\u00e9n la seguridad de Carrot, independientemente de que los usuarios de Carrot lo supieran o no.<\/p>\n<p><strong>DESCUBRE:\u00a0<a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/gemas-crypto\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\">La pr\u00f3xima gema cripto<\/a><\/strong><\/p>\n<h2>\u00bfC\u00f3mo funcion\u00f3 realmente el exploit de Drift Protocol?<\/h2>\n<p>El exploit de Drift, que el propio Drift Protocol confirm\u00f3 que ocurri\u00f3 aproximadamente a las 20:00 UTC del 1 de abril, utiliz\u00f3 lo que los investigadores han descrito como un novedoso exploit de \u201cnonce\u201d duradero, una t\u00e9cnica que manipula la forma en que Solana gestiona la firma de transacciones preautorizadas para comprometer los controles administrativos.<\/p>\n<p>Se sospecha que los atacantes, con v\u00ednculos con grupos patrocinados por el estado de Corea del Norte, pasaron unas tres semanas preparando el ataque antes de ejecutarlo. M\u00e1s del 50% del TVL de Drift fue drenado en minutos, lo que provoc\u00f3 una suspensi\u00f3n inmediata de dep\u00f3sitos y retiros en toda la plataforma.<\/p>\n<figure id=\"attachment_345336\" class=\"wp-caption alignnone\" style=\"width: 1024px\" aria-describedby=\"caption-attachment-345336\"><img decoding=\"async\" class=\"size-large wp-image-345336\" src=\"https:\/\/99bitcoins.com\/wp-content\/uploads\/2026\/05\/photo_2026-05-01_11-00-14-1024x319.jpg\" alt=\"\" width=\"1024\" height=\"319\" \/><figcaption id=\"caption-attachment-345336\" class=\"wp-caption-text\">Fuente: Drift TVL \/ <a class=\"general-link\" href=\"https:\/\/defillama.com\/protocol\/drift?fees=false&amp;events=false\" target=\"_blank\" rel=\"noopener nofollow\">DefiLlama<\/a><\/figcaption><\/figure>\n<p>Carrot manten\u00eda una exposici\u00f3n significativa a trav\u00e9s de las b\u00f3vedas integradas en Drift y posiciones de liquidez. Poco despu\u00e9s del exploit, el equipo detuvo todas las funciones de emisi\u00f3n y reembolso mientras evaluaba los da\u00f1os.<\/p>\n<p>A mediados de abril, el valor neto de los activos de CRT de Carrot se ajust\u00f3 a aproximadamente entre 57,52 USD y 57,58 USD por token, reflejando tanto las p\u00e9rdidas realizadas como las no realizadas. El hackeo de Drift es ahora el mayor exploit DeFi de 2026 y el segundo m\u00e1s grande en la historia de Solana; un dato relevante para cualquiera que eval\u00fae <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/news\/presales\/solana-price-forecast-below-85\/\" target=\"_blank\" rel=\"noopener\">la salud del ecosistema general de Solana<\/a> en este momento.<\/p>\n<p>Carrot oper\u00f3 durante m\u00e1s de dos a\u00f1os antes de este cierre, construyendo lo que describ\u00eda como un \u201csistema operativo de rendimiento\u201d para Solana. No se aplicar\u00e1n tarifas de gesti\u00f3n durante el per\u00edodo de liquidaci\u00f3n, y el equipo ha confirmado que los fondos depositados siguen siendo propiedad legal de los usuarios durante todo el proceso.<\/p>\n<p><strong>EXPLORE: <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/preventas\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Las mejores preventas de criptomonedas a seguir<\/a><\/strong><\/p>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div><b>Siga a 99Bitcoins en <\/b><b><a href=\"https:\/\/x.com\/99BitcoinsHQ\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">X<\/a><\/b><b> para conocer las \u00faltimas actualizaciones del mercado y suscr\u00edbase en <\/b><b><a href=\"https:\/\/www.youtube.com\/@99bitcoins\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">YouTube<\/a><\/b><b> para el an\u00e1lisis diario de expertos.<\/b><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El protocolo Carrot cierra tras un exploit de 8 millones de USD en Solana<\/p>\n","protected":false},"author":135885,"featured_media":33042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[249],"tags":[7],"coin":[74],"class_list":["post-33043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-criptomonedas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD<\/title>\n<meta name=\"description\" content=\"Carrot manten\u00eda una exposici\u00f3n significativa a trav\u00e9s de las b\u00f3vedas integradas en Drift y posiciones de liquidez.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD\" \/>\n<meta property=\"og:description\" content=\"Carrot manten\u00eda una exposici\u00f3n significativa a trav\u00e9s de las b\u00f3vedas integradas en Drift y posiciones de liquidez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T07:12:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T07:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/solana-carrot-protocol-shuts-down-drift-exploit.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1376\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jaume Mart\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Mart\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/\"},\"author\":{\"name\":\"Jaume Mart\u00edn\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\"},\"headline\":\"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD\",\"datePublished\":\"2026-05-12T07:12:03+00:00\",\"dateModified\":\"2026-05-12T07:46:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/\"},\"wordCount\":677,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/solana-carrot-protocol-shuts-down-drift-exploit.webp\",\"keywords\":[\"Noticias Criptomonedas\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/\",\"name\":\"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/solana-carrot-protocol-shuts-down-drift-exploit.webp\",\"datePublished\":\"2026-05-12T07:12:03+00:00\",\"dateModified\":\"2026-05-12T07:46:00+00:00\",\"description\":\"Carrot manten\u00eda una exposici\u00f3n significativa a trav\u00e9s de las b\u00f3vedas integradas en Drift y posiciones de liquidez.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/solana-carrot-protocol-shuts-down-drift-exploit.webp\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/solana-carrot-protocol-shuts-down-drift-exploit.webp\",\"width\":1376,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/cc6aa290fd1659880c1d375d6b27f70d\",\"name\":\"Jaume Mart\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g\",\"caption\":\"Jaume Mart\u00edn\"},\"description\":\"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/jaimemartin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD","description":"Carrot manten\u00eda una exposici\u00f3n significativa a trav\u00e9s de las b\u00f3vedas integradas en Drift y posiciones de liquidez.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/","og_locale":"es_ES","og_type":"article","og_title":"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD","og_description":"Carrot manten\u00eda una exposici\u00f3n significativa a trav\u00e9s de las b\u00f3vedas integradas en Drift y posiciones de liquidez.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/","og_site_name":"99bitcoins ES","article_published_time":"2026-05-12T07:12:03+00:00","article_modified_time":"2026-05-12T07:46:00+00:00","og_image":[{"width":1376,"height":768,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/solana-carrot-protocol-shuts-down-drift-exploit.webp","type":"image\/webp"}],"author":"Jaume Mart\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jaume Mart\u00edn","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/"},"author":{"name":"Jaume Mart\u00edn","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d"},"headline":"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD","datePublished":"2026-05-12T07:12:03+00:00","dateModified":"2026-05-12T07:46:00+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/"},"wordCount":677,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/solana-carrot-protocol-shuts-down-drift-exploit.webp","keywords":["Noticias Criptomonedas"],"articleSection":["Altcoins"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/","name":"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/solana-carrot-protocol-shuts-down-drift-exploit.webp","datePublished":"2026-05-12T07:12:03+00:00","dateModified":"2026-05-12T07:46:00+00:00","description":"Carrot manten\u00eda una exposici\u00f3n significativa a trav\u00e9s de las b\u00f3vedas integradas en Drift y posiciones de liquidez.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/solana-carrot-protocol-shuts-down-drift-exploit.webp","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/05\/solana-carrot-protocol-shuts-down-drift-exploit.webp","width":1376,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/carrot-el-protocolo-de-rendimiento-de-solana-cierra-tras-un-exploit-de-8-millones-de-usd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Carrot, el protocolo de rendimiento de Solana, cierra tras un exploit de 8 millones de USD"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/cc6aa290fd1659880c1d375d6b27f70d","name":"Jaume Mart\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc5ee13a756b8a67783a43312133dcda3e25aafe72e52ddc53654080e642f21b?s=96&d=mm&r=g","caption":"Jaume Mart\u00edn"},"description":"Con un grado en periodismo por la Universitat de Val\u00e8ncia, y 7 a\u00f1os de recorrido en el sector financiero-tecnol\u00f3gico, Jaume ejerce la investigaci\u00f3n y producci\u00f3n de contenidos Web3 y crypto.","url":"https:\/\/99bitcoins.com\/es\/author\/jaimemartin\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/33043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135885"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=33043"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/33043\/revisions"}],"predecessor-version":[{"id":33183,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/33043\/revisions\/33183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/33042"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=33043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=33043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=33043"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=33043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}