{"id":32860,"date":"2026-04-30T08:00:35","date_gmt":"2026-04-30T08:00:35","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=32860"},"modified":"2026-04-30T15:40:00","modified_gmt":"2026-04-30T15:40:00","slug":"quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/","title":{"rendered":"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares"},"content":{"rendered":"<p>\u00bfQui\u00e9n es Evan Tangeman? El joven de 22 a\u00f1os, residente de Newport Beach, California, fue sentenciado el 24 de abril de 2026 a 70 meses en una prisi\u00f3n federal por lavar 3,5 millones de d\u00f3lares en nombre de un sindicato de ciberdelincuentes que rob\u00f3 m\u00e1s de 263 millones de d\u00f3lares en criptomonedas.<\/p>\n<p>Se declar\u00f3 culpable de conspiraci\u00f3n bajo la ley RICO, no por un cargo menor de contabilidad, sino bajo el mismo estatuto utilizado para procesar al crimen organizado, y cumplir\u00e1 tres a\u00f1os adicionales de libertad supervisada una vez que finalice su per\u00edodo en prisi\u00f3n. Fue el noveno acusado en declararse culpable en la investigaci\u00f3n; ni el cabecilla, ni el hacker. \u00c9l era el movilizador del dinero.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Evan Tangeman,\u00a022,\u00a0of Newport Beach, California, was sentenced today to 70 months in prison\u00a0for\u00a0laundering\u00a0millions of dollars\u00a0generated by an\u00a0elaborate social engineering\u00a0scheme orchestrated by a\u00a0multi-state\u00a0criminal enterprise\u00a0that stole more than $263\u00a0million\u00a0in cryptocurrency\u2026 <a href=\"https:\/\/t.co\/LwV1Usb0jY\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/LwV1Usb0jY<\/a><\/p>\n<p>&mdash; U.S. Attorney DC (@USAO_DC) <a href=\"https:\/\/twitter.com\/USAO_DC\/status\/2047805244147425719?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 24, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>El detalle que la mayor\u00eda de los titulares omiten: el papel secundario de Tangeman no suaviz\u00f3 la sentencia. Los fiscales federales en el Tribunal de Distrito de los EE. UU. para el Distrito de Columbia trataron a un participante de nivel medio como un actor criminal serio, una se\u00f1al de que nadie en la cadena operativa es considerado perif\u00e9rico a partir de ahora.<\/p>\n<p>Esta noticia se dio a conocer mientras el precio de Bitcoin se mantiene estable en el d\u00eda, con una ca\u00edda del -0,3% hasta los 77.700 USD, mientras el principal activo digital comienza la semana en un periodo de consolidaci\u00f3n tras un fuerte repunte durante la \u00faltima quincena.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-344825 size-full\" src=\"https:\/\/99bitcoins.com\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-27-at-11.30.01-scaled.png\" alt=\"Los participantes del mercado se preguntan 'Qui\u00e9n es Evan Tangeman' mientras el joven de 22 a\u00f1os recibe casi seis a\u00f1os por su papel en un caso de criptomonedas de 9 cifras\" width=\"2560\" height=\"1164\" \/><\/p>\n<p>(<a class=\"general-link\" href=\"https:\/\/twitter.com\/USAO_DC\/status\/2047805244147425719\" target=\"_blank\" rel=\"noopener nofollow\">FUENTE: TradingView<\/a>)<\/p>\n<h2>Qui\u00e9n es Evan Tangeman: c\u00f3mo un joven de 22 a\u00f1os de Newport Beach termin\u00f3 en una condena federal por lavado de dinero<\/h2>\n<p>El sindicato oper\u00f3 desde al menos octubre de 2023 hasta mayo de 2025, utilizando hackeos e ingenier\u00eda social para robar criptomonedas a v\u00edctimas en todo el pa\u00eds. El robo individual m\u00e1s grande ocurri\u00f3 el 18 de agosto de 2024, cuando los co-conspiradores defraudaron a una v\u00edctima en Washington, D.C. por m\u00e1s de 4.100 Bitcoin, valorados en 263 millones de d\u00f3lares en ese momento y en m\u00e1s de 368 millones de d\u00f3lares para diciembre de 2025.<\/p>\n<p>El trabajo de Tangeman era convertir las criptomonedas robadas en efectivo utilizable, financiando el gusto del grupo por los Lamborghinis, alquileres de lujo y el tipo de estilo de vida que los fiscales describieron como \u00abconstruido sobre una codicia tan descarada que raya en lo caricaturesco\u00bb.<\/p>\n<p>Piense en el lavado de criptomonedas como intentar gastar billetes falsos. No se puede entrar simplemente en un concesionario con Bitcoin robado; la blockchain registra cada transacci\u00f3n y los exchanges tienen equipos de cumplimiento que vigilan las entradas sospechosas.<\/p>\n<p>Por ello, los lavadores estratifican los fondos: los mueven a trav\u00e9s de m\u00faltiples billeteras, convierten entre diferentes monedas, retiran a trav\u00e9s de mezcladores o plataformas P2P y, finalmente, hacen aflorar fondos de apariencia limpia en una cuenta bancaria. Cada paso deja un rastro. Los investigadores forenses de blockchain siguen esos rastros de la misma manera que un detective sigue el rastro del papel, con la diferencia de que el papel nunca se quema.<\/p>\n<p>Cuando los co-conspiradores comenzaron a ser arrestados, Tangeman procedi\u00f3 a destruir pruebas, seg\u00fan la fiscal general adjunta Jeanine Pirro. Esa decisi\u00f3n probablemente influy\u00f3 en el c\u00e1lculo de la sentencia. La blockchain no miente y no olvida, pero intentar que olvide es un problema aparte.<\/p>\n<p><strong>EXCLUSIVO: <a href=\"https:\/\/99bitcoins.com\/es\/comprar-bitcoin\/revolut\/\">comprar Bitcoin con Revolut<\/a><\/strong><\/p>\n<h2>El Patr\u00f3n: por qu\u00e9 el lavado de criptomonedas es ahora una prioridad de sentencia federal<\/h2>\n<p>La aplicaci\u00f3n de la ley federal contra los delitos facilitados por criptomonedas se ha acelerado dr\u00e1sticamente en los \u00faltimos tres a\u00f1os, con el DOJ, el FBI y la Divisi\u00f3n de Investigaci\u00f3n Criminal del IRS tratando el rastreo de blockchain como una herramienta de investigaci\u00f3n est\u00e1ndar en lugar de una capacidad especializada. Las autoridades han demostrado repetidamente que la actividad on-chain puede rastrearse hasta identidades reales, incluso cuando los participantes creen que est\u00e1n operando de forma an\u00f3nima detr\u00e1s de direcciones de billeteras.<\/p>\n<p>Con los traders pregunt\u00e1ndose &#8216;Qui\u00e9n es Evan Tangeman&#8217;, este caso refuerza una postura fiscal que se ha endurecido desde al menos 2022: a los participantes de nivel medio \u2014los lavadores, los que retiran efectivo, los operadores de infraestructura\u2014 no se les est\u00e1n ofreciendo acuerdos de culpabilidad silenciosos. Est\u00e1n siendo acusados bajo la ley RICO, el mismo estatuto que desmantel\u00f3 a la familia Gambino, y sentenciados a penas federales de varios a\u00f1os.<\/p>\n<p>Setenta meses por lavar 3,5 millones de d\u00f3lares, como parte de una operaci\u00f3n mayor de 263 millones de d\u00f3lares, refleja un mensaje deliberado sobre la proporcionalidad o, mejor dicho, la ausencia de ella cuando los fiscales quieren enviar una se\u00f1al disuasoria.<\/p>\n<p>La Oficina del Fiscal de los EE. UU. para el Distrito de Columbia, que anunci\u00f3 la sentencia, ha convertido el criptocrimen a gran escala en una prioridad visible de aplicaci\u00f3n de la ley. Se esperan m\u00e1s acusaciones en este caso a medida que contin\u00fae la investigaci\u00f3n.<\/p>\n<h2>La realidad de la aplicaci\u00f3n de la ley: c\u00f3mo se ve en la pr\u00e1ctica usar criptomonedas il\u00edcitas hoy<\/h2>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">A 22 year old laundered MILLIONS from a $263M BTC heist and only got 70 months<\/p>\n<p>Yesterday Evan Tangeman, a 22 year old from Newport Beach, was sentenced to 70 months in federal prison for laundering at least $3.5 million tied to the largest single victim Bitcoin theft in history\u2026 <a href=\"https:\/\/t.co\/lMtSPHVNxH\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/lMtSPHVNxH<\/a><\/p>\n<p>&mdash; Sweep (@0xSweep) <a href=\"https:\/\/twitter.com\/0xSweep\/status\/2048132825908445619?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 25, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Si usted es un trader minorista ordinario, tenga en cuenta que los riesgos legales de manejar fondos procedentes de actividades delictivas pueden aplicarse incluso si no sabe que el dinero fue robado. Seg\u00fan el T\u00edtulo 18 del C\u00f3digo de EE. UU. \u00a7 1956, usted podr\u00eda ser responsable si tiene motivos para sospechar que los fondos est\u00e1n vinculados a actividades ilegales, especialmente ante patrones de transacciones inusuales o plataformas no reguladas.<\/p>\n<p>El uso de exchanges peer-to-peer o mesas extraburs\u00e1tiles (OTC) lo coloca en los mismos canales que los lavadores de dinero. Si bien esto no lo convierte en un delincuente, significa que sus transacciones podr\u00edan ser escrutadas al igual que las de los infractores. Los delincuentes explotan diversas infraestructuras cripto, y los sistemas de cumplimiento captan cada vez m\u00e1s tambi\u00e9n a transe\u00fantes inocentes.<\/p>\n<p>Recuerde, el seudonimato de una billetera no garantiza protecci\u00f3n legal. A medida que evolucionan los m\u00e9todos para atacar a los poseedores de criptomonedas, tambi\u00e9n lo hacen las herramientas de los investigadores. Tangeman probablemente pens\u00f3 que estaba aislado del riesgo, pero ahora enfrenta una sentencia federal de 70 meses con solo 22 a\u00f1os. Con suerte, esto responde a la pregunta de &#8216;Qui\u00e9n es Evan Tangeman&#8217;.<\/p>\n<p><strong>EXPLORE: <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/preventas\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Las mejores preventas de criptomonedas<\/a><\/strong><\/p>\n<p><strong>Siga a 99Bitcoins en <a class=\"general-link\" href=\"https:\/\/twitter.com\/99bitcoins\" target=\"_blank\" rel=\"noopener nofollow\">X<\/a>, <a class=\"general-link\" href=\"https:\/\/www.youtube.com\/99bitcoins\" target=\"_blank\" rel=\"noopener nofollow\">YouTube<\/a> y <a class=\"general-link\" href=\"https:\/\/t.me\/s\/bitcoinnews99\" target=\"_blank\" rel=\"noopener nofollow\">Telegram<\/a> para obtener m\u00e1s noticias y an\u00e1lisis de criptomonedas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares<\/p>\n","protected":false},"author":135895,"featured_media":32857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[249],"tags":[7],"coin":[74],"class_list":["post-32860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-criptomonedas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares<\/title>\n<meta name=\"description\" content=\"Setenta meses por lavar 3,5 millones de d\u00f3lares, como parte de una operaci\u00f3n mayor de 263 millones de d\u00f3lares, refleja un mensaje deliberado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares\" \/>\n<meta property=\"og:description\" content=\"Setenta meses por lavar 3,5 millones de d\u00f3lares, como parte de una operaci\u00f3n mayor de 263 millones de d\u00f3lares, refleja un mensaje deliberado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T08:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T15:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGxOqinbgAAOQyN.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/\"},\"author\":{\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\"},\"headline\":\"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares\",\"datePublished\":\"2026-04-30T08:00:35+00:00\",\"dateModified\":\"2026-04-30T15:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/\"},\"wordCount\":1126,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/HGxOqinbgAAOQyN.jpeg\",\"keywords\":[\"Noticias Criptomonedas\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/\",\"name\":\"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/HGxOqinbgAAOQyN.jpeg\",\"datePublished\":\"2026-04-30T08:00:35+00:00\",\"dateModified\":\"2026-04-30T15:40:00+00:00\",\"description\":\"Setenta meses por lavar 3,5 millones de d\u00f3lares, como parte de una operaci\u00f3n mayor de 263 millones de d\u00f3lares, refleja un mensaje deliberado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/HGxOqinbgAAOQyN.jpeg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/HGxOqinbgAAOQyN.jpeg\",\"width\":756,\"height\":756},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\",\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"caption\":\"Ver\u00f3nica Llabr\u00e9s\"},\"description\":\"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/verollabres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares","description":"Setenta meses por lavar 3,5 millones de d\u00f3lares, como parte de una operaci\u00f3n mayor de 263 millones de d\u00f3lares, refleja un mensaje deliberado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/","og_locale":"es_ES","og_type":"article","og_title":"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares","og_description":"Setenta meses por lavar 3,5 millones de d\u00f3lares, como parte de una operaci\u00f3n mayor de 263 millones de d\u00f3lares, refleja un mensaje deliberado.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/","og_site_name":"99bitcoins ES","article_published_time":"2026-04-30T08:00:35+00:00","article_modified_time":"2026-04-30T15:40:00+00:00","og_image":[{"width":756,"height":756,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGxOqinbgAAOQyN.jpeg","type":"image\/jpeg"}],"author":"Ver\u00f3nica Llabr\u00e9s","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ver\u00f3nica Llabr\u00e9s","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/"},"author":{"name":"Ver\u00f3nica Llabr\u00e9s","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a"},"headline":"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares","datePublished":"2026-04-30T08:00:35+00:00","dateModified":"2026-04-30T15:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/"},"wordCount":1126,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGxOqinbgAAOQyN.jpeg","keywords":["Noticias Criptomonedas"],"articleSection":["Altcoins"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/","name":"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGxOqinbgAAOQyN.jpeg","datePublished":"2026-04-30T08:00:35+00:00","dateModified":"2026-04-30T15:40:00+00:00","description":"Setenta meses por lavar 3,5 millones de d\u00f3lares, como parte de una operaci\u00f3n mayor de 263 millones de d\u00f3lares, refleja un mensaje deliberado.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGxOqinbgAAOQyN.jpeg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGxOqinbgAAOQyN.jpeg","width":756,"height":756},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/quien-es-evan-tangeman-joven-de-22-anos-recibe-70-meses-de-prision-en-caso-de-lavado-de-criptomonedas-por-263-millones-de-dolares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Qui\u00e9n es Evan Tangeman: joven de 22 a\u00f1os recibe 70 meses de prisi\u00f3n en caso de lavado de criptomonedas por 263 millones de d\u00f3lares"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a","name":"Ver\u00f3nica Llabr\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","caption":"Ver\u00f3nica Llabr\u00e9s"},"description":"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.","url":"https:\/\/99bitcoins.com\/es\/author\/verollabres\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/32860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135895"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=32860"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/32860\/revisions"}],"predecessor-version":[{"id":32866,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/32860\/revisions\/32866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/32857"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=32860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=32860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=32860"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=32860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}