{"id":32824,"date":"2026-04-29T08:00:05","date_gmt":"2026-04-29T08:00:05","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=32824"},"modified":"2026-04-29T21:16:00","modified_gmt":"2026-04-29T21:16:00","slug":"por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/","title":{"rendered":"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP"},"content":{"rendered":"<p>La <a href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/mejores-memecoins\/\"><strong>memecoin<\/strong><\/a> oficial TRUMP ha ca\u00eddo m\u00e1s de un -95% desde su m\u00e1ximo de 75 USD en enero de 2025, y los traders que aprovecharon esa subida han dejado de fingir que la historia tiene un segundo acto. La pr\u00f3xima conferencia en Mar-a-Lago para los 297 mayores poseedores del token apenas atrajo 1.400 millones de USD en volumen de negociaci\u00f3n en el periodo previo, en comparaci\u00f3n con los 12.900 millones de USD antes de la cena equivalente de 2025.<\/p>\n<p>Lo que hace que este colapso en particular merezca atenci\u00f3n no es solo el precio; es la estructura que lo sustenta. Dos entidades, una filial de la Trump Organization y una empresa dirigida por Bill Zanker, socio de Trump de hace mucho tiempo, poseen la gran mayor\u00eda del suministro y cobran comisiones por cada operaci\u00f3n realizada.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Trump\u2019s memecoin, <a href=\"https:\/\/twitter.com\/search?q=%24TRUMP&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$TRUMP<\/a>, was once the talk of Washington. It\u2019s now down more than 95% from its 2025 high.<\/p>\n<p>\u201cPeople are losing on the coin, and they are vocal,&quot; said one crypto investor. &quot;They are the people on Twitter like, \u2018F&#8211;k this coin\u2019 or \u2018It\u2019s a scam.\u2019 And they\u2019re right,\u2026<\/p>\n<p>&mdash; POLITICO (@politico) <a href=\"https:\/\/twitter.com\/politico\/status\/2047328702497804490?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 23, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>La familia Trump y sus socios hab\u00edan obtenido 320 millones de USD en comisiones de negociaci\u00f3n relacionadas con la memecoin hasta abril de 2026, mientras que los compradores minoristas absorbieron las p\u00e9rdidas. Las matem\u00e1ticas sobre qui\u00e9n se benefici\u00f3 aqu\u00ed no son complicadas.<\/p>\n<p>TRUMP cotiza hoy a 2,85 USD, con una modesta subida del +1% en el d\u00eda, un volumen de negociaci\u00f3n en 24 horas de 103 millones de USD y una capitalizaci\u00f3n de mercado de 670 millones de USD, lo que lo convierte en el 86\u00ba activo digital m\u00e1s grande por valoraci\u00f3n.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-344713 size-full\" src=\"https:\/\/99bitcoins.com\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-24-at-14.37.34-scaled.png\" alt=\"The TRUMP memecoin is back in the news following a very public spat with Justin Sun, and the upcoming Mar-a-Lago dinner\" width=\"2560\" height=\"1203\" \/><\/p>\n<p>(<a class=\"general-link\" href=\"https:\/\/www.coingecko.com\/en\/coins\/official-trump\" target=\"_blank\" rel=\"noopener nofollow\">FUENTE: CoinGecko<\/a>)<\/p>\n<p><strong>LEE <a href=\"https:\/\/99bitcoins.com\/es\/guias\/como-comprar-trump\/\">c\u00f3mo comprar TRUMP memecoin<\/a><\/strong><\/p>\n<h2>TRUMP: De los 75 USD al fondo del barril<\/h2>\n<p>La memecoin oficial TRUMP se lanz\u00f3 d\u00edas antes de la investidura de Trump el 20 de enero de 2025, un momento que fue, digamos, deliberado. El token alcanz\u00f3 los 75 USD casi de inmediato, impulsado por una combinaci\u00f3n de fervor pol\u00edtico, FOMO y el tipo de tornado en redes sociales que solo un presidente de los EE. UU. en funciones puede generar.<\/p>\n<p>El token perdi\u00f3 m\u00e1s de la mitad de su valor a los pocos d\u00edas del m\u00e1ximo, y el sangrado nunca se detuvo realmente. Las acusaciones de uso de informaci\u00f3n privilegiada y conflictos de intereses no tardaron en aparecer, y el ecosistema cripto de Trump en general no ha ayudado precisamente al sentimiento.<\/p>\n<p>Justin Sun, quien fuera el principal poseedor en la cena de 2025, demand\u00f3 a World Liberty Financial por la congelaci\u00f3n de sus tenencias de WLFI, a\u00f1adiendo otra capa de disfunci\u00f3n a una marca ya maltrecha y desencadenando una guerra de palabras muy p\u00fablica con Eric Trump.<\/p>\n<p>Morten Christensen, un inversor de criptomonedas que a\u00fan planea asistir al evento de Mar-a-Lago, lo expres\u00f3 claramente: \u201cA nadie le gusta. La gente est\u00e1 perdiendo con la moneda y lo manifiesta. Son las personas en Twitter que ponen: &#8216;A la m*erda esta moneda&#8217; o &#8216;Es una estafa&#8217;. Y b\u00e1sicamente tienen raz\u00f3n\u201d.<\/p>\n<p><strong>DESCUBRA: <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/preventas\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Las mejores preventas de criptomonedas<\/a><\/strong><\/p>\n<h2>\u00bfPuede recuperarse el precio de la memecoin TRUMP o la narrativa ya est\u00e1 rota?<\/h2>\n<p>Seamos directos: la estructura on-chain de TRUMP hace que una recuperaci\u00f3n genuina sea excepcionalmente dif\u00edcil. Cuando la mayor\u00eda del suministro est\u00e1 en manos de dos entidades conectadas que se benefician de las comisiones de negociaci\u00f3n \u2014no de la apreciaci\u00f3n del precio\u2014, la alineaci\u00f3n de incentivos falla desde el principio. Pi\u00e9nselo como un casino donde la casa se lleva una tajada gane usted o pierda. Los traders minoristas son el producto, no el cliente.<\/p>\n<p>David Grider, socio de Finality Capital Partners, se\u00f1al\u00f3 que las memecoins est\u00e1n \u201cmuy fuera de favor en este momento\u201d, con los inversores retir\u00e1ndose masivamente de los activos especulativos. Las acciones de Trump Media &amp; Technology Group han ca\u00eddo un -75% desde la investidura, lo que aumenta la sensaci\u00f3n de que todo el comercio de la marca Trump se ha desinflado.<\/p>\n<p>Incluso los que alguna vez fueron cr\u00edticos vocales en el Capitolio se encogen de hombros; un asesor dem\u00f3crata senior del Senado calific\u00f3 el evento de Mar-a-Lago como \u201chorrible y espantoso\u201d, pero a\u00f1adi\u00f3: \u201cla gente lo ve como lo que es: una estafa&#8230; esto ha ca\u00eddo al fondo del barril\u201d.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">whoever is buying <a href=\"https:\/\/twitter.com\/search?q=%24TRUMP&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$TRUMP<\/a>, i hope your plumbing breaks down in the middle of you taking a shit <a href=\"https:\/\/t.co\/7xHgfQYY2V\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/7xHgfQYY2V<\/a><\/p>\n<p>&mdash; TraderSZ (@trader1sz) <a href=\"https:\/\/twitter.com\/trader1sz\/status\/2046950383684145646?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 22, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>As\u00ed es como se ven los tres escenarios a partir de ahora:<\/p>\n<ul>\n<li><strong>Escenario alcista:<\/strong> Trump dice algo espec\u00edfico y procesable sobre $TRUMP durante su discurso en el almuerzo de Mar-a-Lago, lo que provoca un repunte a corto plazo hacia los 5-8 USD. Es poco probable que se mantenga sin cambios estructurales, pero los traders a corto plazo podr\u00edan extraer un movimiento r\u00e1pido.<\/li>\n<li><strong>Escenario base:<\/strong> El evento transcurre sin un catalizador significativo, el volumen sigue siendo escaso y $TRUMP se mueve en el rango de 2 a 4 USD mientras el mercado de memecoins en general sigue sin contar con el favor de los inversores. El token se convierte en un objeto de colecci\u00f3n pol\u00edtica de nicho en lugar de un instrumento de negociaci\u00f3n activo.<\/li>\n<li><strong>Escenario bajista\/invalidaci\u00f3n:<\/strong> La investigaci\u00f3n del senador Blumenthal sobre posibles violaciones de la SEC gana tracci\u00f3n, o las consecuencias legales adicionales de las <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/es\/news\/presales\/justin-sun-wlfi-manipulation-frozen-wallets\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\">acusaciones de manipulaci\u00f3n de Justin Sun y WLFI<\/a> salpican directamente a $TRUMP. En ese escenario, el nivel de precio actual no ofrece un soporte significativo, y el objetivo honesto se sit\u00faa por debajo de 1 USD.<\/li>\n<\/ul>\n<p>El evento en s\u00ed, el 25 de abril, es el pr\u00f3ximo hito a vigilar; espec\u00edficamente, si el volumen tras el discurso se dispara por encima de los 500 millones de USD en una ventana de 24 horas. Si no lo hace, el escenario base ya estar\u00e1 confirmado.<\/p>\n<p><strong>EXPLORE <a href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/donald-trump\/\">Trump y las criptomonedas<\/a><\/strong><\/p>\n<p><strong>Siga a 99Bitcoins en <a class=\"general-link\" href=\"https:\/\/x.com\/99bitcoins\" target=\"_blank\" rel=\"nofollow noopener\">X<\/a>, <a class=\"general-link\" href=\"https:\/\/www.youtube.com\/99bitcoins\" target=\"_blank\" rel=\"nofollow noopener\">YouTube<\/a> y <a class=\"general-link\" href=\"https:\/\/t.me\/99bitcoins\" target=\"_blank\" rel=\"nofollow noopener\">Telegram<\/a> para m\u00e1s noticias y an\u00e1lisis de criptomonedas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin de Trump<\/p>\n","protected":false},"author":135895,"featured_media":32820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[249],"tags":[7],"coin":[74],"class_list":["post-32824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-criptomonedas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP<\/title>\n<meta name=\"description\" content=\"Incluso los que alguna vez fueron cr\u00edticos vocales en el Capitolio se encogen de hombros; un asesor dem\u00f3crata senior del Senado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP\" \/>\n<meta property=\"og:description\" content=\"Incluso los que alguna vez fueron cr\u00edticos vocales en el Capitolio se encogen de hombros; un asesor dem\u00f3crata senior del Senado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-29T08:00:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T21:16:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGmF2FjWgAArZKA.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/\"},\"author\":{\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\"},\"headline\":\"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP\",\"datePublished\":\"2026-04-29T08:00:05+00:00\",\"dateModified\":\"2026-04-29T21:16:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/\"},\"wordCount\":982,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/HGmF2FjWgAArZKA.jpeg\",\"keywords\":[\"Noticias Criptomonedas\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/\",\"name\":\"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/HGmF2FjWgAArZKA.jpeg\",\"datePublished\":\"2026-04-29T08:00:05+00:00\",\"dateModified\":\"2026-04-29T21:16:00+00:00\",\"description\":\"Incluso los que alguna vez fueron cr\u00edticos vocales en el Capitolio se encogen de hombros; un asesor dem\u00f3crata senior del Senado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/HGmF2FjWgAArZKA.jpeg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/HGmF2FjWgAArZKA.jpeg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\",\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"caption\":\"Ver\u00f3nica Llabr\u00e9s\"},\"description\":\"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/verollabres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP","description":"Incluso los que alguna vez fueron cr\u00edticos vocales en el Capitolio se encogen de hombros; un asesor dem\u00f3crata senior del Senado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP","og_description":"Incluso los que alguna vez fueron cr\u00edticos vocales en el Capitolio se encogen de hombros; un asesor dem\u00f3crata senior del Senado.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/","og_site_name":"99bitcoins ES","article_published_time":"2026-04-29T08:00:05+00:00","article_modified_time":"2026-04-29T21:16:00+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGmF2FjWgAArZKA.jpeg","type":"image\/jpeg"}],"author":"Ver\u00f3nica Llabr\u00e9s","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ver\u00f3nica Llabr\u00e9s","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/"},"author":{"name":"Ver\u00f3nica Llabr\u00e9s","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a"},"headline":"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP","datePublished":"2026-04-29T08:00:05+00:00","dateModified":"2026-04-29T21:16:00+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/"},"wordCount":982,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGmF2FjWgAArZKA.jpeg","keywords":["Noticias Criptomonedas"],"articleSection":["Altcoins"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/","name":"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGmF2FjWgAArZKA.jpeg","datePublished":"2026-04-29T08:00:05+00:00","dateModified":"2026-04-29T21:16:00+00:00","description":"Incluso los que alguna vez fueron cr\u00edticos vocales en el Capitolio se encogen de hombros; un asesor dem\u00f3crata senior del Senado.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGmF2FjWgAArZKA.jpeg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/HGmF2FjWgAArZKA.jpeg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/por-que-los-traders-de-criptomonedas-le-estan-dando-la-espalda-a-la-memecoin-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Por qu\u00e9 los traders de criptomonedas le est\u00e1n dando la espalda a la memecoin TRUMP"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a","name":"Ver\u00f3nica Llabr\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","caption":"Ver\u00f3nica Llabr\u00e9s"},"description":"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.","url":"https:\/\/99bitcoins.com\/es\/author\/verollabres\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/32824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135895"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=32824"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/32824\/revisions"}],"predecessor-version":[{"id":32838,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/32824\/revisions\/32838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/32820"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=32824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=32824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=32824"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=32824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}