{"id":32721,"date":"2026-04-27T07:00:35","date_gmt":"2026-04-27T07:00:35","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=32721"},"modified":"2026-04-23T07:59:03","modified_gmt":"2026-04-23T07:59:03","slug":"el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/","title":{"rendered":"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse"},"content":{"rendered":"<p>Ripple ha publicado una hoja de ruta de varias fases para hacer que el XRP Ledger sea resistente a los ataques de computaci\u00f3n cu\u00e1ntica, con el objetivo de lograr una preparaci\u00f3n poscu\u00e1ntica completa para 2028. El movimiento se produce despu\u00e9s de que una <a class=\"general-link\" href=\"https:\/\/quantumai.google\/\" target=\"_blank\" rel=\"nofollow noopener\">investigaci\u00f3n de Google Quantum AI<\/a> confirmara que la criptograf\u00eda que sustenta a la mayor\u00eda de las blockchains actuales puede, en principio, ser vulnerada por hardware cu\u00e1ntico lo suficientemente avanzado.<\/p>\n<p>Los activos no est\u00e1n en riesgo hoy en d\u00eda. Pero la amenaza ha pasado de ser te\u00f3rica a cre\u00edble, alterando el cronograma de preparaci\u00f3n. La cuesti\u00f3n no es si la computaci\u00f3n cu\u00e1ntica acabar\u00e1 importando para las criptomonedas. La pregunta es si los poseedores de XRP necesitan hacer algo al respecto ahora mismo.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">RIPPLE: <a href=\"https:\/\/twitter.com\/search?q=%24XRP&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$XRP<\/a> LEDGER WILL BE QUANTUM RESISTANT BY 2028<a href=\"https:\/\/twitter.com\/Ripple?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@Ripple<\/a> is making its <a href=\"https:\/\/twitter.com\/search?q=%24XRP&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$XRP<\/a> Ledger quantum-ready. These super-fast machines could one day break the codes that protect digital money today.<\/p>\n<p>The company has a clear plan to complete the upgrades by 2028 across four phases in\u2026 <a href=\"https:\/\/t.co\/RsA5jY2uqb\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/RsA5jY2uqb<\/a><\/p>\n<p>&mdash; BSCN (@BSCNews) <a href=\"https:\/\/twitter.com\/BSCNews\/status\/2046256969518862440?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 20, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>\u00bfQu\u00e9 significa realmente la era poscu\u00e1ntica para XRP Ledger?<\/h2>\n<p>Piense en su monedero de XRP como un candado asegurado con un problema matem\u00e1tico tan dif\u00edcil que ning\u00fan ordenador actual podr\u00eda descifrarlo en un tiempo razonable. Los ordenadores cu\u00e1nticos no solo trabajan m\u00e1s r\u00e1pido; abordan ciertos problemas matem\u00e1ticos de una forma fundamentalmente diferente, como si tuvieran una llave maestra que puede resolver el rompecabezas directamente. Los algoritmos espec\u00edficos que protegen los monederos de blockchain y las firmas de las transacciones son vulnerables a este tipo de ataque.<\/p>\n<p>Existe una amenaza m\u00e1s sutil que se suma a la anterior. Los investigadores la denominan \u00abrecolectar ahora, descifrar despu\u00e9s\u00bb. Cada vez que una cuenta de XRP firma una transacci\u00f3n, su clave p\u00fablica se hace visible en la cadena. Un actor malintencionado podr\u00eda recopilar esos datos hoy mismo y guardarlos, esperando a que el hardware cu\u00e1ntico madure lo suficiente como para utilizarlos. Para cuando el ataque sea t\u00e9cnicamente posible, el terreno ya estar\u00e1 preparado.<\/p>\n<p>Ripple es expl\u00edcito al afirmar que esto no significa que los activos est\u00e9n en riesgo hoy. Pero la posici\u00f3n de la empresa es que los plazos de preparaci\u00f3n ahora son importantes, y que esperar hasta que la amenaza sea inminente ser\u00eda demasiado tarde para ejecutar una migraci\u00f3n segura a trav\u00e9s de una red financiera global activa.<\/p>\n<p>Esta es la misma preocupaci\u00f3n que impulsa las propuestas de defensa cu\u00e1ntica en todo el ecosistema cripto, desde Cardano hasta Bitcoin. Es un problema que afecta a toda la industria y que a\u00fan no cuenta con una \u00fanica soluci\u00f3n consensuada.<\/p>\n<h2>\u00bfQu\u00e9 pasos ha tomado ya Ripple en el XRPL?<\/h2>\n<p><img decoding=\"async\" class=\"alignnone wp-image-344423 size-full\" src=\"https:\/\/99bitcoins.com\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-22-at-13.08.35-scaled.png\" alt=\"Ripple est\u00e1 dando grandes pasos en un intento de asegurar que XRP sea resistente a la cu\u00e1ntica antes de que sea demasiado tarde, con Bitcoin rezagado\" width=\"2560\" height=\"1256\" \/><\/p>\n<p>(<a class=\"general-link\" href=\"https:\/\/www.tradingview.com\/symbols\/XRPUSD\/\" target=\"_blank\" rel=\"noopener nofollow\">FUENTE: TradingView<\/a>)<\/p>\n<p>La hoja de ruta de Ripple para la criptograf\u00eda poscu\u00e1ntica se divide en cuatro fases, y los trabajos ya est\u00e1n en marcha. El equipo de criptograf\u00eda aplicada, que incluye al Dr. Murat Cenk y a la Dra. Aanchal Malhotra, est\u00e1 creando prototipos de soluciones, y el ingeniero Denis Angell ha probado el esquema de firma ML-DSA en la AlphaNet de XRPL.<\/p>\n<p>La Fase 1 sirve como un plan de contingencia para forzar un cambio dr\u00e1stico hacia firmas poscu\u00e1nticas si la criptograf\u00eda cl\u00e1sica falla, utilizando pruebas de conocimiento cero para demostrar la propiedad de las claves. La Fase 2, programada para principios de 2026, explorar\u00e1 m\u00e1s a fondo los algoritmos recomendados por el NIST y evaluar\u00e1 su rendimiento.<\/p>\n<p>La Fase 3, prevista para finales de 2026, implica una transici\u00f3n controlada en la que las firmas resistentes a la cu\u00e1ntica operar\u00e1n junto a las existentes en la Devnet, ayudando a los desarrolladores. Para 2028, la Fase 4 apunta a una transici\u00f3n completa a producci\u00f3n, incluyendo una enmienda formal para la criptograf\u00eda poscu\u00e1ntica nativa.<\/p>\n<p>La ventaja del XRPL reside en su soporte para la rotaci\u00f3n nativa de claves, lo que permite a los usuarios actualizar sus claves sin necesidad de crear nuevas cuentas, a diferencia de Ethereum. Ripple tambi\u00e9n se ha asociado con Project Eleven para mejorar las pruebas de validadores y agilizar el cronograma de la Fase 2.<\/p>\n<p><strong>EXPLORE: <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/como-comprar-xrp\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\">c\u00f3mo comprar Ripple<\/a> y <a href=\"https:\/\/99bitcoins.com\/es\/guias\/como-comprar-plasma-xpl\/\">c\u00f3mo comprar Plasma XPL<\/a><\/strong><\/p>\n<h2>\u00bfDeben preocuparse los poseedores de XRP por el riesgo cu\u00e1ntico ahora mismo?<\/h2>\n<p>La respuesta sincera es: no con urgencia, pero tampoco hay que ignorarlo. Los procesadores cu\u00e1nticos actuales de IBM tienen unos 1.100 c\u00fabits. Romper la criptograf\u00eda utilizada en los monederos de blockchain requerir\u00eda millones. La brecha entre el hardware actual y una amenaza real para los monederos de XRP sigue siendo amplia. El propio planteamiento de Ripple es cauteloso: \u00abEsto no significa que los activos est\u00e9n en riesgo hoy\u00bb.<\/p>\n<p>El objetivo de 2028 para la plena preparaci\u00f3n poscu\u00e1ntica de XRPL tambi\u00e9n se adelanta a la mayor\u00eda de las estimaciones cre\u00edbles sobre cu\u00e1ndo el hardware cu\u00e1ntico podr\u00eda amenazar de forma realista los est\u00e1ndares criptogr\u00e1ficos actuales. Las propuestas para congelar el monedero de Bitcoin de Satoshi reflejan la misma preocupaci\u00f3n a largo plazo: el riesgo no es para ma\u00f1ana, pero la ventana de preparaci\u00f3n es finita.<\/p>\n<p>\u00bfQu\u00e9 cambiar\u00eda el panorama? Un salto repentino en la capacidad del hardware cu\u00e1ntico, o pruebas de que la recopilaci\u00f3n de datos de \u00abrecolectar ahora, descifrar despu\u00e9s\u00bb ya est\u00e1 ocurriendo a gran escala. Ninguna de las dos cosas est\u00e1 confirmada. Pero el NIST ya ha finalizado los est\u00e1ndares de criptograf\u00eda poscu\u00e1ntica, lo que indica que los gobiernos y los organismos de normalizaci\u00f3n est\u00e1n tratando esto como un horizonte de planificaci\u00f3n real, no como un escenario de ciencia ficci\u00f3n.<\/p>\n<p>Para los poseedores de XRP, la implicaci\u00f3n pr\u00e1ctica es estar atentos a los resultados de las pruebas de los validadores de la Fase 2 de Project Eleven a principios de 2026; esos ser\u00e1n los primeros datos de rendimiento en el mundo real que mostrar\u00e1n si la arquitectura resistente a la cu\u00e1ntica de XRPL se mantiene bajo carga.<\/p>\n<h2>Ripple no est\u00e1 sola: c\u00f3mo otras blockchains afrontan el riesgo cu\u00e1ntico<\/h2>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">JUST IN: $14 TRILLION BLACKROCK JUST SAID <a href=\"https:\/\/twitter.com\/hashtag\/BITCOIN?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">#BITCOIN<\/a>&#39;S QUANTUM THREAT &quot;IT&#39;S SOLVABLE&quot;<\/p>\n<p>THE WORLD&#39;S LARGEST ASSET MANAGER IS TELLING YOU THE UPGRADE WILL HAPPEN<\/p>\n<p>MATTER OF TIME \ud83d\ude80 <a href=\"https:\/\/t.co\/fj8eAYQbT9\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/fj8eAYQbT9<\/a><\/p>\n<p>&mdash; The Bitcoin Historian (@pete_rizzo_) <a href=\"https:\/\/twitter.com\/pete_rizzo_\/status\/2046661838474191243?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 21, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>La industria cripto en general est\u00e1 lidiando con el mismo problema a diferentes velocidades. TRON anunci\u00f3 una actualizaci\u00f3n poscu\u00e1ntica llamada QuantumShield a principios de 2026, ejecutando firmas h\u00edbridas en su red de prueba, logrando un rendimiento comparable pero soportando tama\u00f1os de transacci\u00f3n aproximadamente un 30% mayores. Algorand integr\u00f3 pruebas de estado poscu\u00e1nticas ya en 2022.<\/p>\n<p>El debate sobre Bitcoin, como muestran las propuestas en torno a los primeros monederos de Satoshi, se encuentra todav\u00eda en gran medida en fase de discusi\u00f3n, dada la complejidad de coordinar cambios de protocolo en una red descentralizada sin un equipo central.<\/p>\n<p>Lo que diferencia el enfoque de Ripple es la combinaci\u00f3n de una ventaja arquitect\u00f3nica ya existente, la rotaci\u00f3n nativa de claves, con una hoja de ruta estructurada y secuencial e investigaci\u00f3n activa en criptograf\u00eda.<\/p>\n<p>XRPL ya est\u00e1 ejecutando c\u00f3digo de prueba. Se trata de una ventaja significativa, aunque 2028 sigue estando a dos a\u00f1os de distancia y la transici\u00f3n requerir\u00e1 una coordinaci\u00f3n cuidadosa con cada validador, instituci\u00f3n y desarrollador que construya sobre la red.<\/p>\n<p><strong>DESCUBRA: <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/preventas\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Las mejores preventas de criptomonedas<\/a><\/strong><\/p>\n<p><strong>Siga a 99Bitcoins en <a class=\"general-link\" href=\"https:\/\/twitter.com\/99bitcoins\" target=\"_blank\" rel=\"noopener nofollow\">X<\/a>, <a class=\"general-link\" href=\"https:\/\/www.youtube.com\/99bitcoins\" target=\"_blank\" rel=\"noopener nofollow\">YouTube<\/a> y <a class=\"general-link\" href=\"https:\/\/t.me\/s\/bitcoinnews99\" target=\"_blank\" rel=\"noopener nofollow\">Telegram<\/a> para m\u00e1s noticias y an\u00e1lisis de criptomonedas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguridad poscu\u00e1ntica en XRP Ledger: lo que Ripple est\u00e1 haciendo<\/p>\n","protected":false},"author":135895,"featured_media":32720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[249],"tags":[7],"coin":[74],"class_list":["post-32721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-criptomonedas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse<\/title>\n<meta name=\"description\" content=\"Existe una amenaza m\u00e1s sutil que se suma a la anterior. Los investigadores la denominan &quot;recolectar ahora, descifrar despu\u00e9s&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse\" \/>\n<meta property=\"og:description\" content=\"Existe una amenaza m\u00e1s sutil que se suma a la anterior. Los investigadores la denominan &quot;recolectar ahora, descifrar despu\u00e9s&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-27T07:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/\"},\"author\":{\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\"},\"headline\":\"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse\",\"datePublished\":\"2026-04-27T07:00:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/\"},\"wordCount\":1245,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg\",\"keywords\":[\"Noticias Criptomonedas\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/\",\"name\":\"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg\",\"datePublished\":\"2026-04-27T07:00:35+00:00\",\"description\":\"Existe una amenaza m\u00e1s sutil que se suma a la anterior. Los investigadores la denominan \\\"recolectar ahora, descifrar despu\u00e9s\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\",\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"caption\":\"Ver\u00f3nica Llabr\u00e9s\"},\"description\":\"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/verollabres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse","description":"Existe una amenaza m\u00e1s sutil que se suma a la anterior. Los investigadores la denominan \"recolectar ahora, descifrar despu\u00e9s\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/","og_locale":"es_ES","og_type":"article","og_title":"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse","og_description":"Existe una amenaza m\u00e1s sutil que se suma a la anterior. Los investigadores la denominan \"recolectar ahora, descifrar despu\u00e9s\".","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/","og_site_name":"99bitcoins ES","article_published_time":"2026-04-27T07:00:35+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg","type":"image\/jpeg"}],"author":"Ver\u00f3nica Llabr\u00e9s","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ver\u00f3nica Llabr\u00e9s","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/"},"author":{"name":"Ver\u00f3nica Llabr\u00e9s","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a"},"headline":"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse","datePublished":"2026-04-27T07:00:35+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/"},"wordCount":1245,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg","keywords":["Noticias Criptomonedas"],"articleSection":["Altcoins"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/","name":"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg","datePublished":"2026-04-27T07:00:35+00:00","description":"Existe una amenaza m\u00e1s sutil que se suma a la anterior. Los investigadores la denominan \"recolectar ahora, descifrar despu\u00e9s\".","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/ChatGPT-Image-Mar-17-2026-12_11_47-PM-2.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/el-avance-poscuantico-de-xrp-ledger-que-esta-haciendo-realmente-ripple-para-prepararse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/"},{"@type":"ListItem","position":4,"name":"El avance poscu\u00e1ntico de XRP Ledger: qu\u00e9 est\u00e1 haciendo realmente Ripple para prepararse"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a","name":"Ver\u00f3nica Llabr\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","caption":"Ver\u00f3nica Llabr\u00e9s"},"description":"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.","url":"https:\/\/99bitcoins.com\/es\/author\/verollabres\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/32721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135895"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=32721"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/32721\/revisions"}],"predecessor-version":[{"id":32737,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/32721\/revisions\/32737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/32720"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=32721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=32721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=32721"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=32721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}