{"id":29485,"date":"2026-01-06T09:30:13","date_gmt":"2026-01-06T09:30:13","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=29485"},"modified":"2026-01-06T09:29:37","modified_gmt":"2026-01-06T09:29:37","slug":"trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/","title":{"rendered":"Trump amenaza a Colombia y M\u00e9xico mientras Bitcoin supera los 93.000 d\u00f3lares"},"content":{"rendered":"<p>Apenas ha transcurrido una semana de 2026 y Am\u00e9rica Latina ya vuelve a ocupar el centro del tablero geopol\u00edtico. El detonante: la captura de Nicol\u00e1s Maduro en Venezuela, un episodio que, seg\u00fan Donald Trump, abre la puerta a nuevas operaciones militares de Estados Unidos en la regi\u00f3n. Sin embargo, el mercado no reaccion\u00f3 como cabr\u00eda esperar. Lejos de retroceder, <strong>Bitcoin avanz\u00f3 con paso firme y rebas\u00f3 los 93.000 d\u00f3lares<\/strong>, con una subida cercana al 3,3% desde los 89.990 d\u00f3lares.<\/p>\n<p>La calma, no obstante, puede ser enga\u00f1osa. Que el precio se mantenga estable ante un sobresalto pol\u00edtico no equivale a inmunidad. La posibilidad de una escalada mayor \u2014y de nuevas tensiones impulsadas desde Washington\u2014 podr\u00eda acabar alterando el equilibrio, tambi\u00e9n en el universo cripto. En un entorno as\u00ed, la gesti\u00f3n del riesgo vuelve a ser m\u00e1s necesaria que nunca.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">President Trump has declared that America needs Greenland for \u201cnational security.\u201d<\/p>\n<p>Follow: <a href=\"https:\/\/twitter.com\/AFpost?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@AFpost<\/a> <a href=\"https:\/\/t.co\/AzdrU0G5X3\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/AzdrU0G5X3<\/a><\/p>\n<p>&mdash; AF Post (@AFpost) <a href=\"https:\/\/twitter.com\/AFpost\/status\/2007880923459785020?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 4, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>\u00bfQu\u00e9 ha ocurrido y por qu\u00e9 importa a Bitcoin?<\/h2>\n<p>Trump afirm\u00f3 que una operaci\u00f3n militar en Colombia \u201cle suena bien\u201d y a\u00f1adi\u00f3 que \u201calgo habr\u00e1 que hacer\u201d en M\u00e9xico. Adem\u00e1s, extendi\u00f3 sus cr\u00edticas a Cuba tras la intervenci\u00f3n en Venezuela. Colombia, M\u00e9xico y Cuba respondieron condenando la acci\u00f3n estadounidense, advirtiendo de que puede desestabilizar la seguridad regional.<\/p>\n<p class=\"p1\"><div class=\"chart crypto-chart-instance\" id=\"crypto_chart_6a580b3b7d6f0\"\n\tdata-coin-id=\"bitcoin\">\n\t<div class=\"chart__header\">\n\t\t<div class=\"chart__info\">\n\t\t\t<div class=\"chart__info-icon\">\n\t\t\t\t<img id=\"crypto_chart_6a580b3b7d6f0-chart__info-icon-img\" \/>\n\t\t\t\t<div class=\"chart__info-name\" id=\"crypto_chart_6a580b3b7d6f0-chart__info-name\"><\/div>\n\t\t\t\t<div class=\"chart__info-symbol\" id=\"crypto_chart_6a580b3b7d6f0-chart__info-symbol\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-current\">\n\t\t\t\t<div class=\"chart__info-price\" id=\"crypto_chart_6a580b3b7d6f0-chart__info-price\"><\/div>\n\t\t\t\t<div class=\"chart__info-change\" id=\"crypto_chart_6a580b3b7d6f0-chart__info-change\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-extra\">\n\t\t\t\t<div class=\"chart__info-label\">Market Cap<\/div>\n\t\t\t\t<div class=\"chart__info-marketcap\" id=\"crypto_chart_6a580b3b7d6f0-chart__info-marketcap\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"chart__controls\">\n\t\t\t<div class=\"chart__controls-group\">\n\t\t\t\t<button class=\"chart__button chart__button--24h\"\n\t\t\t\t\tid=\"crypto_chart_6a580b3b7d6f0-btn-24h\">24h<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--7d\"\n\t\t\t\t\tid=\"crypto_chart_6a580b3b7d6f0-btn-7d\">7d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--30d\"\n\t\t\t\t\tid=\"crypto_chart_6a580b3b7d6f0-btn-30d\">30d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--1y\"\n\t\t\t\t\tid=\"crypto_chart_6a580b3b7d6f0-btn-1y\">1y<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--all-time\"\n\t\t\t\t\tid=\"crypto_chart_6a580b3b7d6f0-btn-all-time\">All Time<\/button>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"chart__container\">\n\t\t<canvas class=\"chart__canvas\" id=\"crypto_chart_6a580b3b7d6f0-cryptoChart\"><\/canvas>\n\t<\/div>\n<\/div>\n\n<p>En este contexto, la pregunta es inevitable: <strong>\u00bfpor qu\u00e9 Bitcoin subi\u00f3 en lugar de caer?<\/strong><\/p>\n<p>Una explicaci\u00f3n plausible es que los acontecimientos se desarrollaron a tal velocidad que el mercado no tuvo margen para reaccionar con p\u00e1nico. Los primeros anuncios llegaron pronto y redujeron parte de la incertidumbre, dejando poco espacio para ventas apresuradas. En t\u00e9rminos sencillos: <strong>no hubo tiempo para que la inquietud se trasladara a las pantallas<\/strong>.<\/p>\n<p>Aun as\u00ed, el historial invita a la prudencia. No hay garant\u00edas de que futuras operaciones militares se produzcan con la misma rapidez ni con un desenlace similar. Venezuela sigue atravesando un momento especialmente fr\u00e1gil, lejos de una transici\u00f3n pol\u00edtica limpia o pac\u00edfica.<\/p>\n<p>A todo ello se suma un precedente reciente: la incertidumbre comercial que marc\u00f3 buena parte de 2024 y que arrastr\u00f3 efectos a 2025. Las amenazas arancelarias \u2014especialmente en el pulso con China\u2014 desataron episodios de \u201cmodo p\u00e1nico\u201d en los mercados y movimientos bruscos en Bitcoin. Cada ronda de titulares se tradujo en ventas defensivas, con el mercado cripto funcionando como una monta\u00f1a rusa emocional para los inversores.<\/p>\n<h2>\u00bfQu\u00e9 significa esta tensi\u00f3n en Am\u00e9rica Latina para los inversores en Bitcoin?<\/h2>\n<p>Am\u00e9rica Latina ya es, desde hace a\u00f1os, uno de los territorios donde las criptomonedas tienen un uso m\u00e1s cotidiano. En pa\u00edses como <strong>Venezuela<\/strong> o <strong>Argentina<\/strong>, muchas familias recurren a <a href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/stablecoins\/\"><strong><em>stablecoins<\/em><\/strong><\/a> y a Bitcoin como v\u00eda de escape frente a monedas locales debilitadas y controles econ\u00f3micos.<\/p>\n<p>Si la tensi\u00f3n se extiende a Colombia o M\u00e9xico, podr\u00eda activarse una din\u00e1mica similar: <strong>m\u00e1s demanda local de criptoactivos como alternativa monetaria<\/strong>, alimentando el relato de Bitcoin como \u201crefugio\u201d. Pero conviene no confundir demanda regional con garant\u00eda de subida global. La historia demuestra que el precio no siempre responde de forma lineal al aumento del inter\u00e9s en un \u00fanico punto del mapa.<\/p>\n<p>Adem\u00e1s, los episodios de conflicto suelen empujar a los grandes fondos a reducir exposici\u00f3n al riesgo en el corto plazo. Eso implica vender activos vol\u00e1tiles \u2014como las criptomonedas\u2014, refugiarse en liquidez y, en ocasiones, recomprar m\u00e1s adelante a precios inferiores. En otras palabras: <strong>el discurso de refugio no impide ca\u00eddas bruscas cuando el mercado entra en modo defensivo<\/strong>.<\/p>\n<p>Existe tambi\u00e9n un giro pol\u00edtico adicional: Trump no solo recurre a la ret\u00f3rica militar, sino que suele acompa\u00f1arla de instrumentos econ\u00f3micos como sanciones, amenazas arancelarias o presi\u00f3n comercial. Si su equipo decide incluir el \u00e1mbito cripto o los pagos transfronterizos en futuras medidas, aparecer\u00eda un riesgo extra para plataformas, empresas y usuarios en la regi\u00f3n, especialmente en un entorno regulatorio que ya es complejo.<\/p>\n<h2>\u00bfC\u00f3mo deber\u00eda gestionar el riesgo un principiante ante un shock geopol\u00edtico?<\/h2>\n<p>En primer lugar, conviene tomar distancia. Un movimiento de 90.000 a 93.000 d\u00f3lares suena enorme en redes sociales, pero encaja dentro de la volatilidad habitual de Bitcoin. Para un activo de gran capitalizaci\u00f3n que a\u00fan se comporta como una versi\u00f3n \u201chiperactiva\u201d de la renta variable tecnol\u00f3gica, oscilaciones diarias del 3% o 4% no son excepcionales. Si decides invertir, <strong>hazlo asumiendo que una ca\u00edda del 20% o 30% puede ocurrir en cualquier momento<\/strong>.<\/p>\n<p>Segundo: separar relato y estrategia. Que aumente la tensi\u00f3n en Am\u00e9rica Latina no significa que \u201csiempre que hay guerra, Bitcoin sube\u201d. Significa que tu plan debe contemplar escenarios en los que el precio caiga con fuerza por culpa de titulares alarmantes, no solo los d\u00edas en que el mercado avanza sin sobresaltos.<\/p>\n<p>Y, por \u00faltimo, medidas concretas:<\/p>\n<ul>\n<li>Mant\u00e9n en los <a href=\"https:\/\/99bitcoins.com\/es\/mejores-exchanges-cripto\/principiantes\/\"><strong><em>exchanges<\/em><\/strong><\/a> solo el capital destinado a operar.<\/li>\n<li>Guarda las posiciones a largo plazo en carteras bajo tu control.<\/li>\n<li>Vigila indicadores como la volatilidad o la dominancia de BTC, que muchos inversores usan para medir el nivel de miedo y apetito por riesgo, de manera similar a c\u00f3mo los mercados tradicionales siguen el VIX.<\/li>\n<\/ul>\n<p data-is-last-node=\"\" data-is-only-node=\"\">La geopol\u00edtica seguir\u00e1 cruz\u00e1ndose con la narrativa de Bitcoin, nos guste o no. La diferencia entre sobrevivir a los titulares o sufrirlos suele estar en algo simple: <strong>tener reglas claras antes de que llegue el pr\u00f3ximo susto<\/strong>.<\/p>\n<p data-is-last-node=\"\" data-is-only-node=\"\"><strong>DESCUBRE las \u00faltimas <a href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/gemas-crypto\/\">gemas crypto<\/a> que podr\u00edan servir de refugio<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apenas ha transcurrido una semana de 2026 y Am\u00e9rica Latina ya vuelve a ocupar el centro del tablero geopol\u00edtico. El detonante: la captura de Nicol\u00e1s Maduro en Venezuela, un episodio que, seg\u00fan Donald Trump, abre la puerta a nuevas operaciones militares de Estados Unidos en la regi\u00f3n. Sin embargo, el mercado no reaccion\u00f3 como cabr\u00eda..<\/p>\n","protected":false},"author":135878,"featured_media":23514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[248],"tags":[10],"coin":[74],"class_list":["post-29485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trump amenaza a Colombia y M\u00e9xico, Bitcoin supera los 93K<\/title>\n<meta name=\"description\" content=\"Apenas ha transcurrido una semana de 2026 y Am\u00e9rica Latina ya vuelve a ocupar el centro del tablero geopol\u00edtico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump amenaza a Colombia y M\u00e9xico, Bitcoin supera los 93K\" \/>\n<meta property=\"og:description\" content=\"Apenas ha transcurrido una semana de 2026 y Am\u00e9rica Latina ya vuelve a ocupar el centro del tablero geopol\u00edtico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T09:30:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/09\/rendimiento-bitcoin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1433\" \/>\n\t<meta property=\"og:image:height\" content=\"1433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/\"},\"author\":{\"name\":\"Roger\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/7c39d0c90c3f77ffbfc6582191be7ab8\"},\"headline\":\"Trump amenaza a Colombia y M\u00e9xico mientras Bitcoin supera los 93.000 d\u00f3lares\",\"datePublished\":\"2026-01-06T09:30:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/\"},\"wordCount\":944,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/09\\\/rendimiento-bitcoin.jpg\",\"keywords\":[\"Noticias Bitcoin\"],\"articleSection\":[\"Bitcoin\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/\",\"name\":\"Trump amenaza a Colombia y M\u00e9xico, Bitcoin supera los 93K\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/09\\\/rendimiento-bitcoin.jpg\",\"datePublished\":\"2026-01-06T09:30:13+00:00\",\"description\":\"Apenas ha transcurrido una semana de 2026 y Am\u00e9rica Latina ya vuelve a ocupar el centro del tablero geopol\u00edtico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/09\\\/rendimiento-bitcoin.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/09\\\/rendimiento-bitcoin.jpg\",\"width\":1433,\"height\":1433,\"caption\":\"rendimiento bitcoin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bitcoin\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/bitcoin\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Trump amenaza a Colombia y M\u00e9xico mientras Bitcoin supera los 93.000 d\u00f3lares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/7c39d0c90c3f77ffbfc6582191be7ab8\",\"name\":\"Roger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2cadc94d0b1bd8568855beb998374af18d8e38097d23b1f8bc5124c7e592927?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2cadc94d0b1bd8568855beb998374af18d8e38097d23b1f8bc5124c7e592927?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2cadc94d0b1bd8568855beb998374af18d8e38097d23b1f8bc5124c7e592927?s=96&d=mm&r=g\",\"caption\":\"Roger\"},\"description\":\"Editor principal de 99Bitcoins en espa\u00f1ol. Llevo m\u00e1s de 10 a\u00f1os redactando, planificando y liderando el contenido de alto impacto en medios online, con un foco profesional en el sector fintech, blockchain, tecnolog\u00eda, banca, B2B y B2C.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/rogermolins\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump amenaza a Colombia y M\u00e9xico, Bitcoin supera los 93K","description":"Apenas ha transcurrido una semana de 2026 y Am\u00e9rica Latina ya vuelve a ocupar el centro del tablero geopol\u00edtico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/","og_locale":"es_ES","og_type":"article","og_title":"Trump amenaza a Colombia y M\u00e9xico, Bitcoin supera los 93K","og_description":"Apenas ha transcurrido una semana de 2026 y Am\u00e9rica Latina ya vuelve a ocupar el centro del tablero geopol\u00edtico.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/","og_site_name":"99bitcoins ES","article_published_time":"2026-01-06T09:30:13+00:00","og_image":[{"width":1433,"height":1433,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/09\/rendimiento-bitcoin.jpg","type":"image\/jpeg"}],"author":"Roger","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Roger","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/"},"author":{"name":"Roger","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/7c39d0c90c3f77ffbfc6582191be7ab8"},"headline":"Trump amenaza a Colombia y M\u00e9xico mientras Bitcoin supera los 93.000 d\u00f3lares","datePublished":"2026-01-06T09:30:13+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/"},"wordCount":944,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/09\/rendimiento-bitcoin.jpg","keywords":["Noticias Bitcoin"],"articleSection":["Bitcoin"],"inLanguage":"es","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/","name":"Trump amenaza a Colombia y M\u00e9xico, Bitcoin supera los 93K","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/09\/rendimiento-bitcoin.jpg","datePublished":"2026-01-06T09:30:13+00:00","description":"Apenas ha transcurrido una semana de 2026 y Am\u00e9rica Latina ya vuelve a ocupar el centro del tablero geopol\u00edtico.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/09\/rendimiento-bitcoin.jpg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/09\/rendimiento-bitcoin.jpg","width":1433,"height":1433,"caption":"rendimiento bitcoin"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/trump-amenaza-a-colombia-y-mexico-mientras-bitcoin-supera-los-93-000-dolares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Bitcoin","item":"https:\/\/99bitcoins.com\/es\/noticias\/bitcoin\/"},{"@type":"ListItem","position":4,"name":"Trump amenaza a Colombia y M\u00e9xico mientras Bitcoin supera los 93.000 d\u00f3lares"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/7c39d0c90c3f77ffbfc6582191be7ab8","name":"Roger","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2cadc94d0b1bd8568855beb998374af18d8e38097d23b1f8bc5124c7e592927?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2cadc94d0b1bd8568855beb998374af18d8e38097d23b1f8bc5124c7e592927?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2cadc94d0b1bd8568855beb998374af18d8e38097d23b1f8bc5124c7e592927?s=96&d=mm&r=g","caption":"Roger"},"description":"Editor principal de 99Bitcoins en espa\u00f1ol. Llevo m\u00e1s de 10 a\u00f1os redactando, planificando y liderando el contenido de alto impacto en medios online, con un foco profesional en el sector fintech, blockchain, tecnolog\u00eda, banca, B2B y B2C.","url":"https:\/\/99bitcoins.com\/es\/author\/rogermolins\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/29485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135878"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=29485"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/29485\/revisions"}],"predecessor-version":[{"id":29486,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/29485\/revisions\/29486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/23514"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=29485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=29485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=29485"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=29485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}