{"id":26214,"date":"2025-11-01T07:20:20","date_gmt":"2025-11-01T07:20:20","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=26214"},"modified":"2025-10-31T20:42:29","modified_gmt":"2025-10-31T20:42:29","slug":"las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/","title":{"rendered":"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio"},"content":{"rendered":"<p>Ballenas de Ethereum que permanec\u00edan inactivas desde los primeros a\u00f1os del proyecto han vuelto a moverse. Datos en cadena de Santiment revelan que carteras antiguas, muchas de la \u00e9poca de la ICO de 2014, han desplazado grandes cantidades de Ether por primera vez en casi diez a\u00f1os.<\/p>\n<h2>Carteras veteranas vuelven a la vida<\/h2>\n<p>Durante septiembre se registraron dos picos notables en el indicador age consumed, que rastrea cu\u00e1ntos tokens antiguos de ETH cambian de direcci\u00f3n. El 6 de septiembre, el valor super\u00f3 los 500 millones; a finales de mes alcanz\u00f3 los 603 millones. Solo en julio la actividad fue mayor.<\/p>\n<p>Uno de los movimientos m\u00e1s llamativos provino de una cartera que durante la ICO de Ethereum compr\u00f3 20.000 ETH por poco m\u00e1s de 6.000 d\u00f3lares. Este propietario envi\u00f3 recientemente 1.500 ETH a Kraken, unos 6 millones de d\u00f3lares. Los tokens restantes, que ahora valen m\u00e1s de 78 millones, siguen en la cartera.<\/p>\n<p>Otros participantes tempranos dieron pasos similares. Un inversor que en su d\u00eda recibi\u00f3 1 mill\u00f3n de ETH en total traslad\u00f3 150.000 tokens a una nueva direcci\u00f3n para hacer staking. La inversi\u00f3n inicial fue de 310.000 d\u00f3lares y hoy representa un valor cercano a los 4.000 millones.<\/p>\n<p class=\"p1\"><div class=\"chart crypto-chart-instance\" id=\"crypto_chart_6a58152f93e2f\"\n\tdata-coin-id=\"ethereum\">\n\t<div class=\"chart__header\">\n\t\t<div class=\"chart__info\">\n\t\t\t<div class=\"chart__info-icon\">\n\t\t\t\t<img id=\"crypto_chart_6a58152f93e2f-chart__info-icon-img\" \/>\n\t\t\t\t<div class=\"chart__info-name\" id=\"crypto_chart_6a58152f93e2f-chart__info-name\"><\/div>\n\t\t\t\t<div class=\"chart__info-symbol\" id=\"crypto_chart_6a58152f93e2f-chart__info-symbol\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-current\">\n\t\t\t\t<div class=\"chart__info-price\" id=\"crypto_chart_6a58152f93e2f-chart__info-price\"><\/div>\n\t\t\t\t<div class=\"chart__info-change\" id=\"crypto_chart_6a58152f93e2f-chart__info-change\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-extra\">\n\t\t\t\t<div class=\"chart__info-label\">Market Cap<\/div>\n\t\t\t\t<div class=\"chart__info-marketcap\" id=\"crypto_chart_6a58152f93e2f-chart__info-marketcap\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"chart__controls\">\n\t\t\t<div class=\"chart__controls-group\">\n\t\t\t\t<button class=\"chart__button chart__button--24h\"\n\t\t\t\t\tid=\"crypto_chart_6a58152f93e2f-btn-24h\">24h<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--7d\"\n\t\t\t\t\tid=\"crypto_chart_6a58152f93e2f-btn-7d\">7d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--30d\"\n\t\t\t\t\tid=\"crypto_chart_6a58152f93e2f-btn-30d\">30d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--1y\"\n\t\t\t\t\tid=\"crypto_chart_6a58152f93e2f-btn-1y\">1y<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--all-time\"\n\t\t\t\t\tid=\"crypto_chart_6a58152f93e2f-btn-all-time\">All Time<\/button>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"chart__container\">\n\t\t<canvas class=\"chart__canvas\" id=\"crypto_chart_6a58152f93e2f-cryptoChart\"><\/canvas>\n\t<\/div>\n<\/div>\n\n<h2>Qu\u00e9 revela esto sobre la confianza en Ethereum<\/h2>\n<p>Los analistas interpretan el despertar de estas carteras antiguas como se\u00f1al de actividad renovada, aunque no necesariamente de desconfianza. Muchos propietarios venden apenas una peque\u00f1a fracci\u00f3n, mientras la mayor parte de sus tenencias permanece intacta. Eso apunta m\u00e1s a toma de beneficios que a una retirada masiva.<\/p>\n<p>Adem\u00e1s, las transacciones llegan en un momento en que Ethereum ronda su m\u00e1ximo hist\u00f3rico y entidades institucionales como Bitmine ampl\u00edan sus posiciones. Este contraste subraya que el mercado sigue dividido sobre las perspectivas a corto plazo, pero la confianza a largo plazo se mantiene firme.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">An <a href=\"https:\/\/twitter.com\/hashtag\/Ethereum?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">#Ethereum<\/a> ICO participant who received 1,000,000 <a href=\"https:\/\/twitter.com\/search?q=%24ETH&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$ETH<\/a> just woke up after 8 years of dormancy.<\/p>\n<p>He moved 150,000 <a href=\"https:\/\/twitter.com\/search?q=%24ETH&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$ETH<\/a>($645M) to a new wallet for staking. <\/p>\n<p>He invested $310K in the ICO via 3 wallets and received 1,000,000 <a href=\"https:\/\/twitter.com\/search?q=%24ETH&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$ETH<\/a> \u2014 now worth $4.3B.<\/p>\n<p>After staking 150,000 <a href=\"https:\/\/twitter.com\/search?q=%24ETH&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$ETH<\/a>, he\u2026 <a href=\"https:\/\/t.co\/B5CBTBJ2O5\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/B5CBTBJ2O5<\/a><\/p>\n<p>&mdash; Lookonchain (@lookonchain) <a href=\"https:\/\/twitter.com\/lookonchain\/status\/1963770197871046708?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">September 5, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Se\u00f1al para el mercado<\/h2>\n<p>La actividad reciente demuestra que la liquidez en torno a Ethereum aumenta sin ejercer presi\u00f3n directa sobre el precio. Seg\u00fan Santiment y Nansen, solo una peque\u00f1a porci\u00f3n de las monedas antiguas ha llegado a los exchanges. La mayor\u00eda de las carteras permanecen en silencio, lo que sugiere que muchos inversores pioneros mantienen sus posiciones.<\/p>\n<p>Para los analistas, esto resulta alentador. Demuestra que incluso despu\u00e9s de diez a\u00f1os, la convicci\u00f3n en Ethereum perdura, especialmente entre quienes apostaron por la moneda desde el principio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ballenas de Ethereum que permanec\u00edan inactivas desde los primeros a\u00f1os del proyecto han vuelto a moverse. Datos en cadena de Santiment revelan que carteras antiguas, muchas de la \u00e9poca de la ICO de 2014, han desplazado grandes cantidades de Ether por primera vez en casi diez a\u00f1os. Carteras veteranas vuelven a la vida Durante septiembre..<\/p>\n","protected":false},"author":135895,"featured_media":24577,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[249],"tags":[7],"coin":[74],"class_list":["post-26214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-criptomonedas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio<\/title>\n<meta name=\"description\" content=\"Ballenas de Ethereum que permanec\u00edan inactivas desde los primeros a\u00f1os del proyecto han vuelto a moverse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio\" \/>\n<meta property=\"og:description\" content=\"Ballenas de Ethereum que permanec\u00edan inactivas desde los primeros a\u00f1os del proyecto han vuelto a moverse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-01T07:20:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/10\/kiyosaki-ethereum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"716\" \/>\n\t<meta property=\"og:image:height\" content=\"716\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/\"},\"author\":{\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\"},\"headline\":\"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio\",\"datePublished\":\"2025-11-01T07:20:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/\"},\"wordCount\":422,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/10\\\/kiyosaki-ethereum.jpg\",\"keywords\":[\"Noticias Criptomonedas\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/\",\"name\":\"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/10\\\/kiyosaki-ethereum.jpg\",\"datePublished\":\"2025-11-01T07:20:20+00:00\",\"description\":\"Ballenas de Ethereum que permanec\u00edan inactivas desde los primeros a\u00f1os del proyecto han vuelto a moverse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/10\\\/kiyosaki-ethereum.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/10\\\/kiyosaki-ethereum.jpg\",\"width\":716,\"height\":716,\"caption\":\"kiyosaki ethereum\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\",\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"caption\":\"Ver\u00f3nica Llabr\u00e9s\"},\"description\":\"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/verollabres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio","description":"Ballenas de Ethereum que permanec\u00edan inactivas desde los primeros a\u00f1os del proyecto han vuelto a moverse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/","og_locale":"es_ES","og_type":"article","og_title":"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio","og_description":"Ballenas de Ethereum que permanec\u00edan inactivas desde los primeros a\u00f1os del proyecto han vuelto a moverse.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/","og_site_name":"99bitcoins ES","article_published_time":"2025-11-01T07:20:20+00:00","og_image":[{"width":716,"height":716,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/10\/kiyosaki-ethereum.jpg","type":"image\/jpeg"}],"author":"Ver\u00f3nica Llabr\u00e9s","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ver\u00f3nica Llabr\u00e9s","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/"},"author":{"name":"Ver\u00f3nica Llabr\u00e9s","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a"},"headline":"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio","datePublished":"2025-11-01T07:20:20+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/"},"wordCount":422,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/10\/kiyosaki-ethereum.jpg","keywords":["Noticias Criptomonedas"],"articleSection":["Altcoins"],"inLanguage":"es","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/","name":"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/10\/kiyosaki-ethereum.jpg","datePublished":"2025-11-01T07:20:20+00:00","description":"Ballenas de Ethereum que permanec\u00edan inactivas desde los primeros a\u00f1os del proyecto han vuelto a moverse.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/10\/kiyosaki-ethereum.jpg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/10\/kiyosaki-ethereum.jpg","width":716,"height":716,"caption":"kiyosaki ethereum"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/las-ballenas-de-ethereum-despiertan-tras-una-decada-de-silencio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/es\/noticias\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Las ballenas de Ethereum despiertan tras una d\u00e9cada de silencio"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a","name":"Ver\u00f3nica Llabr\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","caption":"Ver\u00f3nica Llabr\u00e9s"},"description":"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.","url":"https:\/\/99bitcoins.com\/es\/author\/verollabres\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/26214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135895"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=26214"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/26214\/revisions"}],"predecessor-version":[{"id":26215,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/26214\/revisions\/26215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/24577"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=26214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=26214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=26214"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=26214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}