{"id":14896,"date":"2025-05-09T09:00:32","date_gmt":"2025-05-09T09:00:32","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=14896"},"modified":"2025-05-09T09:00:32","modified_gmt":"2025-05-09T09:00:32","slug":"el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/","title":{"rendered":"El bitcoin supera los 100.000 d\u00f3lares y el mercado de criptomonedas asciende a 3 billones de d\u00f3lares"},"content":{"rendered":"<p><strong>Viernes, 9 de mayo de 2025 \u2013 No ha tardado mucho. Por primera vez en meses, Bitcoin alcanza los 100.000 d\u00f3lares, y el mercado global de criptomonedas acaba de superar de nuevo la barrera de los 3 billones de d\u00f3lares, gracias en parte a un gran revuelo en el escenario geopol\u00edtico.<\/strong><\/p>\n<p>Un acuerdo comercial recientemente anunciado entre Estados Unidos y el Reino Unido dio a los operadores de los mercados tradicionales y digitales algo por lo que alegrarse.<\/p>\n<p>Es un n\u00famero que no hemos visto en a\u00f1os, y el momento tiene un mont\u00f3n de gente preguntando si este es el comienzo de una ruptura m\u00e1s grande o simplemente una fiebre del az\u00facar de corta duraci\u00f3n.<\/p>\n<p class=\"p1\"><div class=\"chart crypto-chart-instance\" id=\"crypto_chart_6a57fdb66b2c2\"\n\tdata-coin-id=\"btc-bitcoin\">\n\t<div class=\"chart__header\">\n\t\t<div class=\"chart__info\">\n\t\t\t<div class=\"chart__info-icon\">\n\t\t\t\t<img id=\"crypto_chart_6a57fdb66b2c2-chart__info-icon-img\" \/>\n\t\t\t\t<div class=\"chart__info-name\" id=\"crypto_chart_6a57fdb66b2c2-chart__info-name\"><\/div>\n\t\t\t\t<div class=\"chart__info-symbol\" id=\"crypto_chart_6a57fdb66b2c2-chart__info-symbol\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-current\">\n\t\t\t\t<div class=\"chart__info-price\" id=\"crypto_chart_6a57fdb66b2c2-chart__info-price\"><\/div>\n\t\t\t\t<div class=\"chart__info-change\" id=\"crypto_chart_6a57fdb66b2c2-chart__info-change\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-extra\">\n\t\t\t\t<div class=\"chart__info-label\">Market Cap<\/div>\n\t\t\t\t<div class=\"chart__info-marketcap\" id=\"crypto_chart_6a57fdb66b2c2-chart__info-marketcap\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"chart__controls\">\n\t\t\t<div class=\"chart__controls-group\">\n\t\t\t\t<button class=\"chart__button chart__button--24h\"\n\t\t\t\t\tid=\"crypto_chart_6a57fdb66b2c2-btn-24h\">24h<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--7d\"\n\t\t\t\t\tid=\"crypto_chart_6a57fdb66b2c2-btn-7d\">7d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--30d\"\n\t\t\t\t\tid=\"crypto_chart_6a57fdb66b2c2-btn-30d\">30d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--1y\"\n\t\t\t\t\tid=\"crypto_chart_6a57fdb66b2c2-btn-1y\">1y<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--all-time\"\n\t\t\t\t\tid=\"crypto_chart_6a57fdb66b2c2-btn-all-time\">All Time<\/button>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"chart__container\">\n\t\t<canvas class=\"chart__canvas\" id=\"crypto_chart_6a57fdb66b2c2-cryptoChart\"><\/canvas>\n\t<\/div>\n<\/div>\n\n<h2>Bitcoin vuelve a superar los 100.000 d\u00f3lares<\/h2>\n<p>En el centro de la subida, por supuesto, estaba Bitcoin. Subi\u00f3 m\u00e1s de un 5%, cruzando la barrera de las seis cifras y alcanzando los 101.329 d\u00f3lares. Es la primera vez que supera los 100.000 d\u00f3lares desde febrero, y no lo hizo solo. Ethereum tambi\u00e9n subi\u00f3 m\u00e1s de un 14% hasta cruzar los 2.050 d\u00f3lares. Otros grandes nombres como Solana, XRP y Cardano tambi\u00e9n registraron fuertes ganancias, contribuyendo todos al hito de 3 billones de d\u00f3lares de capitalizaci\u00f3n de mercado.<\/p>\n<p>Los operadores no s\u00f3lo est\u00e1n persiguiendo velas verdes aqu\u00ed. El movimiento fue impulsado por algunas buenas noticias raras desde el frente pol\u00edtico mundial.<\/p>\n<h2>El acuerdo comercial que encendi\u00f3 la mecha<\/h2>\n<p>Lo que realmente encendi\u00f3 la mecha fue el anuncio conjunto del presidente Donald Trump y el primer ministro del Reino Unido, Keir Starmer. Los dos l\u00edderes revelaron un acuerdo comercial preliminar destinado a reducir los aranceles e impulsar el acceso al mercado entre los dos pa\u00edses.<\/p>\n<p>Estados Unidos reducir\u00e1 los aranceles a los autom\u00f3viles y metales brit\u00e1nicos. A cambio, el Reino Unido suprime el impuesto sobre los servicios digitales y reduce los aranceles sobre los productos estadounidenses. Se trata de un acuerdo con grandes implicaciones para el comercio y, al parecer, tambi\u00e9n para las criptomonedas.<\/p>\n<p>Lee sobre <a href=\"https:\/\/99bitcoins.com\/es\/analisis\/litecoin-vs-bitcoin\/\"><strong>Litecoin vs Bitcoin<\/strong><\/a><\/p>\n<h2>\u00bfLa reacci\u00f3n de Wall Street? Tambi\u00e9n verde<\/h2>\n<p>La noticia no s\u00f3lo ha animado a las criptomonedas. Los mercados tradicionales tambi\u00e9n se animaron. El Dow subi\u00f3 m\u00e1s de 250 puntos, y el Nasdaq y el S&amp;P 500 tambi\u00e9n registraron ganancias. Parece que los inversores ven este acuerdo como un paso hacia la reducci\u00f3n de las tensiones comerciales, que \u00faltimamente han estado crispando los nervios.<\/p>\n<p>Cuando los mercados tradicionales respiran tranquilos, las criptomonedas tienden a subirse a la misma ola. Y eso es lo que estamos viendo ahora.<\/p>\n<h2>El bitcoin alcanza los 100.000 d\u00f3lares: las instituciones vigilan de cerca<\/h2>\n<p>Entre bastidores, las grandes instituciones est\u00e1n prestando atenci\u00f3n. Cada vez son m\u00e1s las empresas que invierten en activos digitales, especialmente desde que los ETF de Bitcoin obtuvieron luz verde a principios de este a\u00f1o. Eso significa que cuando vuelve la confianza, viene acompa\u00f1ada de mucho dinero.<\/p>\n<p>Y ahora que la capitalizaci\u00f3n del mercado vuelve a estar en el rango de los 3 billones de d\u00f3lares, cada vez se cree m\u00e1s que podr\u00edamos estar prepar\u00e1ndonos para el siguiente tramo de una carrera alcista m\u00e1s larga, suponiendo que los problemas regulatorios no estropeen el motor.<\/p>\n<h2>\u00bfY ahora qu\u00e9?<\/h2>\n<p>Superar los 3 billones de d\u00f3lares es algo m\u00e1s que un simple titular. Es un recordatorio de que las criptomonedas siguen estrechamente ligadas al sentimiento global, especialmente cuando los grandes acuerdos pol\u00edticos insin\u00faan que se avecinan aguas econ\u00f3micas m\u00e1s tranquilas. Tanto si el Bitcoin lidera la carrera como si Ethereum realiza grandes movimientos, los activos digitales vuelven a ser el centro de atenci\u00f3n.<\/p>\n<p>Por ahora, el ambiente es optimista. Pero esto es crypto. Como siempre, puede cambiar r\u00e1pidamente. Lee sobre las <a href=\"https:\/\/99bitcoins.com\/es\/criptomonedas\/volatiles\/\"><strong>criptomonedas m\u00e1s vol\u00e1tiles<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viernes, 9 de mayo de 2025 \u2013 No ha tardado mucho. Por primera vez en meses, Bitcoin alcanza los 100.000 d\u00f3lares, y el mercado global de criptomonedas acaba de superar de nuevo la barrera de los 3 billones de d\u00f3lares, gracias en parte a un gran revuelo en el escenario geopol\u00edtico. Un acuerdo comercial recientemente..<\/p>\n","protected":false},"author":135895,"featured_media":14897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8],"tags":[10],"coin":[74],"class_list":["post-14896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El bitcoin supera los 100.000 d\u00f3lares y el mercado asciende<\/title>\n<meta name=\"description\" content=\"No ha tardado mucho. Por primera vez en meses, Bitcoin alcanza los 100.000 d\u00f3lares, y el mercado global de criptomonedas sube con \u00e9l.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El bitcoin supera los 100.000 d\u00f3lares y el mercado asciende\" \/>\n<meta property=\"og:description\" content=\"No ha tardado mucho. Por primera vez en meses, Bitcoin alcanza los 100.000 d\u00f3lares, y el mercado global de criptomonedas sube con \u00e9l.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-09T09:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/05\/bitcoin-100k.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/\"},\"author\":{\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\"},\"headline\":\"El bitcoin supera los 100.000 d\u00f3lares y el mercado de criptomonedas asciende a 3 billones de d\u00f3lares\",\"datePublished\":\"2025-05-09T09:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/\"},\"wordCount\":676,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/bitcoin-100k.webp\",\"keywords\":[\"Noticias Bitcoin\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/\",\"name\":\"El bitcoin supera los 100.000 d\u00f3lares y el mercado asciende\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/bitcoin-100k.webp\",\"datePublished\":\"2025-05-09T09:00:32+00:00\",\"description\":\"No ha tardado mucho. Por primera vez en meses, Bitcoin alcanza los 100.000 d\u00f3lares, y el mercado global de criptomonedas sube con \u00e9l.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/bitcoin-100k.webp\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/bitcoin-100k.webp\",\"width\":768,\"height\":512,\"caption\":\"bitcoin 100k\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El bitcoin supera los 100.000 d\u00f3lares y el mercado de criptomonedas asciende a 3 billones de d\u00f3lares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\",\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"caption\":\"Ver\u00f3nica Llabr\u00e9s\"},\"description\":\"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/verollabres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El bitcoin supera los 100.000 d\u00f3lares y el mercado asciende","description":"No ha tardado mucho. Por primera vez en meses, Bitcoin alcanza los 100.000 d\u00f3lares, y el mercado global de criptomonedas sube con \u00e9l.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/","og_locale":"es_ES","og_type":"article","og_title":"El bitcoin supera los 100.000 d\u00f3lares y el mercado asciende","og_description":"No ha tardado mucho. Por primera vez en meses, Bitcoin alcanza los 100.000 d\u00f3lares, y el mercado global de criptomonedas sube con \u00e9l.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/","og_site_name":"99bitcoins ES","article_published_time":"2025-05-09T09:00:32+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/05\/bitcoin-100k.webp","type":"image\/webp"}],"author":"Ver\u00f3nica Llabr\u00e9s","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ver\u00f3nica Llabr\u00e9s","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/"},"author":{"name":"Ver\u00f3nica Llabr\u00e9s","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a"},"headline":"El bitcoin supera los 100.000 d\u00f3lares y el mercado de criptomonedas asciende a 3 billones de d\u00f3lares","datePublished":"2025-05-09T09:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/"},"wordCount":676,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/05\/bitcoin-100k.webp","keywords":["Noticias Bitcoin"],"articleSection":["Noticias"],"inLanguage":"es","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/","name":"El bitcoin supera los 100.000 d\u00f3lares y el mercado asciende","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/05\/bitcoin-100k.webp","datePublished":"2025-05-09T09:00:32+00:00","description":"No ha tardado mucho. Por primera vez en meses, Bitcoin alcanza los 100.000 d\u00f3lares, y el mercado global de criptomonedas sube con \u00e9l.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/05\/bitcoin-100k.webp","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/05\/bitcoin-100k.webp","width":768,"height":512,"caption":"bitcoin 100k"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/el-bitcoin-supera-los-100-000-dolares-y-el-mercado-de-criptomonedas-asciende-a-3-billones-de-dolares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"El bitcoin supera los 100.000 d\u00f3lares y el mercado de criptomonedas asciende a 3 billones de d\u00f3lares"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a","name":"Ver\u00f3nica Llabr\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","caption":"Ver\u00f3nica Llabr\u00e9s"},"description":"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.","url":"https:\/\/99bitcoins.com\/es\/author\/verollabres\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/14896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135895"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=14896"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/14896\/revisions"}],"predecessor-version":[{"id":14898,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/14896\/revisions\/14898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/14897"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=14896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=14896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=14896"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=14896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}