{"id":12611,"date":"2025-03-06T14:07:27","date_gmt":"2025-03-06T14:07:27","guid":{"rendered":"https:\/\/99bitcoins.com\/es\/?p=12611"},"modified":"2025-03-06T14:07:27","modified_gmt":"2025-03-06T14:07:27","slug":"suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/","title":{"rendered":"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas"},"content":{"rendered":"<p><strong>Jueves, 6 de marzo de 2025 \u2013 El Senado de Arizona avanza en el proyecto de reserva de Bitcoin y queda por detr\u00e1s de Utah en la carrera por la criptolegislaci\u00f3n.<\/strong><\/p>\n<p>A pesar del reciente anuncio del presidente de Estados Unidos, Donald Trump, de una reserva estrat\u00e9gica de criptomonedas en la que participar\u00edan Bitcoin, Ethereum, Ripple, Solana y Cardano, los bancos centrales tanto de Suiza como de Australia han descartado la idea de incorporar criptomonedas a sus reservas oficiales.<\/p>\n<p>El 1 de marzo de 2025, el presidente del Banco Nacional Suizo (SNB), Martin Schlegel, rechaz\u00f3 la propuesta de mantener parte de sus reservas en bitcoin, como propon\u00eda una iniciativa popular.<\/p>\n<p>Seg\u00fan informes locales, Schlegel dijo que las criptodivisas no cumplen las caracter\u00edsticas esenciales que debe tener una buena moneda.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udca5BREAKING: <\/p>\n<p>SWISS NATIONAL BANK REJECTS BITCOIN \ud83d\udea8<\/p>\n<p>SNB President Martin Schlegel says <a href=\"https:\/\/twitter.com\/search?q=%24BTC&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$BTC<\/a> is too volatile and lacks the qualities of a good currency. <\/p>\n<p>THEY\u2019LL REGRET THIS! <a href=\"https:\/\/t.co\/axuNIFmF8x\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/axuNIFmF8x<\/a><\/p>\n<p>&mdash; Crypto Rover (@rovercrc) <a href=\"https:\/\/twitter.com\/rovercrc\/status\/1895861051474002177?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">March 1, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Mientras tanto, el actual gobierno de Australia ha indicado que no tiene planes de establecer una reserva estrat\u00e9gica de criptodivisas. Sin embargo, el pa\u00eds est\u00e1 a punto de elegir un nuevo gobierno. La \u00faltima encuesta de YouGov muestra que la coalici\u00f3n de centro-derecha mantiene una ligera ventaja sobre el gobierno laborista de centro-izquierda, con una ventaja del 51% frente al 49%.<\/p>\n<h2>Volatilidad de las criptomonedas: Una raz\u00f3n de peso para no incluirlo en las reservas<\/h2>\n<p>En declaraciones a un medio de comunicaci\u00f3n, Tom Matthews, jefe de asuntos corporativos del criptointercambio australiano Swyftx, dijo que aunque la idea de una reserva es popular, tambi\u00e9n puede estar \u00abcargada de complejidad.\u00bb A\u00f1adi\u00f3 que si no se gestiona adecuadamente, la reserva crea el potencial de riesgo de concentraci\u00f3n con algunos tokens.<\/p>\n<p>\u00abEn primer lugar, las criptodivisas son extremadamente vol\u00e1tiles\u00bb, dijo el presidente de SNB, \u00bblo que no es propicio para mantener el valor de las inversiones de SNB a largo plazo.\u00bb<\/p>\n<p>Schlegel continu\u00f3: \u00abEn segundo lugar, nuestras reservas deben ser altamente l\u00edquidas para que puedan utilizarse r\u00e1pidamente con fines de pol\u00edtica monetaria si es necesario. En tercer lugar, las criptomonedas presentan debilidades de seguridad. Son esencialmente software, y todos sabemos que el software puede tener fallos y otros puntos d\u00e9biles.\u00bb<\/p>\n<p>Schlegel tambi\u00e9n describi\u00f3 las criptomonedas como un \u00abfen\u00f3meno de nicho\u00bb, se\u00f1alando que su capitalizaci\u00f3n de mercado sigue siendo relativamente peque\u00f1a en comparaci\u00f3n con los sistemas financieros tradicionales.<\/p>\n<h2>Suiza sigue adelante con la \u00abiniciativa Bitcoin\u00bb<\/h2>\n<p>A pesar del rechazo del SNB, los defensores de las criptodivisas en Suiza siguen adelante con la \u00abIniciativa Bitcoin.\u00bb<\/p>\n<p>Lanzada en diciembre de 2024, esta campa\u00f1a busca enmendar la constituci\u00f3n suiza para exigir al SNB que asigne parte de sus reservas a Bitcoin junto con el oro.<\/p>\n<p>Seg\u00fan la legislaci\u00f3n suiza, el comit\u00e9 de la iniciativa tiene 18 meses para reunir 100.000 firmas para que la propuesta se someta a votaci\u00f3n. A\u00fan no se sabe si la campa\u00f1a tendr\u00e1 \u00e9xito.<\/p>\n<p>En Suiza, una de cada nueve personas invierte en criptoactivos, una estad\u00edstica que refleja la creciente aceptaci\u00f3n general.<\/p>\n<p>Lee m\u00e1s: nuestras <a href=\"https:\/\/99bitcoins.com\/es\/mejores-wallets\/ledger-wallet-opiniones\/\"><strong>opiniones de Ledger<\/strong><\/a>, una wallet fiable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jueves, 6 de marzo de 2025 \u2013 El Senado de Arizona avanza en el proyecto de reserva de Bitcoin y queda por detr\u00e1s de Utah en la carrera por la criptolegislaci\u00f3n. A pesar del reciente anuncio del presidente de Estados Unidos, Donald Trump, de una reserva estrat\u00e9gica de criptomonedas en la que participar\u00edan Bitcoin, Ethereum,..<\/p>\n","protected":false},"author":135895,"featured_media":11877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8],"tags":[10],"coin":[74],"class_list":["post-12611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas<\/title>\n<meta name=\"description\" content=\"Los bancos centrales tanto de Suiza como de Australia han descartado la idea de incorporar criptomonedas a sus reservas oficiales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas\" \/>\n<meta property=\"og:description\" content=\"Los bancos centrales tanto de Suiza como de Australia han descartado la idea de incorporar criptomonedas a sus reservas oficiales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins ES\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-06T14:07:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/02\/gold-bitcoin.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"661\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ver\u00f3nica Llabr\u00e9s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/\"},\"author\":{\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\"},\"headline\":\"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas\",\"datePublished\":\"2025-03-06T14:07:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/\"},\"wordCount\":522,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/02\\\/gold-bitcoin.webp\",\"keywords\":[\"Noticias Bitcoin\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/\",\"name\":\"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/02\\\/gold-bitcoin.webp\",\"datePublished\":\"2025-03-06T14:07:27+00:00\",\"description\":\"Los bancos centrales tanto de Suiza como de Australia han descartado la idea de incorporar criptomonedas a sus reservas oficiales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/02\\\/gold-bitcoin.webp\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/02\\\/gold-bitcoin.webp\",\"width\":1200,\"height\":661,\"caption\":\"gold bitcoin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"name\":\"99bitcoins ES\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/99bitcoins-logo.svg\",\"width\":201,\"height\":43,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/#\\\/schema\\\/person\\\/988e1976cfb93fd9345e5893dec0088a\",\"name\":\"Ver\u00f3nica Llabr\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g\",\"caption\":\"Ver\u00f3nica Llabr\u00e9s\"},\"description\":\"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/es\\\/author\\\/verollabres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas","description":"Los bancos centrales tanto de Suiza como de Australia han descartado la idea de incorporar criptomonedas a sus reservas oficiales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/","og_locale":"es_ES","og_type":"article","og_title":"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas","og_description":"Los bancos centrales tanto de Suiza como de Australia han descartado la idea de incorporar criptomonedas a sus reservas oficiales.","og_url":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/","og_site_name":"99bitcoins ES","article_published_time":"2025-03-06T14:07:27+00:00","og_image":[{"width":1200,"height":661,"url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/02\/gold-bitcoin.webp","type":"image\/webp"}],"author":"Ver\u00f3nica Llabr\u00e9s","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ver\u00f3nica Llabr\u00e9s","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/"},"author":{"name":"Ver\u00f3nica Llabr\u00e9s","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a"},"headline":"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas","datePublished":"2025-03-06T14:07:27+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/"},"wordCount":522,"publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/02\/gold-bitcoin.webp","keywords":["Noticias Bitcoin"],"articleSection":["Noticias"],"inLanguage":"es","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/","url":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/","name":"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas","isPartOf":{"@id":"https:\/\/99bitcoins.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/02\/gold-bitcoin.webp","datePublished":"2025-03-06T14:07:27+00:00","description":"Los bancos centrales tanto de Suiza como de Australia han descartado la idea de incorporar criptomonedas a sus reservas oficiales.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/#primaryimage","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/02\/gold-bitcoin.webp","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2025\/02\/gold-bitcoin.webp","width":1200,"height":661,"caption":"gold bitcoin"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/es\/noticias\/suiza-y-australia-ya-no-estan-interesados-en-una-reserva-estrategica-de-criptomonedas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/99bitcoins.com\/es\/noticias\/"},{"@type":"ListItem","position":3,"name":"Suiza y Australia ya no est\u00e1n interesados en una reserva estrat\u00e9gica de criptomonedas"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/es\/#website","url":"https:\/\/99bitcoins.com\/es\/","name":"99bitcoins ES","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/es\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","contentUrl":"https:\/\/99bitcoins.com\/es\/wp-content\/uploads\/sites\/5\/2024\/10\/99bitcoins-logo.svg","width":201,"height":43,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/es\/#\/schema\/person\/988e1976cfb93fd9345e5893dec0088a","name":"Ver\u00f3nica Llabr\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81488a16db12179ffcbc01e23a6e0b5bb960671dc9da2212fe1f183bda376ead?s=96&d=mm&r=g","caption":"Ver\u00f3nica Llabr\u00e9s"},"description":"Periodista por la Universidad Carlos III de Madrid. Redactora especializada en econom\u00eda, bolsa, mercados y empresas cotizadas. Experiencia en apoyo freelance produciendo noticias y reportajes propios para agencias de medios especializados como Colpisa y Webedia.","url":"https:\/\/99bitcoins.com\/es\/author\/verollabres\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/12611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/users\/135895"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/comments?post=12611"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/12611\/revisions"}],"predecessor-version":[{"id":12612,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/posts\/12611\/revisions\/12612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media\/11877"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/media?parent=12611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/categories?post=12611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/tags?post=12611"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/es\/wp-json\/wp\/v2\/coin?post=12611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}