{"id":75519,"date":"2026-06-22T20:38:42","date_gmt":"2026-06-22T18:38:42","guid":{"rendered":"https:\/\/99bitcoins.com\/de\/?p=75519"},"modified":"2026-06-22T20:37:52","modified_gmt":"2026-06-22T18:37:52","slug":"krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/","title":{"rendered":"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet?"},"content":{"rendered":"<p>Michael Saylors Unternehmen Strategy setzt seine Bitcoin-Strategie trotz der j\u00fcngsten Marktturbulenzen fort. Wie aus aktuellen Unternehmensangaben hervorgeht, hat das Unternehmen weitere 520 Bitcoin erworben und gleichzeitig seine Barreserven deutlich ausgebaut.<br \/>\nDie Nachricht kommt zu einem Zeitpunkt, an dem Investoren die finanzielle Stabilit\u00e4t von Strategy besonders genau beobachten. Erst zuletzt wurde intensiv dar\u00fcber diskutiert, ob die verschiedenen Finanzierungsinstrumente des Unternehmens bei einem schw\u00e4cheren Bitcoin-Markt unter Druck geraten k\u00f6nnten.<\/p>\n    <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\">Das Wichtigste im \u00dcberblick:<\/h2>\r\n        \n    <ul class=\"nnbtc-key-takeaways__list\">\r\n        \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Strategy verkaufte 2,71 Millionen MSTR-Aktien und nahm dadurch netto rund 335,5 Millionen US-Dollar ein.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Ein Teil der Mittel floss in den Kauf von 520 Bitcoin zu einem Durchschnittspreis von 67.068 US-Dollar pro BTC.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Die Barreserven des Unternehmens stiegen auf rund 1,4 Milliarden US-Dollar, w\u00e4hrend der Bitcoin-Bestand auf 847.363 BTC anwuchs.    <\/li>\r\n    \n    <\/ul>\r\n    \n    <\/div>\r\n    \n<h2>Strategy verkauft Millionen Aktien<\/h2>\n<p>Laut den ver\u00f6ffentlichten Daten hat Strategy \u00fcber sein sogenanntes ATM-Programm (At-The-Market Offering) rund 2,71 Millionen neue MSTR-Aktien ausgegeben.<br \/>\nDadurch flossen dem Unternehmen netto etwa 335,5 Millionen US-Dollar zu. Das Kapital soll laut Unternehmenschef Michael Saylor nicht ausschlie\u00dflich f\u00fcr weitere Bitcoin-K\u00e4ufe verwendet werden, sondern auch die Liquidit\u00e4tsreserven st\u00e4rken.<\/p>\n<p>Die Ma\u00dfnahme zeigt, dass Strategy derzeit einen vorsichtigeren Kurs verfolgt als noch in fr\u00fcheren Phasen, in denen nahezu jede Kapitalaufnahme direkt in Bitcoin investiert wurde.<\/p>\n<h2>520 Bitcoin kommen hinzu<\/h2>\n<p>Trotz des st\u00e4rkeren Fokus auf Liquidit\u00e4t kaufte Strategy erneut Bitcoin nach.<br \/>\nF\u00fcr rund 34,9 Millionen US-Dollar wurden insgesamt 520 BTC erworben. Der durchschnittliche Kaufpreis lag dabei bei 67.068 US-Dollar pro Bitcoin.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">STRATEGY BUYS 520 BITCOIN AND RAISES $300 MILLION FOR CASH RESERVE<\/p>\n<p>This capital markets activity was total balance sheet ACCRETIVE for MSTR shareholders, exactly as I predicted:<\/p>\n<p>+520 BTC at $67,068<\/p>\n<p>MSTR ATM $335.5M (2.7M shares)<\/p>\n<p>Preferred: Zero, 4th consecutive week<\/p>\n<p>10.4%\u2026 <a href=\"https:\/\/t.co\/1SaX51hJuV\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/1SaX51hJuV<\/a><\/p>\n<p>&mdash; Adam Livingston (@AdamBLiv) <a href=\"https:\/\/x.com\/AdamBLiv\/status\/2069037972675014784?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">June 22, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Durch den Zukauf steigt der gesamte Bitcoin-Bestand des Unternehmens auf 847.363 BTC. Damit bleibt Strategy mit gro\u00dfem Abstand der weltweit gr\u00f6\u00dfte b\u00f6rsennotierte Bitcoin-Halter.<\/p>\n<h2>Milliardenreserve soll Stabilit\u00e4t schaffen<\/h2>\n<p>Besonders auff\u00e4llig ist jedoch der starke Anstieg der Barreserven.<br \/>\nW\u00e4hrend Strategy zuvor rund 1,1 Milliarden US-Dollar an Liquidit\u00e4t hielt, erh\u00f6hte sich dieser Wert nun auf etwa 1,4 Milliarden US-Dollar.<\/p>\n<p>Laut Michael Saylor soll diese Reserve dazu beitragen, die Bonit\u00e4t der verschiedenen Finanzierungsprodukte des Unternehmens zu st\u00e4rken. In den vergangenen Wochen hatten insbesondere die STRC-Wertpapiere Aufmerksamkeit erhalten, nachdem deren Kurs deutlich unter den angestrebten Wert von 100 US-Dollar gefallen war.<\/p>\n<p>Mit einer gr\u00f6\u00dferen Cash-Position verschafft sich Strategy zus\u00e4tzliche Flexibilit\u00e4t und reduziert kurzfristig den Druck, weitere Finanzierungsma\u00dfnahmen durchf\u00fchren zu m\u00fcssen.<\/p>\n<h2>Nur ein kleiner Teil floss direkt in Bitcoin<\/h2>\n<p>Interessant ist auch die Aufteilung der aufgenommenen Mittel.<br \/>\nVon den insgesamt 335,5 Millionen US-Dollar wurden lediglich rund 34,9 Millionen US-Dollar f\u00fcr Bitcoin-K\u00e4ufe verwendet. Das entspricht knapp \u00fcber zehn Prozent des aufgenommenen Kapitals.<\/p>\n<p>Fast 90 Prozent der Mittel verblieben dagegen in der Unternehmenskasse.<br \/>\nMarktbeobachter sehen darin ein Signal, dass Strategy aktuell st\u00e4rker auf Bilanzst\u00e4rke setzt, anstatt jede verf\u00fcgbare Liquidit\u00e4t unmittelbar in Bitcoin umzuwandeln.<\/p>\n<hr \/>\n<p><strong>Lies auch: <a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/coin-launch\/\">Die besten Krypto Presales 2026<\/a><\/strong><\/p>\n<hr \/>\n<h2>Anleger reagieren unterschiedlich<\/h2>\n<p>W\u00e4hrend Kritiker die Verw\u00e4sserung durch neue Aktienemissionen bem\u00e4ngeln, argumentieren Bef\u00fcrworter, dass die Transaktion langfristig wertsteigernd f\u00fcr die Aktion\u00e4re sein k\u00f6nnte.<\/p>\n<p>Der bekannte Analyst Adam Livingston bezeichnete die Ma\u00dfnahme als \u201ebilanzsteigernd\u201c und verwies darauf, dass sowohl die Bitcoin-Best\u00e4nde als auch die Liquidit\u00e4tsreserven gewachsen seien.<\/p>\n<p>F\u00fcr Bitcoin-Anleger bleibt Strategy damit weiterhin eines der wichtigsten Unternehmen im gesamten Kryptomarkt. Mit mehr als 847.000 BTC kontrolliert das Unternehmen inzwischen rund vier Prozent aller jemals existierenden Bitcoin.<\/p>\n<hr \/>\n<h2>Liquid Chain: Infrastruktur f\u00fcr den n\u00e4chsten Krypto-Boom?<\/h2>\n<p>W\u00e4hrend Unternehmen wie Strategy Milliarden in Bitcoin investieren, richten viele Anleger ihren Blick bereits auf die n\u00e4chste Wachstumsphase des Kryptomarktes.<br \/>\nLiquid Chain entwickelt eine Layer-3-L\u00f6sung, die Liquidit\u00e4t zwischen verschiedenen Blockchain-Netzwerken wie Bitcoin, Ethereum und Solana verbinden soll. Ziel ist es, Kapital effizienter zwischen den gr\u00f6\u00dften \u00d6kosystemen des Marktes bewegen zu k\u00f6nnen.<\/p>\n<p>Der zugeh\u00f6rige $LIQUID-Token befindet sich aktuell noch im Presale. Da die Vorverkaufsphasen mit steigenden Preisen verbunden sind, erhalten fr\u00fche Investoren Zugang zu g\u00fcnstigeren Konditionen.<\/p>\n<p>Zus\u00e4tzlich k\u00f6nnen Teilnehmer ihre Token bereits w\u00e4hrend des Vorverkaufs staken und dadurch laufende Renditen erzielen. Sollte die n\u00e4chste gro\u00dfe Wachstumswelle im Kryptomarkt tats\u00e4chlich durch Infrastruktur, Tokenisierung und institutionelle Adoption angetrieben werden, k\u00f6nnten Projekte wie Liquid Chain besonders stark profitieren.<\/p>\n<p><a href=\"https:\/\/99bitcoins.com\/de\/visit\/liquidchain\" rel=\"nofollow sponsored\" target=\"_blank\"><strong>Jetzt $LIQUID im Presale kaufen.<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Michael Saylors Unternehmen Strategy setzt seine Bitcoin-Strategie trotz der j\u00fcngsten Marktturbulenzen fort. Wie aus aktuellen Unternehmensangaben hervorgeht, hat das Unternehmen weitere 520 Bitcoin erworben und gleichzeitig seine Barreserven deutlich ausgebaut. Die Nachricht kommt zu einem Zeitpunkt, an dem Investoren die finanzielle Stabilit\u00e4t von Strategy besonders genau beobachten. Erst zuletzt wurde intensiv dar\u00fcber diskutiert, ob die..<\/p>\n","protected":false},"author":135977,"featured_media":45075,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[288],"tags":[88],"coin":[101],"class_list":["post-75519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-presales","tag-presale-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet? - 99bitcoins DE<\/title>\n<meta name=\"description\" content=\"Michael Saylors Unternehmen Strategy setzt seine Bitcoin-Strategie trotz der j\u00fcngsten Marktturbulenzen fort. Wie aus aktuellen Unternehmensangaben\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet? - 99bitcoins DE\" \/>\n<meta property=\"og:description\" content=\"Michael Saylors Unternehmen Strategy setzt seine Bitcoin-Strategie trotz der j\u00fcngsten Marktturbulenzen fort. Wie aus aktuellen Unternehmensangaben\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins DE\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-22T18:38:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christoph Peterson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/christophP84\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christoph Peterson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/\"},\"author\":{\"name\":\"Christoph Peterson\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/8570dc147194a473518a2620544f4698\"},\"headline\":\"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet?\",\"datePublished\":\"2026-06-22T18:38:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/\"},\"wordCount\":709,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg\",\"keywords\":[\"Presale Nachrichten\"],\"articleSection\":[\"Presales\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/\",\"name\":\"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet? - 99bitcoins DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg\",\"datePublished\":\"2026-06-22T18:38:42+00:00\",\"description\":\"Michael Saylors Unternehmen Strategy setzt seine Bitcoin-Strategie trotz der j\u00fcngsten Marktturbulenzen fort. Wie aus aktuellen Unternehmensangaben\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg\",\"width\":1200,\"height\":720,\"caption\":\"Strategy kauft diesmal KEINE Bitcoins\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Presales\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/presales\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"name\":\"99bitcoins DE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"width\":327,\"height\":276,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/8570dc147194a473518a2620544f4698\",\"name\":\"Christoph Peterson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"caption\":\"Christoph Peterson\"},\"description\":\"Vor einigen Jahren hat Christoph das Thema Kryptow\u00e4hrungen f\u00fcr sich entdeckt und ist seither leidenschaftlich als Autor und Enthusiast in diesem Bereich aktiv. Sein Interesse gilt vor allem den Themen Kryptow\u00e4hrungen, Blockchain-Technologie und Security Token Offerings (STOs). Als regelm\u00e4\u00dfiger Autor f\u00fcr das Online-Magazin 99Bitcoins berichtet er umfassend \u00fcber die Welt der Krypto- und Blockchain-Technologie und liefert fundierte Analysen zu aktuellen Trends und Entwicklungen in diesem dynamischen Markt.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/christophP84\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/author\\\/christophpeterson\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet? - 99bitcoins DE","description":"Michael Saylors Unternehmen Strategy setzt seine Bitcoin-Strategie trotz der j\u00fcngsten Marktturbulenzen fort. Wie aus aktuellen Unternehmensangaben","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/","og_locale":"de_DE","og_type":"article","og_title":"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet? - 99bitcoins DE","og_description":"Michael Saylors Unternehmen Strategy setzt seine Bitcoin-Strategie trotz der j\u00fcngsten Marktturbulenzen fort. Wie aus aktuellen Unternehmensangaben","og_url":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/","og_site_name":"99bitcoins DE","article_published_time":"2026-06-22T18:38:42+00:00","og_image":[{"width":1200,"height":720,"url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg","type":"image\/jpeg"}],"author":"Christoph Peterson","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/christophP84","twitter_misc":{"Written by":"Christoph Peterson","Est. reading time":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/"},"author":{"name":"Christoph Peterson","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/8570dc147194a473518a2620544f4698"},"headline":"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet?","datePublished":"2026-06-22T18:38:42+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/"},"wordCount":709,"publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg","keywords":["Presale Nachrichten"],"articleSection":["Presales"],"inLanguage":"de","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/","url":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/","name":"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet? - 99bitcoins DE","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg","datePublished":"2026-06-22T18:38:42+00:00","description":"Michael Saylors Unternehmen Strategy setzt seine Bitcoin-Strategie trotz der j\u00fcngsten Marktturbulenzen fort. Wie aus aktuellen Unternehmensangaben","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/#primaryimage","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Metaplanet-und-Saylor-kaufen-Bitcoin.jpg","width":1200,"height":720,"caption":"Strategy kauft diesmal KEINE Bitcoins"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/de\/news\/presales\/krypto-news-saylor-kriegt-die-kurve-bitcoin-gerettet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/99bitcoins.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Presales","item":"https:\/\/99bitcoins.com\/de\/news\/presales\/"},{"@type":"ListItem","position":4,"name":"Krypto News: Saylor kriegt die Kurve! Bitcoin gerettet?"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/de\/#website","url":"https:\/\/99bitcoins.com\/de\/","name":"99bitcoins DE","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/de\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","width":327,"height":276,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/8570dc147194a473518a2620544f4698","name":"Christoph Peterson","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","caption":"Christoph Peterson"},"description":"Vor einigen Jahren hat Christoph das Thema Kryptow\u00e4hrungen f\u00fcr sich entdeckt und ist seither leidenschaftlich als Autor und Enthusiast in diesem Bereich aktiv. Sein Interesse gilt vor allem den Themen Kryptow\u00e4hrungen, Blockchain-Technologie und Security Token Offerings (STOs). Als regelm\u00e4\u00dfiger Autor f\u00fcr das Online-Magazin 99Bitcoins berichtet er umfassend \u00fcber die Welt der Krypto- und Blockchain-Technologie und liefert fundierte Analysen zu aktuellen Trends und Entwicklungen in diesem dynamischen Markt.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/christophP84"],"url":"https:\/\/99bitcoins.com\/de\/author\/christophpeterson\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/75519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/users\/135977"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/comments?post=75519"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/75519\/revisions"}],"predecessor-version":[{"id":75520,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/75519\/revisions\/75520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media\/45075"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media?parent=75519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories?post=75519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/tags?post=75519"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/coin?post=75519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}