{"id":75115,"date":"2026-06-11T19:52:34","date_gmt":"2026-06-11T17:52:34","guid":{"rendered":"https:\/\/99bitcoins.com\/de\/?p=75115"},"modified":"2026-06-11T19:51:42","modified_gmt":"2026-06-11T17:51:42","slug":"rettung-fuer-bitcoin-blackrock-plant-neuen-etf","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/","title":{"rendered":"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF"},"content":{"rendered":"<p>BlackRock baut sein Bitcoin-Angebot weiter aus. Der weltgr\u00f6\u00dfte Verm\u00f6gensverwalter hat eine weitere \u00c4nderung f\u00fcr seinen geplanten iShares Bitcoin Premium Income ETF eingereicht und dabei erstmals die Geb\u00fchrenstruktur offengelegt.<\/p>\n<p>Der neue Fonds soll Anlegern nicht nur Zugang zu Bitcoin erm\u00f6glichen, sondern zus\u00e4tzlich laufende Ertr\u00e4ge generieren. Damit verfolgt BlackRock einen Ansatz, der sich deutlich von klassischen Spot-Bitcoin-ETFs unterscheidet und insbesondere einkommensorientierte Investoren ansprechen k\u00f6nnte.<\/p>\n    <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\">Das Wichtigste im \u00dcberblick:<\/h2>\r\n        \n    <ul class=\"nnbtc-key-takeaways__list\">\r\n        \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        BlackRock hat f\u00fcr seinen geplanten iShares Bitcoin Premium Income ETF (BITA) eine j\u00e4hrliche Geb\u00fchr von 0,65 % bekanntgegeben.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Der Fonds investiert indirekt \u00fcber den Spot-Bitcoin-ETF IBIT in Bitcoin und erzielt zus\u00e4tzliche Ertr\u00e4ge durch den Verkauf von Call-Optionen.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Laut Bloomberg-Analyst Eric Balchunas k\u00f6nnte BlackRock den ETF noch vor konkurrierenden Produkten von Goldman Sachs auf den Markt bringen.    <\/li>\r\n    \n    <\/ul>\r\n    \n    <\/div>\r\n    \n<h2>So funktioniert der neue Bitcoin Income ETF<\/h2>\n<p>Anders als klassische Spot-Bitcoin-ETFs setzt der neue Fonds auf eine sogenannte Covered-Call-Strategie.<\/p>\n<p>Der ETF soll seine Bitcoin-Position \u00fcber BlackRocks erfolgreichen Spot-Bitcoin-ETF IBIT aufbauen. Anschlie\u00dfend werden regelm\u00e4\u00dfig Call-Optionen auf diese Position verkauft, wodurch zus\u00e4tzliche Pr\u00e4mieneinnahmen erzielt werden k\u00f6nnen.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">BLACKROCK REVEALS 0.65% FEE FOR BITCOIN INCOME ETF<\/p>\n<p>BlackRock has filed another amendment for its iShares Bitcoin Premium Income ETF ($BITA), revealing a 65 bps fee and signaling a launch could be imminent.<\/p>\n<p>The fund gains Bitcoin exposure through <a href=\"https:\/\/x.com\/search?q=%24IBIT&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$IBIT<\/a>, then systematically sells\u2026 <a href=\"https:\/\/t.co\/QkOv2UfXZg\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/QkOv2UfXZg<\/a><\/p>\n<p>&mdash; Bitcoin News (@BitcoinNewsCom) <a href=\"https:\/\/x.com\/BitcoinNewsCom\/status\/2064704866845429945?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">June 10, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>F\u00fcr Anleger bedeutet dies, dass sie neben einer Bitcoin-Exponierung auch laufende Ertr\u00e4ge erhalten k\u00f6nnen. Allerdings hat diese Strategie einen Nachteil: Steigt Bitcoin sehr stark an, wird ein Teil des Aufw\u00e4rtspotenzials durch die verkauften Optionen begrenzt.<\/p>\n<hr \/>\n<p><strong>Lies auch: <a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/coin-launch\/\">Die besten Krypto Presales 2026<\/a><\/strong><\/p>\n<hr \/>\n<h2>Geb\u00fchren liegen \u00fcber klassischen Spot-ETFs<\/h2>\n<p>Mit einer j\u00e4hrlichen Verwaltungsgeb\u00fchr von 0,65 % liegt der neue Fonds deutlich \u00fcber den Kosten klassischer Spot-Bitcoin-ETFs.<br \/>\nZum Vergleich: Der iShares Bitcoin Trust (IBIT) z\u00e4hlt zu den g\u00fcnstigeren Bitcoin-ETFs am Markt. Gleichzeitig bleibt die neue Geb\u00fchr jedoch unter vielen etablierten Covered-Call-ETFs, deren Kosten h\u00e4ufig zwischen 0,95 % und 0,99 % liegen.<\/p>\n<p>BlackRock positioniert das Produkt damit zwischen klassischen Bitcoin-Investments und einkommensorientierten Optionsstrategien.<\/p>\n<h2>Wettlauf um den Markt f\u00fcr Bitcoin-Einkommensprodukte<\/h2>\n<p>Der Markt f\u00fcr Bitcoin-ETFs entwickelt sich zunehmend weiter. Nachdem Spot-Bitcoin-ETFs bereits Milliarden von Dollar an institutionellem Kapital angezogen haben, r\u00fccken nun spezialisierte Produkte in den Fokus.<\/p>\n<p>Bloomberg-ETF-Analyst Eric Balchunas geht davon aus, dass BlackRock versucht, seinen Fonds noch vor einem \u00e4hnlichen Produkt von Goldman Sachs an den Markt zu bringen. Der konkurrierende ETF soll Berichten zufolge Anfang Juli wirksam werden.<\/p>\n<p>Die j\u00fcngste Einreichung von BlackRock wird daher von vielen Marktbeobachtern als Signal gewertet, dass der Start des neuen Bitcoin Income ETFs unmittelbar bevorstehen k\u00f6nnte.<\/p>\n<h2>Institutionelles Interesse an Bitcoin w\u00e4chst weiter<\/h2>\n<p>Die Einf\u00fchrung weiterer Bitcoin-basierter Anlageprodukte zeigt, wie stark sich der Markt seit der Zulassung der ersten Spot-Bitcoin-ETFs ver\u00e4ndert hat.<br \/>\nW\u00e4hrend institutionelle Investoren fr\u00fcher oft nur eingeschr\u00e4nkte M\u00f6glichkeiten hatten, in Bitcoin zu investieren, entstehen inzwischen zunehmend Produkte f\u00fcr unterschiedliche Risikoprofile und Anlageziele.<\/p>\n<p>Der geplante Bitcoin Premium Income ETF k\u00f6nnte dabei insbesondere Anleger ansprechen, die von der langfristigen Entwicklung von Bitcoin profitieren m\u00f6chten, gleichzeitig aber Wert auf regelm\u00e4\u00dfige Ertr\u00e4ge legen.<\/p>\n<p>Sollte der Fonds erfolgreich starten, d\u00fcrfte dies ein weiteres Zeichen daf\u00fcr sein, dass Bitcoin zunehmend als etablierte Anlageklasse im traditionellen Finanzsystem angekommen ist.<\/p>\n<hr \/>\n<p><strong>Auch interessant: <a href=\"https:\/\/99bitcoins.com\/de\/krypto-wallet\/\">Die besten Krypto Wallets im Vergleich<\/a><\/strong><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>BlackRock baut sein Bitcoin-Angebot weiter aus. Der weltgr\u00f6\u00dfte Verm\u00f6gensverwalter hat eine weitere \u00c4nderung f\u00fcr seinen geplanten iShares Bitcoin Premium Income ETF eingereicht und dabei erstmals die Geb\u00fchrenstruktur offengelegt. Der neue Fonds soll Anlegern nicht nur Zugang zu Bitcoin erm\u00f6glichen, sondern zus\u00e4tzlich laufende Ertr\u00e4ge generieren. Damit verfolgt BlackRock einen Ansatz, der sich deutlich von klassischen Spot-Bitcoin-ETFs..<\/p>\n","protected":false},"author":135977,"featured_media":47839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[2],"tags":[86],"coin":[101],"class_list":["post-75115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bitcoin-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF - 99bitcoins DE<\/title>\n<meta name=\"description\" content=\"BlackRock baut sein Bitcoin-Angebot weiter aus. Der weltgr\u00f6\u00dfte Verm\u00f6gensverwalter hat eine weitere \u00c4nderung f\u00fcr seinen geplanten iShares Bitcoin Premium\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF - 99bitcoins DE\" \/>\n<meta property=\"og:description\" content=\"BlackRock baut sein Bitcoin-Angebot weiter aus. Der weltgr\u00f6\u00dfte Verm\u00f6gensverwalter hat eine weitere \u00c4nderung f\u00fcr seinen geplanten iShares Bitcoin Premium\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins DE\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-11T17:52:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christoph Peterson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/christophP84\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christoph Peterson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/\"},\"author\":{\"name\":\"Christoph Peterson\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/8570dc147194a473518a2620544f4698\"},\"headline\":\"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF\",\"datePublished\":\"2026-06-11T17:52:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/\"},\"wordCount\":547,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg\",\"keywords\":[\"Bitcoin Nachrichten\"],\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/\",\"name\":\"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF - 99bitcoins DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg\",\"datePublished\":\"2026-06-11T17:52:34+00:00\",\"description\":\"BlackRock baut sein Bitcoin-Angebot weiter aus. Der weltgr\u00f6\u00dfte Verm\u00f6gensverwalter hat eine weitere \u00c4nderung f\u00fcr seinen geplanten iShares Bitcoin Premium\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg\",\"width\":1200,\"height\":720,\"caption\":\"Larry Fink BlackRock spricht \u00fcber Bitcoin und Kryptow\u00e4hrungen als neues digitales Gold \u2013 symbolisches Bild mit M\u00fcnzen und Skyline.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"name\":\"99bitcoins DE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"width\":327,\"height\":276,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/8570dc147194a473518a2620544f4698\",\"name\":\"Christoph Peterson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"caption\":\"Christoph Peterson\"},\"description\":\"Vor einigen Jahren hat Christoph das Thema Kryptow\u00e4hrungen f\u00fcr sich entdeckt und ist seither leidenschaftlich als Autor und Enthusiast in diesem Bereich aktiv. Sein Interesse gilt vor allem den Themen Kryptow\u00e4hrungen, Blockchain-Technologie und Security Token Offerings (STOs). Als regelm\u00e4\u00dfiger Autor f\u00fcr das Online-Magazin 99Bitcoins berichtet er umfassend \u00fcber die Welt der Krypto- und Blockchain-Technologie und liefert fundierte Analysen zu aktuellen Trends und Entwicklungen in diesem dynamischen Markt.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/christophP84\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/author\\\/christophpeterson\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF - 99bitcoins DE","description":"BlackRock baut sein Bitcoin-Angebot weiter aus. Der weltgr\u00f6\u00dfte Verm\u00f6gensverwalter hat eine weitere \u00c4nderung f\u00fcr seinen geplanten iShares Bitcoin Premium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/","og_locale":"de_DE","og_type":"article","og_title":"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF - 99bitcoins DE","og_description":"BlackRock baut sein Bitcoin-Angebot weiter aus. Der weltgr\u00f6\u00dfte Verm\u00f6gensverwalter hat eine weitere \u00c4nderung f\u00fcr seinen geplanten iShares Bitcoin Premium","og_url":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/","og_site_name":"99bitcoins DE","article_published_time":"2026-06-11T17:52:34+00:00","og_image":[{"width":1200,"height":720,"url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg","type":"image\/jpeg"}],"author":"Christoph Peterson","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/christophP84","twitter_misc":{"Written by":"Christoph Peterson","Est. reading time":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/"},"author":{"name":"Christoph Peterson","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/8570dc147194a473518a2620544f4698"},"headline":"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF","datePublished":"2026-06-11T17:52:34+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/"},"wordCount":547,"publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg","keywords":["Bitcoin Nachrichten"],"articleSection":["News"],"inLanguage":"de","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/","url":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/","name":"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF - 99bitcoins DE","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg","datePublished":"2026-06-11T17:52:34+00:00","description":"BlackRock baut sein Bitcoin-Angebot weiter aus. Der weltgr\u00f6\u00dfte Verm\u00f6gensverwalter hat eine weitere \u00c4nderung f\u00fcr seinen geplanten iShares Bitcoin Premium","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/#primaryimage","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Larry-Fink-of-Blackrock-says-Bitcoin-is-like-gold.jpg","width":1200,"height":720,"caption":"Larry Fink BlackRock spricht \u00fcber Bitcoin und Kryptow\u00e4hrungen als neues digitales Gold \u2013 symbolisches Bild mit M\u00fcnzen und Skyline."},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/de\/news\/rettung-fuer-bitcoin-blackrock-plant-neuen-etf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/99bitcoins.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Rettung f\u00fcr Bitcoin? BlackRock plant neuen ETF"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/de\/#website","url":"https:\/\/99bitcoins.com\/de\/","name":"99bitcoins DE","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/de\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","width":327,"height":276,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/8570dc147194a473518a2620544f4698","name":"Christoph Peterson","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","caption":"Christoph Peterson"},"description":"Vor einigen Jahren hat Christoph das Thema Kryptow\u00e4hrungen f\u00fcr sich entdeckt und ist seither leidenschaftlich als Autor und Enthusiast in diesem Bereich aktiv. Sein Interesse gilt vor allem den Themen Kryptow\u00e4hrungen, Blockchain-Technologie und Security Token Offerings (STOs). Als regelm\u00e4\u00dfiger Autor f\u00fcr das Online-Magazin 99Bitcoins berichtet er umfassend \u00fcber die Welt der Krypto- und Blockchain-Technologie und liefert fundierte Analysen zu aktuellen Trends und Entwicklungen in diesem dynamischen Markt.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/christophP84"],"url":"https:\/\/99bitcoins.com\/de\/author\/christophpeterson\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/75115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/users\/135977"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/comments?post=75115"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/75115\/revisions"}],"predecessor-version":[{"id":75116,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/75115\/revisions\/75116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media\/47839"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media?parent=75115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories?post=75115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/tags?post=75115"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/coin?post=75115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}