{"id":74386,"date":"2026-06-04T11:19:03","date_gmt":"2026-06-04T09:19:03","guid":{"rendered":"https:\/\/99bitcoins.com\/de\/?p=74386"},"modified":"2026-06-04T11:18:18","modified_gmt":"2026-06-04T09:18:18","slug":"wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/","title":{"rendered":"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende"},"content":{"rendered":"<p style=\"font-weight: 400\">Strategy gilt als die bekannteste Bitcoin-Treasury-Gesellschaft der Welt. Das Unternehmen rund um Michael Saylor verfolgt seit Jahren die Strategie, Kapital \u00fcber Aktien und verschiedene Finanzinstrumente aufzunehmen, um damit weitere Bitcoin zu kaufen. Zu den j\u00fcngsten Innovationen z\u00e4hlt dabei STRC \u2013 eine neue Vorzugsaktie (Preferred Stock), die Investoren regelm\u00e4\u00dfige Dividenden bietet und Strategy zus\u00e4tzliches Kapital f\u00fcr den Ausbau seiner Bitcoin-Best\u00e4nde verschafft.<\/p>\n<p style=\"font-weight: 400\">Im Gegensatz zu klassischen Stammaktien erhalten Anleger hier einen festen Ertragsanspruch, w\u00e4hrend das Unternehmen frische Liquidit\u00e4t einsammelt. Das Modell gilt als eine Art Br\u00fccke zwischen Anleihe und Aktie und hat an den Kapitalm\u00e4rkten gro\u00dfe Aufmerksamkeit erzeugt.<\/p>\n<p style=\"font-weight: 400\">Nun plant auch Bitmine Immersion Technologies ein \u00e4hnliches Konstrukt \u2013 allerdings mit Ethereum als zentralem Reserve-Asset.<\/p>\n    <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\">Das Wichtigste im \u00dcberblick:<\/h2>\r\n            <ul class=\"nnbtc-key-takeaways__list\">\r\n        \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Bitmine kauft weitere 25.000 ETH trotz massivem Ethereum-B\u00e4renmarkt aktuell.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Unternehmen h\u00e4lt inzwischen \u00fcber 5,4 Millionen ETH im Bestand.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Strategischer Ausbau signalisiert langfristiges Vertrauen in Ethereum und Staking.    <\/li>\r\n    \n    <\/ul>\r\n        <\/div>\r\n    \n<h2 style=\"font-weight: 400\">Bitmine bringt 9,5-Prozent-Dividendenaktie f\u00fcr Ethereum-Investoren<\/h2>\n<p style=\"font-weight: 400\">Bitmine Immersion Technologies hat laut dem eingereichten Prospekt die Ausgabe von 3 Millionen Vorzugsaktien der sogenannten \u201eSeries A Perpetual Preferred Stock\u201c angek\u00fcndigt. Jede Aktie besitzt einen Nennwert von 100 US-Dollar. Damit k\u00f6nnte das Unternehmen insgesamt rund 300 Millionen US-Dollar frisches Kapital einsammeln.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udd25 NEW: Bitcoin miner Bitmine Immersion Technologies filed for a 3 million-share Series A preferred stock offering with a 9.5% annual dividend. <a href=\"https:\/\/t.co\/YejXPw12Nq\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/YejXPw12Nq<\/a><\/p>\n<p>&mdash; Cointelegraph (@Cointelegraph) <a href=\"https:\/\/x.com\/Cointelegraph\/status\/2062293298136469598?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">June 3, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"font-weight: 400\">Das Besondere: Die neuen Vorzugsaktien bieten Anlegern eine feste j\u00e4hrliche Dividende von 9,5 Prozent. Bezogen auf den Ausgabepreis von 100 US-Dollar entspricht dies 9,50 US-Dollar pro Aktie und Jahr. Die Dividenden sollen kumulativ ausgestaltet sein. Falls eine Zahlung zeitweise ausf\u00e4llt, verf\u00e4llt der Anspruch also nicht automatisch, sondern wird grunds\u00e4tzlich weiter angesammelt.<\/p>\n<p style=\"font-weight: 400\">Die Konstruktion erinnert stark an die j\u00fcngsten Kapitalmarktinstrumente von Strategy. Statt jedoch auf Bitcoin setzt Bitmine mittlerweile klar auf Ethereum als Treasury-Asset. Das Unternehmen verfolgt das Ziel, m\u00f6glichst gro\u00dfe ETH-Best\u00e4nde aufzubauen und diese zus\u00e4tzlich \u00fcber Staking-Ertr\u00e4ge produktiv einzusetzen.<\/p>\n<p style=\"font-weight: 400\">Nach Einsch\u00e4tzung verschiedener Marktbeobachter liegt genau hier der entscheidende Unterschied zu klassischen Bitcoin-Treasury-Modellen. W\u00e4hrend Bitcoin selbst keine nativen Cashflows erzeugt, generiert Ethereum durch Staking laufende Ertr\u00e4ge. Diese k\u00f6nnen wiederum zur Finanzierung der Dividendenzahlungen genutzt werden.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Here is what this means for <a href=\"https:\/\/x.com\/fundstrat?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@fundstrat<\/a> and <a href=\"https:\/\/x.com\/search?q=%24BMNR&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$BMNR<\/a> <a href=\"https:\/\/x.com\/BitMNR?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@BitMNR<\/a> in simple words:<\/p>\n<p>1. <a href=\"https:\/\/x.com\/search?q=%24BMNR&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$BMNR<\/a> sells shares for $100 a piece 3M shares (6X current market value) and raises $300M<\/p>\n<p>2. <a href=\"https:\/\/x.com\/fundstrat?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@fundstrat<\/a> promises to pay 9.5% dividend annually. So roughly $30M<\/p>\n<p>3. Bitmine\u2018s annual staking rewards are\u2026 <a href=\"https:\/\/t.co\/552ykaQKi1\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/552ykaQKi1<\/a><\/p>\n<p>&mdash; Wolf Of Dubai \ud83d\udcb2 (@realwolfofdubai) <a href=\"https:\/\/x.com\/realwolfofdubai\/status\/2062308295491330181?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">June 3, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"font-weight: 400\">Rechnet man die geplante Emission vollst\u00e4ndig durch, m\u00fcsste Bitmine bei einem Volumen von 300 Millionen US-Dollar j\u00e4hrlich rund 28,5 Millionen US-Dollar an Dividenden aussch\u00fctten. Bef\u00fcrworter des Modells argumentieren, dass die Staking-Ertr\u00e4ge auf einen deutlich gr\u00f6\u00dferen Ethereum-Bestand diese Kosten langfristig decken k\u00f6nnten.<\/p>\n<p style=\"font-weight: 400\">F\u00fcr Investoren entsteht dadurch eine interessante Kombination: Sie erhalten einen festen Dividendenanspruch von 9,5 Prozent, w\u00e4hrend Bitmine zus\u00e4tzlich Kapital f\u00fcr weitere Ethereum-K\u00e4ufe einsammelt. Das Unternehmen muss dabei \u2013 anders als bei klassischen Krediten \u2013 keine festen R\u00fcckzahlungen leisten und vermeidet zugleich eine klassische Verschuldung.<\/p>\n<p style=\"font-weight: 400\">Sollte die Platzierung erfolgreich verlaufen, k\u00f6nnte Bitmine damit einen neuen Finanzierungsweg f\u00fcr Ethereum-Treasury-Unternehmen etablieren. \u00c4hnlich wie Strategy die Kapitalm\u00e4rkte f\u00fcr Bitcoin ge\u00f6ffnet hat, versucht Bitmine nun offenbar, institutionelles Kapital \u00fcber dividendenstarke Vorzugsaktien in das Ethereum-\u00d6kosystem zu lenken. Gerade in einem Umfeld schwacher Kryptokurse k\u00f6nnte die Kombination aus hoher Dividendenrendite und langfristigem Ethereum-Exposure f\u00fcr Anleger attraktiv wirken.<\/p>\n<h2 style=\"font-weight: 400\">Trotz Ethereum-Crash: Bitmine kauft weitere 25.000 ETH<\/h2>\n<p style=\"font-weight: 400\">W\u00e4hrend Ethereum im laufenden B\u00e4renmarkt massiv unter Druck steht und zuletzt zeitweise unter die Marke von 2.000 US-Dollar gefallen ist, bleibt Bitmine Immersion Technologies konsequent bullish. Das Unternehmen hat laut aktuellen On-Chain-Daten weitere 25.000 ETH \u00fcbernommen, die von BitGo an eine Wallet von Bitmine transferiert wurden. Der Gegenwert der Transaktion bel\u00e4uft sich auf rund 48 Millionen US-Dollar.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Bitmine Adds Another $47.98M in <a href=\"https:\/\/x.com\/hashtag\/Ethereum?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">#Ethereum<\/a> Amid Market Weakness.<\/p>\n<p>Roughly 10 hours ago, the company received an additional 25,000 ETH, valued at about $47.98 million, from BitGo.<\/p>\n<p>This latest transfer adds to Bitmine\u2019s already substantial position. The firm now holds approximately\u2026 <a href=\"https:\/\/t.co\/pw2MmPfpfa\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/pw2MmPfpfa<\/a><\/p>\n<p>&mdash; TheCryptoBasic (@thecryptobasic) <a href=\"https:\/\/x.com\/thecryptobasic\/status\/2062098182562345333?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">June 3, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"font-weight: 400\">Damit setzt Bitmine seine aggressive Ethereum-Treasury-Strategie fort und nutzt die aktuelle Marktschw\u00e4che offenbar gezielt f\u00fcr weitere Zuk\u00e4ufe. Nach dem j\u00fcngsten Transfer soll das Unternehmen inzwischen rund 5,42 Millionen ETH kontrollieren. Auf Basis aktueller Marktpreise entspricht dies einem Bestand von mehr als 10 Milliarden US-Dollar und macht Bitmine zu einem der gr\u00f6\u00dften institutionellen Ethereum-Halter weltweit.<\/p>\n<p style=\"font-weight: 400\">Bemerkenswert ist dabei vor allem das Timing. Viele Investoren f\u00fcrchten angesichts des Kursr\u00fcckgangs weitere Verluste, w\u00e4hrend Bitmine genau das Gegenteil macht und seine Position weiter ausbaut. Das deutet darauf hin, dass das Management Ethereum auf dem aktuellen Kursniveau als langfristig attraktiv bewertet. Gleichzeitig k\u00f6nnten die umfangreichen ETH-Best\u00e4nde k\u00fcnftig zus\u00e4tzliche Ertr\u00e4ge \u00fcber Staking generieren. Zusammen mit der geplanten 9,5-Prozent-Vorzugsaktie verfolgt Bitmine damit eine Strategie, die stark an Strategy bei Bitcoin erinnert \u2013 allerdings mit Ethereum als zentralem Reserve-Asset und den zus\u00e4tzlichen M\u00f6glichkeiten des Stakings.<\/p>\n<hr \/>\n<p><strong>Lies auch: <a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/coin-launch\/\">Die besten Krypto Presales 2026<\/a><\/strong><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>Strategy gilt als die bekannteste Bitcoin-Treasury-Gesellschaft der Welt. Das Unternehmen rund um Michael Saylor verfolgt seit Jahren die Strategie, Kapital \u00fcber Aktien und verschiedene Finanzinstrumente aufzunehmen, um damit weitere Bitcoin zu kaufen. Zu den j\u00fcngsten Innovationen z\u00e4hlt dabei STRC \u2013 eine neue Vorzugsaktie (Preferred Stock), die Investoren regelm\u00e4\u00dfige Dividenden bietet und Strategy zus\u00e4tzliches Kapital f\u00fcr..<\/p>\n","protected":false},"author":135977,"featured_media":50440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[42],"tags":[87],"coin":[101],"class_list":["post-74386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-altcoin-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende - 99bitcoins DE<\/title>\n<meta name=\"description\" content=\"Strategy gilt als die bekannteste Bitcoin-Treasury-Gesellschaft der Welt. Das Unternehmen rund um Michael Saylor verfolgt seit Jahren die Strategie,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende - 99bitcoins DE\" \/>\n<meta property=\"og:description\" content=\"Strategy gilt als die bekannteste Bitcoin-Treasury-Gesellschaft der Welt. Das Unternehmen rund um Michael Saylor verfolgt seit Jahren die Strategie,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins DE\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-04T09:19:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Ethereum-between-greed-and-panic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christoph Peterson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/christophP84\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christoph Peterson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/\"},\"author\":{\"name\":\"Christoph Peterson\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/8225f76bd482a22c0b6162ac3d91e8c0\"},\"headline\":\"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende\",\"datePublished\":\"2026-06-04T09:19:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/\"},\"wordCount\":757,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Ethereum-between-greed-and-panic.jpg\",\"keywords\":[\"Altcoin Nachrichten\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/\",\"name\":\"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende - 99bitcoins DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Ethereum-between-greed-and-panic.jpg\",\"datePublished\":\"2026-06-04T09:19:03+00:00\",\"description\":\"Strategy gilt als die bekannteste Bitcoin-Treasury-Gesellschaft der Welt. Das Unternehmen rund um Michael Saylor verfolgt seit Jahren die Strategie,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Ethereum-between-greed-and-panic.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Ethereum-between-greed-and-panic.jpg\",\"width\":1200,\"height\":720,\"caption\":\"Dramatisches Ethereum-Bild mit Feuer-und-Eis-Motiv, das Gier und Panik an den Kryptom\u00e4rkten symbolisiert\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"name\":\"99bitcoins DE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"width\":327,\"height\":276,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/8225f76bd482a22c0b6162ac3d91e8c0\",\"name\":\"Christoph Peterson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"caption\":\"Christoph Peterson\"},\"description\":\"Vor einigen Jahren hat Christoph das Thema Kryptow\u00e4hrungen f\u00fcr sich entdeckt und ist seither leidenschaftlich als Autor und Enthusiast in diesem Bereich aktiv. Sein Interesse gilt vor allem den Themen Kryptow\u00e4hrungen, Blockchain-Technologie und Security Token Offerings (STOs). Als regelm\u00e4\u00dfiger Autor f\u00fcr das Online-Magazin 99Bitcoins berichtet er umfassend \u00fcber die Welt der Krypto- und Blockchain-Technologie und liefert fundierte Analysen zu aktuellen Trends und Entwicklungen in diesem dynamischen Markt.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/christophP84\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/author\\\/christophpeterson\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende - 99bitcoins DE","description":"Strategy gilt als die bekannteste Bitcoin-Treasury-Gesellschaft der Welt. Das Unternehmen rund um Michael Saylor verfolgt seit Jahren die Strategie,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/","og_locale":"de_DE","og_type":"article","og_title":"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende - 99bitcoins DE","og_description":"Strategy gilt als die bekannteste Bitcoin-Treasury-Gesellschaft der Welt. Das Unternehmen rund um Michael Saylor verfolgt seit Jahren die Strategie,","og_url":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/","og_site_name":"99bitcoins DE","article_published_time":"2026-06-04T09:19:03+00:00","og_image":[{"width":1200,"height":720,"url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Ethereum-between-greed-and-panic.jpg","type":"image\/jpeg"}],"author":"Christoph Peterson","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/christophP84","twitter_misc":{"Written by":"Christoph Peterson","Est. reading time":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/"},"author":{"name":"Christoph Peterson","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/8225f76bd482a22c0b6162ac3d91e8c0"},"headline":"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende","datePublished":"2026-06-04T09:19:03+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/"},"wordCount":757,"publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Ethereum-between-greed-and-panic.jpg","keywords":["Altcoin Nachrichten"],"articleSection":["Altcoins"],"inLanguage":"de","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/","url":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/","name":"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende - 99bitcoins DE","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Ethereum-between-greed-and-panic.jpg","datePublished":"2026-06-04T09:19:03+00:00","description":"Strategy gilt als die bekannteste Bitcoin-Treasury-Gesellschaft der Welt. Das Unternehmen rund um Michael Saylor verfolgt seit Jahren die Strategie,","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/#primaryimage","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Ethereum-between-greed-and-panic.jpg","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Ethereum-between-greed-and-panic.jpg","width":1200,"height":720,"caption":"Dramatisches Ethereum-Bild mit Feuer-und-Eis-Motiv, das Gier und Panik an den Kryptom\u00e4rkten symbolisiert"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/wie-strategy-ethereum-gigant-bitmine-plant-neue-aktie-mit-95-dividende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/99bitcoins.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Wie Strategy: Ethereum-Gigant Bitmine plant neue Aktie mit 9,5 % Dividende"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/de\/#website","url":"https:\/\/99bitcoins.com\/de\/","name":"99bitcoins DE","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/de\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","width":327,"height":276,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/8225f76bd482a22c0b6162ac3d91e8c0","name":"Christoph Peterson","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","caption":"Christoph Peterson"},"description":"Vor einigen Jahren hat Christoph das Thema Kryptow\u00e4hrungen f\u00fcr sich entdeckt und ist seither leidenschaftlich als Autor und Enthusiast in diesem Bereich aktiv. Sein Interesse gilt vor allem den Themen Kryptow\u00e4hrungen, Blockchain-Technologie und Security Token Offerings (STOs). Als regelm\u00e4\u00dfiger Autor f\u00fcr das Online-Magazin 99Bitcoins berichtet er umfassend \u00fcber die Welt der Krypto- und Blockchain-Technologie und liefert fundierte Analysen zu aktuellen Trends und Entwicklungen in diesem dynamischen Markt.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/christophP84"],"url":"https:\/\/99bitcoins.com\/de\/author\/christophpeterson\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/74386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/users\/135977"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/comments?post=74386"}],"version-history":[{"count":3,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/74386\/revisions"}],"predecessor-version":[{"id":74655,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/74386\/revisions\/74655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media\/50440"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media?parent=74386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories?post=74386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/tags?post=74386"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/coin?post=74386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}