{"id":74058,"date":"2026-06-02T12:06:25","date_gmt":"2026-06-02T10:06:25","guid":{"rendered":"https:\/\/99bitcoins.com\/de\/?p=74058"},"modified":"2026-06-02T12:05:32","modified_gmt":"2026-06-02T10:05:32","slug":"bitcoin-etf-outflows-negativ-rekord","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/","title":{"rendered":"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord"},"content":{"rendered":"<p>Die US-Spot-Bitcoin-ETFs haben laut Daten von CoinGlass nun an elf aufeinanderfolgenden Tagen Nettoabfl\u00fcsse verzeichnet. Dies stellt die l\u00e4ngste anhaltende Negativserie seit der Einf\u00fchrung dieser Anlageprodukte im Januar 2024 dar.<\/p>\n<p>Die Verkaufswellen kamen schubweise: Wie <a class=\"general-link\" href=\"https:\/\/www.bloomberg.com\/news\/articles\/2026-05-29\/us-bitcoin-btc-etfs-bleed-2-8-billion-in-longest-outflow-streak\" target=\"_blank\" rel=\"noopener nofollow\">Bloomberg berichtete<\/a>, gab es Ende Mai 2026 eine R\u00fccknahmewelle von rund 2,8 Milliarden Dollar \u00fcber einen Zeitraum von neun Handelstagen. Ein w\u00f6chentlicher Abfluss von 1,26 Milliarden Dollar zu Beginn desselben Monats hatte den Druck bereits zuvor versch\u00e4rft.<\/p>\n    <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\">Das Wichtigste im \u00dcberblick:<\/h2>\r\n            <ul class=\"nnbtc-key-takeaways__list\">\r\n        \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Historische Negativserie: Mit elf Tagen ununterbrochenen Abfl\u00fcssen erleben Bitcoin-ETFs die l\u00e4ngste Verlustphase seit ihrem Start.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Milliarden-R\u00fcckzug bei Fonds: Allein Ende Mai zogen institutionelle Anleger rund 2,8 Milliarden Dollar aus den ETF-Produkten ab.\u00a0    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Starke On-Chain-Halter: Trotz der massiven Verk\u00e4ufe von Papier-Bitcoin bleibt die \u00dcberzeugung langfristiger Spot-Halter unersch\u00fcttert.<span style=\"font-weight: 400\">.<\/span>    <\/li>\r\n    \n    <\/ul>\r\n        <\/div>\r\n    \n<p>Hier zeigt sich das zentrale Spannungsfeld: W\u00e4hrend institutionelle Investoren sich mit ungew\u00f6hnlicher Ausdauer aus dem Bitcoin-ETF-Mantel zur\u00fcckziehen, zeigen On-Chain-Daten, dass sich langfristige Spot-Halter \u2013 also diejenigen, die echtes Bitcoin in Self-Custody-Wallets besitzen \u2013 kaum bewegt haben. Zwei Gruppen, derselbe Verm\u00f6genswert, aber v\u00f6llig unterschiedliche Reaktionen auf das makro\u00f6konomische Umfeld.<\/p>\n<p><strong>Ebenfalls interessant: <a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/neue-kryptowaehrungen\/\">Neue Kryptow\u00e4hrungen mit Potenzial 2026<\/a><\/strong><\/p>\n<h2>Bitcoin-ETF-Abfl\u00fcsse: Was die Serie wirklich bedeutet<\/h2>\n<p>Man kann sich einen Spot-Bitcoin-ETF wie eine Garderobe in einer gro\u00dfen Finanzinstitution vorstellen. Die Institution gibt ihr Bitcoin-Exposure am Eingang ab und erh\u00e4lt daf\u00fcr ein Ticket \u2013 einen Anteil am Fonds \u2013, den sie jederzeit wieder gegen ihren \u201eMantel\u201c eintauschen kann.<\/p>\n<p>Der Mantel selbst (das eigentliche Bitcoin) liegt in Cold Storage bei einem Verwahrer wie Coinbase. Wenn ein institutioneller Anleger Anteile zur\u00fcckgibt, verkauft der Fonds mechanisch Bitcoin, um diese R\u00fccknahme zu bedienen. Die Entscheidung zur R\u00fccknahme ist dabei kein Urteil \u00fcber den langfristigen Wert von Bitcoin, sondern oft eine Entscheidung auf Portfolioebene, die durch andere Entwicklungen im Buch des Investors getrieben wird.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/content-img-1-1.jpg\" alt=\"\" \/><\/p>\n<p>Diese mechanische Realit\u00e4t ist ein wichtiger Kontext f\u00fcr die aktuelle Serie. Die kumulierten Nettozufl\u00fcsse in US-Spot-Bitcoin-ETFs seit ihrem Start im Januar 2024 bleiben strukturell positiv. Die 2,8 Milliarden Dollar, die in den letzten Wochen abgezogen wurden, stehen einer viel gr\u00f6\u00dferen Kapitalbasis gegen\u00fcber, die investiert blieb.<\/p>\n<p>BlackRocks IBIT und Fidelitys FBTC, die beiden gr\u00f6\u00dften Fonds nach verwaltetem Verm\u00f6gen, mussten den Gro\u00dfteil der j\u00fcngsten R\u00fccknahmen verkraften, wobei IBIT w\u00e4hrend der Mai-Phase wiederholt die gr\u00f6\u00dften Abfl\u00fcsse an Einzeltagen verzeichnete. Die Serie ist zwar signifikant, stellt aber f\u00fcr sich genommen noch keinen Beweis f\u00fcr einen strukturellen Ausstieg dar.<\/p>\n<p>Wie bereits unsere <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/news\/bitcoin-btc\/bitcoin-etf-10-day-outflow-streak\/\" target=\"_blank\" rel=\"noopener\">fr\u00fchere Berichterstattung \u00fcber die 10-t\u00e4gige Abflussphase<\/a> desselben Trends dokumentierte, baute sich das R\u00fccknahmemuster stufenweise auf, anstatt als einzelner Schock einzutreten. Der aktuelle 11-Tage-Lauf setzt diese Welle fort, was darauf hindeutet, dass die zugrunde liegende Ursache noch nicht gel\u00f6st ist.<\/p>\n<h2>Taktische Pause oder struktureller Ausstieg? Die Serie richtig lesen<\/h2>\n<p>Der bisherige Rekord f\u00fcr aufeinanderfolgende Abflusstage bei US-Spot-Bitcoin-ETFs wurde Anfang 2025 mit einer acht Tage dauernden Serie aufgestellt. Diese endete mit einer deutlichen Trendwende bei den Zufl\u00fcssen, sobald der ausl\u00f6sende makro\u00f6konomische Katalysator nachlie\u00df.<\/p>\n<p>Der Bloomberg-ETF-Analyst Eric Balchunas hat konsistent darauf hingewiesen, dass gro\u00dfe Abfluss-Cluster tendenziell Rebalancing-Entscheidungen auf Portfolioebene widerspiegeln, die oberhalb der Anlageklasse getroffen werden \u2013 und keine Urteile \u00fcber Bitcoin speziell sind. Diese Unterscheidung \u2013 Rotation statt R\u00fcckzug \u2013 ist entscheidend, um die aktuelle Lage zu verstehen.<\/p>\n<p>Hier wird auch das Konzept des \u201ePapier-Bitcoins\u201c n\u00fctzlich. In ETFs gehaltenes Bitcoin ist Papier-Bitcoin: Es ist ein Exposure zum Asset, das durch ein Finanzprodukt vermittelt wird, welches in einem institutionellen Portfolio neben Aktien, Anleihen und Rohstoffen existiert. Wenn sich die Makro-Bedingungen \u00e4ndern, reagieren Portfoliomanager auf das gesamte Buch, nicht nur auf eine einzelne Position.<\/p>\n<p>Spot-Halter, die Bitcoin \u00fcber mehrere Zyklen hinweg direkt akkumuliert haben, verf\u00fcgen \u00fcber eine v\u00f6llig andere Kostenbasis und ein anderes Entscheidungsger\u00fcst. Sie reagieren nicht auf dieselben Trigger.<\/p>\n<p>Die Divergenz, die wir derzeit erleben, ist genau diese Spaltung. Wie unser Explainer dazu, <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/news\/bitcoin-btc\/bitcoin-news-etf-outflows-what-it-means-btc-usd\/\" target=\"_blank\" rel=\"noopener\">was Bitcoin-ETF-Abfl\u00fcsse f\u00fcr die BTC-Kursentwicklung bedeuten<\/a>, erl\u00e4utert, k\u00f6nnen anhaltende institutionelle Verk\u00e4ufe den Preis dr\u00fccken, selbst wenn die zugrunde liegende On-Chain-\u00dcberzeugung intakt bleibt. Dies ist das unangenehme Niemandsland, in dem sich der Markt derzeit bewegt.<\/p>\n<p><strong>Mehr erfahren: <a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/coin-launch\/\">Die Top Krypto Presale Coins f\u00fcr 2026 im \u00dcberblick<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die US-Spot-Bitcoin-ETFs haben laut Daten von CoinGlass nun an elf aufeinanderfolgenden Tagen Nettoabfl\u00fcsse verzeichnet. Dies stellt die l\u00e4ngste anhaltende Negativserie seit der Einf\u00fchrung dieser Anlageprodukte im Januar 2024 dar. Die Verkaufswellen kamen schubweise: Wie Bloomberg berichtete, gab es Ende Mai 2026 eine R\u00fccknahmewelle von rund 2,8 Milliarden Dollar \u00fcber einen Zeitraum von neun Handelstagen. Ein..<\/p>\n","protected":false},"author":135977,"featured_media":74050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[40],"tags":[86],"coin":[101],"class_list":["post-74058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin-btc","tag-bitcoin-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord<\/title>\n<meta name=\"description\" content=\"Rekord-Abfluss bei Bitcoin-ETFs: 11 Tage in Folge im Minus. Was hinter den Milliarden-Verk\u00e4ufen steckt und warum Spot-Halter gelassen bleiben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord\" \/>\n<meta property=\"og:description\" content=\"Rekord-Abfluss bei Bitcoin-ETFs: 11 Tage in Folge im Minus. Was hinter den Milliarden-Verk\u00e4ufen steckt und warum Spot-Halter gelassen bleiben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins DE\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-02T10:06:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christoph Peterson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/christophP84\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christoph Peterson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/\"},\"author\":{\"name\":\"Christoph Peterson\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/8570dc147194a473518a2620544f4698\"},\"headline\":\"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord\",\"datePublished\":\"2026-06-02T10:06:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/\"},\"wordCount\":721,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/06\\\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg\",\"keywords\":[\"Bitcoin Nachrichten\"],\"articleSection\":[\"Bitcoin\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/\",\"name\":\"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/06\\\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg\",\"datePublished\":\"2026-06-02T10:06:25+00:00\",\"description\":\"Rekord-Abfluss bei Bitcoin-ETFs: 11 Tage in Folge im Minus. Was hinter den Milliarden-Verk\u00e4ufen steckt und warum Spot-Halter gelassen bleiben.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/06\\\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/06\\\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/bitcoin-etf-outflows-negativ-rekord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bitcoin\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-btc\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"name\":\"99bitcoins DE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"width\":327,\"height\":276,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/8570dc147194a473518a2620544f4698\",\"name\":\"Christoph Peterson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g\",\"caption\":\"Christoph Peterson\"},\"description\":\"Vor einigen Jahren hat Christoph das Thema Kryptow\u00e4hrungen f\u00fcr sich entdeckt und ist seither leidenschaftlich als Autor und Enthusiast in diesem Bereich aktiv. Sein Interesse gilt vor allem den Themen Kryptow\u00e4hrungen, Blockchain-Technologie und Security Token Offerings (STOs). Als regelm\u00e4\u00dfiger Autor f\u00fcr das Online-Magazin 99Bitcoins berichtet er umfassend \u00fcber die Welt der Krypto- und Blockchain-Technologie und liefert fundierte Analysen zu aktuellen Trends und Entwicklungen in diesem dynamischen Markt.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/christophP84\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/author\\\/christophpeterson\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord","description":"Rekord-Abfluss bei Bitcoin-ETFs: 11 Tage in Folge im Minus. Was hinter den Milliarden-Verk\u00e4ufen steckt und warum Spot-Halter gelassen bleiben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/","og_locale":"de_DE","og_type":"article","og_title":"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord","og_description":"Rekord-Abfluss bei Bitcoin-ETFs: 11 Tage in Folge im Minus. Was hinter den Milliarden-Verk\u00e4ufen steckt und warum Spot-Halter gelassen bleiben.","og_url":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/","og_site_name":"99bitcoins DE","article_published_time":"2026-06-02T10:06:25+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg","type":"image\/jpeg"}],"author":"Christoph Peterson","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/christophP84","twitter_misc":{"Written by":"Christoph Peterson","Est. reading time":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/"},"author":{"name":"Christoph Peterson","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/8570dc147194a473518a2620544f4698"},"headline":"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord","datePublished":"2026-06-02T10:06:25+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/"},"wordCount":721,"publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg","keywords":["Bitcoin Nachrichten"],"articleSection":["Bitcoin"],"inLanguage":"de","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/","url":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/","name":"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg","datePublished":"2026-06-02T10:06:25+00:00","description":"Rekord-Abfluss bei Bitcoin-ETFs: 11 Tage in Folge im Minus. Was hinter den Milliarden-Verk\u00e4ufen steckt und warum Spot-Halter gelassen bleiben.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/#primaryimage","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/bitcoin-etf-outflows-record-streak-institutional-selling-ana-featured.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/bitcoin-etf-outflows-negativ-rekord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/99bitcoins.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Bitcoin","item":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-btc\/"},{"@type":"ListItem","position":4,"name":"Bitcoin-ETFs: 11 Tage Abfl\u00fcsse markieren neuen Negativ-Rekord"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/de\/#website","url":"https:\/\/99bitcoins.com\/de\/","name":"99bitcoins DE","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/de\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","width":327,"height":276,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/8570dc147194a473518a2620544f4698","name":"Christoph Peterson","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0eea0fe6769cb60ae341cd563cbb9f0a44b244ea2e18d2cdf701f982f9020ca?s=96&d=mm&r=g","caption":"Christoph Peterson"},"description":"Vor einigen Jahren hat Christoph das Thema Kryptow\u00e4hrungen f\u00fcr sich entdeckt und ist seither leidenschaftlich als Autor und Enthusiast in diesem Bereich aktiv. Sein Interesse gilt vor allem den Themen Kryptow\u00e4hrungen, Blockchain-Technologie und Security Token Offerings (STOs). Als regelm\u00e4\u00dfiger Autor f\u00fcr das Online-Magazin 99Bitcoins berichtet er umfassend \u00fcber die Welt der Krypto- und Blockchain-Technologie und liefert fundierte Analysen zu aktuellen Trends und Entwicklungen in diesem dynamischen Markt.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/christophP84"],"url":"https:\/\/99bitcoins.com\/de\/author\/christophpeterson\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/74058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/users\/135977"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/comments?post=74058"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/74058\/revisions"}],"predecessor-version":[{"id":74060,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/74058\/revisions\/74060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media\/74050"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media?parent=74058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories?post=74058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/tags?post=74058"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/coin?post=74058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}