{"id":61171,"date":"2026-01-26T14:18:21","date_gmt":"2026-01-26T14:18:21","guid":{"rendered":"https:\/\/99bitcoins.com\/de\/?p=61171"},"modified":"2026-01-26T13:59:37","modified_gmt":"2026-01-26T13:59:37","slug":"mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/","title":{"rendered":"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker &#8222;John Lick&#8220; entlarvte sich selbst durch Prahlerei"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Der mutma\u00dfliche Krypto-Hacker \u201eJohn Lick\u201c soll soll \u00fcber Insider-Zugriff mehr als 40 Millionen USD von US-Regierungsbeh\u00f6rden gestohlen haben. Das Verr\u00fcckte an der Geschichte ist, dass John Lick die Gelder durch Zugriff auf die Wallets seines Vaters erlangen konnte, und sich selbst durch seine eigene Prahlsucht entlarvte.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">    <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\">Das Wichtigste im \u00dcberblick:<\/h2>\r\n            <ul class=\"nnbtc-key-takeaways__list\">\r\n             <li class=\"nnbtc-key-takeaways__list-item\">\r\n        John Daghita alias \u201eJohn Lick\u201c soll \u00fcber 40 Mio. USD aus US-Regierungs-Wallets (u. a. Bitfinex-Beschlagnahmungen) gestohlen haben, insgesamt \u00fcber 90 Mio. USD in verd\u00e4chtigen Transfers.    <\/li>\r\n         <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Sein Vater leitet CMDSS, das einen Vertrag mit dem US Marshals Service zur Verwaltung und Liquidation beschlagnahmter Kryptos hatte \u2013 daher mutma\u00dflicher Insider-Zugriff.    <\/li>\r\n         <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Die Enttarnung erfolgte durch einen aufgezeichneten \u201eband-for-band\u201c-Streit auf Telegram mit Dritan Kapplani Jr., bei dem er Wallets mit Millionenbetr\u00e4gen flexte.    <\/li>\r\n         <li class=\"nnbtc-key-takeaways__list-item\">\r\n        ZachXBT ver\u00f6ffentlichte On-Chain-Beweise, Transaktions-Cluster und Verbindungen; CMDSS l\u00f6schte danach Website, X-Account und LinkedIn.    <\/li>\r\n         <li class=\"nnbtc-key-takeaways__list-item\">\r\n        John Daghita trollt weiter (u. a. sandte er ZachXBT 0.6767 ETH aus gestohlenen Funds); keine offizielle Anklage bisher, aber Strafverfolgung gilt als sehr wahrscheinlich.    <\/li>\r\n         <\/ul>\r\n        <\/div>\r\n    <\/span><\/p>\n<h2><span style=\"font-weight: 400\">John Lick \u2013 Krypto-Diebstahl von US-Beh\u00f6rden-Wallets in zweistelliger Millionenh\u00f6he<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Die Story des Hackers \u201cJohn Lick\u201d bzw. John Daghita d\u00fcrfte eine der verr\u00fccktesten Hacker-Geschichten des Jahres werden. ZachXBT, ein bekannter Krypto-Analyst und Krypto-Detektiv, <\/span><a href=\"https:\/\/x.com\/zachxbt\/status\/2014685263327351116\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">machte dabei wieder einmal auf den Fall aufmerksam<\/span><\/a><span style=\"font-weight: 400\">. Insgesamt sollen sich alle gestohlenen Assets von John Lick\u00a0 \u00fcber 90 Millionen US-Dollar in Bitcoin, <\/span><a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/bitcoin-alternative\/\"><span style=\"font-weight: 400\">Bitcoin Alternativen<\/span><\/a><span style=\"font-weight: 400\">, Ethereum und anderen Altcoins betragen.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">1\/ Meet the threat actor John (Lick), who was caught flexing $23M in a wallet address directly tied to $90M+  in suspected thefts from the US Government in 2024 and multiple other unidentified victims from Nov 2025 to Dec 2025. <a href=\"https:\/\/t.co\/SBAFU5hTnE\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/SBAFU5hTnE<\/a><\/p>\n<p>&mdash; ZachXBT (@zachxbt) <a href=\"https:\/\/twitter.com\/zachxbt\/status\/2014685263327351116?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 23, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Spektakul\u00e4r wird der Fall dadurch dass ein gro\u00dfer Anteil dieser Gelder aus <\/span><a href=\"https:\/\/99bitcoins.com\/de\/krypto-wallet\/\"><span style=\"font-weight: 400\">Krypto Wallets<\/span><\/a><span style=\"font-weight: 400\"> von US-Beh\u00f6rden stammen. Die mutma\u00dflich gestohlenen Summen stammen selbst aus kriminellen Kontexten, aus denen die US-Regierung sie beschlagnahmt hat. Darunter befinden sich beispielsweise Assets aus dem Bitfinex-Hack oder aus Darknet-M\u00e4rkten. ZachXBT sch\u00e4tzt, dass John Lick aus US-Regierungs-Adressen mehr als 40 Millionen Dollar abgezweigt hatte.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Hacker soll Zugang \u00fcber seinen Vater gehabt haben<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Die Krux an der Sache ist, dass John Daghita der Sohn des Eigent\u00fcmers und Pr\u00e4sidenten des Unternehmens CMDSS (Crypto Management &amp; Disposition Services o. \u00c4.) sein soll. Dieses Unternehmen hatte einen aktiven Regierungsvertrag in Virginia, um f\u00fcr den US Marshals Service beschlagnahmte Kryptow\u00e4hrungen zu managen, zu sichern und zu liquidieren.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Durch diesen Vertrag hatte CMDSS legitimen Zugriff auf Cold-Wallets und Multisig-Systeme \u2013 genau jene Adressen, aus denen sp\u00e4ter Gelder verschwunden sind. ZachXBT ver\u00f6ffentlichte Onchain-Graphen, Transaktions-Cluster und Verbindungen zu Telegram-Chats, die zeigen sollen, dass Teile der gestohlenen Funds in <\/span><a href=\"https:\/\/99bitcoins.com\/de\/krypto-wallet\/ohne-verifizierung\/\"><span style=\"font-weight: 400\">Wallets ohne Verifizierung<\/span><\/a><span style=\"font-weight: 400\"> landeten, die \u201eLick\u201c geh\u00f6rte oder von ihm kontrolliert wurden.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">John Lick entlarvte sich durch \u201cBand-to-Band\u201d Prahlerei<\/span><\/h2>\n<p><span style=\"font-weight: 400\">ZachXBT teilte weiterhin, dass die Identit\u00e4t von John Lick nur durch einen hitzigen Streit mit einem anderen Krypto-Dieb namens Dritan Kapplani Jr. enth\u00fcllt werden konnte. Die beiden gerieten in einen Streit, wer von beiden reicher ist und einigten sich darauf, sich gegenseitig Wallet-Betr\u00e4ge zu zeigen. Im Jargon der Krypto-Diebe nennt man so etwas \u201eband for band\u201c \u2013 also quasi ein Wallet-Vergleichsduell, wie ZachXBT erkl\u00e4rend dazu schreibt.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">3\/ In part 1 of the recording Dritan mocks John however John screenshares Exodus Wallet which shows the Tron address below with $2.3M:<br \/> TMrWCLMS3ibDbKLcnNYhLggohRuLUSoHJg <a href=\"https:\/\/t.co\/jvcjIVEpaE\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/jvcjIVEpaE<\/a><\/p>\n<p>&mdash; ZachXBT (@zachxbt) <a href=\"https:\/\/twitter.com\/zachxbt\/status\/2014685270868660288?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 23, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Genau diese Band-for-Band-Sitzung wurde jedoch zum Verh\u00e4ngnis f\u00fcr John Lick. Denn die die komplette Auseinandersetzung wurde aufgezeichnet. Durch den Leak der Aufzeichnungen konnten jedenfalls die Adressen von John Lick nachverfolgt und mutma\u00dflich seine wahre Identit\u00e4t enth\u00fcllt werden. Das Wallet enthielt zu diesem Zeitpunkt rund 23 Millionen USD.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Verbindung von John Lick zu John Daghita kam durch eine Cybercrime-Community auf Telegram auf. Die F\u00e4hrte erscheint derzeit hei\u00df zu sein, ist jedoch noch nicht vollst\u00e4ndig gekl\u00e4rt.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Wie geht es nun weiter in dem Fall?<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Der Fall ist noch relativ frisch, sodass es bis jetzt noch keine \u00f6ffentlich bekannte Strafverfolgung bzgl. John Lick gibt. Auch gibt es weder Stellungnahmen durch die betroffenen Beh\u00f6rden noch eine offizielle Anklage von John Daghita. Die Firma CMDSS sowie Dean Daghita, John Daghita, selbst haben inzwischen jedoch ihre Online-Pr\u00e4senz vollst\u00e4ndig gel\u00f6scht.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Dies d\u00fcrfte als Best\u00e4tigung gelten, dass die Geschehnisse so wie sie ZachXBT berichtet hat, zumindest in Teilen der Wahrheit entsprechen. Denn die Firma d\u00fcrfte durch den massiven Reputationsverlust nachhaltig gesch\u00e4digt sein und der zuk\u00fcnftige Erfolg damit stark zweifelhaft sein.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Sehr wahrscheinlich ist, dass die Strafverfolgungsbeh\u00f6rden John Daghita bald verfolgen und in Haft nehmen d\u00fcrften und dass nach der Festnahme ein formaler Anklageprozess beginnt. Bislang ist John Daghita jedoch noch auf freiem Fu\u00df und versucht, ZachXBT auf Telegram zu trollen. Erst vor wenigen Minuten (beim Schreiben des Artikels) machte ZachXBT auch darauf aufmerksam, dass John Daghita ihm 0.6767 ETH (1,6K Euro) an seine \u00f6ffentliche Ethereum-Adresse schickte.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der mutma\u00dfliche Krypto-Hacker \u201eJohn Lick\u201c soll soll \u00fcber Insider-Zugriff mehr als 40 Millionen USD von US-Regierungsbeh\u00f6rden gestohlen haben. Das Verr\u00fcckte an der Geschichte ist, dass John Lick die Gelder durch Zugriff auf die Wallets seines Vaters erlangen konnte, und sich selbst durch seine eigene Prahlsucht entlarvte.\u00a0 John Lick \u2013 Krypto-Diebstahl von US-Beh\u00f6rden-Wallets in zweistelliger Millionenh\u00f6he..<\/p>\n","protected":false},"author":136078,"featured_media":61178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[42],"tags":[87],"coin":[101],"class_list":["post-61171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-altcoin-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mutma\u00dflicher 90 Mio. USD Krypto-Hacker &quot;John Lick&quot; entlarvte sich selbst durch Prahlerei - 99bitcoins DE<\/title>\n<meta name=\"description\" content=\"Der mutma\u00dfliche Krypto-Hacker \u201eJohn Lick\u201c soll soll \u00fcber Insider-Zugriff mehr als 40 Millionen USD von US-Regierungsbeh\u00f6rden gestohlen haben. Das\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker &quot;John Lick&quot; entlarvte sich selbst durch Prahlerei - 99bitcoins DE\" \/>\n<meta property=\"og:description\" content=\"Der mutma\u00dfliche Krypto-Hacker \u201eJohn Lick\u201c soll soll \u00fcber Insider-Zugriff mehr als 40 Millionen USD von US-Regierungsbeh\u00f6rden gestohlen haben. Das\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins DE\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-26T14:18:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael Sprick\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zeeko76\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael Sprick\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/\"},\"author\":{\"name\":\"Michael Sprick\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/d74ddedded928d3825124905cfbfccd4\"},\"headline\":\"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker &#8222;John Lick&#8220; entlarvte sich selbst durch Prahlerei\",\"datePublished\":\"2026-01-26T14:18:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/\"},\"wordCount\":784,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg\",\"keywords\":[\"Altcoin Nachrichten\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/\",\"name\":\"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker \\\"John Lick\\\" entlarvte sich selbst durch Prahlerei - 99bitcoins DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg\",\"datePublished\":\"2026-01-26T14:18:21+00:00\",\"description\":\"Der mutma\u00dfliche Krypto-Hacker \u201eJohn Lick\u201c soll soll \u00fcber Insider-Zugriff mehr als 40 Millionen USD von US-Regierungsbeh\u00f6rden gestohlen haben. Das\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg\",\"width\":1456,\"height\":816,\"caption\":\"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker \\\"John Lick\\\" entlarvte sich selbst durch Prahlerei\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker &#8222;John Lick&#8220; entlarvte sich selbst durch Prahlerei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"name\":\"99bitcoins DE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"width\":327,\"height\":276,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/d74ddedded928d3825124905cfbfccd4\",\"name\":\"Michael Sprick\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g\",\"caption\":\"Michael Sprick\"},\"description\":\"Michael Sprick ist ein freiberuflicher Journalist und Content Writer mit Schwerpunkt Blockchain und Web3 und wohnt in Barcelona. In der Vergangenheit hat er u.a. f\u00fcr btc-echo.de und f\u00fcr die BSV Blockchain Association gearbeitet.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/zeeko76\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/author\\\/michaelsprick\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker \"John Lick\" entlarvte sich selbst durch Prahlerei - 99bitcoins DE","description":"Der mutma\u00dfliche Krypto-Hacker \u201eJohn Lick\u201c soll soll \u00fcber Insider-Zugriff mehr als 40 Millionen USD von US-Regierungsbeh\u00f6rden gestohlen haben. Das","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/","og_locale":"de_DE","og_type":"article","og_title":"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker \"John Lick\" entlarvte sich selbst durch Prahlerei - 99bitcoins DE","og_description":"Der mutma\u00dfliche Krypto-Hacker \u201eJohn Lick\u201c soll soll \u00fcber Insider-Zugriff mehr als 40 Millionen USD von US-Regierungsbeh\u00f6rden gestohlen haben. Das","og_url":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/","og_site_name":"99bitcoins DE","article_published_time":"2026-01-26T14:18:21+00:00","og_image":[{"width":1456,"height":816,"url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg","type":"image\/jpeg"}],"author":"Michael Sprick","twitter_card":"summary_large_image","twitter_creator":"@zeeko76","twitter_misc":{"Written by":"Michael Sprick","Est. reading time":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/"},"author":{"name":"Michael Sprick","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/d74ddedded928d3825124905cfbfccd4"},"headline":"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker &#8222;John Lick&#8220; entlarvte sich selbst durch Prahlerei","datePublished":"2026-01-26T14:18:21+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/"},"wordCount":784,"publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg","keywords":["Altcoin Nachrichten"],"articleSection":["Altcoins"],"inLanguage":"de","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/","url":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/","name":"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker \"John Lick\" entlarvte sich selbst durch Prahlerei - 99bitcoins DE","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg","datePublished":"2026-01-26T14:18:21+00:00","description":"Der mutma\u00dfliche Krypto-Hacker \u201eJohn Lick\u201c soll soll \u00fcber Insider-Zugriff mehr als 40 Millionen USD von US-Regierungsbeh\u00f6rden gestohlen haben. Das","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/#primaryimage","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Mutmasslicher-90-Mio.-USD-Krypto-Hacker-John-Lick-entlarvte-sich-selbst-durch-Prahlerei.jpg","width":1456,"height":816,"caption":"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker \"John Lick\" entlarvte sich selbst durch Prahlerei"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/mutmasslicher-90-mio-usd-krypto-hacker-john-lick-entlarvte-sich-selbst-durch-prahlerei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/99bitcoins.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Mutma\u00dflicher 90 Mio. USD Krypto-Hacker &#8222;John Lick&#8220; entlarvte sich selbst durch Prahlerei"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/de\/#website","url":"https:\/\/99bitcoins.com\/de\/","name":"99bitcoins DE","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/de\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","width":327,"height":276,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/d74ddedded928d3825124905cfbfccd4","name":"Michael Sprick","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g","caption":"Michael Sprick"},"description":"Michael Sprick ist ein freiberuflicher Journalist und Content Writer mit Schwerpunkt Blockchain und Web3 und wohnt in Barcelona. In der Vergangenheit hat er u.a. f\u00fcr btc-echo.de und f\u00fcr die BSV Blockchain Association gearbeitet.","sameAs":["https:\/\/x.com\/zeeko76"],"url":"https:\/\/99bitcoins.com\/de\/author\/michaelsprick\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/61171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/users\/136078"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/comments?post=61171"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/61171\/revisions"}],"predecessor-version":[{"id":61179,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/61171\/revisions\/61179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media\/61178"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media?parent=61171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories?post=61171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/tags?post=61171"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/coin?post=61171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}