{"id":48415,"date":"2025-10-20T13:39:00","date_gmt":"2025-10-20T13:39:00","guid":{"rendered":"https:\/\/99bitcoins.com\/de\/?p=48415"},"modified":"2025-10-20T13:37:59","modified_gmt":"2025-10-20T13:37:59","slug":"fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/","title":{"rendered":"FED warnt: Krypto-Hacker warten nur auf Quantencomputer"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Die US-Notenbank FED warnt Blockchain-User in ihrer Studie <\/span><a href=\"https:\/\/www.federalreserve.gov\/econres\/feds\/harvest-now-decrypt-later-examining-post-quantum-cryptography-and-the-data-privacy-risks-for-distributed-ledger-networks.htm\" rel=\"nofollow\" target=\"_blank\"><i><span style=\"font-weight: 400\">Harvest Now, Decrypt Later<\/span><\/i><\/a><span style=\"font-weight: 400\"> vor Quantencomputing.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Dass Kryptow\u00e4hrungen m\u00f6glicherweise von Quantencomputern geknackt werden k\u00f6nnten, besch\u00e4ftigt seit Jahren die Branche. Sind die <\/span><a href=\"https:\/\/99bitcoins.com\/de\/bitcoin-kaufen\/\"><span style=\"font-weight: 400\">Bitcoins<\/span><\/a><span style=\"font-weight: 400\"> in meiner Krypto-Wallet auf dem Rechner bedroht, wenn die Technologie rasant fortschreitet und der erste voll einsatzf\u00e4hige Quantencomputer in Betrieb geht?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Laut der FED gibt es schon jetzt reale Gefahren, die allerdings mehr auf gestohlenen Blockchain-Daten von Usern liegen als auf den gespeicherten Kryptow\u00e4hrungen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">     <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\">Das Wichtigste in K\u00fcrze:<\/h2>\r\n        \n    <ul class=\"nnbtc-key-takeaways__list\">\r\n        \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Derzeit gibt es keine unmittelbare Bedrohung von Quantencomputing f\u00fcr Bitcoin und andere Kryptow\u00e4hrungen.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Aber die Sicherheit von privaten Daten auf der Blockchain ist in Gefahr, und zwar schon jetzt, sagt die FED.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Quantencomputing ist noch weit entfernt. Doch schon jetzt klauen Hacker Daten, um diese sp\u00e4ter zu entschl\u00fcsseln.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Konkrete Gefahren zeigen sich bei Datendiebst\u00e4hlen von pers\u00f6nlichen Daten, die auch private Schl\u00fcssel enthalten k\u00f6nnen, um Krypto-Wallets zu hacken.    <\/li>\r\n    \n    <\/ul>\r\n    \n    <\/div>\r\n    <\/span><\/p>\n<h2><span style=\"font-weight: 400\">Welche Gefahren gibt es durch Quantencomputing?<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Digitale Signaturen und asymmetrisch verschl\u00fcsselte Daten stellen das R\u00fcckgrat der digitalen Wirtschaft dar. Googles experimenteller Quantencomputer hat innerhalb von 20 Sekunden das geschafft, wof\u00fcr der beste IBM-Computer, der Summit, laut Forschern 10.000 Jahre ben\u00f6tigt h\u00e4tte. Diese Zahl wurde zwar sp\u00e4ter von IBM auf 2,5 Jahre korrigiert, sie zeigt aber immer noch die unglaubliche Leistungsf\u00e4higkeit der Technologie.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Wenn es Computer gibt, die eine solche Rechenleistung besitzen, dann sind Kryptow\u00e4hrungen und alle anderen kryptografisch gesicherten G\u00fcter und Daten zweifelsohne in Gefahr. Wer aber jetzt glaubt, er k\u00f6nne sich die n\u00e4chsten Jahre und Jahrzehnte entspannt zur\u00fccklehnen, dem sei die Studie der US-Notenbank FED ans Herz gelegt.\u00a0<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-48420\" src=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker1_20102025.png\" alt=\"\" width=\"1113\" height=\"572\" srcset=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker1_20102025.png 1113w, https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker1_20102025-300x154.png 300w, https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker1_20102025-1024x526.png 1024w, https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker1_20102025-768x395.png 768w\" sizes=\"(max-width: 1113px) 100vw, 1113px\" \/><\/p>\n<p><a href=\"https:\/\/thequantuminsider.com\/2025\/10\/06\/federal-reserve-warns-quantum-computers-could-expose-bitcoins-hidden-past\/\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">Quelle<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400\">Wenn Hacker heute Daten stehlen, glaubt die \u00d6ffentlichkeit, die Datens\u00e4tze w\u00fcrden umgehend im Darknet zum Verkauf angeboten. Doch dies ist nicht immer die prim\u00e4re Vorgehensweise von Dieben, denn die Kriminellen speichern die gro\u00dfen Datenmengen, um sie sp\u00e4ter, wenn die Technologie durch Quantencomputer reif daf\u00fcr ist, zu entschl\u00fcsseln und f\u00fcr ihre Zwecke zu nutzen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Mit jedem noch so kleinen Fortschritt der Quantentechnologie kommen die Kriminellen ihrem Ziel ein St\u00fcck n\u00e4her. Kryptografie wird fr\u00fcher oder sp\u00e4ter angreifbar sein, da sind sich viele Experten einig. Die Distributed-Ledger-Technologie ist die Grundlage von vertrauenslosen Netzwerken, wie der Bitcoin-Blockchain. Die Verschl\u00fcsselung mit privaten Schl\u00fcsseln, so die FED-Studie, ist besonders anf\u00e4llig f\u00fcr leistungsstarke Quantencomputer der Zukunft.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Selbst wenn die Hacker im Moment des Diebstahls von Daten nichts mit diesen anfangen k\u00f6nnen, besteht die gro\u00dfe Gefahr, dass sie die Integrit\u00e4t, Sicherheit und den Datenschutz von Blockchain-Netzwerken aushebeln. Eigene Governance-Methoden und Anforderungen sind bisher nicht standardisiert. Governance-Token erm\u00f6glichen h\u00e4ufig jedem Anleger, Stimmrechte auszu\u00fcben. Dabei steht immer das gegenseitige Vertrauen im Vordergrund.\u00a0<\/span><\/p>\n<blockquote><p><b><i>Eine neue Studie der US-Notenbank Federal Reserve warnt davor, dass Quantencomputer eines Tages die private Historie von Bitcoin und anderen Blockchain-Netzwerken entschl\u00fcsseln und so Transaktionsdaten offenlegen k\u00f6nnten, die einst als f\u00fcr immer sicher galten.<\/i><\/b><\/p><\/blockquote>\n<p><a href=\"https:\/\/thequantuminsider.com\/2025\/10\/06\/federal-reserve-warns-quantum-computers-could-expose-bitcoins-hidden-past\/\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">Quelle<\/span><\/a><\/p>\n<h2><span style=\"font-weight: 400\">Privatsph\u00e4re k\u00f6nnte durch Quantencomputer f\u00fcr immer verloren sein<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Die Studie wurde vom Federal Reserve Board und der Federal Reserve Bank of Chicago ver\u00f6ffentlicht und befasst sich mit dem Konzept von Harvest Now, Decrypt Later, kurz HNDL. Das Konzept k\u00f6nnte weitreichende Folgen haben, hei\u00dft es in der FED-Studie, denn Angreifer laden schon heute verschl\u00fcsselte Daten und Informationen herunter, um sie sp\u00e4ter mit leistungsf\u00e4higen Quantencomputern zu entschl\u00fcsseln. Ein Gesch\u00e4ft f\u00fcr die Zukunft also, auf lange Sicht ausgelegt. Es zeigt aber auch die Anf\u00e4lligkeit und den Irrglauben, dem die Menschen unterlegen sind, wenn es um ihre Privatsph\u00e4re im Internet geht. Bitcoin ist nicht anonym, auch wenn es zahlreiche Anbieter gibt, die damit werben, man k\u00f6nne Bitcoin anonym bei ihnen kaufen. Bitcoin ist pseudonym. Das allein zeigt schon, dass es Schwachstellen im kryptografischen Verschl\u00fcsselungsweg gibt. Es gibt allerdings einige <\/span><a href=\"https:\/\/99bitcoins.com\/de\/krypto-wallet\/ohne-verifizierung\/\"><span style=\"font-weight: 400\">Krypto-B\u00f6rsen ohne Verifizierung<\/span><\/a><span style=\"font-weight: 400\">, die den Schutz der privaten Daten gew\u00e4hrleisten.\u00a0<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-48418\" src=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker2_20102025.jpg\" alt=\"\" width=\"1505\" height=\"790\" srcset=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker2_20102025.jpg 1505w, https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker2_20102025-300x157.jpg 300w, https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker2_20102025-1024x538.jpg 1024w, https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Hacker2_20102025-768x403.jpg 768w\" sizes=\"(max-width: 1505px) 100vw, 1505px\" \/><\/p>\n<p><a href=\"https:\/\/www.mara.com\/posts\/bitcoin-vs-quantum-computing-more-hype-than-reality\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">Quelle<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400\">Bei <\/span><a href=\"https:\/\/99bitcoins.com\/de\/krypto-wallet\/\"><span style=\"font-weight: 400\">Krypto-Wallets<\/span><\/a><span style=\"font-weight: 400\"> kommen private Schl\u00fcssel ins Spiel, die schon allzu h\u00e4ufig von Dieben in unterschiedlichster Weise entwendet wurden. In Zukunft kommt noch die Quantencomputer-Technologie dazu. Die gesamte Bitcoin-Transaktionshistorie per Mausklick und innerhalb von Sekunden offengelegt? Kein Problem f\u00fcr die Supercomputer der Zukunft!<\/span><\/p>\n<blockquote><p><b><i>Krypto-Anleger m\u00fcssen achtsam sein und sich stets \u00fcber die neuesten Sicherheitsaspekte bei der Verwahrung ihrer digitalen Assets sowie ihrer privaten Daten im Netz informieren.\u00a0<\/i><\/b><\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">Das Papier der Federal Reserve erkl\u00e4rt, dass die Unver\u00e4nderlichkeit verteilter Ledger \u2013 ein Merkmal, das f\u00fcr seine Vertrauensbildung gepriesen wird \u2013 zugleich ihre gr\u00f6\u00dfte Schwachstelle gegen\u00fcber Quantenbedrohungen ist. Ihre angepriesene Unver\u00e4nderbarkeit durch das dauerhafte Speichern der Transaktionen macht zugleich T\u00fcr und Tor f\u00fcr Quantencomputing auf.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Was bedeutet das f\u00fcr Krypto-H\u00e4ndler?<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Vor allem \u00e4ltere Krypto-Wallet-Adressen sind schw\u00e4cher kryptografisch gesch\u00fctzt als die neueren Produkte. Auch bei \u00e4lteren ruhenden Wallet-Adressen sehen die Verfasser der Studie h\u00f6here Risiken als bei aktuellen Versionen. Explizit warnt die Studie auch vor <\/span><a href=\"https:\/\/bitcoinwiki.org\/wiki\/address-reuse\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">wiederverwendeten Bitcoin-Adressen<\/span><\/a><span style=\"font-weight: 400\">, die die Privatsph\u00e4re und die Sicherheit der Transaktionspartner sowie der zuk\u00fcnftigen Werte unter Quantencomputing nicht gew\u00e4hrleisten k\u00f6nnen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Der Bitcoin-Miner MARA behauptet, dass Bitcoin gegen\u00fcber Quantencomputing widerstandsf\u00e4hig ist. Doch das ist nur eine Sichtweise, wenn man die oben genannten Aspekte ber\u00fccksichtigt. Dennoch hat der Bitcoin-Miner-Gigant recht, denn:<\/span><\/p>\n<blockquote><p><b><i>Der Proof-of-Work von Bitcoin passt die Mining-Schwierigkeit alle 2.016 Bl\u00f6cke an, um eine konstante Blockzeit von ca. 10 Minuten zu gew\u00e4hrleisten. W\u00fcrde ein Quantencomputer Bl\u00f6cke schneller minen, w\u00fcrde sich das Netzwerk anpassen und unfaire Vorteile verhindern.\u00a0<\/i><\/b><\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">Quelle: <\/span><a href=\"http:\/\/mara.com\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">Mara.com<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400\">Quantencomputer greifen nicht nur die Integrit\u00e4t von Krypto-Netzwerken an. Auch im Finanzsektor werden immer mehr Distributed-Ledger, nicht nur die Blockchain, eingesetzt, um erlaubnislose Netzwerke zu schaffen. Diese sind in der Lage, in Echtzeit auf Bedrohungen zu reagieren, was es Angreifern zus\u00e4tzlich schwer macht, an Informationen zu gelangen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die US-Notenbank FED warnt Blockchain-User in ihrer Studie Harvest Now, Decrypt Later vor Quantencomputing.\u00a0 Dass Kryptow\u00e4hrungen m\u00f6glicherweise von Quantencomputern geknackt werden k\u00f6nnten, besch\u00e4ftigt seit Jahren die Branche. Sind die Bitcoins in meiner Krypto-Wallet auf dem Rechner bedroht, wenn die Technologie rasant fortschreitet und der erste voll einsatzf\u00e4hige Quantencomputer in Betrieb geht?\u00a0 Laut der FED gibt..<\/p>\n","protected":false},"author":136139,"featured_media":48417,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[42],"tags":[87],"coin":[101],"class_list":["post-48415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-altcoin-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FED warnt: Krypto-Hacker warten nur auf Quantencomputer<\/title>\n<meta name=\"description\" content=\"Die US-Notenbank FED warnt Blockchain-User in ihrer Studie Harvest Now, Decrypt Later vor Quantencomputing.\u00a0 Dass Kryptow\u00e4hrungen m\u00f6glicherweise von\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FED warnt: Krypto-Hacker warten nur auf Quantencomputer\" \/>\n<meta property=\"og:description\" content=\"Die US-Notenbank FED warnt Blockchain-User in ihrer Studie Harvest Now, Decrypt Later vor Quantencomputing.\u00a0 Dass Kryptow\u00e4hrungen m\u00f6glicherweise von\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins DE\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-20T13:39:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Warnung-vor-Quantencomputer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paul Schr\u00f6der\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@schrderpau21504\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paul Schr\u00f6der\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/\"},\"author\":{\"name\":\"Paul Schr\u00f6der\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/4ef50d9a7da977406ebbce284fe02612\"},\"headline\":\"FED warnt: Krypto-Hacker warten nur auf Quantencomputer\",\"datePublished\":\"2025-10-20T13:39:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/\"},\"wordCount\":1010,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Warnung-vor-Quantencomputer.jpg\",\"keywords\":[\"Altcoin Nachrichten\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/\",\"name\":\"FED warnt: Krypto-Hacker warten nur auf Quantencomputer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Warnung-vor-Quantencomputer.jpg\",\"datePublished\":\"2025-10-20T13:39:00+00:00\",\"description\":\"Die US-Notenbank FED warnt Blockchain-User in ihrer Studie Harvest Now, Decrypt Later vor Quantencomputing.\u00a0 Dass Kryptow\u00e4hrungen m\u00f6glicherweise von\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Warnung-vor-Quantencomputer.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/10\\\/Warnung-vor-Quantencomputer.jpg\",\"width\":1200,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"FED warnt: Krypto-Hacker warten nur auf Quantencomputer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"name\":\"99bitcoins DE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"width\":327,\"height\":276,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/4ef50d9a7da977406ebbce284fe02612\",\"name\":\"Paul Schr\u00f6der\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12527ceba077a23513f08b46e7097368c032094e95179b77eda929f7466685df?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12527ceba077a23513f08b46e7097368c032094e95179b77eda929f7466685df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12527ceba077a23513f08b46e7097368c032094e95179b77eda929f7466685df?s=96&d=mm&r=g\",\"caption\":\"Paul Schr\u00f6der\"},\"description\":\"Paul ist hauptberuflicher Content-Writer mit einem Schwerpunkt auf Kryptow\u00e4hrungen und Finanzthemen. Seine Leidenschaft f\u00fcr Krypto begann 2016, als er seinen ersten Bitcoin f\u00fcr rund 900\u202fDollar kaufte. Seitdem hat er sich immer wieder intensiv mit dem Markt besch\u00e4ftigt. 2024 machte er sich als Texter selbstst\u00e4ndig und schrieb von Anfang an am liebsten \u00fcber Bitcoin, Blockchain und digitale M\u00e4rkte. Seit 2025 unterst\u00fctzt er die Redaktion von 99Bitcoins mit Kryptonews. Wenn er nicht gerade schreibt, ist er als digitaler Teilzeitnomade unterwegs und entdeckt neue L\u00e4nder und Kulturen.\",\"sameAs\":[\"linkedin.com\\\/in\\\/paul-schr\u00f6der-a07422390\",\"https:\\\/\\\/x.com\\\/schrderpau21504\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/author\\\/paulschroeder\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FED warnt: Krypto-Hacker warten nur auf Quantencomputer","description":"Die US-Notenbank FED warnt Blockchain-User in ihrer Studie Harvest Now, Decrypt Later vor Quantencomputing.\u00a0 Dass Kryptow\u00e4hrungen m\u00f6glicherweise von","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/","og_locale":"de_DE","og_type":"article","og_title":"FED warnt: Krypto-Hacker warten nur auf Quantencomputer","og_description":"Die US-Notenbank FED warnt Blockchain-User in ihrer Studie Harvest Now, Decrypt Later vor Quantencomputing.\u00a0 Dass Kryptow\u00e4hrungen m\u00f6glicherweise von","og_url":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/","og_site_name":"99bitcoins DE","article_published_time":"2025-10-20T13:39:00+00:00","og_image":[{"width":1200,"height":720,"url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Warnung-vor-Quantencomputer.jpg","type":"image\/jpeg"}],"author":"Paul Schr\u00f6der","twitter_card":"summary_large_image","twitter_creator":"@schrderpau21504","twitter_misc":{"Written by":"Paul Schr\u00f6der","Est. reading time":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/"},"author":{"name":"Paul Schr\u00f6der","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/4ef50d9a7da977406ebbce284fe02612"},"headline":"FED warnt: Krypto-Hacker warten nur auf Quantencomputer","datePublished":"2025-10-20T13:39:00+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/"},"wordCount":1010,"publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Warnung-vor-Quantencomputer.jpg","keywords":["Altcoin Nachrichten"],"articleSection":["Altcoins"],"inLanguage":"de","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/","url":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/","name":"FED warnt: Krypto-Hacker warten nur auf Quantencomputer","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Warnung-vor-Quantencomputer.jpg","datePublished":"2025-10-20T13:39:00+00:00","description":"Die US-Notenbank FED warnt Blockchain-User in ihrer Studie Harvest Now, Decrypt Later vor Quantencomputing.\u00a0 Dass Kryptow\u00e4hrungen m\u00f6glicherweise von","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/#primaryimage","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Warnung-vor-Quantencomputer.jpg","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Warnung-vor-Quantencomputer.jpg","width":1200,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/fed-warnt-krypto-hacker-warten-nur-auf-quantencomputer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/99bitcoins.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/"},{"@type":"ListItem","position":4,"name":"FED warnt: Krypto-Hacker warten nur auf Quantencomputer"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/de\/#website","url":"https:\/\/99bitcoins.com\/de\/","name":"99bitcoins DE","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/de\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","width":327,"height":276,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/4ef50d9a7da977406ebbce284fe02612","name":"Paul Schr\u00f6der","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/12527ceba077a23513f08b46e7097368c032094e95179b77eda929f7466685df?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12527ceba077a23513f08b46e7097368c032094e95179b77eda929f7466685df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12527ceba077a23513f08b46e7097368c032094e95179b77eda929f7466685df?s=96&d=mm&r=g","caption":"Paul Schr\u00f6der"},"description":"Paul ist hauptberuflicher Content-Writer mit einem Schwerpunkt auf Kryptow\u00e4hrungen und Finanzthemen. Seine Leidenschaft f\u00fcr Krypto begann 2016, als er seinen ersten Bitcoin f\u00fcr rund 900\u202fDollar kaufte. Seitdem hat er sich immer wieder intensiv mit dem Markt besch\u00e4ftigt. 2024 machte er sich als Texter selbstst\u00e4ndig und schrieb von Anfang an am liebsten \u00fcber Bitcoin, Blockchain und digitale M\u00e4rkte. Seit 2025 unterst\u00fctzt er die Redaktion von 99Bitcoins mit Kryptonews. Wenn er nicht gerade schreibt, ist er als digitaler Teilzeitnomade unterwegs und entdeckt neue L\u00e4nder und Kulturen.","sameAs":["linkedin.com\/in\/paul-schr\u00f6der-a07422390","https:\/\/x.com\/schrderpau21504"],"url":"https:\/\/99bitcoins.com\/de\/author\/paulschroeder\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/48415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/users\/136139"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/comments?post=48415"}],"version-history":[{"count":3,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/48415\/revisions"}],"predecessor-version":[{"id":48431,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/48415\/revisions\/48431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media\/48417"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media?parent=48415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories?post=48415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/tags?post=48415"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/coin?post=48415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}