{"id":41760,"date":"2025-08-28T15:43:32","date_gmt":"2025-08-28T15:43:32","guid":{"rendered":"https:\/\/99bitcoins.com\/de\/?p=41760"},"modified":"2025-08-28T15:40:03","modified_gmt":"2025-08-28T15:40:03","slug":"ethereum-cathie-wood-investiert-erneut-in-bitmine","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/","title":{"rendered":"Ethereum: Cathie Wood investiert erneut in BitMine"},"content":{"rendered":"<p>Seit das Schlimmste der Korrektur am Kryptomarkt \u00fcberstanden ist, bewegen sich die Kurse der gr\u00f6\u00dften Coins eher seitw\u00e4rts. Bitcoin bewegt sich um die 113.000 Dollar Marke und Ethereum steigt immer wieder mal auf \u00fcber 4.600 Dollar, kann diese Marke aber nicht verteidigen. Dennoch hat vor allem Ethereum eine beeindruckende Rallye hinter sich. Der Kurs der zweitgr\u00f6\u00dften Kryptow\u00e4hrung der Welt hat sich seit April mehr als verdreifacht. Wer denkt, dass an diesem Punkt schon Schluss ist, k\u00f6nnte sich irren. Zumindest sieht das Star-Investorin Cathie Wood so.<\/p>\n    <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\">Das Wichtigste im \u00dcberblick:<\/h2>\r\n        \n    <ul class=\"nnbtc-key-takeaways__list\">\r\n        \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        BitMine ist das gr\u00f6\u00dfte Ethereum-Treasury-Unternehmen der Welt.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Neben dem Milliard\u00e4r Peter Thiel hat auch Star-Investoren Cathie Wood in BitMine investiert.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Ark Invest h\u00e4lt BitMine Aktien im Wert von \u00fcber 295 Millionen Dollar.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        In 3 verschiedenen ETFs, die von Ark Invest ausgegeben werden, sind nun auch BitMine-Aktien enthalten.    <\/li>\r\n    \n    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Ark Invest geh\u00f6rt auch zu den Emittenten der Spot Ethereum ETFs.    <\/li>\r\n    \n    <\/ul>\r\n    \n    <\/div>\r\n    \n<h2>BitMine setzt voll auf Ethereum<\/h2>\n<p>BitMine hat sich in den letzten zwei Monaten einen Namen gemacht. Mit Wall Street Legende Tom Lee als Chairman hat das Unternehmen seinen Fokus von Bitcoin vollst\u00e4ndig auf Ethereum verlagert. BitMine hat inzwischen die gr\u00f6\u00dfte Ethereum-Reserve der Welt aufgebaut und h\u00e4lt $ETH im Wert von \u00fcber 8 Milliarden Dollar, auch wenn Jack Mallers das f\u00fcr keine gute Idee h\u00e4lt.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Absolutely unprecedented.<\/p>\n<p>Tom Lee has acquired almost $10 billion ETH over the past 50 days.<\/p>\n<p>Over 1.7m ETH.<\/p>\n<p>1.4% of all ETH supply.<\/p>\n<p>If Tom gets to his 5% target and ETH goes above $12k Bitmine would be larger than Microstrategy. <a href=\"https:\/\/t.co\/DpIZv55DBC\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/DpIZv55DBC<\/a><\/p>\n<p>&mdash; RYAN S\u039eAN ADAMS &#8211; rsa.eth \ud83e\udd84 (@RyanSAdams) <a href=\"https:\/\/twitter.com\/RyanSAdams\/status\/1960030779267760133?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">August 25, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Tom Lee geht in seinen <a href=\"https:\/\/99bitcoins.com\/de\/krypto-prognosen\/ethereum\/\">Ethereum-Prognosen<\/a> davon aus, dass der Kurs bis zum Jahresende schon auf 10.000 &#8211; 15.000 Dollar steigen wird. Lee betont immer wieder, dass Ethereum f\u00fcr ihn jetzt an diesem Punkt steht, an dem Bitcoin im Jahr 2017 stand.<\/p>\n<p>Er geht daher davon aus, dass jetzt die beste Zeit ist, um <a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/ethereum\/\">Ethereum zu kaufen<\/a>, solange der Kurs noch nicht f\u00fcnfstellig ist. Analysten betonen inzwischen, dass BitMine gr\u00f6\u00dfer als MicroStrategy werden k\u00f6nnte, das gr\u00f6\u00dfte Bitcoin-Treasury Unternehmen der Welt, wenn der $ETH-Kurs auf 12.000 Dollar steigen w\u00fcrde.<\/p>\n<h2>Cathie Wood steigt ein<\/h2>\n<p>Lee hat mit seinem Konzept schnell viel Aufsehen erregt und BitMine hat SharpLink dadurch auch schnell abh\u00e4ngen k\u00f6nnen. Auch SharpLink setzt auf den Aufbau einer Ethereum-Reserve, wobei der Bestand hier noch deutlich kleiner ist. Das liegt daran, dass Lee offenbar den besseren Draht zu Gro\u00dfinvestoren hat. Schon fr\u00fch wurde bekannt, dass der Milliard\u00e4r Peter Thiel BitMine-Aktien gekauft hat und nun ist auch Star-Investorin Cathie Wood erneut eingestiegen und hat ihre Position vergr\u00f6\u00dfert.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Cathie Wood and Ark Invest currently hold $295.3M of Bitmine Immersion Technologies <a href=\"https:\/\/twitter.com\/search?q=%24BMNR&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$BMNR<\/a> across 3 ETFs:<a href=\"https:\/\/twitter.com\/search?q=%24ARKK&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$ARKK<\/a> \u2192 $198.5M (2.68% weighting in the ETF)<a href=\"https:\/\/twitter.com\/search?q=%24ARKF&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$ARKF<\/a> \u2192 $33.9M (2.53%)<a href=\"https:\/\/twitter.com\/search?q=%24ARKW&amp;src=ctag&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">$ARKW<\/a> \u2192 $62.9M (2.67%) <a href=\"https:\/\/t.co\/4LRw4BrHai\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/4LRw4BrHai<\/a><\/p>\n<p>&mdash; Ark Invest Tracker (@ArkkDaily) <a href=\"https:\/\/twitter.com\/ArkkDaily\/status\/1961066992795811988?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">August 28, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Mit ihrem Unternehmen Ark Invest hat Wood im gro\u00dfen Stil investiert und Aktien im Wert von fast 300 Millionen Dollar bei drei verschiedenen ETFs, die von Ark Invest ausgegeben werden, beigemischt. Es ist kein Geheimnis, dass Wood zu den Bef\u00fcrwortern von Ethereum geh\u00f6rt. Immerhin ist Ark Invest auch unter den Emittenten der Spot Ethereum ETFs zu finden.<\/p>\n<h2>Geht die Rallye weiter?<\/h2>\n<p>Aus der Strategie von Unternehmen wie BitMine und SharpLink hat sich eine Kettenreaktion ergeben. Die Tatsache, dass die beiden Unternehmen zusammen \u00fcber 10 Milliarden Dollar aufgebracht haben, um Ethereum kaufen, hat den $ETH-Kurs stark angetrieben. Das hat wiederum daf\u00fcr gesorgt, dass die ersten K\u00e4ufe schon einen ordentlichen Buchgewinn eingebracht haben und die Aktienkurse der Unternehmen ebenfalls durch die Decke gegangen sind.<\/p>\n<p>Steigende Aktienkurse haben daf\u00fcr gesorgt, dass BitMine und SharpLink ihre neu emittierten Aktien \u00fcber ATM-Verk\u00e4ufe schnell auf den Markt bringen konnten, um frisches Kapital f\u00fcr weitere Ethereum-K\u00e4ufe aufzubringen. Ein Effekt, der sich bis zu einem gewissen Punkt immer weiter selbst verst\u00e4rkt hat. Inzwischen sind die Rallyes von Ethereum und den Aktien aber ins Stocken geraten. Die Chancen stehen aber gut, dass sich das schon bald wieder \u00e4ndert. W\u00e4hrend mit Bitcoin und Ethereum in den letzten Tagen nicht viel zu holen ist, sehen sich viele Anleger bei <a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/neue-kryptowaehrungen\/\">neuen Kryptow\u00e4hrungen<\/a> um, um den n\u00e4chsten Altcoin zu finden, der \u00e4hnlich stark performt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit das Schlimmste der Korrektur am Kryptomarkt \u00fcberstanden ist, bewegen sich die Kurse der gr\u00f6\u00dften Coins eher seitw\u00e4rts. Bitcoin bewegt sich um die 113.000 Dollar Marke und Ethereum steigt immer wieder mal auf \u00fcber 4.600 Dollar, kann diese Marke aber nicht verteidigen. Dennoch hat vor allem Ethereum eine beeindruckende Rallye hinter sich. Der Kurs der..<\/p>\n","protected":false},"author":135839,"featured_media":41763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[42],"tags":[87],"coin":[101],"class_list":["post-41760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoins","tag-altcoin-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ethereum: Cathie Wood investiert erneut in BitMine - 99bitcoins DE<\/title>\n<meta name=\"description\" content=\"Seit das Schlimmste der Korrektur am Kryptomarkt \u00fcberstanden ist, bewegen sich die Kurse der gr\u00f6\u00dften Coins eher seitw\u00e4rts. Bitcoin bewegt sich um die\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ethereum: Cathie Wood investiert erneut in BitMine - 99bitcoins DE\" \/>\n<meta property=\"og:description\" content=\"Seit das Schlimmste der Korrektur am Kryptomarkt \u00fcberstanden ist, bewegen sich die Kurse der gr\u00f6\u00dften Coins eher seitw\u00e4rts. Bitcoin bewegt sich um die\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins DE\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T15:43:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Ethereum-Cathie-Wood.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manuel Lippitz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Lippitz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/\"},\"author\":{\"name\":\"Manuel Lippitz\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/cb2c31cc79b925ab43a963c1ba54a190\"},\"headline\":\"Ethereum: Cathie Wood investiert erneut in BitMine\",\"datePublished\":\"2025-08-28T15:43:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/\"},\"wordCount\":674,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Ethereum-Cathie-Wood.jpg\",\"keywords\":[\"Altcoin Nachrichten\"],\"articleSection\":[\"Altcoins\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/\",\"name\":\"Ethereum: Cathie Wood investiert erneut in BitMine - 99bitcoins DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Ethereum-Cathie-Wood.jpg\",\"datePublished\":\"2025-08-28T15:43:32+00:00\",\"description\":\"Seit das Schlimmste der Korrektur am Kryptomarkt \u00fcberstanden ist, bewegen sich die Kurse der gr\u00f6\u00dften Coins eher seitw\u00e4rts. Bitcoin bewegt sich um die\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Ethereum-Cathie-Wood.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Ethereum-Cathie-Wood.jpg\",\"width\":1200,\"height\":720,\"caption\":\"Wood kauft BitMine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/ethereum-cathie-wood-investiert-erneut-in-bitmine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altcoins\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/altcoins\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ethereum: Cathie Wood investiert erneut in BitMine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"name\":\"99bitcoins DE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"width\":327,\"height\":276,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/cb2c31cc79b925ab43a963c1ba54a190\",\"name\":\"Manuel Lippitz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28103266185ef5268ba93a405757fa6cfa921be40a845db2e7fe4a62f3cc832?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28103266185ef5268ba93a405757fa6cfa921be40a845db2e7fe4a62f3cc832?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28103266185ef5268ba93a405757fa6cfa921be40a845db2e7fe4a62f3cc832?s=96&d=mm&r=g\",\"caption\":\"Manuel Lippitz\"},\"description\":\"Nach 10 Jahren als leitender Angestellter hat sich Manuel 2019 mit einer eigenen Immobilienfirma in die Selbstst\u00e4ndigkeit gewagt. Bis heute hat er vier Unternehmen gegr\u00fcndet oder mit aufgebaut und mit dem Bau des ersten eigenen Mining Rigs wurde neben der Leidenschaft f\u00fcr Immobilien auch das Interesse an Kryptow\u00e4hrungen geweckt. Seitdem schreibt Manuel f\u00fcr namhafte Krypto-Nachrichtenseiten wie Coincierge, Wallstreet Online, Finanznachrichten und Finanzen.net. Nachdem er ein Buch \u00fcber KI ver\u00f6ffentlicht hat, spricht er auf seinem Youtube-Kanal und seinem Blog\u00a0\u00fcber Investments und Unternehmertum.\",\"sameAs\":[\"https:\\\/\\\/at.linkedin.com\\\/in\\\/manuel-lippitz\",\"https:\\\/\\\/www.youtube.com\\\/@vomdealerzumvermieter\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/author\\\/manuel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ethereum: Cathie Wood investiert erneut in BitMine - 99bitcoins DE","description":"Seit das Schlimmste der Korrektur am Kryptomarkt \u00fcberstanden ist, bewegen sich die Kurse der gr\u00f6\u00dften Coins eher seitw\u00e4rts. Bitcoin bewegt sich um die","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/","og_locale":"de_DE","og_type":"article","og_title":"Ethereum: Cathie Wood investiert erneut in BitMine - 99bitcoins DE","og_description":"Seit das Schlimmste der Korrektur am Kryptomarkt \u00fcberstanden ist, bewegen sich die Kurse der gr\u00f6\u00dften Coins eher seitw\u00e4rts. Bitcoin bewegt sich um die","og_url":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/","og_site_name":"99bitcoins DE","article_published_time":"2025-08-28T15:43:32+00:00","og_image":[{"width":1200,"height":720,"url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Ethereum-Cathie-Wood.jpg","type":"image\/jpeg"}],"author":"Manuel Lippitz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Manuel Lippitz","Est. reading time":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/"},"author":{"name":"Manuel Lippitz","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/cb2c31cc79b925ab43a963c1ba54a190"},"headline":"Ethereum: Cathie Wood investiert erneut in BitMine","datePublished":"2025-08-28T15:43:32+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/"},"wordCount":674,"publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Ethereum-Cathie-Wood.jpg","keywords":["Altcoin Nachrichten"],"articleSection":["Altcoins"],"inLanguage":"de","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/","url":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/","name":"Ethereum: Cathie Wood investiert erneut in BitMine - 99bitcoins DE","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Ethereum-Cathie-Wood.jpg","datePublished":"2025-08-28T15:43:32+00:00","description":"Seit das Schlimmste der Korrektur am Kryptomarkt \u00fcberstanden ist, bewegen sich die Kurse der gr\u00f6\u00dften Coins eher seitw\u00e4rts. Bitcoin bewegt sich um die","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/#primaryimage","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Ethereum-Cathie-Wood.jpg","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Ethereum-Cathie-Wood.jpg","width":1200,"height":720,"caption":"Wood kauft BitMine"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/ethereum-cathie-wood-investiert-erneut-in-bitmine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/99bitcoins.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Altcoins","item":"https:\/\/99bitcoins.com\/de\/news\/altcoins\/"},{"@type":"ListItem","position":4,"name":"Ethereum: Cathie Wood investiert erneut in BitMine"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/de\/#website","url":"https:\/\/99bitcoins.com\/de\/","name":"99bitcoins DE","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/de\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","width":327,"height":276,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/cb2c31cc79b925ab43a963c1ba54a190","name":"Manuel Lippitz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d28103266185ef5268ba93a405757fa6cfa921be40a845db2e7fe4a62f3cc832?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d28103266185ef5268ba93a405757fa6cfa921be40a845db2e7fe4a62f3cc832?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d28103266185ef5268ba93a405757fa6cfa921be40a845db2e7fe4a62f3cc832?s=96&d=mm&r=g","caption":"Manuel Lippitz"},"description":"Nach 10 Jahren als leitender Angestellter hat sich Manuel 2019 mit einer eigenen Immobilienfirma in die Selbstst\u00e4ndigkeit gewagt. Bis heute hat er vier Unternehmen gegr\u00fcndet oder mit aufgebaut und mit dem Bau des ersten eigenen Mining Rigs wurde neben der Leidenschaft f\u00fcr Immobilien auch das Interesse an Kryptow\u00e4hrungen geweckt. Seitdem schreibt Manuel f\u00fcr namhafte Krypto-Nachrichtenseiten wie Coincierge, Wallstreet Online, Finanznachrichten und Finanzen.net. Nachdem er ein Buch \u00fcber KI ver\u00f6ffentlicht hat, spricht er auf seinem Youtube-Kanal und seinem Blog\u00a0\u00fcber Investments und Unternehmertum.","sameAs":["https:\/\/at.linkedin.com\/in\/manuel-lippitz","https:\/\/www.youtube.com\/@vomdealerzumvermieter"],"url":"https:\/\/99bitcoins.com\/de\/author\/manuel\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/41760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/users\/135839"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/comments?post=41760"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/41760\/revisions"}],"predecessor-version":[{"id":66488,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/41760\/revisions\/66488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media\/41763"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media?parent=41760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories?post=41760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/tags?post=41760"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/coin?post=41760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}