{"id":24599,"date":"2025-04-23T11:48:01","date_gmt":"2025-04-23T11:48:01","guid":{"rendered":"https:\/\/99bitcoins.com\/de\/?p=24599"},"modified":"2025-04-23T11:48:01","modified_gmt":"2025-04-23T11:48:01","slug":"bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/","title":{"rendered":"Bitcoin is in Good Hands &#8211; die letzte Nachricht von Satoshi Nakamoto?"},"content":{"rendered":"<p><span style=\"font-weight: 400\">&#8222;Bitcoin is in good hands&#8220; &#8211; am heutigen Tag im Jahre 2008 hinterlie\u00df Satoshi Nakamoto eine seiner letzten Nachrichten.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">    <div class=\"nnbtc-key-takeaways\">\r\n        <h2 class=\"nnbtc-key-takeaways__title\">Das Wichtigste im \u00dcberblick:<\/h2>\r\n            <ul class=\"nnbtc-key-takeaways__list\">\r\n        <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Satoshi Nakamoto verschwand 2011 und hinterlie\u00df seine letzte Nachricht an Mike Hearn, dass Bitcoin in guten H\u00e4nden sei.    <\/li>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Gavin Andresen \u00fcbernahm die Kontrolle \u00fcber das Bitcoin-Repository und die Alert Keys nach Nakamotos Weggang.    <\/li>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Nakamoto bat Andresen, Bitcoin als seri\u00f6ses Open-Source-Projekt zu pr\u00e4sentieren, nicht als \u201ePiratenw\u00e4hrung\u201c.    <\/li>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Andresen fiel in Ungnade, nachdem er 2016 Craig Wright als Satoshi Nakamoto unterst\u00fctzte.    <\/li>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <li class=\"nnbtc-key-takeaways__list-item\">\r\n        Ein Gerichtsurteil im Fall COPA vs. Wright best\u00e4tigte, dass Wright nicht Satoshi Nakamoto ist.    <\/li>\r\n    <\/span><\/p>\n<p><span style=\"font-weight: 400\">    <\/ul>\r\n        <\/div>\r\n    <\/span><\/p>\n<h2><span style=\"font-weight: 400\">Letzte Email von Satoshi Nakamoto an Mike Hearn: Bitcoin in Good Hands<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Ein \u201cpeer-to-peer electronic cash system\u201d, so lautete das Whitepaper von Satoshi Nakamoto. Es war digitales Cash, das nicht von den zentralen Banken kontrolliert werden konnte. Obwohl Satoshi Nakamoto offenbar schon Jahre und wom\u00f6glich Jahrzehnte in die Forschung investiert hatte, fiel der <\/span><a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/coin-launch\/\"><span style=\"font-weight: 400\">Coin Launch<\/span><\/a><span style=\"font-weight: 400\"> von Bitcoin in das Jahr 2009 \u2013 zuf\u00e4lligerweise mit der damaligen Finanzkrise zusammen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Doch der Entwickler Satoshi Nakamoto stieg bereits wenige Jahre nach der Ver\u00f6ffentlichung aus der Entwicklung von Bitcoin aus. Bereits 2011 entsendete er eine Nachricht, die sein Verschwinden ank\u00fcndigte. Damals tradete Bitcoin zwischen 2 bis 3 USD, damals war noch unvorstellbar, dass Bitcoin mal \u00fcber 100.000 USD steigen w\u00fcrde (siehe unsere <\/span><a href=\"https:\/\/99bitcoins.com\/de\/krypto-kaufen\/guenstige-kryptowaehrungen\/\"><span style=\"font-weight: 400\">Bitcoin Prognose<\/span><\/a><span style=\"font-weight: 400\">).<\/span><\/p>\n<h2><span style=\"font-weight: 400\">\u201cBitcoi<\/span><span style=\"font-weight: 400\">n is in good hands with Gavin\u201d &#8211; wer ist Gavin?<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Empf\u00e4nger der letzten Nachricht war der Bitcoin Core-Entwickler Mike Hearn, der sich mit Satoshi Nakamoto direkt \u00fcber die Entwicklung von Bitcoin und damit verbundenen Herausforderungen austauschte. Die letzte Nachricht lautete:<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u00a0&#8222;Ich habe mich anderen Dingen zugewandt. Bei Gavin und allen anderen ist es in guten H\u00e4nden.&#8220;\u00a0 (Original: \u201cI&#8217;ve moved on to other things. It&#8217;s in good hands with Gavin and everyone\u201d)<\/span><\/p>\n<p><span style=\"font-weight: 400\">Mit diesen Worten verschwand Satoshi Nakamoto von der Bildfl\u00e4che. Bei heutigen Zitaten wird oft weggelassen, dass Satoshi Nakamoto allen voran einen Gavin herausstellte. Wer war dieser Gavin?<\/span><\/p>\n<p><span style=\"font-weight: 400\">Es handelte sich bei dem Entwickler um Gavin Andresen. Dieser arbeitete seit 2010 an der Entwicklung von Bitcoin mit. Dabei erhielt er schrittweise mehr Vertrauen von Satoshi Nakamoto, da er guten Code und ein hohes Engagement zeigte. Nakamoto \u00fcbergab ihm daraufhin die Kontrolle \u00fcber das Bitcoin-Code-Repository auf SourceForge, was damals etwa das \u00c4quivalent von GitHub war.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Gavin Andresens Rolle nach Satoshi Nakamoto<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Gavin Andresen erhielt drei Tage nach Mike Hearn, jedoch die eigentlich letzte Nachricht von Satoshi Nakamoto, die er auch auf seinem <\/span><a href=\"http:\/\/gavinandresen.ninja\/eleven-years-ago-today\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">Blog ver\u00f6ffentlichte<\/span><\/a><span style=\"font-weight: 400\">. Darin \u00e4u\u00dferte er seinen Wunsch, dass Andresen ihn nicht als \u201emysteri\u00f6se Schattengestalt\u201c darstellen solle. Dies w\u00fcrde den Eindruck verst\u00e4rken, dass Bitcoin eine \u201cPiratenw\u00e4hrung\u201d (pirate currency) w\u00e4re.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Stattdessen solle er den Fokus auf das Open-Source-Projekt und die Entwickler-Community legen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Auch in dieser Email wiederholte Satoshi Nakamoto noch einmal, dass er mit anderen Projekten besch\u00e4ftigt ist und nicht mehr verf\u00fcgbar sein wird. Er \u00fcbergab Andresen auch die Kontrolle \u00fcber die Alert Keys. Diese dienten als Informationssystem an Nodes, um beispielsweise \u00fcber wichtige Updates zu informieren und wurden 2016 aus dem Bitcoin-Protokoll entfernt.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Andresen antwortete auf diese Email noch und erw\u00e4hnte, dass er von einer CIA-Organisation eingeladen worden ist, um Bitcoin vorzustellen. Danach meldete Nakamoto sich nicht mehr.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Gavin Andresen f\u00e4llt in der Bitcoin-Community in Ungnade<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Andresen sollte sp\u00e4ter in der Bitcoin-Community in Ungnade fallen. 2015 wurde Dr Craig S Wright von den Magazinen Wired und Gizmodo als Erfinder von Bitcoin gedoxxt. Viele Bitcoiner hielten dies f\u00fcr unm\u00f6glich und forderten Beweise von Craig Wright, wobei der Private Key zum Genesis Block oder zu bekannten Adressen von Satoshi Nakamotos <\/span><a href=\"https:\/\/99bitcoins.com\/de\/krypto-wallet\/\"><span style=\"font-weight: 400\">Krypto Wallet<\/span><\/a><span style=\"font-weight: 400\"> als Beweis gefordert wurde.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Wright lud schlie\u00dflich Andresen, Jon Matonis und noch einige andere dazu ein, privat als Satoshi Nakamoto Nachrichten mit einem privaten Schl\u00fcssel von Nakamoto zu zeichnen. Andresen <\/span><a href=\"http:\/\/gavinandresen.ninja\/satoshi\" rel=\"nofollow\" target=\"_blank\"><span style=\"font-weight: 400\">berichtete auf seinem Blog<\/span><\/a><span style=\"font-weight: 400\"> selbst von dieser Begegnung, die 2016 in London stattfand.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Bitcoin-Community entfernte Andresen aus der Bitcoin-Entwicklung, nachdem Andresen \u00f6ffentlich bekanntgegeben hatte, dass er \u00fcberzeugt sei, Bitcoin sei von Craig Wright entwickelt worden.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Inzwischen glaubt allerdings auch Andresen nicht mehr, dass Wright tats\u00e4chlich der Erfinder von Bitcoin ist, und ein Gericht hat beim Fall COPA vs. Wright offiziell geurteilt, dass es sich bei Wright um einen L\u00fcgner handelt.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Bitcoin is in good hands&#8220; &#8211; am heutigen Tag im Jahre 2008 hinterlie\u00df Satoshi Nakamoto eine seiner letzten Nachrichten. &nbsp; Letzte Email von Satoshi Nakamoto an Mike Hearn: Bitcoin in Good Hands Ein \u201cpeer-to-peer electronic cash system\u201d, so lautete das Whitepaper von Satoshi Nakamoto. Es war digitales Cash, das nicht von den zentralen Banken kontrolliert..<\/p>\n","protected":false},"author":136078,"featured_media":24600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[40,2],"tags":[86],"coin":[200],"class_list":["post-24599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin-btc","category-news","tag-bitcoin-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bitcoin is in Good Hands - die letzte Nachricht von Satoshi Nakamoto? - 99bitcoins DE<\/title>\n<meta name=\"description\" content=\"&quot;Bitcoin is in good hands&quot; - am heutigen Tag im Jahre 2008 hinterlie\u00df Satoshi Nakamoto eine seiner letzten Nachrichten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bitcoin is in Good Hands - die letzte Nachricht von Satoshi Nakamoto? - 99bitcoins DE\" \/>\n<meta property=\"og:description\" content=\"&quot;Bitcoin is in good hands&quot; - am heutigen Tag im Jahre 2008 hinterlie\u00df Satoshi Nakamoto eine seiner letzten Nachrichten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins DE\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-23T11:48:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/bitcoin-in-good-hands.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael Sprick\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zeeko76\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael Sprick\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/\"},\"author\":{\"name\":\"Michael Sprick\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/6090500b4949e15e2568fa054e5e43de\"},\"headline\":\"Bitcoin is in Good Hands &#8211; die letzte Nachricht von Satoshi Nakamoto?\",\"datePublished\":\"2025-04-23T11:48:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/\"},\"wordCount\":743,\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/04\\\/bitcoin-in-good-hands.jpg\",\"keywords\":[\"Bitcoin Nachrichten\"],\"articleSection\":[\"Bitcoin\",\"News\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/\",\"name\":\"Bitcoin is in Good Hands - die letzte Nachricht von Satoshi Nakamoto? - 99bitcoins DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/04\\\/bitcoin-in-good-hands.jpg\",\"datePublished\":\"2025-04-23T11:48:01+00:00\",\"description\":\"\\\"Bitcoin is in good hands\\\" - am heutigen Tag im Jahre 2008 hinterlie\u00df Satoshi Nakamoto eine seiner letzten Nachrichten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/04\\\/bitcoin-in-good-hands.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/04\\\/bitcoin-in-good-hands.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bitcoin is in Good Hands &#8211; die letzte Nachricht von Satoshi Nakamoto?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"name\":\"99bitcoins DE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"width\":327,\"height\":276,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/person\\\/6090500b4949e15e2568fa054e5e43de\",\"name\":\"Michael Sprick\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g\",\"caption\":\"Michael Sprick\"},\"description\":\"Michael Sprick ist ein freiberuflicher Journalist und Content Writer mit Schwerpunkt Blockchain und Web3 und wohnt in Barcelona. In der Vergangenheit hat er u.a. f\u00fcr btc-echo.de und f\u00fcr die BSV Blockchain Association gearbeitet.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/zeeko76\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/author\\\/michaelsprick\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bitcoin is in Good Hands - die letzte Nachricht von Satoshi Nakamoto? - 99bitcoins DE","description":"\"Bitcoin is in good hands\" - am heutigen Tag im Jahre 2008 hinterlie\u00df Satoshi Nakamoto eine seiner letzten Nachrichten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/","og_locale":"de_DE","og_type":"article","og_title":"Bitcoin is in Good Hands - die letzte Nachricht von Satoshi Nakamoto? - 99bitcoins DE","og_description":"\"Bitcoin is in good hands\" - am heutigen Tag im Jahre 2008 hinterlie\u00df Satoshi Nakamoto eine seiner letzten Nachrichten.","og_url":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/","og_site_name":"99bitcoins DE","article_published_time":"2025-04-23T11:48:01+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/bitcoin-in-good-hands.jpg","type":"image\/jpeg"}],"author":"Michael Sprick","twitter_card":"summary_large_image","twitter_creator":"@zeeko76","twitter_misc":{"Written by":"Michael Sprick","Est. reading time":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/"},"author":{"name":"Michael Sprick","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/6090500b4949e15e2568fa054e5e43de"},"headline":"Bitcoin is in Good Hands &#8211; die letzte Nachricht von Satoshi Nakamoto?","datePublished":"2025-04-23T11:48:01+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/"},"wordCount":743,"publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/bitcoin-in-good-hands.jpg","keywords":["Bitcoin Nachrichten"],"articleSection":["Bitcoin","News"],"inLanguage":"de","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/","url":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/","name":"Bitcoin is in Good Hands - die letzte Nachricht von Satoshi Nakamoto? - 99bitcoins DE","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/bitcoin-in-good-hands.jpg","datePublished":"2025-04-23T11:48:01+00:00","description":"\"Bitcoin is in good hands\" - am heutigen Tag im Jahre 2008 hinterlie\u00df Satoshi Nakamoto eine seiner letzten Nachrichten.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/#primaryimage","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/bitcoin-in-good-hands.jpg","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/bitcoin-in-good-hands.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/de\/news\/bitcoin-is-in-good-hands-die-letzte-nachricht-von-satoshi-nakamoto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/99bitcoins.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Bitcoin is in Good Hands &#8211; die letzte Nachricht von Satoshi Nakamoto?"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/de\/#website","url":"https:\/\/99bitcoins.com\/de\/","name":"99bitcoins DE","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/de\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","width":327,"height":276,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/person\/6090500b4949e15e2568fa054e5e43de","name":"Michael Sprick","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41c93e13a8d4e3f5296fa2280b4c4a1c6c5fd9fe06430288c9faaf5e3e3fb172?s=96&d=mm&r=g","caption":"Michael Sprick"},"description":"Michael Sprick ist ein freiberuflicher Journalist und Content Writer mit Schwerpunkt Blockchain und Web3 und wohnt in Barcelona. In der Vergangenheit hat er u.a. f\u00fcr btc-echo.de und f\u00fcr die BSV Blockchain Association gearbeitet.","sameAs":["https:\/\/x.com\/zeeko76"],"url":"https:\/\/99bitcoins.com\/de\/author\/michaelsprick\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/24599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/users\/136078"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/comments?post=24599"}],"version-history":[{"count":1,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/24599\/revisions"}],"predecessor-version":[{"id":24601,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts\/24599\/revisions\/24601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media\/24600"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/media?parent=24599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories?post=24599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/tags?post=24599"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/coin?post=24599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}