{"id":2,"count":575,"description":"","link":"https:\/\/99bitcoins.com\/de\/news\/","name":"News","slug":"news","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News Archiv - 99bitcoins DE<\/title>\n<meta name=\"description\" content=\"Die neuesten Krypto News im \u00dcberblick - Aktuelle Nachrichten zu Bitcoin und allen wichtigen Altcoins - Professionell aufgearbeitet und leicht verst\u00e4ndlich\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/de\/news\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News Archiv - 99bitcoins DE\" \/>\n<meta property=\"og:description\" content=\"Die neuesten Krypto News im \u00dcberblick - Aktuelle Nachrichten zu Bitcoin und allen wichtigen Altcoins - Professionell aufgearbeitet und leicht verst\u00e4ndlich\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/de\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"99bitcoins DE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/\",\"name\":\"News Archiv - 99bitcoins DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\"},\"description\":\"Die neuesten Krypto News im \u00dcberblick - Aktuelle Nachrichten zu Bitcoin und allen wichtigen Altcoins - Professionell aufgearbeitet und leicht verst\u00e4ndlich\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"name\":\"99bitcoins DE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#organization\",\"name\":\"99bitcoins\",\"alternateName\":\"99bitcoins\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/99Bitcoins-Logo.png\",\"width\":327,\"height\":276,\"caption\":\"99bitcoins\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News Archiv - 99bitcoins DE","description":"Die neuesten Krypto News im \u00dcberblick - Aktuelle Nachrichten zu Bitcoin und allen wichtigen Altcoins - Professionell aufgearbeitet und leicht verst\u00e4ndlich","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/de\/news\/","og_locale":"de_DE","og_type":"article","og_title":"News Archiv - 99bitcoins DE","og_description":"Die neuesten Krypto News im \u00dcberblick - Aktuelle Nachrichten zu Bitcoin und allen wichtigen Altcoins - Professionell aufgearbeitet und leicht verst\u00e4ndlich","og_url":"https:\/\/99bitcoins.com\/de\/news\/","og_site_name":"99bitcoins DE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/99bitcoins.com\/de\/news\/","url":"https:\/\/99bitcoins.com\/de\/news\/","name":"News Archiv - 99bitcoins DE","isPartOf":{"@id":"https:\/\/99bitcoins.com\/de\/#website"},"description":"Die neuesten Krypto News im \u00dcberblick - Aktuelle Nachrichten zu Bitcoin und allen wichtigen Altcoins - Professionell aufgearbeitet und leicht verst\u00e4ndlich","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/de\/news\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/de\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/de\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/de\/#website","url":"https:\/\/99bitcoins.com\/de\/","name":"99bitcoins DE","description":"","publisher":{"@id":"https:\/\/99bitcoins.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/99bitcoins.com\/de\/#organization","name":"99bitcoins","alternateName":"99bitcoins","url":"https:\/\/99bitcoins.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","contentUrl":"https:\/\/99bitcoins.com\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/99Bitcoins-Logo.png","width":327,"height":276,"caption":"99bitcoins"},"image":{"@id":"https:\/\/99bitcoins.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/99bitcoins.com\/de\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}