{"id":685,"date":"2025-02-12T11:50:17","date_gmt":"2025-02-12T11:50:17","guid":{"rendered":"https:\/\/99bitcoins.com\/br\/?p=685"},"modified":"2025-03-21T10:10:09","modified_gmt":"2025-03-21T10:10:09","slug":"grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/","title":{"rendered":"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano"},"content":{"rendered":"<p>A Grayscale Investments, uma das maiores gestoras de ativos digitais do mundo, apresentou um pedido \u00e0 Comiss\u00e3o de Valores Mobili\u00e1rios dos Estados Unidos (SEC) para lan\u00e7ar o primeiro fundo negociado em bolsa (ETF) de Cardano (ADA).<\/p>\n<p>Caso aprovado, o ETF permitir\u00e1 que investidores tenham exposi\u00e7\u00e3o ao ADA sem precisar adquirir diretamente o ativo digital.<\/p>\n<p>O movimento destaca o crescente interesse institucional por ativos de criptomoedas e pode representar um marco significativo para a ado\u00e7\u00e3o da Cardano no mercado financeiro tradicional.<\/p>\n<h2>Proposta da Grayscale para o ETF de Cardano<\/h2>\n<p>A Grayscale apresentou o pedido em colabora\u00e7\u00e3o com a NYSE Arca, que busca listar o ETF na Bolsa de Valores de Nova York.<\/p>\n<p>Assim, o fundo permitiria que investidores institucionais e de varejo negociassem Cardano de maneira regulamentada, com a seguran\u00e7a dos mercados tradicionais.<\/p>\n<p>Caso a SEC aprove a proposta, esse ser\u00e1 o primeiro produto financeiro da Grayscale focado exclusivamente em ADA. Al\u00e9m disso, a Coinbase Custody Trust Company foi designada para custodiar os ativos do fundo, enquanto a BNY Mellon Asset Servicing atuar\u00e1 como administradora.<\/p>\n<p>A aprova\u00e7\u00e3o desse fundo abriria novas portas para Cardano. Aumentando sua liquidez e potencialmente impactando positivamente seu valor de mercado, por exemplo.<\/p>\n<h3>Vis\u00e3o de Charles Hoskinson para a Cardano em 2025<\/h3>\n<p>A Cardano foi criada com o objetivo de oferecer uma blockchain mais escal\u00e1vel e sustent\u00e1vel. Seu fundador, Charles Hoskinson, tamb\u00e9m cofundador do Ethereum, decidiu seguir um caminho independente para construir uma plataforma que resolvesse problemas de escalabilidade e governan\u00e7a.<\/p>\n<p>Hoskinson tem se posicionado ativamente sobre o papel das criptomoedas no setor financeiro. Ele critica a falta de clareza regulat\u00f3ria nos Estados Unidos e defende que os criptoativos sejam reconhecidos como uma classe leg\u00edtima de investimentos.<\/p>\n<p>Recentemente, Hoskinson afirmou que <a href=\"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/bitcoin-bull-novo-token-distribui-recompensas-com-a-alta-do-btc\/\">a Cardano pode se tornar a casa do Bitcoin<\/a>, gra\u00e7as \u00e0 nova ponte lan\u00e7ada na rede.<\/p>\n<p>Essa integra\u00e7\u00e3o permite que transa\u00e7\u00f5es de <a href=\"https:\/\/99bitcoins.com\/br\/criptomoedas\/bitcoin\/minerar\/\">Bitcoin<\/a> ocorram na blockchain da Cardano, reduzindo taxas e aumentando a escalabilidade da principal criptomoeda do mercado. Com essa funcionalidade, a Cardano poderia operar como uma camada 2 (L2) do Bitcoin, o que ampliaria significativamente sua utilidade e aceita\u00e7\u00e3o no setor de criptomoedas.<\/p>\n<h3>ETFs da Grayscale: entre aprova\u00e7\u00f5es e rejei\u00e7\u00f5es<\/h3>\n<p>A Grayscale tem sido protagonista na busca por aprova\u00e7\u00e3o de ETFs cripto nos Estados Unidos. Seu maior sucesso foi a convers\u00e3o do Grayscale Bitcoin Trust (GBTC) em um ETF de Bitcoin \u00e0 vista, ap\u00f3s anos de disputa com a SEC.<\/p>\n<p>Essa conquista abriu caminho para produtos semelhantes e impulsionou o interesse institucional em criptomoedas.<\/p>\n<p>Al\u00e9m do Bitcoin, a Grayscale solicitou ETFs para Ethereum, Solana e XRP. No entanto, enquanto o ETF de Ethereum ainda est\u00e1 sob an\u00e1lise, os pedidos para Solana e XRP enfrentam obst\u00e1culos regulat\u00f3rios.<\/p>\n<p>A SEC adota uma postura rigorosa quanto a ativos digitais al\u00e9m do Bitcoin. Contudo, a mudan\u00e7a de governo nos EUA denota um aumento nas expectativas de altera\u00e7\u00e3o de entedimento da SEC.<\/p>\n<p>Com o pedido para o ETF de Cardano, a Grayscale busca expandir sua oferta de produtos e fortalecer a posi\u00e7\u00e3o da ADA no mercado financeiro. A resposta da SEC pode influenciar futuras iniciativas da empresa e determinar o ritmo de ado\u00e7\u00e3o institucional para outras altcoins.<\/p>\n<h3>O impacto potencial do ETF de Cardano no mercado<\/h3>\n<p>Caso seja aprovado, o ETF de Cardano poder\u00e1 atrair uma nova onda de investidores. Produtos financeiros regulamentados aumentam a acessibilidade e a liquidez dos ativos subjacentes, por exemplo. Assim, a introdu\u00e7\u00e3o de um ETF pode facilitar o investimento de grandes fundos e institui\u00e7\u00f5es que, at\u00e9 agora, tinham dificuldades em acessar o mercado cripto de maneira segura.<\/p>\n<p>Al\u00e9m disso, a criptomoeda apresentou uma valoriza\u00e7\u00e3o total de 14% nos \u00faltimos dias, superando o desempenho de outras altcoins. O volume de negocia\u00e7\u00e3o da ADA tamb\u00e9m aumentou significativamente, indicando um crescimento no interesse de investidores institucionais e de varejo.<\/p>\n<p>Historicamente, a simples entrada de um ativo na lista de ETFs em an\u00e1lise tem sido um catalisador para aumentos de pre\u00e7o, e o caso da Cardano n\u00e3o foi diferente.<\/p>\n<p>A inje\u00e7\u00e3o de liquidez, aliada ao aumento da aten\u00e7\u00e3o do mercado, fortalece o potencial da ADA de sustentar essa valoriza\u00e7\u00e3o, principalmente se o ETF for aprovado. No entanto, especialistas alertam que a volatilidade do mercado pode gerar corre\u00e7\u00f5es no curto prazo. Tornando, portanto, essencial a observa\u00e7\u00e3o dos pr\u00f3ximos passos da SEC.<\/p>\n<p>A poss\u00edvel entrada da Cardano no mercado de ETFs refor\u00e7a a legitimidade dos criptoativos como uma classe de investimento consolidada. Caso aprovado, o ETF pode atrair grandes fundos de investimento e impulsionar o reconhecimento da ADA no setor financeiro global.<\/p>\n<h3>Rela\u00e7\u00e3o da SEC com ETFs de criptomoedas<\/h3>\n<p>A SEC tem adotado uma postura cautelosa quanto \u00e0 aprova\u00e7\u00e3o de ETFs de criptomoedas. A aprova\u00e7\u00e3o do ETF de Bitcoin foi uma vit\u00f3ria importante, mas a ag\u00eancia ainda reluta em liberar produtos baseados em altcoins.<\/p>\n<p>O principal argumento \u00e9 que muitos desses ativos podem ser classificados como valores mobili\u00e1rios, exigindo uma regulamenta\u00e7\u00e3o diferenciada.<\/p>\n<p>Contudo, a decis\u00e3o sobre o ETF de Cardano ser\u00e1 um teste crucial para a abordagem da SEC em rela\u00e7\u00e3o a outras criptomoedas. Se aprovado, <a href=\"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/b3-lanca-opcoes-de-bitcoin-e-futuros-de-ethereum-e-solana\/\">pode abrir caminho para ETFs de outras altcoins<\/a>. Se rejeitado, refor\u00e7ar\u00e1 a resist\u00eancia da ag\u00eancia a esses produtos.<\/p>\n<h2>Futuro da Cardano no mercado institucional<\/h2>\n<p>A Cardano continua atraindo aten\u00e7\u00e3o pelo seu desenvolvimento constante e sua abordagem acad\u00eamica para inova\u00e7\u00e3o em blockchain. Assim, com uma comunidade ativa e uma base tecnol\u00f3gica s\u00f3lida, a criptomoeda se posiciona como uma alternativa vi\u00e1vel a projetos como Ethereum.<\/p>\n<p>Se a Grayscale obtiver sucesso com a aprova\u00e7\u00e3o do ETF, a Cardano poder\u00e1 se consolidar ainda mais como um dos principais ativos digitais para investimentos institucionais. Isso aumentaria, ali\u00e1s, sua aceita\u00e7\u00e3o e poderia impulsionar parcerias estrat\u00e9gicas com grandes players do setor financeiro.<\/p>\n<p>A tentativa da Grayscale de lan\u00e7ar o primeiro ETF de Cardano representa um avan\u00e7o significativo para a criptomoeda e o setor cripto em geral. A Cardano tem se consolidado como uma blockchain inovadora, e sua inclus\u00e3o no mercado de ETFs pode acelerar sua ado\u00e7\u00e3o global.<\/p>\n<p>Enquanto a SEC avalia a proposta, a expectativa dos investidores cresce, tornando essa uma das movimenta\u00e7\u00f5es mais importantes para o futuro do ADA. Independentemente do resultado, o interesse institucional pela Cardano continua aumentando, sinalizando que a criptomoeda pode ter um papel fundamental no mercado financeiro nos pr\u00f3ximos anos.<\/p>\n<div id=\"acfifjfajpekbmhmjppnmmjgmhjkildl\" class=\"acfifjfajpekbmhmjppnmmjgmhjkildl\"><\/div>\n<div id=\"acfifjfajpekbmhmjppnmmjgmhjkildl\" class=\"acfifjfajpekbmhmjppnmmjgmhjkildl\"><\/div>\n<div id=\"acfifjfajpekbmhmjppnmmjgmhjkildl\" class=\"acfifjfajpekbmhmjppnmmjgmhjkildl\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Grayscale Investments, uma das maiores gestoras de ativos digitais do mundo, apresentou um pedido \u00e0 Comiss\u00e3o de Valores Mobili\u00e1rios dos Estados Unidos (SEC) para lan\u00e7ar o primeiro fundo negociado em bolsa (ETF) de Cardano (ADA). Caso aprovado, o ETF permitir\u00e1 que investidores tenham exposi\u00e7\u00e3o ao ADA sem precisar adquirir diretamente o ativo digital. O..<\/p>\n","protected":false},"author":136047,"featured_media":701,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[6],"tags":[81,79,74],"coin":[2,53,76,77,82],"class_list":["post-685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoin","tag-cardano","tag-etfs","tag-altcoin-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano - 99Bitcoins Brasil<\/title>\n<meta name=\"description\" content=\"Grayscale solicita \u00e0 SEC a aprova\u00e7\u00e3o do primeiro ETF de Cardano \u00e0 vista, impulsionando o interesse institucional e o mercado da criptomoeda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano - 99Bitcoins Brasil\" \/>\n<meta property=\"og:description\" content=\"Grayscale solicita \u00e0 SEC a aprova\u00e7\u00e3o do primeiro ETF de Cardano \u00e0 vista, impulsionando o interesse institucional e o mercado da criptomoeda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-12T11:50:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T10:10:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/Grayscale-solicita-ETF-de-Cardano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela de Lacerda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Grayscale solicita \u00e0 SEC a aprova\u00e7\u00e3o do primeiro ETF de Cardano \u00e0 vista, impulsionando o interesse institucional e o mercado da criptomoeda.\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela de Lacerda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/\"},\"author\":{\"name\":\"Daniela de Lacerda\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/83df205cf2cb5c732d5bde671d21ab84\"},\"headline\":\"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano\",\"datePublished\":\"2025-02-12T11:50:17+00:00\",\"dateModified\":\"2025-03-21T10:10:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/\"},\"wordCount\":1106,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/Grayscale-solicita-ETF-de-Cardano.jpg\",\"keywords\":[\"Cardano\",\"ETFs\",\"Not\u00edcias de Altcoin\"],\"articleSection\":[\"Not\u00edcias de Altcoin\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/\",\"name\":\"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano - 99Bitcoins Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/Grayscale-solicita-ETF-de-Cardano.jpg\",\"datePublished\":\"2025-02-12T11:50:17+00:00\",\"dateModified\":\"2025-03-21T10:10:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/83df205cf2cb5c732d5bde671d21ab84\"},\"description\":\"Grayscale solicita \u00e0 SEC a aprova\u00e7\u00e3o do primeiro ETF de Cardano \u00e0 vista, impulsionando o interesse institucional e o mercado da criptomoeda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/Grayscale-solicita-ETF-de-Cardano.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/Grayscale-solicita-ETF-de-Cardano.jpg\",\"width\":1200,\"height\":685,\"caption\":\"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Not\u00edcias de Altcoin\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"name\":\"99Bitcoins Brasil\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/83df205cf2cb5c732d5bde671d21ab84\",\"name\":\"Daniela de Lacerda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g\",\"caption\":\"Daniela de Lacerda\"},\"description\":\"Daniela de Lacerda \u00e9 jornalista e pesquisadora, mestra em comunica\u00e7\u00e3o. H\u00e1 quatro anos atua como curadora de inova\u00e7\u00e3o em m\u00eddia, tecnologia e economia, incluindo o setor de criptomoedas. Como editora e rep\u00f3rter, trabalhou em grandes ve\u00edculos de comunica\u00e7\u00e3o do Brasil, nacionais e regionais, como a Editora Abril. Morou no Recife, em S\u00e3o Paulo e em Lisboa, onde estudou m\u00eddias digitais na Universidade Nova de Lisboa.\",\"sameAs\":[\"http:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/daniela-de-lacerda\\\/\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/author\\\/danielalacerda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano - 99Bitcoins Brasil","description":"Grayscale solicita \u00e0 SEC a aprova\u00e7\u00e3o do primeiro ETF de Cardano \u00e0 vista, impulsionando o interesse institucional e o mercado da criptomoeda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/","og_locale":"pt_BR","og_type":"article","og_title":"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano - 99Bitcoins Brasil","og_description":"Grayscale solicita \u00e0 SEC a aprova\u00e7\u00e3o do primeiro ETF de Cardano \u00e0 vista, impulsionando o interesse institucional e o mercado da criptomoeda.","og_url":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/","og_site_name":"99Bitcoins Brasil","article_published_time":"2025-02-12T11:50:17+00:00","article_modified_time":"2025-03-21T10:10:09+00:00","og_image":[{"width":1200,"height":685,"url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/Grayscale-solicita-ETF-de-Cardano.jpg","type":"image\/jpeg"}],"author":"Daniela de Lacerda","twitter_card":"summary_large_image","twitter_description":"Grayscale solicita \u00e0 SEC a aprova\u00e7\u00e3o do primeiro ETF de Cardano \u00e0 vista, impulsionando o interesse institucional e o mercado da criptomoeda.","twitter_misc":{"Written by":"Daniela de Lacerda","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/"},"author":{"name":"Daniela de Lacerda","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/83df205cf2cb5c732d5bde671d21ab84"},"headline":"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano","datePublished":"2025-02-12T11:50:17+00:00","dateModified":"2025-03-21T10:10:09+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/"},"wordCount":1106,"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/Grayscale-solicita-ETF-de-Cardano.jpg","keywords":["Cardano","ETFs","Not\u00edcias de Altcoin"],"articleSection":["Not\u00edcias de Altcoin"],"inLanguage":"pt-BR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/","url":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/","name":"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano - 99Bitcoins Brasil","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/Grayscale-solicita-ETF-de-Cardano.jpg","datePublished":"2025-02-12T11:50:17+00:00","dateModified":"2025-03-21T10:10:09+00:00","author":{"@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/83df205cf2cb5c732d5bde671d21ab84"},"description":"Grayscale solicita \u00e0 SEC a aprova\u00e7\u00e3o do primeiro ETF de Cardano \u00e0 vista, impulsionando o interesse institucional e o mercado da criptomoeda.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/#primaryimage","url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/Grayscale-solicita-ETF-de-Cardano.jpg","contentUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/Grayscale-solicita-ETF-de-Cardano.jpg","width":1200,"height":685,"caption":"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/grayscale-pressiona-sec-para-aprovar-o-primeiro-etf-de-cardano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/99bitcoins.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Not\u00edcias de Altcoin","item":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/"},{"@type":"ListItem","position":4,"name":"Grayscale pressiona SEC para aprovar o primeiro ETF de Cardano"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/br\/#website","url":"https:\/\/99bitcoins.com\/br\/","name":"99Bitcoins Brasil","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/83df205cf2cb5c732d5bde671d21ab84","name":"Daniela de Lacerda","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g","caption":"Daniela de Lacerda"},"description":"Daniela de Lacerda \u00e9 jornalista e pesquisadora, mestra em comunica\u00e7\u00e3o. H\u00e1 quatro anos atua como curadora de inova\u00e7\u00e3o em m\u00eddia, tecnologia e economia, incluindo o setor de criptomoedas. Como editora e rep\u00f3rter, trabalhou em grandes ve\u00edculos de comunica\u00e7\u00e3o do Brasil, nacionais e regionais, como a Editora Abril. Morou no Recife, em S\u00e3o Paulo e em Lisboa, onde estudou m\u00eddias digitais na Universidade Nova de Lisboa.","sameAs":["http:\/\/99bitcoins.com\/br\/","https:\/\/www.linkedin.com\/in\/daniela-de-lacerda\/"],"url":"https:\/\/99bitcoins.com\/br\/author\/danielalacerda\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/users\/136047"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/comments?post=685"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/685\/revisions"}],"predecessor-version":[{"id":39202,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/685\/revisions\/39202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media\/701"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media?parent=685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/categories?post=685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/tags?post=685"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/coin?post=685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}