{"id":39978,"date":"2026-04-15T17:28:56","date_gmt":"2026-04-15T17:28:56","guid":{"rendered":"https:\/\/99bitcoins.com\/br\/?p=39978"},"modified":"2026-04-15T17:28:56","modified_gmt":"2026-04-15T17:28:56","slug":"bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/","title":{"rendered":"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel?"},"content":{"rendered":"<p>O CIO da Bitwise, Matt Hougan, argumenta que o mercado endere\u00e7\u00e1vel do Bitcoin poderia eventualmente superar o do ouro, atualmente em torno de 20 trilh\u00f5es de USD, caso a fragmenta\u00e7\u00e3o geopol\u00edtica continue se acelerando.<\/p>\n<p>A afirma\u00e7\u00e3o n\u00e3o \u00e9 abstrata: o memorando de Hougan de abril de 2026 enquadra o Bitcoin n\u00e3o apenas como uma reserva de valor competindo com o ouro, mas como um ativo de liquida\u00e7\u00e3o politicamente neutro para um mundo onde o sistema financeiro dominado pelo d\u00f3lar est\u00e1 se fragmentando pelas costuras.<\/p>\n<p>Isso \u00e9 relevante agora porque o Bitcoin subiu 12% entre 27 de fevereiro e 10 de abril de 2026, enquanto o S&amp;P 500 caiu 1% e o ouro recuou 10% durante o mesmo intervalo de tens\u00f5es elevadas entre Ir\u00e3 e EUA. Essa n\u00e3o \u00e9 uma coincid\u00eancia que a <a class=\"general-link\" href=\"https:\/\/bitwiseinvestments.com\/\" target=\"_blank\" rel=\"noopener nofollow\">Bitwise<\/a> esteja disposta a ignorar. A quest\u00e3o \u00e9 se trata-se de um sinal duradouro ou de uma anomalia isolada travestida de tese.<\/p>\n<figure id=\"attachment_343739\" class=\"wp-caption aligncenter\" style=\"width: 726px\" aria-describedby=\"caption-attachment-343739\"><img decoding=\"async\" class=\"size-full wp-image-343739\" src=\"https:\/\/99bitcoins.com\/wp-content\/uploads\/2026\/04\/matt.webp\" alt=\"\" width=\"726\" height=\"795\" \/><figcaption id=\"caption-attachment-343739\" class=\"wp-caption-text\">Fonte: <a class=\"general-link\" href=\"https:\/\/x.com\/Matt_Hougan\/status\/2044095946334843168\" target=\"_blank\" rel=\"noopener nofollow\">Matt Hougan<\/a> no X<\/figcaption><\/figure>\n<h2>O que significa realmente &#8216;Bitcoin superar o ouro&#8217;?<\/h2>\n<p>A compara\u00e7\u00e3o com o &#8216;ouro digital&#8217; \u00e9 usada com tanta frequ\u00eancia que perdeu a maior parte do seu sentido. Eis o que ela realmente implica: o ouro \u00e9 valioso principalmente porque nenhum governo individual o controla, \u00e9 escasso e possui um hist\u00f3rico de 5.000 anos como reserva de valor. O Bitcoin apresenta a mesma proposta \u2014 oferta fixa de 21 milh\u00f5es de moedas, sem emissor central \u2014 mas adiciona dois elementos que o ouro n\u00e3o pode oferecer: atravessa fronteiras instantaneamente e \u00e9 liquidado sem a necessidade de um banco.<\/p>\n<p>A tese de Hougan vai um n\u00edvel al\u00e9m. Ele define a avalia\u00e7\u00e3o do Bitcoin como duas apostas empilhadas. A primeira \u00e9 a aposta padr\u00e3o no ouro digital: o Bitcoin captura uma fra\u00e7\u00e3o do mercado de 20 trilh\u00f5es de USD do ouro \u00e0 medida que as institui\u00e7\u00f5es diversificam.<\/p>\n<p>A segunda \u00e9 o que ele chama de uma op\u00e7\u00e3o de compra (call option) &#8216;fora do dinheiro&#8217; \u2014 a possibilidade especulativa de o Bitcoin se tornar uma camada de liquida\u00e7\u00e3o neutra para pa\u00edses que foram exclu\u00eddos do sistema Swift ou que o est\u00e3o evitando deliberadamente.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">JUST IN: \ud83c\uddee\ud83c\uddf7 Iran to require ships passing through the Strait of Hormuz to pay tolls in Bitcoin, FT reports. <a href=\"https:\/\/t.co\/6yoIEys139\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/6yoIEys139<\/a><\/p>\n<p>&mdash; Watcher.Guru (@WatcherGuru) <a href=\"https:\/\/twitter.com\/WatcherGuru\/status\/2041867478033195336?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 8, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Essa segunda aposta \u00e9 onde entra o \u00e2ngulo do Ir\u00e3. Surgiram relatos de uma proposta, destacada pelo Financial Times, na qual um porta-voz das exporta\u00e7\u00f5es de petr\u00f3leo iranianas sugeriu uma taxa de 1 USD por barril em Bitcoin para navios que transitam pelo Estreito de Ormuz.<\/p>\n<p>Se isso algum dia se concretizar\u00e1 n\u00e3o \u00e9 o ponto principal. O fato de que tal proposta est\u00e1 sendo feita indica a dire\u00e7\u00e3o para onde a press\u00e3o est\u00e1 apontando. Voc\u00ea pode acompanhar o contexto geopol\u00edtico mais amplo sobre as <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/news\/bitcoin-btc\/us-iran-talks-sanctions-bitcoin-global-liquidity\/\" target=\"_blank\" rel=\"noopener\">tens\u00f5es entre EUA e Ir\u00e3 e a resposta do Bitcoin \u00e0s san\u00e7\u00f5es<\/a> para entender melhor por que essa din\u00e2mica est\u00e1 ganhando for\u00e7a.<\/p>\n<h2>Por que a tese do Bitcoin impulsionado por conflitos possui evid\u00eancias reais<\/h2>\n<p>A guerra entre R\u00fassia e Ucr\u00e2nia em 2022 forneceu ao mundo um estudo de caso n\u00e3o planejado do que acontece quando uma grande economia \u00e9 cortada do sistema do d\u00f3lar. A liquida\u00e7\u00e3o comercial russa em yuan passou de menos de 2% antes da invas\u00e3o para quase 40% no in\u00edcio de 2024. O com\u00e9rcio bilateral entre R\u00fassia e China agora \u00e9 liquidado em mais de 99% em rublos e yuan. A desdolariza\u00e7\u00e3o n\u00e3o \u00e9 mais uma teoria marginal \u2014 s\u00e3o dados comerciais documentados.<\/p>\n<p>O comportamento do Bitcoin durante a atual janela de tens\u00e3o entre Ir\u00e3 e EUA corrobora essa vis\u00e3o. Enquanto o mercado amplo operava em queda, o Bitcoin ultrapassou brevemente os 75.000 USD e manteve sua posi\u00e7\u00e3o de uma forma que o ouro \u2014 tradicionalmente a prote\u00e7\u00e3o preferencial em conflitos \u2014 n\u00e3o conseguiu. Essa \u00e9 uma diverg\u00eancia significativa. O ouro caiu 10% na mesma janela. Se o Bitcoin deveria ser a reserva de valor inferior, ele n\u00e3o agiu como tal.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">In a world where countries have weaponized their financial rails, bitcoin is emerging as an apolitical alternative. <a href=\"https:\/\/t.co\/9ECmJy3aAK\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/9ECmJy3aAK<\/a><\/p>\n<p>&mdash; carlisle (@0xcarlisle) <a href=\"https:\/\/twitter.com\/0xcarlisle\/status\/2044102339720818925?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 14, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>O capital institucional est\u00e1 atento. Os fluxos de entrada em ETFs de Bitcoin \u00e0 vista continuaram durante per\u00edodos de estresse geopol\u00edtico, sugerindo que os grandes alocadores est\u00e3o, no m\u00ednimo, tratando o Bitcoin como uma prote\u00e7\u00e3o que vale a pena manter ao lado, e n\u00e3o em vez de, ativos de ref\u00fagio tradicionais. A conclus\u00e3o de Hougan \u2014 de que, se o Bitcoin funcionar tanto como reserva de valor quanto como ativo de liquida\u00e7\u00e3o, um pre\u00e7o-alvo de 1 milh\u00e3o de USD se torna uma base plaus\u00edvel em vez de um ponto fora da curva \u2014 parece extrema at\u00e9 que se fa\u00e7a as contas contra a capitaliza\u00e7\u00e3o de mercado total do ouro.<\/p>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div><b>Siga o 99Bitcoins no <\/b><b><a href=\"https:\/\/x.com\/99BitcoinsHQ\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">X<\/a><\/b><b> para as \u00faltimas atualiza\u00e7\u00f5es do mercado e inscreva-se no <\/b><b><a href=\"https:\/\/www.youtube.com\/@99bitcoins\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">YouTube<\/a><\/b><b> para an\u00e1lise di\u00e1ria de especialistas.<\/b><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bitwise: Conflito global pode levar o Bitcoin a superar o ouro<\/p>\n","protected":false},"author":136254,"featured_media":39977,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[5],"tags":[51],"coin":[2],"class_list":["post-39978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel? - 99Bitcoins Brasil<\/title>\n<meta name=\"description\" content=\"O CIO da Bitwise, Matt Hougan, argumenta que o mercado endere\u00e7\u00e1vel do Bitcoin poderia eventualmente superar o do ouro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel? - 99Bitcoins Brasil\" \/>\n<meta property=\"og:description\" content=\"O CIO da Bitwise, Matt Hougan, argumenta que o mercado endere\u00e7\u00e1vel do Bitcoin poderia eventualmente superar o do ouro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T17:28:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/bitcoin-gold-geopolitical-settlement.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1792\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipe editorial do 99Bitcoins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe editorial do 99Bitcoins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/\"},\"author\":{\"name\":\"Equipe editorial do 99Bitcoins\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/7ed63544911dda5f5ee710350491aa93\"},\"headline\":\"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel?\",\"datePublished\":\"2026-04-15T17:28:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/\"},\"wordCount\":825,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/04\\\/bitcoin-gold-geopolitical-settlement.webp\",\"keywords\":[\"Bitcoin\"],\"articleSection\":[\"Not\u00edcias de Bitcoin\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/\",\"name\":\"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel? - 99Bitcoins Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/04\\\/bitcoin-gold-geopolitical-settlement.webp\",\"datePublished\":\"2026-04-15T17:28:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/7ed63544911dda5f5ee710350491aa93\"},\"description\":\"O CIO da Bitwise, Matt Hougan, argumenta que o mercado endere\u00e7\u00e1vel do Bitcoin poderia eventualmente superar o do ouro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/04\\\/bitcoin-gold-geopolitical-settlement.webp\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/04\\\/bitcoin-gold-geopolitical-settlement.webp\",\"width\":1792,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Not\u00edcias de Bitcoin\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/bitcoin\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"name\":\"99Bitcoins Brasil\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/7ed63544911dda5f5ee710350491aa93\",\"name\":\"Equipe editorial do 99Bitcoins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g\",\"caption\":\"Equipe editorial do 99Bitcoins\"},\"description\":\"Desde 2013, a equipe editorial do 99Bitcoins oferece conte\u00fado especializado, confi\u00e1vel e de f\u00e1cil compreens\u00e3o sobre criptomoedas. Nosso time de analistas e pesquisadores experientes simplifica temas complexos tanto para iniciantes quanto para entusiastas do mercado cripto.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/author\\\/equipeeditorialdo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel? - 99Bitcoins Brasil","description":"O CIO da Bitwise, Matt Hougan, argumenta que o mercado endere\u00e7\u00e1vel do Bitcoin poderia eventualmente superar o do ouro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/","og_locale":"pt_BR","og_type":"article","og_title":"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel? - 99Bitcoins Brasil","og_description":"O CIO da Bitwise, Matt Hougan, argumenta que o mercado endere\u00e7\u00e1vel do Bitcoin poderia eventualmente superar o do ouro","og_url":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/","og_site_name":"99Bitcoins Brasil","article_published_time":"2026-04-15T17:28:56+00:00","og_image":[{"width":1792,"height":1024,"url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/bitcoin-gold-geopolitical-settlement.webp","type":"image\/webp"}],"author":"Equipe editorial do 99Bitcoins","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Equipe editorial do 99Bitcoins","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/"},"author":{"name":"Equipe editorial do 99Bitcoins","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/7ed63544911dda5f5ee710350491aa93"},"headline":"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel?","datePublished":"2026-04-15T17:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/"},"wordCount":825,"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/bitcoin-gold-geopolitical-settlement.webp","keywords":["Bitcoin"],"articleSection":["Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/","url":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/","name":"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel? - 99Bitcoins Brasil","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/bitcoin-gold-geopolitical-settlement.webp","datePublished":"2026-04-15T17:28:56+00:00","author":{"@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/7ed63544911dda5f5ee710350491aa93"},"description":"O CIO da Bitwise, Matt Hougan, argumenta que o mercado endere\u00e7\u00e1vel do Bitcoin poderia eventualmente superar o do ouro","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/#primaryimage","url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/bitcoin-gold-geopolitical-settlement.webp","contentUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/bitcoin-gold-geopolitical-settlement.webp","width":1792,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/bitwise-afirma-que-conflito-global-pode-expandir-o-mercado-do-bitcoin-para-alem-do-ouro-isso-e-plausivel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/99bitcoins.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Not\u00edcias de Bitcoin","item":"https:\/\/99bitcoins.com\/br\/noticias\/bitcoin\/"},{"@type":"ListItem","position":4,"name":"Bitwise afirma que conflito global pode expandir o mercado do Bitcoin para al\u00e9m do ouro: isso \u00e9 plaus\u00edvel?"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/br\/#website","url":"https:\/\/99bitcoins.com\/br\/","name":"99Bitcoins Brasil","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/7ed63544911dda5f5ee710350491aa93","name":"Equipe editorial do 99Bitcoins","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g","caption":"Equipe editorial do 99Bitcoins"},"description":"Desde 2013, a equipe editorial do 99Bitcoins oferece conte\u00fado especializado, confi\u00e1vel e de f\u00e1cil compreens\u00e3o sobre criptomoedas. Nosso time de analistas e pesquisadores experientes simplifica temas complexos tanto para iniciantes quanto para entusiastas do mercado cripto.","url":"https:\/\/99bitcoins.com\/br\/author\/equipeeditorialdo\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/39978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/users\/136254"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/comments?post=39978"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/39978\/revisions"}],"predecessor-version":[{"id":39990,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/39978\/revisions\/39990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media\/39977"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media?parent=39978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/categories?post=39978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/tags?post=39978"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/coin?post=39978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}