{"id":39971,"date":"2026-04-15T13:00:10","date_gmt":"2026-04-15T13:00:10","guid":{"rendered":"https:\/\/99bitcoins.com\/br\/?p=39971"},"modified":"2026-04-15T12:54:24","modified_gmt":"2026-04-15T12:54:24","slug":"proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/","title":{"rendered":"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp"},"content":{"rendered":"<p>O Bitcoin apresenta um bom desempenho esta semana, registrando uma alta de 4%, mas a comunidade tem um novo motivo para prestar aten\u00e7\u00e3o al\u00e9m dos gr\u00e1ficos de pre\u00e7os. O cypherpunk e CTO da Casa, Jameson Lopp, prop\u00f4s algo que soa quase cinematogr\u00e1fico: congelar o Bitcoin que se acredita estar na carteira original de <a class=\"general-link\" href=\"https:\/\/en.wikipedia.org\/wiki\/Satoshi_Nakamoto\" target=\"_blank\" rel=\"noopener nofollow\">Satoshi Nakamoto<\/a> antes que computadores qu\u00e2nticos possam viol\u00e1-la. As implica\u00e7\u00f5es completas ainda est\u00e3o sendo debatidas e, obviamente, nem todos concordam.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udca5BREAKING:<\/p>\n<p>Bitcoin developers propose freezing early wallets to protect them from future quantum attacks.<\/p>\n<p>If implemented, it would also remove fears of Satoshi\u2019s coins ever moving. <a href=\"https:\/\/t.co\/narF5XHoJr\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/narF5XHoJr<\/a><\/p>\n<p>&mdash; Crypto Rover (@cryptorover) <a href=\"https:\/\/twitter.com\/cryptorover\/status\/2044334182428713333?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 15, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>A proposta centra-se em 74 bilh\u00f5es de d\u00f3lares em Bitcoins antigos, minerados nos primeiros anos da rede e potencialmente ligados a Satoshi Nakamoto, cuja identidade permanece como um dos grandes mist\u00e9rios n\u00e3o resolvidos das criptomoedas.<\/p>\n<h2>\u00c9 realmente poss\u00edvel congelar a carteira de Satoshi?<\/h2>\n<p>Esta carteira utiliza um formato <a class=\"general-link\" href=\"http:\/\/99bitcoins.com\" target=\"_blank\" rel=\"noopener\">criptogr\u00e1fico<\/a> antigo chamado Pay-to-Public-Key (P2PK). Ele exp\u00f5e a chave p\u00fablica diretamente, tornando-a teoricamente vulner\u00e1vel a computadores qu\u00e2nticos suficientemente avan\u00e7ados. No argumento de Lopp, se ningu\u00e9m puder provar que Satoshi est\u00e1 vivo para reivindicar as moedas, congel\u00e1-las \u00e9 prefer\u00edvel a assistir a um invasor qu\u00e2ntico drenar o tesouro original do Bitcoin. Um mecanismo de soft fork foi sugerido como o caminho t\u00e9cnico a seguir.<\/p>\n<p>O debate atinge o cerne do que \u00e9 o Bitcoin: propriedade, protocolo ou bem p\u00fablico. E surge em um momento em que o \u00edmpeto de pre\u00e7o do BTC j\u00e1 est\u00e1 exigindo aten\u00e7\u00e3o.<\/p>\n<div class=\"chart crypto-chart-instance\" id=\"crypto_chart_6a57b0335a16b\"\n\tdata-coin-id=\"bitcoin\">\n\t<div class=\"chart__header\">\n\t\t<div class=\"chart__info\">\n\t\t\t<div class=\"chart__info-icon\">\n\t\t\t\t<img id=\"crypto_chart_6a57b0335a16b-chart__info-icon-img\" \/>\n\t\t\t\t<div class=\"chart__info-name\" id=\"crypto_chart_6a57b0335a16b-chart__info-name\"><\/div>\n\t\t\t\t<div class=\"chart__info-symbol\" id=\"crypto_chart_6a57b0335a16b-chart__info-symbol\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-current\">\n\t\t\t\t<div class=\"chart__info-price\" id=\"crypto_chart_6a57b0335a16b-chart__info-price\"><\/div>\n\t\t\t\t<div class=\"chart__info-change\" id=\"crypto_chart_6a57b0335a16b-chart__info-change\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-extra\">\n\t\t\t\t<div class=\"chart__info-label\">Market Cap<\/div>\n\t\t\t\t<div class=\"chart__info-marketcap\" id=\"crypto_chart_6a57b0335a16b-chart__info-marketcap\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"chart__controls\">\n\t\t\t<div class=\"chart__controls-group\">\n\t\t\t\t<button class=\"chart__button chart__button--24h\"\n\t\t\t\t\tid=\"crypto_chart_6a57b0335a16b-btn-24h\">24h<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--7d\"\n\t\t\t\t\tid=\"crypto_chart_6a57b0335a16b-btn-7d\">7d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--30d\"\n\t\t\t\t\tid=\"crypto_chart_6a57b0335a16b-btn-30d\">30d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--1y\"\n\t\t\t\t\tid=\"crypto_chart_6a57b0335a16b-btn-1y\">1y<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--all-time\"\n\t\t\t\t\tid=\"crypto_chart_6a57b0335a16b-btn-all-time\">All Time<\/button>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"chart__container\">\n\t\t<canvas class=\"chart__canvas\" id=\"crypto_chart_6a57b0335a16b-cryptoChart\"><\/canvas>\n\t<\/div>\n<\/div>\n\n<p>O Bitcoin mant\u00e9m-se firme ap\u00f3s um per\u00edodo de volatilidade. A faixa de 48 horas variou de 72.000 USD a 76.000 USD, com o volume de negocia\u00e7\u00e3o saltando 24% para 59 bilh\u00f5es de d\u00f3lares. O ganho semanal situa-se em +4%, impulsionado em parte por um rali desencadeado por cessar-fogo que liquidou entre 470 e 595 milh\u00f5es de d\u00f3lares em posi\u00e7\u00f5es vendidas (short), o squeeze mais acentuado desde mar\u00e7o.<\/p>\n<h2>LiquidChain pode sobreviver \u00e0 computa\u00e7\u00e3o qu\u00e2ntica<\/h2>\n<p>O Bitcoin a 73.000 USD \u00e9 empolgante, mas um valor de mercado de 1,4 trilh\u00e3o de d\u00f3lares significa que a matem\u00e1tica da multiplica\u00e7\u00e3o torna-se mais dif\u00edcil, exceto para investidores com capital massivo, na casa dos bilh\u00f5es de d\u00f3lares. Os investidores que buscam retornos assim\u00e9tricos est\u00e3o cada vez mais voltados para projetos de infraestrutura em est\u00e1gio inicial antes que cheguem aos mercados p\u00fablicos. \u00c9 nessa janela que a <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/br\/visit\/liquidchain\" target=\"_blank\" rel=\"nofollow noopener sponsored\">LiquidChain<\/a> se encontra atualmente.<\/p>\n<p>A LiquidChain ($LIQUID) \u00e9 um projeto de infraestrutura de Camada 3 constru\u00eddo em torno de uma frustra\u00e7\u00e3o espec\u00edfica que a maioria dos usu\u00e1rios de DeFi j\u00e1 sentiu: a liquidez de Bitcoin, Ethereum e Solana vive em silos separados, for\u00e7ando os usu\u00e1rios a passarem por pontes (bridges) complexas e transa\u00e7\u00f5es de m\u00faltiplas etapas.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">No entry. Only initiation. \u27c1\ud83d\udc41<a href=\"https:\/\/t.co\/vqvBcdSQYC\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/vqvBcdSQYC<\/a> <a href=\"https:\/\/t.co\/aiOryR1ERN\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/aiOryR1ERN<\/a><\/p>\n<p>&mdash; LiquidChain (@getliquidchain) <a href=\"https:\/\/twitter.com\/getliquidchain\/status\/2044293986052124979?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">April 15, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>A Camada de Liquidez Unificada da LiquidChain funde os tr\u00eas ecossistemas em um \u00fanico ambiente de execu\u00e7\u00e3o, onde os desenvolvedores implementam uma vez e acessam as tr\u00eas redes, enquanto os usu\u00e1rios obt\u00eam execu\u00e7\u00e3o em uma \u00fanica etapa com liquida\u00e7\u00e3o verific\u00e1vel.<\/p>\n<p>O pre\u00e7o da pr\u00e9-venda est\u00e1 em <strong>0,01449 USD<\/strong>, com <strong>670.000 USD<\/strong> arrecadados at\u00e9 o momento, ent\u00e3o ainda \u00e9 cedo, mas o tempo para adquirir a pre\u00e7os baixos est\u00e1 se esgotando. O debate sobre computa\u00e7\u00e3o qu\u00e2ntica, inclusive, refor\u00e7a o porqu\u00ea de uma infraestrutura cross-chain que n\u00e3o dependa das premissas criptogr\u00e1ficas de uma \u00fanica rede ter uma tese coerente de longo prazo.<\/p>\n<p><strong>Pesquise a LiquidChain cuidadosamente antes de comprometer capital. Para aqueles que fizeram a li\u00e7\u00e3o de casa: <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/br\/visit\/liquidchain\" target=\"_blank\" rel=\"nofollow noopener sponsored\">explore a pr\u00e9-venda da LiquidChain aqui<\/a>.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jameson Lopp prop\u00f5e o congelamento de 74 bilh\u00f5es de d\u00f3lares nas carteiras de Bitcoin de Satoshi para prote\u00e7\u00e3o contra amea\u00e7as de computa\u00e7\u00e3o qu\u00e2ntica. Al\u00e9m disso: an\u00e1lise de pre\u00e7o do BTC com n\u00edveis-alvo de 80.000 USD e zonas de suporte explicadas.<\/p>\n","protected":false},"author":136254,"featured_media":39967,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8],"tags":[51],"coin":[2],"class_list":["post-39971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pre-vendas","tag-bitcoin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp - 99Bitcoins Brasil<\/title>\n<meta name=\"description\" content=\"O Bitcoin apresenta um bom desempenho esta semana, registrando uma alta de 4%, mas a comunidade tem um novo motivo para prestar aten\u00e7\u00e3o al\u00e9m dos gr\u00e1ficos de pre\u00e7os\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp - 99Bitcoins Brasil\" \/>\n<meta property=\"og:description\" content=\"O Bitcoin apresenta um bom desempenho esta semana, registrando uma alta de 4%, mas a comunidade tem um novo motivo para prestar aten\u00e7\u00e3o al\u00e9m dos gr\u00e1ficos de pre\u00e7os\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T13:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe editorial do 99Bitcoins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe editorial do 99Bitcoins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/\"},\"author\":{\"name\":\"Equipe editorial do 99Bitcoins\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/7ed63544911dda5f5ee710350491aa93\"},\"headline\":\"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp\",\"datePublished\":\"2026-04-15T13:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/\"},\"wordCount\":637,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/04\\\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg\",\"keywords\":[\"Bitcoin\"],\"articleSection\":[\"Pr\u00e9-vendas\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/\",\"name\":\"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp - 99Bitcoins Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/04\\\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg\",\"datePublished\":\"2026-04-15T13:00:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/7ed63544911dda5f5ee710350491aa93\"},\"description\":\"O Bitcoin apresenta um bom desempenho esta semana, registrando uma alta de 4%, mas a comunidade tem um novo motivo para prestar aten\u00e7\u00e3o al\u00e9m dos gr\u00e1ficos de pre\u00e7os\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/04\\\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/04\\\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pr\u00e9-vendas\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/pre-vendas\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"name\":\"99Bitcoins Brasil\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/7ed63544911dda5f5ee710350491aa93\",\"name\":\"Equipe editorial do 99Bitcoins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g\",\"caption\":\"Equipe editorial do 99Bitcoins\"},\"description\":\"Desde 2013, a equipe editorial do 99Bitcoins oferece conte\u00fado especializado, confi\u00e1vel e de f\u00e1cil compreens\u00e3o sobre criptomoedas. Nosso time de analistas e pesquisadores experientes simplifica temas complexos tanto para iniciantes quanto para entusiastas do mercado cripto.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/author\\\/equipeeditorialdo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp - 99Bitcoins Brasil","description":"O Bitcoin apresenta um bom desempenho esta semana, registrando uma alta de 4%, mas a comunidade tem um novo motivo para prestar aten\u00e7\u00e3o al\u00e9m dos gr\u00e1ficos de pre\u00e7os","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/","og_locale":"pt_BR","og_type":"article","og_title":"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp - 99Bitcoins Brasil","og_description":"O Bitcoin apresenta um bom desempenho esta semana, registrando uma alta de 4%, mas a comunidade tem um novo motivo para prestar aten\u00e7\u00e3o al\u00e9m dos gr\u00e1ficos de pre\u00e7os","og_url":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/","og_site_name":"99Bitcoins Brasil","article_published_time":"2026-04-15T13:00:10+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg","type":"image\/jpeg"}],"author":"Equipe editorial do 99Bitcoins","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Equipe editorial do 99Bitcoins","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/"},"author":{"name":"Equipe editorial do 99Bitcoins","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/7ed63544911dda5f5ee710350491aa93"},"headline":"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp","datePublished":"2026-04-15T13:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/"},"wordCount":637,"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg","keywords":["Bitcoin"],"articleSection":["Pr\u00e9-vendas"],"inLanguage":"pt-BR","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/","url":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/","name":"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp - 99Bitcoins Brasil","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg","datePublished":"2026-04-15T13:00:10+00:00","author":{"@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/7ed63544911dda5f5ee710350491aa93"},"description":"O Bitcoin apresenta um bom desempenho esta semana, registrando uma alta de 4%, mas a comunidade tem um novo motivo para prestar aten\u00e7\u00e3o al\u00e9m dos gr\u00e1ficos de pre\u00e7os","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/#primaryimage","url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg","contentUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/04\/satoshi-nakamoto-statue-wallet-frozen-theme.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/proposta-de-congelar-74-bilhoes-de-dolares-em-bitcoin-na-carteira-de-satoshi-para-combater-computacao-quantica-sugestao-de-jameson-lopp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/99bitcoins.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Pr\u00e9-vendas","item":"https:\/\/99bitcoins.com\/br\/noticias\/pre-vendas\/"},{"@type":"ListItem","position":4,"name":"Proposta de congelar 74 bilh\u00f5es de d\u00f3lares em Bitcoin na carteira de Satoshi para combater computa\u00e7\u00e3o qu\u00e2ntica: Sugest\u00e3o de Jameson Lopp"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/br\/#website","url":"https:\/\/99bitcoins.com\/br\/","name":"99Bitcoins Brasil","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/7ed63544911dda5f5ee710350491aa93","name":"Equipe editorial do 99Bitcoins","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g","caption":"Equipe editorial do 99Bitcoins"},"description":"Desde 2013, a equipe editorial do 99Bitcoins oferece conte\u00fado especializado, confi\u00e1vel e de f\u00e1cil compreens\u00e3o sobre criptomoedas. Nosso time de analistas e pesquisadores experientes simplifica temas complexos tanto para iniciantes quanto para entusiastas do mercado cripto.","url":"https:\/\/99bitcoins.com\/br\/author\/equipeeditorialdo\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/39971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/users\/136254"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/comments?post=39971"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/39971\/revisions"}],"predecessor-version":[{"id":39980,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/39971\/revisions\/39980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media\/39967"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media?parent=39971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/categories?post=39971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/tags?post=39971"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/coin?post=39971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}