{"id":38063,"date":"2026-01-23T10:02:48","date_gmt":"2026-01-23T10:02:48","guid":{"rendered":"https:\/\/99bitcoins.com\/br\/?p=38063"},"modified":"2026-01-23T10:02:11","modified_gmt":"2026-01-23T10:02:11","slug":"mercado-cripto-hoje-23-01","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/","title":{"rendered":"Mercado cripto hoje (23\/01) &#8211; Davos exp\u00f5e falhas do sistema financeiro: o que o BTC ganha com isso?"},"content":{"rendered":"<p>O mercado cripto hoje (23\/01) parece calmo. O Bitcoin se mant\u00e9m est\u00e1vel logo abaixo de 90.000 USD. O Ethereum, embora tenha ca\u00eddo 10% esta semana, parece pronto para se beneficiar das conversas de tokeniza\u00e7\u00e3o em Davos.<\/p>\n<p>Ali\u00e1s, Davos est\u00e1 expondo rachaduras no antigo sistema financeiro enquanto, acidentalmente, anuncia um novo. A taxa de engajamento em conversas sobre Bitcoin come\u00e7a a subir durante este mercado de baixa sentimento.<\/p>\n<p>Davos se tornou um bom ve\u00edculo para o mercado cripto com liquida\u00e7\u00f5es, garantias, liquidez e saques. Palavras que decidem quem sobrevive ao pr\u00f3ximo choque financeiro. \u00c0 medida que os pain\u00e9is est\u00e3o terminando, fica claro que criptoativos s\u00e3o eficientes e que o tempo \u00e9 tudo o que precisamos.<\/p>\n<div class=\"chart crypto-chart-instance\" id=\"crypto_chart_6a57c7b553ed1\"\n\tdata-coin-id=\"bitcoin\">\n\t<div class=\"chart__header\">\n\t\t<div class=\"chart__info\">\n\t\t\t<div class=\"chart__info-icon\">\n\t\t\t\t<img id=\"crypto_chart_6a57c7b553ed1-chart__info-icon-img\" \/>\n\t\t\t\t<div class=\"chart__info-name\" id=\"crypto_chart_6a57c7b553ed1-chart__info-name\"><\/div>\n\t\t\t\t<div class=\"chart__info-symbol\" id=\"crypto_chart_6a57c7b553ed1-chart__info-symbol\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-current\">\n\t\t\t\t<div class=\"chart__info-price\" id=\"crypto_chart_6a57c7b553ed1-chart__info-price\"><\/div>\n\t\t\t\t<div class=\"chart__info-change\" id=\"crypto_chart_6a57c7b553ed1-chart__info-change\"><\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"chart__info-extra\">\n\t\t\t\t<div class=\"chart__info-label\">Market Cap<\/div>\n\t\t\t\t<div class=\"chart__info-marketcap\" id=\"crypto_chart_6a57c7b553ed1-chart__info-marketcap\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"chart__controls\">\n\t\t\t<div class=\"chart__controls-group\">\n\t\t\t\t<button class=\"chart__button chart__button--24h\"\n\t\t\t\t\tid=\"crypto_chart_6a57c7b553ed1-btn-24h\">24h<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--7d\"\n\t\t\t\t\tid=\"crypto_chart_6a57c7b553ed1-btn-7d\">7d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--30d\"\n\t\t\t\t\tid=\"crypto_chart_6a57c7b553ed1-btn-30d\">30d<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--1y\"\n\t\t\t\t\tid=\"crypto_chart_6a57c7b553ed1-btn-1y\">1y<\/button>\n\t\t\t\t<button class=\"chart__button chart__button--all-time\"\n\t\t\t\t\tid=\"crypto_chart_6a57c7b553ed1-btn-all-time\">All Time<\/button>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"chart__container\">\n\t\t<canvas class=\"chart__canvas\" id=\"crypto_chart_6a57c7b553ed1-cryptoChart\"><\/canvas>\n\t<\/div>\n<\/div>\n\n<h2>Davos e o teste de estresse de 14 bilh\u00f5es de USD que o cripto suportou<\/h2>\n<p>Uma das maiores conversas em Davos veio de CZ, cofundador da Binance, que casualmente mencionou um n\u00famero que abalou os banqueiros tradicionais. 14 bilh\u00f5es de USD em saques l\u00edquidos ap\u00f3s o colapso da FTX, com 7 bilh\u00f5es de USD saindo em um \u00fanico dia. Os bancos, por outro lado, ele sugeriu, entrariam em colapso sob press\u00e3o semelhante, enquanto o cripto processou tudo.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">In a single week, Binance processed $14B in withdrawals.<\/p>\n<p>All without freezing access or breaking flow.<a href=\"https:\/\/twitter.com\/cz_binance?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@cz_binance<\/a> highlighted this at Davos as a live proof of crypto infra under real stress.<\/p>\n<p>Few traditional banks could stay solvent under that kind of load.<\/p>\n<p>Transparency, full\u2026 <a href=\"https:\/\/t.co\/alIJYJuko4\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/alIJYJuko4<\/a><\/p>\n<p>&mdash; nezuko \u2661 (@nezukodefi) <a href=\"https:\/\/twitter.com\/nezukodefi\/status\/2014319594782044587?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 22, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>O CEO da Coinbase, Brian Armstrong, tamb\u00e9m est\u00e1 alimentando o argumento ao apontar algo raramente pensado. Os bancos emprestam seu dinheiro sem perguntar.<\/p>\n<p>Pouco antes disso, ele tamb\u00e9m teve uma troca acalorada com o governador do Banco da Fran\u00e7a. Armstrong enquadrou o Bitcoin como um livro-raz\u00e3o de responsabilidade, especialmente para pa\u00edses que lidam com gastos deficit\u00e1rios impulsionados pela infla\u00e7\u00e3o.<\/p>\n<p style=\"padding-left: 40px\"><b>\ud83d\udc49Procurando pela <\/b><a href=\"https:\/\/99bitcoins.com\/br\/criptomoedas\/bitcoin\/grafico-preco-hoje\/\"><b>previs\u00e3o Bitcoin<\/b><\/a><b> e estimativas de pre\u00e7o para os pr\u00f3ximos anos? Neste artigo, apresentaremos uma an\u00e1lise t\u00e9cnica<\/b><span style=\"font-weight: 400\">.<\/span><\/p>\n<p>Armstrong destacou que o Bitcoin \u00e9 descentralizado, sem uma \u00fanica entidade controlando-o, durante o argumento, em oposi\u00e7\u00e3o ao que o governador do Banco da Fran\u00e7a est\u00e1 tentando propor.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">JUST IN: Coinbase CEO calls out Franch Central Bank governer:<\/p>\n<p>\u201cBitcoin doesn&#39;t have a money printer. It&#39;s more independent\u201d <a href=\"https:\/\/t.co\/2eW02mEaCy\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/2eW02mEaCy<\/a><\/p>\n<p>&mdash; Bitcoin Magazine (@BitcoinMagazine) <a href=\"https:\/\/twitter.com\/BitcoinMagazine\/status\/2013948341080441300?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 21, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Tokeniza\u00e7\u00e3o e m\u00e1quinas<\/h2>\n<p>Tokeniza\u00e7\u00e3o em um Davos dominado por cripto. Vimos l\u00edderes falando sobre ativos reais, liquida\u00e7\u00f5es reais e ganhos reais de efici\u00eancia. CZ, novamente, at\u00e9 sugeriu um futuro onde agentes de IA transacionam usando as redes de cripto, pulando cart\u00f5es e bancos inteiramente porque a automa\u00e7\u00e3o n\u00e3o precisa de intermedi\u00e1rios.<\/p>\n<p>As stablecoins de cripto tamb\u00e9m est\u00e3o em destaque em Davos. As stablecoins s\u00e3o enquadradas n\u00e3o como ferramentas especulativas, mas como infraestrutura de backend, e j\u00e1 processam mais volume do que Visa e Mastercard. Jeremy Allaire, da Circle, argumentou que stablecoins que rendem juros n\u00e3o s\u00e3o uma amea\u00e7a \u00e0 soberania, mas uma vantagem competitiva. Brad Garlinghouse, da Ripple, chamou os <a href=\"https:\/\/x.com\/bgarlinghouse\/status\/2013947648093413811?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E2013947648093413811%7Ctwgr%5Eb59b6184470cff4097baa7cbfbedbea0cd3ee4c7%7Ctwcon%5Es1_&amp;ref_url=https%3A%2F%2F99bitcoins.com%2Fnews%2Faltcoins%2Fcrypto-market-news-today-january-23-bank-cant-handle-14-billion-withdrawal-what-crypto-learn-from-davos%2F\" rel=\"nofollow\" target=\"_blank\">debates de &#8216;animados&#8217;<\/a>.<\/p>\n<p>Ativos do mundo real agora somam cerca de 28 bilh\u00f5es de USD no TVL de DeFi, com proje\u00e7\u00f5es que chegam aos trilh\u00f5es at\u00e9 2030. O Ethereum se beneficia, naturalmente, especialmente com o JP Morgan ativo no Ethereum.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udea8 BREAKING:<\/p>\n<p>J.P. Morgan, the world\u2019s largest bank, is now live on Ethereum.<\/p>\n<p>The official RWA product is My OnChain Net Yield Fund (\u201cMONY\u201d), powered by JPM Kinexys.<\/p>\n<p>Tokenization isn\u2019t theory anymore.<br \/>It\u2019s bank-grade financial infrastructure. <a href=\"https:\/\/t.co\/NwFJMgwehw\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/NwFJMgwehw<\/a><\/p>\n<p>&mdash; Merlijn The Trader (@MerlijnTrader) <a href=\"https:\/\/twitter.com\/MerlijnTrader\/status\/2014246659497119916?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 22, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\"><b>\ud83d\udc49 Saiba tamb\u00e9m sobre<\/b><b> investimento em <a href=\"https:\/\/99bitcoins.com\/br\/trading\/futuros-perpetuos-guia-negociacao\/\">futuros de Bitcoin<\/a><\/b><b>. 99Bitcoins tem um guia sobre o tema.<\/b><\/p>\n<h2>Regula\u00e7\u00e3o, realidade e momento<\/h2>\n<p>A regula\u00e7\u00e3o substituiu a ret\u00f3rica. CZ alertou que as regras globais n\u00e3o ser\u00e3o \u00fanicas para todos. Finan\u00e7as n\u00e3o s\u00e3o uma tomada universal. Armstrong defendeu os rendimentos das stablecoins como uma forma de manter os EUA competitivos com seu d\u00f3lar, enquanto David Sacks vinculou a lideran\u00e7a em cripto diretamente \u00e0 domin\u00e2ncia da IA. At\u00e9 os bancos seguiram o mesmo caminho, com executivos chamando abertamente o blockchain de futuro.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\u203c\ufe0fDAVID SACKS: \u201cAFTER THE MARKET STRUCTURE BILL PASSES, BANKS ARE GOING TO FULLY GET INTO CRYPTO\u201d\u203c\ufe0f<\/p>\n<p>Just in from Davos 2026.\ud83d\ude0f\ud83d\udca8<\/p>\n<p>Watch.\ud83d\udc47 <a href=\"https:\/\/t.co\/FZvjKDyDGg\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/FZvjKDyDGg<\/a><\/p>\n<p>&mdash; SMQKE (@SMQKEDQG) <a href=\"https:\/\/twitter.com\/SMQKEDQG\/status\/2013974510798594306?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">January 21, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Os Emirados \u00c1rabes Unidos receberam elogios como um centro de inova\u00e7\u00e3o, os modelos de privacidade mudaram para conformidade configur\u00e1vel, e as a\u00e7\u00f5es tokenizadas atingiram recordes de capitaliza\u00e7\u00e3o de mercado. Nada disso pareceu especulativo desta vez. Em Davos, o tom em rela\u00e7\u00e3o ao cripto foi pr\u00e1tico, e \u00e9 otimista.<\/p>\n<p>Reuni\u00f5es anteriores de Davos n\u00e3o entregaram nada; esta forneceu projetos para o que vem a seguir para o cripto. Na minha opini\u00e3o, se as finan\u00e7as fossem encanamento, o TradFi ainda estaria discutindo materiais de tubula\u00e7\u00e3o enquanto o cripto simplesmente redireciona a \u00e1gua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mercado de cripto est\u00e1 calmo hoje. O Bitcoin se mant\u00e9m est\u00e1vel logo abaixo de 90.000 USD. O Ethereum, embora tenha ca\u00eddo 10% esta semana, parece pronto para se beneficiar das conversas de tokeniza\u00e7\u00e3o em Davos. Davos est\u00e1 expondo rachaduras no sistema antigo enquanto, acidentalmente, anuncia o novo. A taxa de engajamento em conversas sobre Bitcoin come\u00e7a a subir durante este mercado de baixa sentimento.<\/p>\n","protected":false},"author":136254,"featured_media":38065,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[7],"tags":[320,51,1751,119],"coin":[2],"class_list":["post-38063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-binance","tag-bitcoin","tag-davos","tag-ethereum"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercado cripto hoje - Davos e as falhas do sistema banc\u00e1rio - 99Bitcoins Brasil<\/title>\n<meta name=\"description\" content=\"Davos se tornou um ve\u00edculo para o mercado cripto com liquida\u00e7\u00f5es, garantias e liquidez - Quem sobrevive ao pr\u00f3ximo choque financeiro?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercado cripto hoje - Davos e as falhas do sistema banc\u00e1rio - 99Bitcoins Brasil\" \/>\n<meta property=\"og:description\" content=\"Davos se tornou um ve\u00edculo para o mercado cripto com liquida\u00e7\u00f5es, garantias e liquidez - Quem sobrevive ao pr\u00f3ximo choque financeiro?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T10:02:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/Davos-2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"879\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe editorial do 99Bitcoins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe editorial do 99Bitcoins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/\"},\"author\":{\"name\":\"Equipe editorial do 99Bitcoins\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/7ed63544911dda5f5ee710350491aa93\"},\"headline\":\"Mercado cripto hoje (23\\\/01) &#8211; Davos exp\u00f5e falhas do sistema financeiro: o que o BTC ganha com isso?\",\"datePublished\":\"2026-01-23T10:02:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/\"},\"wordCount\":870,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/01\\\/Davos-2026.jpg\",\"keywords\":[\"Binance\",\"Bitcoin\",\"Davos\",\"Ethereum\"],\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/\",\"name\":\"Mercado cripto hoje - Davos e as falhas do sistema banc\u00e1rio - 99Bitcoins Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/01\\\/Davos-2026.jpg\",\"datePublished\":\"2026-01-23T10:02:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/7ed63544911dda5f5ee710350491aa93\"},\"description\":\"Davos se tornou um ve\u00edculo para o mercado cripto com liquida\u00e7\u00f5es, garantias e liquidez - Quem sobrevive ao pr\u00f3ximo choque financeiro?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/01\\\/Davos-2026.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/01\\\/Davos-2026.jpg\",\"width\":1200,\"height\":879,\"caption\":\"mercado cripto hoje - Davos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/mercado-cripto-hoje-23-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Not\u00edcias do Mercado\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mercado cripto hoje (23\\\/01) &#8211; Davos exp\u00f5e falhas do sistema financeiro: o que o BTC ganha com isso?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"name\":\"99Bitcoins Brasil\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/7ed63544911dda5f5ee710350491aa93\",\"name\":\"Equipe editorial do 99Bitcoins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g\",\"caption\":\"Equipe editorial do 99Bitcoins\"},\"description\":\"Desde 2013, a equipe editorial do 99Bitcoins oferece conte\u00fado especializado, confi\u00e1vel e de f\u00e1cil compreens\u00e3o sobre criptomoedas. Nosso time de analistas e pesquisadores experientes simplifica temas complexos tanto para iniciantes quanto para entusiastas do mercado cripto.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/author\\\/equipeeditorialdo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercado cripto hoje - Davos e as falhas do sistema banc\u00e1rio - 99Bitcoins Brasil","description":"Davos se tornou um ve\u00edculo para o mercado cripto com liquida\u00e7\u00f5es, garantias e liquidez - Quem sobrevive ao pr\u00f3ximo choque financeiro?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/","og_locale":"pt_BR","og_type":"article","og_title":"Mercado cripto hoje - Davos e as falhas do sistema banc\u00e1rio - 99Bitcoins Brasil","og_description":"Davos se tornou um ve\u00edculo para o mercado cripto com liquida\u00e7\u00f5es, garantias e liquidez - Quem sobrevive ao pr\u00f3ximo choque financeiro?","og_url":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/","og_site_name":"99Bitcoins Brasil","article_published_time":"2026-01-23T10:02:48+00:00","og_image":[{"width":1200,"height":879,"url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/Davos-2026.jpg","type":"image\/jpeg"}],"author":"Equipe editorial do 99Bitcoins","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Equipe editorial do 99Bitcoins","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/"},"author":{"name":"Equipe editorial do 99Bitcoins","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/7ed63544911dda5f5ee710350491aa93"},"headline":"Mercado cripto hoje (23\/01) &#8211; Davos exp\u00f5e falhas do sistema financeiro: o que o BTC ganha com isso?","datePublished":"2026-01-23T10:02:48+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/"},"wordCount":870,"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/Davos-2026.jpg","keywords":["Binance","Bitcoin","Davos","Ethereum"],"articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/","url":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/","name":"Mercado cripto hoje - Davos e as falhas do sistema banc\u00e1rio - 99Bitcoins Brasil","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/Davos-2026.jpg","datePublished":"2026-01-23T10:02:48+00:00","author":{"@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/7ed63544911dda5f5ee710350491aa93"},"description":"Davos se tornou um ve\u00edculo para o mercado cripto com liquida\u00e7\u00f5es, garantias e liquidez - Quem sobrevive ao pr\u00f3ximo choque financeiro?","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/#primaryimage","url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/Davos-2026.jpg","contentUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2026\/01\/Davos-2026.jpg","width":1200,"height":879,"caption":"mercado cripto hoje - Davos"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/mercado-cripto-hoje-23-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/99bitcoins.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Not\u00edcias do Mercado","item":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/"},{"@type":"ListItem","position":4,"name":"Mercado cripto hoje (23\/01) &#8211; Davos exp\u00f5e falhas do sistema financeiro: o que o BTC ganha com isso?"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/br\/#website","url":"https:\/\/99bitcoins.com\/br\/","name":"99Bitcoins Brasil","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/7ed63544911dda5f5ee710350491aa93","name":"Equipe editorial do 99Bitcoins","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29dd3e1c017de28afadb78e40787ca65f0c1985cdc427601886788700b303504?s=96&d=mm&r=g","caption":"Equipe editorial do 99Bitcoins"},"description":"Desde 2013, a equipe editorial do 99Bitcoins oferece conte\u00fado especializado, confi\u00e1vel e de f\u00e1cil compreens\u00e3o sobre criptomoedas. Nosso time de analistas e pesquisadores experientes simplifica temas complexos tanto para iniciantes quanto para entusiastas do mercado cripto.","url":"https:\/\/99bitcoins.com\/br\/author\/equipeeditorialdo\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/38063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/users\/136254"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/comments?post=38063"}],"version-history":[{"count":2,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/38063\/revisions"}],"predecessor-version":[{"id":38064,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/38063\/revisions\/38064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media\/38065"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media?parent=38063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/categories?post=38063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/tags?post=38063"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/coin?post=38063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}