{"id":29033,"date":"2025-10-09T17:45:29","date_gmt":"2025-10-09T17:45:29","guid":{"rendered":"https:\/\/99bitcoins.com\/br\/?p=29033"},"modified":"2025-10-09T17:46:50","modified_gmt":"2025-10-09T17:46:50","slug":"aster-em-risco-de-queda","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/","title":{"rendered":"Aster em risco: perda de suporte pode gerar queda de 30%, revela an\u00e1lise"},"content":{"rendered":"<p>O desempenho do Aster (ASTER) nesta quinta-feira (9\/10) \u00e9 preocupante. O pre\u00e7o j\u00e1 despencou cerca de 15% no dia, tornando o desempenho do ativo o pior entre as principais criptomoedas.<\/p>\n<p>O cen\u00e1rio chama aten\u00e7\u00e3o porque o ASTER havia se destacado semanas atr\u00e1s, ao valorizar mais de 2.000% em poucos dias. Agora, no entanto, os sinais s\u00e3o de enfraquecimento.<\/p>\n<p>Dados do CoinGecko mostram que o ativo negocia 30% abaixo da m\u00e1xima hist\u00f3rica de US$ 2,41. Al\u00e9m disso, corre o risco de perder a marca psicol\u00f3gica de US$ 1,50, movimento que poderia abrir espa\u00e7o para novas quedas.<\/p>\n<h2>A ascens\u00e3o e as pol\u00eamicas do ASTER<\/h2>\n<p>O Aster \u00e9 uma exchange descentralizada (DEX) dentro da BNB Chain, rede blockchain da Binance. O projeto rapidamente chamou a aten\u00e7\u00e3o, recebendo, inclusive, o endosso p\u00fablico do ex-CEO da <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/br\/trading\/corretoras-criptomoedas-iniciantes\/\" target=\"_blank\" rel=\"noopener\">corretora de criptomoedas<\/a>, Changpeng Zhao (CZ).<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">That&#39;s the correct quote! It&#39;s not that hard.\ud83e\udd23 <a href=\"https:\/\/t.co\/SNFLOyVIS0\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/SNFLOyVIS0<\/a><\/p>\n<p>&mdash; CZ \ud83d\udd36 BNB (@cz_binance) <a href=\"https:\/\/twitter.com\/cz_binance\/status\/1972018483304321384?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">September 27, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Em setembro, a plataforma chegou a liderar o setor de derivativos\u00a0descentralizados. No m\u00eas, seu volume de negocia\u00e7\u00e3o se aproximou da marca de US$ 500 bilh\u00f5es, consolidando o projeto como destaque no segmento DeFi.<\/p>\n<p>Por\u00e9m, a euforia durou pouco. Alguns analistas passaram a questionar a legitimidade das opera\u00e7\u00f5es, levantando acusa\u00e7\u00f5es de fraude contra a equipe do Aster.<\/p>\n<p>O golpe mais duro veio quando a DeFi Llama, uma das principais plataformas de dados do setor, decidiu retirar as informa\u00e7\u00f5es de negocia\u00e7\u00e3o da DEX.<\/p>\n<p>Essa decis\u00e3o abalou a confian\u00e7a dos investidores e gerou forte press\u00e3o vendedora sobre o token nativo. O resultado foi a queda acentuada de pre\u00e7o, que agora amea\u00e7a romper suportes importantes.<\/p>\n<h2>ASTER em risco<\/h2>\n<p>A queda desta quinta-feira (9\/10) levou o ASTER a testar novamente o n\u00edvel de retra\u00e7\u00e3o de 0,5 Fibonacci como suporte.<\/p>\n<p>Historicamente, esse n\u00edvel j\u00e1 proporcionou dois saltos relevantes: um de 50% e outro de 40%. Por\u00e9m, cada toque torna o suporte mais fr\u00e1gil, o que aumenta a chance de rompimento.<\/p>\n<figure id=\"attachment_29036\" aria-describedby=\"caption-attachment-29036\" style=\"width: 1357px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-29036\" src=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/ASTERUSDT_2025-10-09_13-53-31.png\" alt=\"Gr\u00e1fico do Aster (ASTER) no TradingView\" width=\"1357\" height=\"868\" srcset=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/ASTERUSDT_2025-10-09_13-53-31.png 1357w, https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/ASTERUSDT_2025-10-09_13-53-31-300x192.png 300w, https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/ASTERUSDT_2025-10-09_13-53-31-1024x655.png 1024w, https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/ASTERUSDT_2025-10-09_13-53-31-768x491.png 768w\" sizes=\"(max-width: 1357px) 100vw, 1357px\" \/><figcaption id=\"caption-attachment-29036\" class=\"wp-caption-text\">Gr\u00e1fico do ASTER no TradingView<\/figcaption><\/figure>\n<p>Caso esse patamar seja perdido, o pr\u00f3ximo alvo t\u00e9cnico se encontra em US$ 1,20, correspondente \u00e0 retra\u00e7\u00e3o de 0,618. Esse movimento representaria uma desvaloriza\u00e7\u00e3o de aproximadamente 30% em rela\u00e7\u00e3o ao pre\u00e7o atual.<\/p>\n<p>Os indicadores t\u00e9cnicos refor\u00e7am esse risco. O \u00cdndice de For\u00e7a Relativa (RSI) caiu abaixo de 50, sinalizando perda de for\u00e7a compradora. J\u00e1 o Chaikin Money Flow (CMF) entrou em territ\u00f3rio negativo, mostrando sa\u00edda de capital do ativo.<\/p>\n<figure id=\"attachment_29037\" aria-describedby=\"caption-attachment-29037\" style=\"width: 1335px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-29037\" src=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Captura-de-tela-2025-10-09-135453.png\" alt=\"RSI e CMF do Aster (ASTER) no TradingView\" width=\"1335\" height=\"323\" srcset=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Captura-de-tela-2025-10-09-135453.png 1335w, https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Captura-de-tela-2025-10-09-135453-300x73.png 300w, https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Captura-de-tela-2025-10-09-135453-1024x248.png 1024w, https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/10\/Captura-de-tela-2025-10-09-135453-768x186.png 768w\" sizes=\"(max-width: 1335px) 100vw, 1335px\" \/><figcaption id=\"caption-attachment-29037\" class=\"wp-caption-text\">RSI e CMF do ASTER no TradingView<\/figcaption><\/figure>\n<p>Esses sinais combinados sugerem que os vendedores mant\u00eam o controle no curto prazo, o que pode acelerar novas quedas.<\/p>\n<h2>Ponto de vista do 99Bitcoins<\/h2>\n<p>Na minha vis\u00e3o, o Aster ainda se configura como um hype passageiro, precisando provar sua sustentabilidade no longo prazo. O salto de pre\u00e7o inicial foi impressionante, mas os <a class=\"general-link\" href=\"https:\/\/x.com\/anndylian\/status\/1975014852650574098\" target=\"_blank\" rel=\"nofollow noopener\">questionamentos sobre a transpar\u00eancia<\/a>\u00a0pesam muito.<\/p>\n<p>Se a moeda n\u00e3o recuperar a credibilidade, o suporte atual dificilmente se manter\u00e1 por muito tempo. Assim, novas opera\u00e7\u00f5es no ativo se tornam extremamente arriscadas.<\/p>\n<p><b>\ud83d\udca1Descubra!<\/b><a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/br\/criptomoedas\/previsao\/proxima-criptomoeda-1000x\/\" target=\"_blank\" rel=\"noopener\"> <b>Pr\u00f3xima criptomoeda com potencial de 1000x<\/b><\/a><b> \u2013 candidatas a disparar em 2025.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O desempenho do Aster (ASTER) nesta quinta-feira (9\/10) \u00e9 preocupante. O pre\u00e7o j\u00e1 despencou cerca de 15% no dia, tornando o desempenho do ativo o pior entre as principais criptomoedas. O cen\u00e1rio chama aten\u00e7\u00e3o porque o ASTER havia se destacado semanas atr\u00e1s, ao valorizar mais de 2.000% em poucos dias. Agora, no entanto, os sinais..<\/p>\n","protected":false},"author":136211,"featured_media":27350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[6],"tags":[1352,72,160],"coin":[1351],"class_list":["post-29033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoin","tag-aster","tag-presales","tag-previsao-de-precos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aster em risco: perda de suporte pode gerar queda de 30%.- 99Bitcoins Brasil<\/title>\n<meta name=\"description\" content=\"O desempenho do ASTER nesta quinta-feira (9\/10) \u00e9 preocupante. O pre\u00e7o do ativo j\u00e1 despencou cerca de 15% no dia, e segue enfraquecendo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aster em risco: perda de suporte pode gerar queda de 30%.- 99Bitcoins Brasil\" \/>\n<meta property=\"og:description\" content=\"O desempenho do ASTER nesta quinta-feira (9\/10) \u00e9 preocupante. O pre\u00e7o do ativo j\u00e1 despencou cerca de 15% no dia, e segue enfraquecendo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-09T17:45:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T17:46:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/ASTER.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"andersonmuller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"andersonmuller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/\"},\"author\":{\"name\":\"andersonmuller\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/70f920069101505fc59819ab2382f47a\"},\"headline\":\"Aster em risco: perda de suporte pode gerar queda de 30%, revela an\u00e1lise\",\"datePublished\":\"2025-10-09T17:45:29+00:00\",\"dateModified\":\"2025-10-09T17:46:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/\"},\"wordCount\":546,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/09\\\/ASTER.png\",\"keywords\":[\"Aster\",\"Not\u00edcias de Pr\u00e9-venda\",\"previs\u00e3o de pre\u00e7os\"],\"articleSection\":[\"Not\u00edcias de Altcoin\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/\",\"name\":\"Aster em risco: perda de suporte pode gerar queda de 30%.- 99Bitcoins Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/09\\\/ASTER.png\",\"datePublished\":\"2025-10-09T17:45:29+00:00\",\"dateModified\":\"2025-10-09T17:46:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/70f920069101505fc59819ab2382f47a\"},\"description\":\"O desempenho do ASTER nesta quinta-feira (9\\\/10) \u00e9 preocupante. O pre\u00e7o do ativo j\u00e1 despencou cerca de 15% no dia, e segue enfraquecendo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/09\\\/ASTER.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/09\\\/ASTER.png\",\"width\":1200,\"height\":453,\"caption\":\"Aster hoje: pre\u00e7o pode continuar subindo, em meio a bear market?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/aster-em-risco-de-queda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Not\u00edcias de Altcoin\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Aster em risco: perda de suporte pode gerar queda de 30%, revela an\u00e1lise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"name\":\"99Bitcoins Brasil\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/70f920069101505fc59819ab2382f47a\",\"name\":\"andersonmuller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ad8f83f9808b4091ec47e051faa52e29be5584b3a228c163b07787a8890434a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ad8f83f9808b4091ec47e051faa52e29be5584b3a228c163b07787a8890434a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ad8f83f9808b4091ec47e051faa52e29be5584b3a228c163b07787a8890434a?s=96&d=mm&r=g\",\"caption\":\"andersonmuller\"},\"description\":\"Anderson \u00e9 formado em Administra\u00e7\u00e3o, com p\u00f3s-gradua\u00e7\u00e3o em Investimentos e Blockchain. Atua como escritor e analista no mercado de criptomoedas desde 2020, tendo produzido mais de 4 mil artigos e an\u00e1lises desde ent\u00e3o.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/author\\\/andersonmuller\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aster em risco: perda de suporte pode gerar queda de 30%.- 99Bitcoins Brasil","description":"O desempenho do ASTER nesta quinta-feira (9\/10) \u00e9 preocupante. O pre\u00e7o do ativo j\u00e1 despencou cerca de 15% no dia, e segue enfraquecendo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/","og_locale":"pt_BR","og_type":"article","og_title":"Aster em risco: perda de suporte pode gerar queda de 30%.- 99Bitcoins Brasil","og_description":"O desempenho do ASTER nesta quinta-feira (9\/10) \u00e9 preocupante. O pre\u00e7o do ativo j\u00e1 despencou cerca de 15% no dia, e segue enfraquecendo.","og_url":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/","og_site_name":"99Bitcoins Brasil","article_published_time":"2025-10-09T17:45:29+00:00","article_modified_time":"2025-10-09T17:46:50+00:00","og_image":[{"width":1200,"height":453,"url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/ASTER.png","type":"image\/png"}],"author":"andersonmuller","twitter_card":"summary_large_image","twitter_misc":{"Written by":"andersonmuller","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/"},"author":{"name":"andersonmuller","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/70f920069101505fc59819ab2382f47a"},"headline":"Aster em risco: perda de suporte pode gerar queda de 30%, revela an\u00e1lise","datePublished":"2025-10-09T17:45:29+00:00","dateModified":"2025-10-09T17:46:50+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/"},"wordCount":546,"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/ASTER.png","keywords":["Aster","Not\u00edcias de Pr\u00e9-venda","previs\u00e3o de pre\u00e7os"],"articleSection":["Not\u00edcias de Altcoin"],"inLanguage":"pt-BR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/","url":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/","name":"Aster em risco: perda de suporte pode gerar queda de 30%.- 99Bitcoins Brasil","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/ASTER.png","datePublished":"2025-10-09T17:45:29+00:00","dateModified":"2025-10-09T17:46:50+00:00","author":{"@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/70f920069101505fc59819ab2382f47a"},"description":"O desempenho do ASTER nesta quinta-feira (9\/10) \u00e9 preocupante. O pre\u00e7o do ativo j\u00e1 despencou cerca de 15% no dia, e segue enfraquecendo.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/#primaryimage","url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/ASTER.png","contentUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/09\/ASTER.png","width":1200,"height":453,"caption":"Aster hoje: pre\u00e7o pode continuar subindo, em meio a bear market?"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/aster-em-risco-de-queda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/99bitcoins.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Not\u00edcias de Altcoin","item":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/"},{"@type":"ListItem","position":4,"name":"Aster em risco: perda de suporte pode gerar queda de 30%, revela an\u00e1lise"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/br\/#website","url":"https:\/\/99bitcoins.com\/br\/","name":"99Bitcoins Brasil","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/70f920069101505fc59819ab2382f47a","name":"andersonmuller","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/4ad8f83f9808b4091ec47e051faa52e29be5584b3a228c163b07787a8890434a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ad8f83f9808b4091ec47e051faa52e29be5584b3a228c163b07787a8890434a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ad8f83f9808b4091ec47e051faa52e29be5584b3a228c163b07787a8890434a?s=96&d=mm&r=g","caption":"andersonmuller"},"description":"Anderson \u00e9 formado em Administra\u00e7\u00e3o, com p\u00f3s-gradua\u00e7\u00e3o em Investimentos e Blockchain. Atua como escritor e analista no mercado de criptomoedas desde 2020, tendo produzido mais de 4 mil artigos e an\u00e1lises desde ent\u00e3o.","url":"https:\/\/99bitcoins.com\/br\/author\/andersonmuller\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/29033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/users\/136211"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/comments?post=29033"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/29033\/revisions"}],"predecessor-version":[{"id":29051,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/29033\/revisions\/29051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media\/27350"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media?parent=29033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/categories?post=29033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/tags?post=29033"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/coin?post=29033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}