{"id":2039,"date":"2025-02-26T12:32:13","date_gmt":"2025-02-26T12:32:13","guid":{"rendered":"https:\/\/99bitcoins.com\/br\/?p=2039"},"modified":"2025-02-26T12:32:13","modified_gmt":"2025-02-26T12:32:13","slug":"autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/","title":{"rendered":"Autoridades dos Estados Unidos recuperaram US$ 31 milh\u00f5es em ativos furtados em hack"},"content":{"rendered":"<p>Autoridades dos Estados Unidos recuperaram US$ 31 milh\u00f5es em criptomoedas relacionadas ao hack da platataforma DeFi <span style=\"font-weight: 400\">Uranium Finance, em 2021. E a<\/span>s identidades dos hackers n\u00e3o foram divulgadas. <span style=\"font-weight: 400\">A plataforma j\u00e1 n\u00e3o existe.<\/span><\/p>\n<p>A Uranium foi <span style=\"font-weight: 400\">lan\u00e7ada em abril de 2021 na BNB Chain.\u00a0<\/span><span style=\"font-weight: 400\">Menos de um m\u00eas depois do lan\u00e7amento, hackers exploraram vulnerabilidades dos contratos inteligentes da Uranium. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Desse modo, manipularam balan\u00e7os e desviaram fundos. <\/span>Na ocasi\u00e3o, os valores furtados inclu\u00edram cerca de\u00a0<span style=\"font-weight: 400\"> US$ 36,8 milh\u00f5es em BNB e Binance USD (BUSD). <\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, levaram 80 Bitcoin (BTC), 1.800 Ether (ETH), 26.500 Polkadot (DOT), 5,7 million Tether (USDT), 638.000 Cardano (ADA) e 112.000 tokens U92 (criptomoeda nativa da Uranium).<\/span><\/p>\n<p>Desde o hack, o site da Uranium saiu do ar, e suas redes sociais ficaram inativas. Como resultado, as v\u00edtimas ficaram sem ter como buscar compensa\u00e7\u00e3o por suas perdas.<\/p>\n<p>Agora, os investigadores envolvidos no caso est\u00e3o buscando informa\u00e7\u00f5es sobre esses usu\u00e1rios e, por outro lado, aguardando que algumas das v\u00edtimas tamb\u00e9m procurem as autoridades<\/p>\n<h2>Hacks ca\u00edram 44% em compara\u00e7\u00e3o com 2024<\/h2>\n<p>Crimes cibern\u00e9ticos relacionados a criptomoedas apresentaram um expressivo decl\u00ednio em janeiro deste ano. Nesse m\u00eas, hackers furtaram US$ 73 milh\u00f5es, em 99 casos diferentes. Isso representa uma redu\u00e7\u00e3o de 44% em compara\u00e7\u00e3o a janeiro de 2024.<\/p>\n<p><span style=\"font-weight: 400\">Apesar de essa diminui\u00e7\u00e3o ser um sinal positivo no que diz respeito \u00e0 seguran\u00e7a do mercado cripto, os n\u00fameros s\u00e3o bem maiores do que os registrados em dezembro de 2024. Na \u00e9poca, hackers levaram &#8220;apenas&#8221; US$ 3,8 milh\u00f5es, segundo relat\u00f3rio da<\/span><span style=\"font-weight: 400\">\u00a0Immunefi.<\/span><\/p>\n<p>Enquanto isso, este m\u00eas de fevereiro tem sido um dos piores quando se trata de hacks. <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/portugal\/maior-hack-da-historia-das-criptomoedas\/\" target=\"_blank\" rel=\"noopener\">O golpe mais recente, envolvendo a Bybit<\/a>, drenou a cold wallet de Ethereum (ETH) da corretora. Como resultado, o furto correspondeu a cerca de US$ 1,5 bilh\u00e3o em cripto.<\/p>\n<p><b><i>Voc\u00ea tamb\u00e9m pode se interessar por essa leitura:<\/i><\/b><a href=\"https:\/\/99bitcoins.com\/br\/trading\/corretoras-bitcoin\/\"> <b>Corretoras Bitcoin: Guia de Plataformas de Trading para Brasileiros<\/b><\/a><\/p>\n<h2><strong>Banco brasileiro foi alvo de golpe recente<\/strong><\/h2>\n<p>Ainda neste m\u00eas de fevereiro, aqui no Brasil, um epis\u00f3dio de hack envolveu o banco Neon. Ap\u00f3s ter acesso ao banco de dados da empresa, um hacker solicitou RS$ 2,8 milh\u00f5es em Bitcoins (BTC). Em troca, n\u00e3o divulgaria as informa\u00e7\u00f5es dos clientes do banco digital.<\/p>\n<p>O banco n\u00e3o confirmou o n\u00famero de clientes afetados. No total, o Neon tem cerca de 30 milh\u00f5es de usu\u00e1rios. Segundo a institui\u00e7\u00e3o, a investiga\u00e7\u00e3o est\u00e1 em andamento.<\/p>\n<p><a class=\"general-link\" href=\"https:\/\/valor.globo.com\/financas\/noticia\/2025\/02\/12\/suposto-hacker-obtem-dados-de-30-milhoes-de-clientes-de-banco-e-pede-recompensa-de-r-28-milhoes-por-ter-achado-falha.ghtml\" target=\"_blank\" rel=\"noopener nofollow\">Reportagem<\/a> do jornal Valor revelou que o hacker teve acesso a iinforma\u00e7\u00f5escomo, por exemplo, nome, CPF, CNPJ, telefone,\u00a0 renda, fotos de documentos, selfies e hist\u00f3rico de compras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades dos Estados Unidos recuperaram US$ 31 milh\u00f5es em criptomoedas relacionadas ao hack da platataforma DeFi Uranium Finance, em 2021. E as identidades dos hackers n\u00e3o foram divulgadas. A plataforma j\u00e1 n\u00e3o existe. A Uranium foi lan\u00e7ada em abril de 2021 na BNB Chain.\u00a0Menos de um m\u00eas depois do lan\u00e7amento, hackers exploraram vulnerabilidades dos contratos..<\/p>\n","protected":false},"author":136047,"featured_media":2048,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[7],"tags":[187,87,181,188,185,184,186],"coin":[103,2,189,76,190],"class_list":["post-2039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-banco-neon","tag-brasil","tag-estados-unidos","tag-golpes-ciberneticos","tag-hack","tag-hacker","tag-uranium-finance"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack cripto<\/title>\n<meta name=\"description\" content=\"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack de 2021. Recentemente, banco brasileiro tamb\u00e9m foi alvo de golpe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack cripto\" \/>\n<meta property=\"og:description\" content=\"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack de 2021. Recentemente, banco brasileiro tamb\u00e9m foi alvo de golpe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-26T12:32:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/hacker-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela de Lacerda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela de Lacerda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/\"},\"author\":{\"name\":\"Daniela de Lacerda\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/83df205cf2cb5c732d5bde671d21ab84\"},\"headline\":\"Autoridades dos Estados Unidos recuperaram US$ 31 milh\u00f5es em ativos furtados em hack\",\"datePublished\":\"2025-02-26T12:32:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/\"},\"wordCount\":458,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/hacker-unsplash.jpg\",\"keywords\":[\"Banco Neon\",\"Brasil\",\"Estados Unidos\",\"golpes cibern\u00e9ticos\",\"hack\",\"hacker\",\"Uranium Finance\"],\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/\",\"name\":\"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack cripto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/hacker-unsplash.jpg\",\"datePublished\":\"2025-02-26T12:32:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/83df205cf2cb5c732d5bde671d21ab84\"},\"description\":\"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack de 2021. Recentemente, banco brasileiro tamb\u00e9m foi alvo de golpe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/hacker-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/hacker-unsplash.jpg\",\"width\":1599,\"height\":840,\"caption\":\"Imagem: Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Not\u00edcias do Mercado\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Autoridades dos Estados Unidos recuperaram US$ 31 milh\u00f5es em ativos furtados em hack\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"name\":\"99Bitcoins Brasil\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/83df205cf2cb5c732d5bde671d21ab84\",\"name\":\"Daniela de Lacerda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g\",\"caption\":\"Daniela de Lacerda\"},\"description\":\"Daniela de Lacerda \u00e9 jornalista e pesquisadora, mestra em comunica\u00e7\u00e3o. H\u00e1 quatro anos atua como curadora de inova\u00e7\u00e3o em m\u00eddia, tecnologia e economia, incluindo o setor de criptomoedas. Como editora e rep\u00f3rter, trabalhou em grandes ve\u00edculos de comunica\u00e7\u00e3o do Brasil, nacionais e regionais, como a Editora Abril. Morou no Recife, em S\u00e3o Paulo e em Lisboa, onde estudou m\u00eddias digitais na Universidade Nova de Lisboa.\",\"sameAs\":[\"http:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/daniela-de-lacerda\\\/\"],\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/author\\\/danielalacerda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack cripto","description":"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack de 2021. Recentemente, banco brasileiro tamb\u00e9m foi alvo de golpe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/","og_locale":"pt_BR","og_type":"article","og_title":"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack cripto","og_description":"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack de 2021. Recentemente, banco brasileiro tamb\u00e9m foi alvo de golpe.","og_url":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/","og_site_name":"99Bitcoins Brasil","article_published_time":"2025-02-26T12:32:13+00:00","og_image":[{"width":1599,"height":840,"url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/hacker-unsplash.jpg","type":"image\/jpeg"}],"author":"Daniela de Lacerda","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniela de Lacerda","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/"},"author":{"name":"Daniela de Lacerda","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/83df205cf2cb5c732d5bde671d21ab84"},"headline":"Autoridades dos Estados Unidos recuperaram US$ 31 milh\u00f5es em ativos furtados em hack","datePublished":"2025-02-26T12:32:13+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/"},"wordCount":458,"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/hacker-unsplash.jpg","keywords":["Banco Neon","Brasil","Estados Unidos","golpes cibern\u00e9ticos","hack","hacker","Uranium Finance"],"articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/","url":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/","name":"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack cripto","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/hacker-unsplash.jpg","datePublished":"2025-02-26T12:32:13+00:00","author":{"@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/83df205cf2cb5c732d5bde671d21ab84"},"description":"Autoridades dos EUA recuperam US$ 31 milh\u00f5es em hack de 2021. Recentemente, banco brasileiro tamb\u00e9m foi alvo de golpe.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/#primaryimage","url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/hacker-unsplash.jpg","contentUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/hacker-unsplash.jpg","width":1599,"height":840,"caption":"Imagem: Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/autoridades-dos-estados-unidos-recuperaram-us-31-milhoes-em-ativos-furtados-em-hack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/99bitcoins.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Not\u00edcias do Mercado","item":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/"},{"@type":"ListItem","position":4,"name":"Autoridades dos Estados Unidos recuperaram US$ 31 milh\u00f5es em ativos furtados em hack"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/br\/#website","url":"https:\/\/99bitcoins.com\/br\/","name":"99Bitcoins Brasil","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/83df205cf2cb5c732d5bde671d21ab84","name":"Daniela de Lacerda","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/28cbb488d6f1b7586be98a9652c4c1e2538318bb72115fc6dc3b1256ecf6cf53?s=96&d=mm&r=g","caption":"Daniela de Lacerda"},"description":"Daniela de Lacerda \u00e9 jornalista e pesquisadora, mestra em comunica\u00e7\u00e3o. H\u00e1 quatro anos atua como curadora de inova\u00e7\u00e3o em m\u00eddia, tecnologia e economia, incluindo o setor de criptomoedas. Como editora e rep\u00f3rter, trabalhou em grandes ve\u00edculos de comunica\u00e7\u00e3o do Brasil, nacionais e regionais, como a Editora Abril. Morou no Recife, em S\u00e3o Paulo e em Lisboa, onde estudou m\u00eddias digitais na Universidade Nova de Lisboa.","sameAs":["http:\/\/99bitcoins.com\/br\/","https:\/\/www.linkedin.com\/in\/daniela-de-lacerda\/"],"url":"https:\/\/99bitcoins.com\/br\/author\/danielalacerda\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/2039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/users\/136047"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/comments?post=2039"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/2039\/revisions"}],"predecessor-version":[{"id":2056,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/2039\/revisions\/2056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media\/2048"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media?parent=2039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/categories?post=2039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/tags?post=2039"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/coin?post=2039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}