{"id":1950,"date":"2025-02-26T13:03:55","date_gmt":"2025-02-26T13:03:55","guid":{"rendered":"https:\/\/99bitcoins.com\/br\/?p=1950"},"modified":"2025-02-26T13:03:55","modified_gmt":"2025-02-26T13:03:55","slug":"raydium-despenca-com-rumores-de-novo-concorrente-na-solana","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/","title":{"rendered":"Raydium despenca com rumores de novo concorrente na Solana"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Na \u00faltima segunda-feira (24\/02), o token Raydium (RAY) sofreu uma desvaloriza\u00e7\u00e3o acentuada em meio \u00e0 crescente especula\u00e7\u00e3o de que a Pump.fun est\u00e1 desenvolvendo seu pr\u00f3prio recurso de criador de mercado automatizado (AMM).<\/span><\/p>\n<p><span style=\"font-weight: 400\">Se confirmado, o dom\u00ednio da Raydium como DEX da Solana pode estar com os dias contados.<\/span><\/p>\n<p><span style=\"font-weight: 400\">O rumor <\/span>surgiu do<span style=\"font-weight: 400\"> usu\u00e1rio do X (antigo Twitter) \u201ctrenchdiver\u201d, afirmando que a Pump.fun est\u00e1 testando pools de liquidez AMM.<\/span><\/p>\n<p><span style=\"font-weight: 400\"> Em resumo, essa tecnologia permite que os usu\u00e1rios negociem criptomoedas diretamente contra liquidez em contratos inteligentes, eliminando a necessidade de uma contraparte tradicional.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, &#8220;trenchdiver&#8221; <a class=\"general-link\" href=\"https:\/\/x.com\/trenchdiver101\/status\/1893814646718730393\" target=\"_blank\" rel=\"nofollow noopener\">tamb\u00e9m compartilhou um link<\/a> para uma interface beta com o logotipo Pump.fun, sugerindo que o projeto est\u00e1 bem encaminhado.<\/span><\/p>\n<h2>Pump.fun pode lan\u00e7ar AMM pr\u00f3prio<\/h2>\n<p><span style=\"font-weight: 400\">Atualmente, quando as memecoins lan\u00e7adas na Pump.fun atraem atividade de negocia\u00e7\u00e3o suficiente, elas transitam para a Raydium para serem negociadas. Essa transi\u00e7\u00e3o ocorre por meio de um processo chamado de \u201ccurva de liga\u00e7\u00e3o\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">No entanto, se a <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/pump-fun-plataforma-remove-de-circulacao-us-287-milhoes-em-tokens-solana\/\" target=\"_blank\" rel=\"noopener\">Pump.fun lan\u00e7ar seu AMM<\/a>, ela poder\u00e1 manter esses tokens em seu pr\u00f3prio ecossistema, potencialmente prejudicando o papel da Raydium.<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cParece que eles planejam que os tokens Pump sejam graduados em seus pr\u00f3prios pools, em vez de depender da Raydium\u201d, afirmou &#8220;trenchdiver&#8221;. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Dessa forma, essa mudan\u00e7a pode permitir que a Pump.fun extraia mais taxas ou implemente recompensas para seus detentores de tokens.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">EXCLUSIVE : <a href=\"https:\/\/twitter.com\/pumpdotfun?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">@pumpdotfun<\/a> is working on their own AMM liquidity pools, which is currently being tested on <a href=\"https:\/\/t.co\/nuir86gnkl\" rel=\"nofollow\" target=\"_blank\">https:\/\/t.co\/nuir86gnkl<\/a><\/p>\n<p>It seems they are planning to have pump tokens graduate to their own pools instead of Raydium so they can either extract more fees on Solana or have\u2026 <a href=\"https:\/\/t.co\/svmWfl6Rlt\" rel=\"nofollow\" target=\"_blank\">pic.twitter.com\/svmWfl6Rlt<\/a><\/p>\n<p>&mdash; trenchdiver (@trenchdiver101) <a href=\"https:\/\/twitter.com\/trenchdiver101\/status\/1893814646718730393?ref_src=twsrc%5Etfw\" rel=\"nofollow\" target=\"_blank\">February 24, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Apoiando essas especula\u00e7\u00f5es, dados on-chain de 20 de fevereiro mostram que a Pump.fun adicionou seu primeiro token de teste, Snowfall (CRACK), ao seu pool de liquidez AMM.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A Pump.fun nomeou o token em homenagem a uma s\u00e9rie de televis\u00e3o de 2017, que retratava a epidemia de crack dos anos 1980.<\/span><\/p>\n<p><span style=\"font-weight: 400\"> O valor de mercado do token disparou para US$ 5,4 milh\u00f5es em uma hora ap\u00f3s a publica\u00e7\u00e3o de &#8220;trenchdiver&#8221;, de acordo com dados do DEX Screener.<\/span><\/p>\n<p><span style=\"font-weight: 400\">No entanto, o token sofreu uma volatilidade significativa, com seu valor de mercado caindo para US$ 1,8 milh\u00e3o ap\u00f3s um decl\u00ednio de 40% no pre\u00e7o.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A Pump.fun ainda n\u00e3o confirmou oficialmente nenhum plano de desenvolvimento de AMM, mas as rea\u00e7\u00f5es do mercado foram r\u00e1pidas. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Tyler Warner, um apresentador de podcast, observou que o token da Raydium \u201cdespencou\u201d ap\u00f3s a not\u00edcia. Registrando uma queda de 25%, para US$ 3,22, em 24 horas, de acordo com dados do CoinGecko.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Enquanto isso, o RAY est\u00e1 sendo negociado atualmente a US$ 3,09, o que representa uma queda de mais de 28% no \u00faltimo dia. De acordo com <\/span><a class=\"general-link\" href=\"https:\/\/timetotrade.eu\/raydium-ray-price-analysis-can-the-token-recover-after-a-sharp-decline\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"font-weight: 400\">analistas<\/span><\/a><span style=\"font-weight: 400\">, se o RAY n\u00e3o conseguir se manter acima do suporte imediato de US$ 3,15, ele pode testar o n\u00edvel de US$ 3,00. Se cair, pode abrir a porta para novas quedas em dire\u00e7\u00e3o a US$ 2,85.<\/span><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p>\u00a0<\/p>\n<h2>Solana supera Ethereum como principal ecossistema para novos desenvolvedores<\/h2>\n<p><span style=\"font-weight: 400\">Conforme relatado, a <\/span><span style=\"font-weight: 400\">Solana ultrapassou o Ethereum<\/span>\u00a0como o principal destino para novos desenvolvedores em 2024. Quebrando, assim, o dom\u00ednio de <span style=\"font-weight: 400\">oito anos do Ethereum no espa\u00e7o.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Solana viu 7.625 novos desenvolvedores se juntarem ao seu ecossistema neste ano, superando os 6.456 do Ethereum. O aumento foi impulsionado, em grande parte, pelo aumento da atividade de desenvolvedores na \u00c1sia.<\/span><\/p>\n<p><span style=\"font-weight: 400\">O impulso da Solana come\u00e7ou em julho, quando ela ultrapassou oficialmente o Ethereum na integra\u00e7\u00e3o de novos desenvolvedores pela primeira vez desde 2016. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Essa tend\u00eancia continuou at\u00e9 o final de 2024, com a atividade de desenvolvedores da Solana crescendo 83%\u00a0 ao ano .<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima segunda-feira (24\/02), o token Raydium (RAY) sofreu uma desvaloriza\u00e7\u00e3o acentuada em meio \u00e0 crescente especula\u00e7\u00e3o de que a Pump.fun est\u00e1 desenvolvendo seu pr\u00f3prio recurso de criador de mercado automatizado (AMM). Se confirmado, o dom\u00ednio da Raydium como DEX da Solana pode estar com os dias contados. O rumor surgiu do usu\u00e1rio do X..<\/p>\n","protected":false},"author":136063,"featured_media":1811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[6],"tags":[19,66,182,191,80],"coin":[183,77],"class_list":["post-1950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoin","tag-criptomoedas","tag-memecoins","tag-pump-fun","tag-raydium","tag-solana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raydium despenca com rumores de novo concorrente na Solana - 99Bitcoins Brasil<\/title>\n<meta name=\"description\" content=\"A Raydim (RAY) est\u00e1 prestes a ter seu dom\u00ednio amea\u00e7ado com a concorr\u00eancia de mais um protocolo na disputa por formadores liquidez de mercado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raydium despenca com rumores de novo concorrente na Solana - 99Bitcoins Brasil\" \/>\n<meta property=\"og:description\" content=\"A Raydim (RAY) est\u00e1 prestes a ter seu dom\u00ednio amea\u00e7ado com a concorrencia de mais um protocolo na disputa por formadores liquidez de mercado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-26T13:03:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/solana-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thiago Venturini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"A Raydim (RAY) est\u00e1 prestes a ter seu dom\u00ednio amea\u00e7ado com a concorrencia de mais um protocolo na disputa por formadores liquidez de mercado.\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thiago Venturini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/\"},\"author\":{\"name\":\"Thiago Venturini\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/6dd74f728e10f96ff018439df51dd54d\"},\"headline\":\"Raydium despenca com rumores de novo concorrente na Solana\",\"datePublished\":\"2025-02-26T13:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/\"},\"wordCount\":587,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/solana-unsplash.jpg\",\"keywords\":[\"criptomoedas\",\"memecoins\",\"Pump.fun\",\"Raydium\",\"Solana\"],\"articleSection\":[\"Not\u00edcias de Altcoin\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/\",\"name\":\"Raydium despenca com rumores de novo concorrente na Solana - 99Bitcoins Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/solana-unsplash.jpg\",\"datePublished\":\"2025-02-26T13:03:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/6dd74f728e10f96ff018439df51dd54d\"},\"description\":\"A Raydim (RAY) est\u00e1 prestes a ter seu dom\u00ednio amea\u00e7ado com a concorr\u00eancia de mais um protocolo na disputa por formadores liquidez de mercado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/solana-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/solana-unsplash.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Imagem: Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Not\u00edcias de Altcoin\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/altcoin\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Raydium despenca com rumores de novo concorrente na Solana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"name\":\"99Bitcoins Brasil\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/6dd74f728e10f96ff018439df51dd54d\",\"name\":\"Thiago Venturini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dfb221ce1353c15bca09b9ab5b072f17344ecfea360a6b29e5673e5da0c2045?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dfb221ce1353c15bca09b9ab5b072f17344ecfea360a6b29e5673e5da0c2045?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dfb221ce1353c15bca09b9ab5b072f17344ecfea360a6b29e5673e5da0c2045?s=96&d=mm&r=g\",\"caption\":\"Thiago Venturini\"},\"description\":\"Thiago Venturini \u00e9 graduado em Comunica\u00e7\u00e3o pela Universidade Federal da Bahia (UFBA). Trabalho 3 anos como rep\u00f3rter cient\u00edfico cobrindo temas sobre ci\u00eancia e tecnologia. Gosta de descobrir projetos em fase mbrion\u00e1ria e revalar ao p\u00fablico mais amplo. Seu encontro com o universo das criptomoedas ocorreu em 2019. Desde ent\u00e3o se dedica a utilizar seu conhecimento para produzir conte\u00fade com lighugem simples cative o p\u00fablico mais amplo. Trabalhou por 3 anos no BeInCrypto, onde publicou mais de 1500 artigos sobre os diversos setores do mercado de criptomoedas, blockchain e Web3.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/author\\\/thiagobarboza\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raydium despenca com rumores de novo concorrente na Solana - 99Bitcoins Brasil","description":"A Raydim (RAY) est\u00e1 prestes a ter seu dom\u00ednio amea\u00e7ado com a concorr\u00eancia de mais um protocolo na disputa por formadores liquidez de mercado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/","og_locale":"pt_BR","og_type":"article","og_title":"Raydium despenca com rumores de novo concorrente na Solana - 99Bitcoins Brasil","og_description":"A Raydim (RAY) est\u00e1 prestes a ter seu dom\u00ednio amea\u00e7ado com a concorrencia de mais um protocolo na disputa por formadores liquidez de mercado.","og_url":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/","og_site_name":"99Bitcoins Brasil","article_published_time":"2025-02-26T13:03:55+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/solana-unsplash.jpg","type":"image\/jpeg"}],"author":"Thiago Venturini","twitter_card":"summary_large_image","twitter_description":"A Raydim (RAY) est\u00e1 prestes a ter seu dom\u00ednio amea\u00e7ado com a concorrencia de mais um protocolo na disputa por formadores liquidez de mercado.","twitter_misc":{"Written by":"Thiago Venturini","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/"},"author":{"name":"Thiago Venturini","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/6dd74f728e10f96ff018439df51dd54d"},"headline":"Raydium despenca com rumores de novo concorrente na Solana","datePublished":"2025-02-26T13:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/"},"wordCount":587,"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/solana-unsplash.jpg","keywords":["criptomoedas","memecoins","Pump.fun","Raydium","Solana"],"articleSection":["Not\u00edcias de Altcoin"],"inLanguage":"pt-BR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/","url":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/","name":"Raydium despenca com rumores de novo concorrente na Solana - 99Bitcoins Brasil","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/solana-unsplash.jpg","datePublished":"2025-02-26T13:03:55+00:00","author":{"@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/6dd74f728e10f96ff018439df51dd54d"},"description":"A Raydim (RAY) est\u00e1 prestes a ter seu dom\u00ednio amea\u00e7ado com a concorr\u00eancia de mais um protocolo na disputa por formadores liquidez de mercado.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/#primaryimage","url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/solana-unsplash.jpg","contentUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/solana-unsplash.jpg","width":1200,"height":800,"caption":"Imagem: Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/raydium-despenca-com-rumores-de-novo-concorrente-na-solana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/99bitcoins.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Not\u00edcias de Altcoin","item":"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/"},{"@type":"ListItem","position":4,"name":"Raydium despenca com rumores de novo concorrente na Solana"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/br\/#website","url":"https:\/\/99bitcoins.com\/br\/","name":"99Bitcoins Brasil","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/6dd74f728e10f96ff018439df51dd54d","name":"Thiago Venturini","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1dfb221ce1353c15bca09b9ab5b072f17344ecfea360a6b29e5673e5da0c2045?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1dfb221ce1353c15bca09b9ab5b072f17344ecfea360a6b29e5673e5da0c2045?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1dfb221ce1353c15bca09b9ab5b072f17344ecfea360a6b29e5673e5da0c2045?s=96&d=mm&r=g","caption":"Thiago Venturini"},"description":"Thiago Venturini \u00e9 graduado em Comunica\u00e7\u00e3o pela Universidade Federal da Bahia (UFBA). Trabalho 3 anos como rep\u00f3rter cient\u00edfico cobrindo temas sobre ci\u00eancia e tecnologia. Gosta de descobrir projetos em fase mbrion\u00e1ria e revalar ao p\u00fablico mais amplo. Seu encontro com o universo das criptomoedas ocorreu em 2019. Desde ent\u00e3o se dedica a utilizar seu conhecimento para produzir conte\u00fade com lighugem simples cative o p\u00fablico mais amplo. Trabalhou por 3 anos no BeInCrypto, onde publicou mais de 1500 artigos sobre os diversos setores do mercado de criptomoedas, blockchain e Web3.","url":"https:\/\/99bitcoins.com\/br\/author\/thiagobarboza\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/1950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/users\/136063"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/comments?post=1950"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/1950\/revisions"}],"predecessor-version":[{"id":2057,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/1950\/revisions\/2057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media\/1811"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media?parent=1950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/categories?post=1950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/tags?post=1950"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/coin?post=1950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}